{"id":7302,"date":"2019-09-17T15:49:17","date_gmt":"2019-09-17T20:49:17","guid":{"rendered":"http:\/\/ltam.newsroom.fb.com\/?p=7302"},"modified":"2020-11-09T17:30:51","modified_gmt":"2020-11-09T23:30:51","slug":"estructura-y-gobernanza-del-consejo-asesor-de-contenido","status":"publish","type":"post","link":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/","title":{"rendered":"Estructura y gobernanza del Consejo Asesor de Contenido"},"content":{"rendered":"<p><em>Por Brent Harris, Director de Gobernanza y Asuntos Internacionales<br \/>\n<\/em><br \/>\n<em>\u00abA las personas les importan las pol\u00edticas de contenido que establecemos y las decisiones que tomamos cada d\u00eda. Por ello, siempre nos debemos esforzar por mejorar. El Consejo asesor de contenido representa para nosotros una manera de mejorar la calidad de nuestra toma de decisiones y de ser m\u00e1s transparentes, as\u00ed como de brindar a otras partes las herramientas necesarias para ayudarnos a lograrlo. Esta Acta constitutiva es un paso fundamental para lo que deseamos que se convierta en un modelo para nuestro sector\u00bb. &#8211; Nick Clegg, VP of Global Affairs and Communications, Facebook<br \/>\n<\/em><br \/>\nDesde noviembre, cuando <a href=\"https:\/\/www.facebook.com\/notes\/mark-zuckerberg\/a-blueprint-for-content-governance-and-enforcement\/10156443129621634\/?hc_location=ufi\">Mark\u00a0Zuckerberg escribi\u00f3 por primera vez<\/a> acerca de su visi\u00f3n sobre c\u00f3mo se debe gestionar y controlar el contenido en Facebook, un equipo de nuestra empresa ha estado trabajando para dise\u00f1ar este organismo, con la ayuda de <a href=\"https:\/\/newsroom.fb.com\/news\/2019\/06\/global-feedback-on-oversight-board\/\">aportes y comentarios<\/a> de personas de todo el mundo.<\/p>\n<p>Hoy anunciamos m\u00e1s detalles sobre la estructura del Consejo asesor de contenido y su relaci\u00f3n con Facebook a trav\u00e9s de un Acta Constitutiva. En este documento constitutivo central se define la misi\u00f3n del Consejo y se describe su relaci\u00f3n con Facebook. Adem\u00e1s, se establecen sus miembros, la gobernanza y las autoridades para la toma de decisiones, a la vez que se determinan diversos factores, como el tama\u00f1o, el alcance y las facultades del Consejo. En las pr\u00f3ximas semanas, esta Acta constitutiva estar\u00e1 disponible en distintos idiomas a trav\u00e9s de un nuevo sitio web del Consejo.<\/p>\n<p>Junto con el Acta se incluir\u00e1 una <a href=\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/mark-letter_es_la-reviewed-2.pdf\">carta de Mark\u00a0Zuckerberg<\/a>, donde se explican la finalidad y los objetivos del Consejo.<\/p>\n<p><strong>Documentos constitutivos<\/strong><br \/>\nEsta Acta constitutiva es solo una parte de la extensa documentaci\u00f3n por la cual se regir\u00e1 el Consejo asesor de contenido. Tambi\u00e9n estamos redactando estatutos que ofrecer\u00e1n m\u00e1s detalles operativos sobre la independencia institucional y las normas de procedimiento del Consejo. En estos estatutos se incluir\u00e1n los mecanismos de responsabilidad, como un c\u00f3digo de conducta y la inhabilitaci\u00f3n de miembros del Consejo. Tambi\u00e9n se describir\u00e1n los procesos para conformar paneles, desarrollar materiales de casos e implementar las decisiones del Consejo. Si bien preparamos estos estatutos en nombre del Consejo, solo el Consejo podr\u00e1, en \u00faltima instancia, modificarlos.<\/p>\n<p><strong>Estructura de gobernanza<\/strong><br \/>\nRecibimos varios comentarios clave en donde nos ped\u00edan garantizar que el Consejo sea independiente de Facebook. Una de las formas en que estamos abordando esta petici\u00f3n es mediante el establecimiento de un Fideicomiso independiente. El Consejo asesor de contenido, el Fideicomiso y Facebook tendr\u00e1n roles y responsabilidades separados, y todos trabajar\u00e1n conjuntamente para garantizar el \u00e9xito del Consejo.<\/p>\n<p>Como parte de nuestras iniciativas generales de transparencia, se publicar\u00e1n documentos fiduciarios, en los que se establecer\u00e1 la relaci\u00f3n formal entre el Consejo, el Fideicomiso y Facebook.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-7305\" src=\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/governance_v11-copy_online_es_la-2.jpg?resize=960%2C967\" alt=\"\" width=\"960\" height=\"967\" \/><br \/>\n<strong>Decisiones relativas al dise\u00f1o del Consejo<\/strong><br \/>\nJunto con el Acta final, tambi\u00e9n ofrecemos un resumen donde se desglosan los elementos del <a href=\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/draft-charter-oversight-board-for-content-decisions-2.pdf\">Acta inicial<\/a>, los comentarios que recibimos y los argumentos que respaldan nuestras decisiones sobre el dise\u00f1o de este Consejo.<\/p>\n<p>Muchos temas generaron un debate saludable y constructivo, especialmente estas cuatro \u00e1reas:<\/p>\n<ul>\n<li><strong>Gobernanza: <\/strong>la mayor\u00eda de las personas que consultamos respaldaron nuestra decisi\u00f3n de establecer un Fideicomiso independiente. Consideran que esto puede ayudar a garantizar la autonom\u00eda del Consejo, a la vez que proporciona un medio para contar con m\u00e1s controles de responsabilidad. Como se describi\u00f3 anteriormente, este Fideicomiso ofrecer\u00e1 la infraestructura para el respaldo y la compensaci\u00f3n del Consejo.<\/li>\n<li><strong>Miembros:<\/strong> nos comprometemos a seleccionar a un grupo diverso y calificado de 40\u00a0miembros para el Consejo, quienes prestar\u00e1n servicio durante un per\u00edodo de tres a\u00f1os. Coincidimos con la opini\u00f3n de que Facebook no deber\u00eda ser la \u00fanica parte responsable de designar a todo el Consejo. Por lo tanto, Facebook seleccionar\u00e1 a un grupo reducido de miembros iniciales, quienes colaborar\u00e1n en la elecci\u00f3n de otros miembros. Como consecuencia, el propio Consejo ser\u00e1 responsable de la selecci\u00f3n de todos los miembros futuros, tal como se explic\u00f3 en nuestra publicaci\u00f3n de septiembre. El Fideicomiso luego designar\u00e1 a los miembros formalmente.<\/li>\n<li><strong>Precedente:<\/strong> en lo que respecta al Consejo, en el Acta final se ratifica que se espera que, en general, los paneles se remitan a decisiones pasadas, lo cual se alinea con los comentarios recibidos durante el per\u00edodo de consulta p\u00fablica. En cuanto a Facebook, el Consejo tambi\u00e9n puede solicitar que su decisi\u00f3n se aplique a otras instancias o reproducciones del mismo contenido. En tales casos, Facebook lo har\u00e1 siempre que sea t\u00e9cnica y operativamente posible.<\/li>\n<li><strong>Implementaci\u00f3n:<\/strong> Facebook implementar\u00e1 de manera oportuna las decisiones de contenido del Consejo, las cuales son vinculantes. Adem\u00e1s, el Consejo puede formular recomendaciones de pol\u00edticas a Facebook, como parte del dictamen general sobre cada caso individual. As\u00ed es como se prev\u00e9 que las decisiones del Consejo tengan una influencia duradera en las pol\u00edticas, los procedimientos y las pr\u00e1cticas de Facebook.<\/li>\n<\/ul>\n<h5><strong>Proceso<\/strong><\/h5>\n<p>Tanto Facebook como sus usuarios podr\u00e1n derivar casos al Consejo para su revisi\u00f3n. Por ahora, el Consejo comenzar\u00e1 sus operaciones atendiendo casos iniciados por Facebook. Durante el primer semestre de 2020, pondremos a disposici\u00f3n de los usuarios un sistema para que puedan presentar apelaciones ante el Consejo.<\/p>\n<p>A grandes rasgos, describimos el proceso b\u00e1sico mediante el cual el Consejo seleccionar\u00e1 y revisar\u00e1 los casos, y decidir\u00e1 sobre ellos, y c\u00f3mo Facebook implementar\u00e1 las decisiones y responder\u00e1 ante ellas.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-7311 aligncenter\" src=\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/process_decision-flow_v8-copy_online_es_la-1-2.jpg?resize=678%2C2744\" alt=\"\" width=\"678\" height=\"2744\" \/><\/p>\n<p>Como primer paso, identificamos pautas acerca de c\u00f3mo priorizaremos nuestros casos m\u00e1s dif\u00edciles y significativos para las derivaciones de Facebook al Consejo. Consideramos actualmente distintos indicadores que demuestran que los casos son dif\u00edciles y significativos:<\/p>\n<ul>\n<li><strong>Importancia:<\/strong> la importancia implica que el contenido tiene un impacto en el mundo real. El contenido en cuesti\u00f3n debe incluir temas que son graves, de gran escala y relevantes para el discurso p\u00fablico. Estos factores incluyen:\n<ul>\n<li><strong><em>Gravedad.<\/em><\/strong> El contenido amenaza la expresi\u00f3n, seguridad, privacidad, dignidad o igualdad de una persona.<\/li>\n<li><strong><em>Escala<\/em><\/strong><strong>.<\/strong> El contenido llega o afecta a un gran n\u00famero de personas, o ilustra una tendencia o un problema de mayor envergadura en Facebook.<\/li>\n<li><strong><em>Discurso p\u00fablico.<\/em><\/strong> El contenido genera un debate p\u00fablico significativo o un discurso pol\u00edtico y social importante.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Dificultad: <\/strong>la decisi\u00f3n acerca del contenido plantea preguntas sobre la pol\u00edtica actual o su cumplimiento. Pueden presentarse argumentos s\u00f3lidos para la eliminaci\u00f3n o la conservaci\u00f3n del contenido. Estos factores incluyen:\n<ul>\n<li><strong><em>En disputa.<\/em><\/strong> No hay acuerdo en cuanto a la decisi\u00f3n de Facebook acerca del contenido o las pol\u00edticas subyacentes.<\/li>\n<li><strong><em>Incierto.<\/em><\/strong> No hay certeza sobre la decisi\u00f3n correcta de acuerdo con la pol\u00edtica de Facebook.<\/li>\n<li><strong><em>En conflicto. <\/em><\/strong>Existe cierta tensi\u00f3n entre valores de igual importancia. Una persona sensata podr\u00eda aceptar los argumentos tanto para eliminar como para conservar el contenido, y cualquiera de estas dos decisiones requiere un compromiso entre ambos valores.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Si bien hoy alcanzamos un hito importante, a\u00fan queda mucho m\u00e1s trabajo por hacer.<\/p>\n<p>Durante los pr\u00f3ximos meses, continuaremos probando nuestras hip\u00f3tesis y garantizando la disponibilidad operativa del Consejo. En especial, nos centraremos en buscar, seleccionar y capacitar a los miembros del Consejo, en finalizar los estatutos que complementar\u00e1n el Acta constitutiva y en trabajar en pos de que el Consejo atienda sus primeros casos a principios de 2020.<\/p>\n<p>Nos comprometemos a consultar a especialistas externos en cada etapa y esperamos poder brindar m\u00e1s novedades acerca de nuestro progreso.<\/p>\n","protected":false},"excerpt":{"rendered":"Por Brent Harris, Director de Gobernanza y Asuntos Internacionales \u00abA las personas les importan las pol\u00edticas de contenido que establecemos y las decisiones que tomamos cada d\u00eda. Por ello, siempre nos debemos esforzar por mejorar. El Consejo asesor de contenido representa para nosotros una manera de mejorar la calidad de nuestra toma de decisiones y de ser m\u00e1s transparentes, as\u00ed como de brindar a otras partes las herramientas necesarias para ayudarnos a lograrlo. Esta Acta constitutiva es un paso fundamental para lo que deseamos que se convierta en un modelo para nuestro sector\u00bb. &#8211; Nick Clegg, VP of Global Affairs and Communications, Facebook Desde noviembre, cuando Mark\u00a0Zuckerberg escribi\u00f3 por primera vez acerca de su visi\u00f3n sobre c\u00f3mo se debe gestionar y controlar el contenido en Facebook, un equipo de nuestra empresa ha estado trabajando para dise\u00f1ar este organismo, con la ayuda de aportes y comentarios de personas de todo el mundo. Hoy anunciamos m\u00e1s detalles sobre la estructura del Consejo asesor de contenido y su relaci\u00f3n con Facebook a trav\u00e9s de un Acta Constitutiva. En este documento constitutivo central se define la misi\u00f3n del Consejo y se describe su relaci\u00f3n con Facebook. Adem\u00e1s, se establecen sus miembros, la gobernanza y las autoridades para la toma de decisiones, a la vez que se determinan diversos factores, como el tama\u00f1o, el alcance y las facultades del Consejo. En las pr\u00f3ximas semanas, esta Acta constitutiva estar\u00e1 disponible en distintos idiomas a trav\u00e9s de un nuevo sitio web del Consejo. Junto con el Acta se incluir\u00e1 una carta de Mark\u00a0Zuckerberg, donde se explican la finalidad y los objetivos del Consejo. Documentos constitutivos Esta Acta constitutiva es solo una parte de la extensa documentaci\u00f3n por la cual se regir\u00e1 el Consejo asesor de contenido. Tambi\u00e9n estamos redactando estatutos que ofrecer\u00e1n m\u00e1s detalles operativos sobre la independencia institucional y las normas de procedimiento del Consejo. En estos estatutos se incluir\u00e1n los mecanismos de responsabilidad, como un c\u00f3digo de conducta y la inhabilitaci\u00f3n de miembros del Consejo. Tambi\u00e9n se describir\u00e1n los procesos para conformar paneles, desarrollar materiales de casos e implementar las decisiones del Consejo. Si bien preparamos estos estatutos en nombre del Consejo, solo el Consejo podr\u00e1, en \u00faltima instancia, modificarlos. Estructura de gobernanza Recibimos varios comentarios clave en donde nos ped\u00edan garantizar que el Consejo sea independiente de Facebook. Una de las formas en que estamos abordando esta petici\u00f3n es mediante el establecimiento de un Fideicomiso independiente. El Consejo asesor de contenido, el Fideicomiso y Facebook tendr\u00e1n roles y responsabilidades separados, y todos trabajar\u00e1n conjuntamente para garantizar el \u00e9xito del Consejo. Como parte de nuestras iniciativas generales de transparencia, se publicar\u00e1n documentos fiduciarios, en los que se establecer\u00e1 la relaci\u00f3n formal entre el Consejo, el Fideicomiso y Facebook. Decisiones relativas al dise\u00f1o del Consejo Junto con el Acta final, tambi\u00e9n ofrecemos un resumen donde se desglosan los elementos del Acta inicial, los comentarios que recibimos y los argumentos que respaldan nuestras decisiones sobre el dise\u00f1o de este Consejo. Muchos temas generaron un debate saludable y constructivo, especialmente estas cuatro \u00e1reas: Gobernanza: la mayor\u00eda de las personas que consultamos respaldaron nuestra decisi\u00f3n de establecer un Fideicomiso independiente. Consideran que esto puede ayudar a garantizar la autonom\u00eda del Consejo, a la vez que proporciona un medio para contar con m\u00e1s controles de responsabilidad. Como se describi\u00f3 anteriormente, este Fideicomiso ofrecer\u00e1 la infraestructura para el respaldo y la compensaci\u00f3n del Consejo. Miembros: nos comprometemos a seleccionar a un grupo diverso y calificado de 40\u00a0miembros para el Consejo, quienes prestar\u00e1n servicio durante un per\u00edodo de tres a\u00f1os. Coincidimos con la opini\u00f3n de que Facebook no deber\u00eda ser la \u00fanica parte responsable de designar a todo el Consejo. Por lo tanto, Facebook seleccionar\u00e1 a un grupo reducido de miembros iniciales, quienes colaborar\u00e1n en la elecci\u00f3n de otros miembros. Como consecuencia, el propio Consejo ser\u00e1 responsable de la selecci\u00f3n de todos los miembros futuros, tal como se explic\u00f3 en nuestra publicaci\u00f3n de septiembre. El Fideicomiso luego designar\u00e1 a los miembros formalmente. Precedente: en lo que respecta al Consejo, en el Acta final se ratifica que se espera que, en general, los paneles se remitan a decisiones pasadas, lo cual se alinea con los comentarios recibidos durante el per\u00edodo de consulta p\u00fablica. En cuanto a Facebook, el Consejo tambi\u00e9n puede solicitar que su decisi\u00f3n se aplique a otras instancias o reproducciones del mismo contenido. En tales casos, Facebook lo har\u00e1 siempre que sea t\u00e9cnica y operativamente posible. Implementaci\u00f3n: Facebook implementar\u00e1 de manera oportuna las decisiones de contenido del Consejo, las cuales son vinculantes. Adem\u00e1s, el Consejo puede formular recomendaciones de pol\u00edticas a Facebook, como parte del dictamen general sobre cada caso individual. As\u00ed es como se prev\u00e9 que las decisiones del Consejo tengan una influencia duradera en las pol\u00edticas, los procedimientos y las pr\u00e1cticas de Facebook. Proceso Tanto Facebook como sus usuarios podr\u00e1n derivar casos al Consejo para su revisi\u00f3n. Por ahora, el Consejo comenzar\u00e1 sus operaciones atendiendo casos iniciados por Facebook. Durante el primer semestre de 2020, pondremos a disposici\u00f3n de los usuarios un sistema para que puedan presentar apelaciones ante el Consejo. A grandes rasgos, describimos el proceso b\u00e1sico mediante el cual el Consejo seleccionar\u00e1 y revisar\u00e1 los casos, y decidir\u00e1 sobre ellos, y c\u00f3mo Facebook implementar\u00e1 las decisiones y responder\u00e1 ante ellas. Como primer paso, identificamos pautas acerca de c\u00f3mo priorizaremos nuestros casos m\u00e1s dif\u00edciles y significativos para las derivaciones de Facebook al Consejo. Consideramos actualmente distintos indicadores que demuestran que los casos son dif\u00edciles y significativos: Importancia: la importancia implica que el contenido tiene un impacto en el mundo real. El contenido en cuesti\u00f3n debe incluir temas que son graves, de gran escala y relevantes para el discurso p\u00fablico. Estos factores incluyen: Gravedad. El contenido amenaza la expresi\u00f3n, seguridad, privacidad, dignidad o igualdad de una persona. Escala. El contenido llega o afecta a un gran n\u00famero de personas, o ilustra una tendencia o un problema de mayor envergadura en Facebook. Discurso p\u00fablico. El contenido genera un debate p\u00fablico significativo o un discurso pol\u00edtico y social importante. Dificultad: la decisi\u00f3n acerca del contenido plantea preguntas sobre la pol\u00edtica actual o su cumplimiento. Pueden presentarse argumentos s\u00f3lidos para la eliminaci\u00f3n o la conservaci\u00f3n del contenido. Estos factores incluyen: En disputa. No hay acuerdo en cuanto a la decisi\u00f3n de Facebook acerca del contenido o las pol\u00edticas subyacentes. Incierto. No hay certeza sobre la decisi\u00f3n correcta de acuerdo con la pol\u00edtica de Facebook. En conflicto. Existe cierta tensi\u00f3n entre valores de igual importancia. Una persona sensata podr\u00eda aceptar los argumentos tanto para eliminar como para conservar el contenido, y cualquiera de estas dos decisiones requiere un compromiso entre ambos valores. Si bien hoy alcanzamos un hito importante, a\u00fan queda mucho m\u00e1s trabajo por hacer. Durante los pr\u00f3ximos meses, continuaremos probando nuestras hip\u00f3tesis y garantizando la disponibilidad operativa del Consejo. En especial, nos centraremos en buscar, seleccionar y capacitar a los miembros del Consejo, en finalizar los estatutos que complementar\u00e1n el Acta constitutiva y en trabajar en pos de que el Consejo atienda sus primeros casos a principios de 2020. Nos comprometemos a consultar a especialistas externos en cada etapa y esperamos poder brindar m\u00e1s novedades acerca de nuestro progreso.","protected":false},"author":154972825,"featured_media":7304,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[243948106,1],"tags":[],"class_list":["post-7302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-consejo-asesor-de-contenido","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estructura y gobernanza del Consejo Asesor de Contenido | Acerca de Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estructura y gobernanza del Consejo Asesor de Contenido | Acerca de Meta\" \/>\n<meta property=\"og:description\" content=\"Por Brent Harris, Director de Gobernanza y Asuntos Internacionales \u00abA las personas les importan las pol\u00edticas de contenido que establecemos y las decisiones que tomamos cada d\u00eda. Por ello, siempre nos debemos esforzar por mejorar. El Consejo asesor de contenido representa para nosotros una manera de mejorar la calidad de nuestra toma de decisiones y de ser m\u00e1s transparentes, as\u00ed como de brindar a otras partes las herramientas necesarias para ayudarnos a lograrlo. Esta Acta constitutiva es un paso fundamental para lo que deseamos que se convierta en un modelo para nuestro sector\u00bb. &#8211; Nick Clegg, VP of Global Affairs and Communications, Facebook Desde noviembre, cuando Mark\u00a0Zuckerberg escribi\u00f3 por primera vez acerca de su visi\u00f3n sobre c\u00f3mo se debe gestionar y controlar el contenido en Facebook, un equipo de nuestra empresa ha estado trabajando para dise\u00f1ar este organismo, con la ayuda de aportes y comentarios de personas de todo el mundo. Hoy anunciamos m\u00e1s detalles sobre la estructura del Consejo asesor de contenido y su relaci\u00f3n con Facebook a trav\u00e9s de un Acta Constitutiva. En este documento constitutivo central se define la misi\u00f3n del Consejo y se describe su relaci\u00f3n con Facebook. Adem\u00e1s, se establecen sus miembros, la gobernanza y las autoridades para la toma de decisiones, a la vez que se determinan diversos factores, como el tama\u00f1o, el alcance y las facultades del Consejo. En las pr\u00f3ximas semanas, esta Acta constitutiva estar\u00e1 disponible en distintos idiomas a trav\u00e9s de un nuevo sitio web del Consejo. Junto con el Acta se incluir\u00e1 una carta de Mark\u00a0Zuckerberg, donde se explican la finalidad y los objetivos del Consejo. Documentos constitutivos Esta Acta constitutiva es solo una parte de la extensa documentaci\u00f3n por la cual se regir\u00e1 el Consejo asesor de contenido. Tambi\u00e9n estamos redactando estatutos que ofrecer\u00e1n m\u00e1s detalles operativos sobre la independencia institucional y las normas de procedimiento del Consejo. En estos estatutos se incluir\u00e1n los mecanismos de responsabilidad, como un c\u00f3digo de conducta y la inhabilitaci\u00f3n de miembros del Consejo. Tambi\u00e9n se describir\u00e1n los procesos para conformar paneles, desarrollar materiales de casos e implementar las decisiones del Consejo. Si bien preparamos estos estatutos en nombre del Consejo, solo el Consejo podr\u00e1, en \u00faltima instancia, modificarlos. Estructura de gobernanza Recibimos varios comentarios clave en donde nos ped\u00edan garantizar que el Consejo sea independiente de Facebook. Una de las formas en que estamos abordando esta petici\u00f3n es mediante el establecimiento de un Fideicomiso independiente. El Consejo asesor de contenido, el Fideicomiso y Facebook tendr\u00e1n roles y responsabilidades separados, y todos trabajar\u00e1n conjuntamente para garantizar el \u00e9xito del Consejo. Como parte de nuestras iniciativas generales de transparencia, se publicar\u00e1n documentos fiduciarios, en los que se establecer\u00e1 la relaci\u00f3n formal entre el Consejo, el Fideicomiso y Facebook. Decisiones relativas al dise\u00f1o del Consejo Junto con el Acta final, tambi\u00e9n ofrecemos un resumen donde se desglosan los elementos del Acta inicial, los comentarios que recibimos y los argumentos que respaldan nuestras decisiones sobre el dise\u00f1o de este Consejo. Muchos temas generaron un debate saludable y constructivo, especialmente estas cuatro \u00e1reas: Gobernanza: la mayor\u00eda de las personas que consultamos respaldaron nuestra decisi\u00f3n de establecer un Fideicomiso independiente. Consideran que esto puede ayudar a garantizar la autonom\u00eda del Consejo, a la vez que proporciona un medio para contar con m\u00e1s controles de responsabilidad. Como se describi\u00f3 anteriormente, este Fideicomiso ofrecer\u00e1 la infraestructura para el respaldo y la compensaci\u00f3n del Consejo. Miembros: nos comprometemos a seleccionar a un grupo diverso y calificado de 40\u00a0miembros para el Consejo, quienes prestar\u00e1n servicio durante un per\u00edodo de tres a\u00f1os. Coincidimos con la opini\u00f3n de que Facebook no deber\u00eda ser la \u00fanica parte responsable de designar a todo el Consejo. Por lo tanto, Facebook seleccionar\u00e1 a un grupo reducido de miembros iniciales, quienes colaborar\u00e1n en la elecci\u00f3n de otros miembros. Como consecuencia, el propio Consejo ser\u00e1 responsable de la selecci\u00f3n de todos los miembros futuros, tal como se explic\u00f3 en nuestra publicaci\u00f3n de septiembre. El Fideicomiso luego designar\u00e1 a los miembros formalmente. Precedente: en lo que respecta al Consejo, en el Acta final se ratifica que se espera que, en general, los paneles se remitan a decisiones pasadas, lo cual se alinea con los comentarios recibidos durante el per\u00edodo de consulta p\u00fablica. En cuanto a Facebook, el Consejo tambi\u00e9n puede solicitar que su decisi\u00f3n se aplique a otras instancias o reproducciones del mismo contenido. En tales casos, Facebook lo har\u00e1 siempre que sea t\u00e9cnica y operativamente posible. Implementaci\u00f3n: Facebook implementar\u00e1 de manera oportuna las decisiones de contenido del Consejo, las cuales son vinculantes. Adem\u00e1s, el Consejo puede formular recomendaciones de pol\u00edticas a Facebook, como parte del dictamen general sobre cada caso individual. As\u00ed es como se prev\u00e9 que las decisiones del Consejo tengan una influencia duradera en las pol\u00edticas, los procedimientos y las pr\u00e1cticas de Facebook. Proceso Tanto Facebook como sus usuarios podr\u00e1n derivar casos al Consejo para su revisi\u00f3n. Por ahora, el Consejo comenzar\u00e1 sus operaciones atendiendo casos iniciados por Facebook. Durante el primer semestre de 2020, pondremos a disposici\u00f3n de los usuarios un sistema para que puedan presentar apelaciones ante el Consejo. A grandes rasgos, describimos el proceso b\u00e1sico mediante el cual el Consejo seleccionar\u00e1 y revisar\u00e1 los casos, y decidir\u00e1 sobre ellos, y c\u00f3mo Facebook implementar\u00e1 las decisiones y responder\u00e1 ante ellas. Como primer paso, identificamos pautas acerca de c\u00f3mo priorizaremos nuestros casos m\u00e1s dif\u00edciles y significativos para las derivaciones de Facebook al Consejo. Consideramos actualmente distintos indicadores que demuestran que los casos son dif\u00edciles y significativos: Importancia: la importancia implica que el contenido tiene un impacto en el mundo real. El contenido en cuesti\u00f3n debe incluir temas que son graves, de gran escala y relevantes para el discurso p\u00fablico. Estos factores incluyen: Gravedad. El contenido amenaza la expresi\u00f3n, seguridad, privacidad, dignidad o igualdad de una persona. Escala. El contenido llega o afecta a un gran n\u00famero de personas, o ilustra una tendencia o un problema de mayor envergadura en Facebook. Discurso p\u00fablico. El contenido genera un debate p\u00fablico significativo o un discurso pol\u00edtico y social importante. Dificultad: la decisi\u00f3n acerca del contenido plantea preguntas sobre la pol\u00edtica actual o su cumplimiento. Pueden presentarse argumentos s\u00f3lidos para la eliminaci\u00f3n o la conservaci\u00f3n del contenido. Estos factores incluyen: En disputa. No hay acuerdo en cuanto a la decisi\u00f3n de Facebook acerca del contenido o las pol\u00edticas subyacentes. Incierto. No hay certeza sobre la decisi\u00f3n correcta de acuerdo con la pol\u00edtica de Facebook. En conflicto. Existe cierta tensi\u00f3n entre valores de igual importancia. Una persona sensata podr\u00eda aceptar los argumentos tanto para eliminar como para conservar el contenido, y cualquiera de estas dos decisiones requiere un compromiso entre ambos valores. Si bien hoy alcanzamos un hito importante, a\u00fan queda mucho m\u00e1s trabajo por hacer. Durante los pr\u00f3ximos meses, continuaremos probando nuestras hip\u00f3tesis y garantizando la disponibilidad operativa del Consejo. En especial, nos centraremos en buscar, seleccionar y capacitar a los miembros del Consejo, en finalizar los estatutos que complementar\u00e1n el Acta constitutiva y en trabajar en pos de que el Consejo atienda sus primeros casos a principios de 2020. Nos comprometemos a consultar a especialistas externos en cada etapa y esperamos poder brindar m\u00e1s novedades acerca de nuestro progreso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/\" \/>\n<meta property=\"og:site_name\" content=\"Acerca de Meta\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-17T20:49:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-09T23:30:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/oversight-board-report-1.jpg?resize=1024,575\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"carogarayzar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/\"},\"author\":\"Facebook company\",\"headline\":\"Estructura y gobernanza del Consejo Asesor de Contenido\",\"datePublished\":\"2019-09-17T20:49:17+00:00\",\"dateModified\":\"2020-11-09T23:30:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/\"},\"wordCount\":1286,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/#organization\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/oversight-board-report-1.jpg?fit=1920%2C1079\",\"articleSection\":[\"El Consejo asesor de contenido\",\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/\",\"url\":\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/\",\"name\":\"Estructura y gobernanza del Consejo Asesor de Contenido | Acerca de Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/oversight-board-report-1.jpg?fit=1920%2C1079\",\"datePublished\":\"2019-09-17T20:49:17+00:00\",\"dateModified\":\"2020-11-09T23:30:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/\"]}],\"author\":\"Acerca de Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#primaryimage\",\"url\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/oversight-board-report-1.jpg?fit=1920%2C1079\",\"contentUrl\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/oversight-board-report-1.jpg?fit=1920%2C1079\",\"width\":1920,\"height\":1079},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/ltam\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estructura y gobernanza del Consejo Asesor de Contenido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/ltam\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"Acerca de Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/ltam\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/ltam\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/ltam\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/about.fb.com\/ltam\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estructura y gobernanza del Consejo Asesor de Contenido | Acerca de Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/","og_locale":"es_ES","og_type":"article","og_title":"Estructura y gobernanza del Consejo Asesor de Contenido | Acerca de Meta","og_description":"Por Brent Harris, Director de Gobernanza y Asuntos Internacionales \u00abA las personas les importan las pol\u00edticas de contenido que establecemos y las decisiones que tomamos cada d\u00eda. Por ello, siempre nos debemos esforzar por mejorar. El Consejo asesor de contenido representa para nosotros una manera de mejorar la calidad de nuestra toma de decisiones y de ser m\u00e1s transparentes, as\u00ed como de brindar a otras partes las herramientas necesarias para ayudarnos a lograrlo. Esta Acta constitutiva es un paso fundamental para lo que deseamos que se convierta en un modelo para nuestro sector\u00bb. &#8211; Nick Clegg, VP of Global Affairs and Communications, Facebook Desde noviembre, cuando Mark\u00a0Zuckerberg escribi\u00f3 por primera vez acerca de su visi\u00f3n sobre c\u00f3mo se debe gestionar y controlar el contenido en Facebook, un equipo de nuestra empresa ha estado trabajando para dise\u00f1ar este organismo, con la ayuda de aportes y comentarios de personas de todo el mundo. Hoy anunciamos m\u00e1s detalles sobre la estructura del Consejo asesor de contenido y su relaci\u00f3n con Facebook a trav\u00e9s de un Acta Constitutiva. En este documento constitutivo central se define la misi\u00f3n del Consejo y se describe su relaci\u00f3n con Facebook. Adem\u00e1s, se establecen sus miembros, la gobernanza y las autoridades para la toma de decisiones, a la vez que se determinan diversos factores, como el tama\u00f1o, el alcance y las facultades del Consejo. En las pr\u00f3ximas semanas, esta Acta constitutiva estar\u00e1 disponible en distintos idiomas a trav\u00e9s de un nuevo sitio web del Consejo. Junto con el Acta se incluir\u00e1 una carta de Mark\u00a0Zuckerberg, donde se explican la finalidad y los objetivos del Consejo. Documentos constitutivos Esta Acta constitutiva es solo una parte de la extensa documentaci\u00f3n por la cual se regir\u00e1 el Consejo asesor de contenido. Tambi\u00e9n estamos redactando estatutos que ofrecer\u00e1n m\u00e1s detalles operativos sobre la independencia institucional y las normas de procedimiento del Consejo. En estos estatutos se incluir\u00e1n los mecanismos de responsabilidad, como un c\u00f3digo de conducta y la inhabilitaci\u00f3n de miembros del Consejo. Tambi\u00e9n se describir\u00e1n los procesos para conformar paneles, desarrollar materiales de casos e implementar las decisiones del Consejo. Si bien preparamos estos estatutos en nombre del Consejo, solo el Consejo podr\u00e1, en \u00faltima instancia, modificarlos. Estructura de gobernanza Recibimos varios comentarios clave en donde nos ped\u00edan garantizar que el Consejo sea independiente de Facebook. Una de las formas en que estamos abordando esta petici\u00f3n es mediante el establecimiento de un Fideicomiso independiente. El Consejo asesor de contenido, el Fideicomiso y Facebook tendr\u00e1n roles y responsabilidades separados, y todos trabajar\u00e1n conjuntamente para garantizar el \u00e9xito del Consejo. Como parte de nuestras iniciativas generales de transparencia, se publicar\u00e1n documentos fiduciarios, en los que se establecer\u00e1 la relaci\u00f3n formal entre el Consejo, el Fideicomiso y Facebook. Decisiones relativas al dise\u00f1o del Consejo Junto con el Acta final, tambi\u00e9n ofrecemos un resumen donde se desglosan los elementos del Acta inicial, los comentarios que recibimos y los argumentos que respaldan nuestras decisiones sobre el dise\u00f1o de este Consejo. Muchos temas generaron un debate saludable y constructivo, especialmente estas cuatro \u00e1reas: Gobernanza: la mayor\u00eda de las personas que consultamos respaldaron nuestra decisi\u00f3n de establecer un Fideicomiso independiente. Consideran que esto puede ayudar a garantizar la autonom\u00eda del Consejo, a la vez que proporciona un medio para contar con m\u00e1s controles de responsabilidad. Como se describi\u00f3 anteriormente, este Fideicomiso ofrecer\u00e1 la infraestructura para el respaldo y la compensaci\u00f3n del Consejo. Miembros: nos comprometemos a seleccionar a un grupo diverso y calificado de 40\u00a0miembros para el Consejo, quienes prestar\u00e1n servicio durante un per\u00edodo de tres a\u00f1os. Coincidimos con la opini\u00f3n de que Facebook no deber\u00eda ser la \u00fanica parte responsable de designar a todo el Consejo. Por lo tanto, Facebook seleccionar\u00e1 a un grupo reducido de miembros iniciales, quienes colaborar\u00e1n en la elecci\u00f3n de otros miembros. Como consecuencia, el propio Consejo ser\u00e1 responsable de la selecci\u00f3n de todos los miembros futuros, tal como se explic\u00f3 en nuestra publicaci\u00f3n de septiembre. El Fideicomiso luego designar\u00e1 a los miembros formalmente. Precedente: en lo que respecta al Consejo, en el Acta final se ratifica que se espera que, en general, los paneles se remitan a decisiones pasadas, lo cual se alinea con los comentarios recibidos durante el per\u00edodo de consulta p\u00fablica. En cuanto a Facebook, el Consejo tambi\u00e9n puede solicitar que su decisi\u00f3n se aplique a otras instancias o reproducciones del mismo contenido. En tales casos, Facebook lo har\u00e1 siempre que sea t\u00e9cnica y operativamente posible. Implementaci\u00f3n: Facebook implementar\u00e1 de manera oportuna las decisiones de contenido del Consejo, las cuales son vinculantes. Adem\u00e1s, el Consejo puede formular recomendaciones de pol\u00edticas a Facebook, como parte del dictamen general sobre cada caso individual. As\u00ed es como se prev\u00e9 que las decisiones del Consejo tengan una influencia duradera en las pol\u00edticas, los procedimientos y las pr\u00e1cticas de Facebook. Proceso Tanto Facebook como sus usuarios podr\u00e1n derivar casos al Consejo para su revisi\u00f3n. Por ahora, el Consejo comenzar\u00e1 sus operaciones atendiendo casos iniciados por Facebook. Durante el primer semestre de 2020, pondremos a disposici\u00f3n de los usuarios un sistema para que puedan presentar apelaciones ante el Consejo. A grandes rasgos, describimos el proceso b\u00e1sico mediante el cual el Consejo seleccionar\u00e1 y revisar\u00e1 los casos, y decidir\u00e1 sobre ellos, y c\u00f3mo Facebook implementar\u00e1 las decisiones y responder\u00e1 ante ellas. Como primer paso, identificamos pautas acerca de c\u00f3mo priorizaremos nuestros casos m\u00e1s dif\u00edciles y significativos para las derivaciones de Facebook al Consejo. Consideramos actualmente distintos indicadores que demuestran que los casos son dif\u00edciles y significativos: Importancia: la importancia implica que el contenido tiene un impacto en el mundo real. El contenido en cuesti\u00f3n debe incluir temas que son graves, de gran escala y relevantes para el discurso p\u00fablico. Estos factores incluyen: Gravedad. El contenido amenaza la expresi\u00f3n, seguridad, privacidad, dignidad o igualdad de una persona. Escala. El contenido llega o afecta a un gran n\u00famero de personas, o ilustra una tendencia o un problema de mayor envergadura en Facebook. Discurso p\u00fablico. El contenido genera un debate p\u00fablico significativo o un discurso pol\u00edtico y social importante. Dificultad: la decisi\u00f3n acerca del contenido plantea preguntas sobre la pol\u00edtica actual o su cumplimiento. Pueden presentarse argumentos s\u00f3lidos para la eliminaci\u00f3n o la conservaci\u00f3n del contenido. Estos factores incluyen: En disputa. No hay acuerdo en cuanto a la decisi\u00f3n de Facebook acerca del contenido o las pol\u00edticas subyacentes. Incierto. No hay certeza sobre la decisi\u00f3n correcta de acuerdo con la pol\u00edtica de Facebook. En conflicto. Existe cierta tensi\u00f3n entre valores de igual importancia. Una persona sensata podr\u00eda aceptar los argumentos tanto para eliminar como para conservar el contenido, y cualquiera de estas dos decisiones requiere un compromiso entre ambos valores. Si bien hoy alcanzamos un hito importante, a\u00fan queda mucho m\u00e1s trabajo por hacer. Durante los pr\u00f3ximos meses, continuaremos probando nuestras hip\u00f3tesis y garantizando la disponibilidad operativa del Consejo. En especial, nos centraremos en buscar, seleccionar y capacitar a los miembros del Consejo, en finalizar los estatutos que complementar\u00e1n el Acta constitutiva y en trabajar en pos de que el Consejo atienda sus primeros casos a principios de 2020. Nos comprometemos a consultar a especialistas externos en cada etapa y esperamos poder brindar m\u00e1s novedades acerca de nuestro progreso.","og_url":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/","og_site_name":"Acerca de Meta","article_published_time":"2019-09-17T20:49:17+00:00","article_modified_time":"2020-11-09T23:30:51+00:00","og_image":[{"width":1024,"height":575,"url":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/oversight-board-report-1.jpg?resize=1024,575","type":"image\/jpeg"}],"author":"carogarayzar","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/"},"author":"Facebook company","headline":"Estructura y gobernanza del Consejo Asesor de Contenido","datePublished":"2019-09-17T20:49:17+00:00","dateModified":"2020-11-09T23:30:51+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/"},"wordCount":1286,"publisher":{"@id":"https:\/\/about.fb.com\/ltam\/#organization"},"image":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/oversight-board-report-1.jpg?fit=1920%2C1079","articleSection":["El Consejo asesor de contenido","Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/","url":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/","name":"Estructura y gobernanza del Consejo Asesor de Contenido | Acerca de Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/ltam\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#primaryimage"},"image":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/oversight-board-report-1.jpg?fit=1920%2C1079","datePublished":"2019-09-17T20:49:17+00:00","dateModified":"2020-11-09T23:30:51+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/"]}],"author":"Acerca de Meta"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#primaryimage","url":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/oversight-board-report-1.jpg?fit=1920%2C1079","contentUrl":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/oversight-board-report-1.jpg?fit=1920%2C1079","width":1920,"height":1079},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/ltam\/news\/2019\/09\/estructura-y-gobernanza-del-consejo-asesor-de-contenido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/ltam\/"},{"@type":"ListItem","position":2,"name":"Estructura y gobernanza del Consejo Asesor de Contenido"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/ltam\/#website","url":"https:\/\/about.fb.com\/news\/","name":"Acerca de Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/ltam\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/ltam\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/ltam\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/ltam\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/about.fb.com\/ltam\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/ltam\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2019\/09\/oversight-board-report-1.jpg?fit=1920%2C1079","_links":{"self":[{"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/posts\/7302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/users\/154972825"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/comments?post=7302"}],"version-history":[{"count":1,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/posts\/7302\/revisions"}],"predecessor-version":[{"id":7491,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/posts\/7302\/revisions\/7491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/media\/7304"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/media?parent=7302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/categories?post=7302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/tags?post=7302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}