{"id":6048,"date":"2017-06-15T20:29:45","date_gmt":"2017-06-15T20:29:45","guid":{"rendered":"http:\/\/ltam.newsroom.fb.com\/?p=6048"},"modified":"2017-06-15T20:29:45","modified_gmt":"2017-06-15T20:29:45","slug":"preguntas-dificiles","status":"publish","type":"post","link":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/","title":{"rendered":"Preguntas dif\u00edciles"},"content":{"rendered":"<p><i>Por<\/i> <a href=\"https:\/\/www.facebook.com\/elliot\"><i>Elliot Schrage<\/i><\/a><i>, Vicepresidente de Pol\u00edticas P\u00fablicas y Comunicaciones<\/i><\/p>\n<p>Hoy comenzamos algo nuevo.<\/p>\n<p>Facebook es el lugar donde las personas publican fotos con sus amigos, se informan, forman grupos de apoyo y acompa\u00f1an la gesti\u00f3n de los pol\u00edticos. Lo que comenz\u00f3 como un espacio para que estudiantes universitarios en Estados Unidos pudieran mantenerse en contacto es hoy una plataforma utilizada por casi 2.000 millones de personas en el mundo. Las decisiones que tomamos en Facebook afectan la forma en que las personas se enteran de lo que sucede en el mundo y se comunican con sus seres queridos.<\/p>\n<p>Esto va mucho m\u00e1s all\u00e1 de nosotros. A medida que m\u00e1s y m\u00e1s de nuestras vidas se extiende online y las tecnolog\u00edas digitales transforman la forma en que vivimos, todos nos enfrentamos a nuevas y desafiantes preguntas &#8211; desde cu\u00e1l es la mejor manera de proteger nuestra privacidad en Internet, hasta el significado de la libertad de expresi\u00f3n y el futuro del periodismo a nivel global.<\/p>\n<p>En Facebook debatimos estas preguntas a diario en profundidad y libremente, y consultamos a expertos de todo el mundo. Tomamos muy en serio nuestra responsabilidad sobre el impacto e influencia que tenemos.<\/p>\n<p>Queremos ampliar esta conversaci\u00f3n. Por eso hoy lanzamos una nueva iniciativa para dialogar con mayor apertura sobre tem\u00e1ticas complejas. Esperamos que sea un espacio no solo para explicar algunas de nuestras decisiones, sino tambi\u00e9n para explorar preguntas dif\u00edciles, como por ejemplo:<\/p>\n<ul>\n<li>\u00bfC\u00f3mo deber\u00edan actuar las plataformas para evitar que terroristas difundan propaganda online?<\/li>\n<li>\u00bfQu\u00e9 deber\u00eda suceder con la identidad online de una persona tras su muerte?<\/li>\n<li>\u00bfQu\u00e9 tan agresivamente deben las compa\u00f1\u00edas de redes sociales monitorear y remover publicaciones e im\u00e1genes controvertidas de sus plataformas? \u00bfQui\u00e9n decide qu\u00e9 es controvertido, especialmente en una comunidad global con un amplio abanico de normas culturales?<\/li>\n<li>\u00bfQui\u00e9n define qu\u00e9 es una noticia falsa y qu\u00e9 es, simplemente, un discurso pol\u00edtico controvertido?<\/li>\n<li>\u00bfSon las redes sociales buenas para la democracia?<\/li>\n<li>\u00bfC\u00f3mo podemos usa datos para beneficio de todos sin perjudicar la confianza de las personas?<\/li>\n<li>\u00bfDe qu\u00e9 manera deber\u00edan los j\u00f3venes usuarios de Internet ser orientados en las nuevas maneras de expresarse en un ambiente seguro?<\/li>\n<\/ul>\n<p>No esperamos que todos est\u00e9n de acuerdo con las decisiones que tomamos. No siempre estamos de acuerdo internamente. Aprendemos con el transcurso del tiempo y, a veces, nos equivocamos. Sin embargo, aun cuando la comunidad sea esc\u00e9ptica con respecto a nuestras decisiones, esperamos que estas publicaciones aporten mayor claridad sobre nuestro acercamiento a estos temas y sobre la seriedad con que los abordamos. Creemos que al ser m\u00e1s abiertos y expl\u00edcitos, podremos minimizar los errores y corregirlos con mayor rapidez.<br \/>\nNuestra primera publicaci\u00f3n aborda la propagaci\u00f3n del terrorismo online, incluyendo las formas en que estamos trabajando con otros y el uso de nueva tecnolog\u00eda.<\/p>\n<p>Queremos contar con tu opini\u00f3n sobre qu\u00e9 otros temas debemos tratar y sobre qu\u00e9 cosas podr\u00edamos estar haciendo mejor. Te invitamos a enviar tus sugerencias a <a href=\"mailto:hardquestions@fb.com\">hardquestions@fb.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Por Elliot Schrage, Vicepresidente de Pol\u00edticas P\u00fablicas y Comunicaciones Hoy comenzamos algo nuevo. Facebook es el lugar donde las personas publican fotos con sus amigos, se informan, forman grupos de apoyo y acompa\u00f1an la gesti\u00f3n de los pol\u00edticos. Lo que comenz\u00f3 como un espacio para que estudiantes universitarios en Estados Unidos pudieran mantenerse en contacto es hoy una plataforma utilizada por casi 2.000 millones de personas en el mundo. Las decisiones que tomamos en Facebook afectan la forma en que las personas se enteran de lo que sucede en el mundo y se comunican con sus seres queridos. Esto va mucho m\u00e1s all\u00e1 de nosotros. A medida que m\u00e1s y m\u00e1s de nuestras vidas se extiende online y las tecnolog\u00edas digitales transforman la forma en que vivimos, todos nos enfrentamos a nuevas y desafiantes preguntas &#8211; desde cu\u00e1l es la mejor manera de proteger nuestra privacidad en Internet, hasta el significado de la libertad de expresi\u00f3n y el futuro del periodismo a nivel global. En Facebook debatimos estas preguntas a diario en profundidad y libremente, y consultamos a expertos de todo el mundo. Tomamos muy en serio nuestra responsabilidad sobre el impacto e influencia que tenemos. Queremos ampliar esta conversaci\u00f3n. Por eso hoy lanzamos una nueva iniciativa para dialogar con mayor apertura sobre tem\u00e1ticas complejas. Esperamos que sea un espacio no solo para explicar algunas de nuestras decisiones, sino tambi\u00e9n para explorar preguntas dif\u00edciles, como por ejemplo: \u00bfC\u00f3mo deber\u00edan actuar las plataformas para evitar que terroristas difundan propaganda online? \u00bfQu\u00e9 deber\u00eda suceder con la identidad online de una persona tras su muerte? \u00bfQu\u00e9 tan agresivamente deben las compa\u00f1\u00edas de redes sociales monitorear y remover publicaciones e im\u00e1genes controvertidas de sus plataformas? \u00bfQui\u00e9n decide qu\u00e9 es controvertido, especialmente en una comunidad global con un amplio abanico de normas culturales? \u00bfQui\u00e9n define qu\u00e9 es una noticia falsa y qu\u00e9 es, simplemente, un discurso pol\u00edtico controvertido? \u00bfSon las redes sociales buenas para la democracia? \u00bfC\u00f3mo podemos usa datos para beneficio de todos sin perjudicar la confianza de las personas? \u00bfDe qu\u00e9 manera deber\u00edan los j\u00f3venes usuarios de Internet ser orientados en las nuevas maneras de expresarse en un ambiente seguro? No esperamos que todos est\u00e9n de acuerdo con las decisiones que tomamos. No siempre estamos de acuerdo internamente. Aprendemos con el transcurso del tiempo y, a veces, nos equivocamos. Sin embargo, aun cuando la comunidad sea esc\u00e9ptica con respecto a nuestras decisiones, esperamos que estas publicaciones aporten mayor claridad sobre nuestro acercamiento a estos temas y sobre la seriedad con que los abordamos. Creemos que al ser m\u00e1s abiertos y expl\u00edcitos, podremos minimizar los errores y corregirlos con mayor rapidez. Nuestra primera publicaci\u00f3n aborda la propagaci\u00f3n del terrorismo online, incluyendo las formas en que estamos trabajando con otros y el uso de nueva tecnolog\u00eda. Queremos contar con tu opini\u00f3n sobre qu\u00e9 otros temas debemos tratar y sobre qu\u00e9 cosas podr\u00edamos estar haciendo mejor. Te invitamos a enviar tus sugerencias a hardquestions@fb.com.","protected":false},"author":95829248,"featured_media":6049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[54,243947919],"tags":[],"class_list":["post-6048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-preguntas-dificiles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preguntas dif\u00edciles | Acerca de Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preguntas dif\u00edciles | Acerca de Meta\" \/>\n<meta property=\"og:description\" content=\"Por Elliot Schrage, Vicepresidente de Pol\u00edticas P\u00fablicas y Comunicaciones Hoy comenzamos algo nuevo. Facebook es el lugar donde las personas publican fotos con sus amigos, se informan, forman grupos de apoyo y acompa\u00f1an la gesti\u00f3n de los pol\u00edticos. Lo que comenz\u00f3 como un espacio para que estudiantes universitarios en Estados Unidos pudieran mantenerse en contacto es hoy una plataforma utilizada por casi 2.000 millones de personas en el mundo. Las decisiones que tomamos en Facebook afectan la forma en que las personas se enteran de lo que sucede en el mundo y se comunican con sus seres queridos. Esto va mucho m\u00e1s all\u00e1 de nosotros. A medida que m\u00e1s y m\u00e1s de nuestras vidas se extiende online y las tecnolog\u00edas digitales transforman la forma en que vivimos, todos nos enfrentamos a nuevas y desafiantes preguntas &#8211; desde cu\u00e1l es la mejor manera de proteger nuestra privacidad en Internet, hasta el significado de la libertad de expresi\u00f3n y el futuro del periodismo a nivel global. En Facebook debatimos estas preguntas a diario en profundidad y libremente, y consultamos a expertos de todo el mundo. Tomamos muy en serio nuestra responsabilidad sobre el impacto e influencia que tenemos. Queremos ampliar esta conversaci\u00f3n. Por eso hoy lanzamos una nueva iniciativa para dialogar con mayor apertura sobre tem\u00e1ticas complejas. Esperamos que sea un espacio no solo para explicar algunas de nuestras decisiones, sino tambi\u00e9n para explorar preguntas dif\u00edciles, como por ejemplo: \u00bfC\u00f3mo deber\u00edan actuar las plataformas para evitar que terroristas difundan propaganda online? \u00bfQu\u00e9 deber\u00eda suceder con la identidad online de una persona tras su muerte? \u00bfQu\u00e9 tan agresivamente deben las compa\u00f1\u00edas de redes sociales monitorear y remover publicaciones e im\u00e1genes controvertidas de sus plataformas? \u00bfQui\u00e9n decide qu\u00e9 es controvertido, especialmente en una comunidad global con un amplio abanico de normas culturales? \u00bfQui\u00e9n define qu\u00e9 es una noticia falsa y qu\u00e9 es, simplemente, un discurso pol\u00edtico controvertido? \u00bfSon las redes sociales buenas para la democracia? \u00bfC\u00f3mo podemos usa datos para beneficio de todos sin perjudicar la confianza de las personas? \u00bfDe qu\u00e9 manera deber\u00edan los j\u00f3venes usuarios de Internet ser orientados en las nuevas maneras de expresarse en un ambiente seguro? No esperamos que todos est\u00e9n de acuerdo con las decisiones que tomamos. No siempre estamos de acuerdo internamente. Aprendemos con el transcurso del tiempo y, a veces, nos equivocamos. Sin embargo, aun cuando la comunidad sea esc\u00e9ptica con respecto a nuestras decisiones, esperamos que estas publicaciones aporten mayor claridad sobre nuestro acercamiento a estos temas y sobre la seriedad con que los abordamos. Creemos que al ser m\u00e1s abiertos y expl\u00edcitos, podremos minimizar los errores y corregirlos con mayor rapidez. Nuestra primera publicaci\u00f3n aborda la propagaci\u00f3n del terrorismo online, incluyendo las formas en que estamos trabajando con otros y el uso de nueva tecnolog\u00eda. Queremos contar con tu opini\u00f3n sobre qu\u00e9 otros temas debemos tratar y sobre qu\u00e9 cosas podr\u00edamos estar haciendo mejor. Te invitamos a enviar tus sugerencias a hardquestions@fb.com.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/\" \/>\n<meta property=\"og:site_name\" content=\"Acerca de Meta\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-15T20:29:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2017\/06\/friendshipmap.jpg?fit=960%2C480\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"camilagfb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/\"},\"author\":\"Facebook company\",\"headline\":\"Preguntas dif\u00edciles\",\"datePublished\":\"2017-06-15T20:29:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/\"},\"wordCount\":527,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/#organization\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2017\/06\/friendshipmap.jpg?fit=960%2C480\",\"articleSection\":[\"General\",\"Preguntas Dif\u00edciles\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/\",\"url\":\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/\",\"name\":\"Preguntas dif\u00edciles | Acerca de Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2017\/06\/friendshipmap.jpg?fit=960%2C480\",\"datePublished\":\"2017-06-15T20:29:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/\"]}],\"author\":\"Acerca de Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#primaryimage\",\"url\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2017\/06\/friendshipmap.jpg?fit=960%2C480\",\"contentUrl\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2017\/06\/friendshipmap.jpg?fit=960%2C480\",\"width\":960,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/ltam\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preguntas dif\u00edciles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/ltam\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"Acerca de Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/ltam\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/ltam\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/ltam\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/about.fb.com\/ltam\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preguntas dif\u00edciles | Acerca de Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/","og_locale":"es_ES","og_type":"article","og_title":"Preguntas dif\u00edciles | Acerca de Meta","og_description":"Por Elliot Schrage, Vicepresidente de Pol\u00edticas P\u00fablicas y Comunicaciones Hoy comenzamos algo nuevo. Facebook es el lugar donde las personas publican fotos con sus amigos, se informan, forman grupos de apoyo y acompa\u00f1an la gesti\u00f3n de los pol\u00edticos. Lo que comenz\u00f3 como un espacio para que estudiantes universitarios en Estados Unidos pudieran mantenerse en contacto es hoy una plataforma utilizada por casi 2.000 millones de personas en el mundo. Las decisiones que tomamos en Facebook afectan la forma en que las personas se enteran de lo que sucede en el mundo y se comunican con sus seres queridos. Esto va mucho m\u00e1s all\u00e1 de nosotros. A medida que m\u00e1s y m\u00e1s de nuestras vidas se extiende online y las tecnolog\u00edas digitales transforman la forma en que vivimos, todos nos enfrentamos a nuevas y desafiantes preguntas &#8211; desde cu\u00e1l es la mejor manera de proteger nuestra privacidad en Internet, hasta el significado de la libertad de expresi\u00f3n y el futuro del periodismo a nivel global. En Facebook debatimos estas preguntas a diario en profundidad y libremente, y consultamos a expertos de todo el mundo. Tomamos muy en serio nuestra responsabilidad sobre el impacto e influencia que tenemos. Queremos ampliar esta conversaci\u00f3n. Por eso hoy lanzamos una nueva iniciativa para dialogar con mayor apertura sobre tem\u00e1ticas complejas. Esperamos que sea un espacio no solo para explicar algunas de nuestras decisiones, sino tambi\u00e9n para explorar preguntas dif\u00edciles, como por ejemplo: \u00bfC\u00f3mo deber\u00edan actuar las plataformas para evitar que terroristas difundan propaganda online? \u00bfQu\u00e9 deber\u00eda suceder con la identidad online de una persona tras su muerte? \u00bfQu\u00e9 tan agresivamente deben las compa\u00f1\u00edas de redes sociales monitorear y remover publicaciones e im\u00e1genes controvertidas de sus plataformas? \u00bfQui\u00e9n decide qu\u00e9 es controvertido, especialmente en una comunidad global con un amplio abanico de normas culturales? \u00bfQui\u00e9n define qu\u00e9 es una noticia falsa y qu\u00e9 es, simplemente, un discurso pol\u00edtico controvertido? \u00bfSon las redes sociales buenas para la democracia? \u00bfC\u00f3mo podemos usa datos para beneficio de todos sin perjudicar la confianza de las personas? \u00bfDe qu\u00e9 manera deber\u00edan los j\u00f3venes usuarios de Internet ser orientados en las nuevas maneras de expresarse en un ambiente seguro? No esperamos que todos est\u00e9n de acuerdo con las decisiones que tomamos. No siempre estamos de acuerdo internamente. Aprendemos con el transcurso del tiempo y, a veces, nos equivocamos. Sin embargo, aun cuando la comunidad sea esc\u00e9ptica con respecto a nuestras decisiones, esperamos que estas publicaciones aporten mayor claridad sobre nuestro acercamiento a estos temas y sobre la seriedad con que los abordamos. Creemos que al ser m\u00e1s abiertos y expl\u00edcitos, podremos minimizar los errores y corregirlos con mayor rapidez. Nuestra primera publicaci\u00f3n aborda la propagaci\u00f3n del terrorismo online, incluyendo las formas en que estamos trabajando con otros y el uso de nueva tecnolog\u00eda. Queremos contar con tu opini\u00f3n sobre qu\u00e9 otros temas debemos tratar y sobre qu\u00e9 cosas podr\u00edamos estar haciendo mejor. Te invitamos a enviar tus sugerencias a hardquestions@fb.com.","og_url":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/","og_site_name":"Acerca de Meta","article_published_time":"2017-06-15T20:29:45+00:00","og_image":[{"url":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2017\/06\/friendshipmap.jpg?fit=960%2C480","width":960,"height":480,"type":"image\/jpeg"}],"author":"camilagfb","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/"},"author":"Facebook company","headline":"Preguntas dif\u00edciles","datePublished":"2017-06-15T20:29:45+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/"},"wordCount":527,"publisher":{"@id":"https:\/\/about.fb.com\/ltam\/#organization"},"image":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2017\/06\/friendshipmap.jpg?fit=960%2C480","articleSection":["General","Preguntas Dif\u00edciles"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/","url":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/","name":"Preguntas dif\u00edciles | Acerca de Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/ltam\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#primaryimage"},"image":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2017\/06\/friendshipmap.jpg?fit=960%2C480","datePublished":"2017-06-15T20:29:45+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/"]}],"author":"Acerca de Meta"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#primaryimage","url":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2017\/06\/friendshipmap.jpg?fit=960%2C480","contentUrl":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2017\/06\/friendshipmap.jpg?fit=960%2C480","width":960,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/ltam\/news\/2017\/06\/preguntas-dificiles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/ltam\/"},{"@type":"ListItem","position":2,"name":"Preguntas dif\u00edciles"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/ltam\/#website","url":"https:\/\/about.fb.com\/news\/","name":"Acerca de Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/ltam\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/ltam\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/ltam\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/ltam\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/about.fb.com\/ltam\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/ltam\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2017\/06\/friendshipmap.jpg?fit=960%2C480","_links":{"self":[{"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/posts\/6048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/users\/95829248"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/comments?post=6048"}],"version-history":[{"count":1,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/posts\/6048\/revisions"}],"predecessor-version":[{"id":6050,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/posts\/6048\/revisions\/6050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/media\/6049"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/media?parent=6048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/categories?post=6048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/tags?post=6048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}