{"id":5360,"date":"2016-03-07T22:52:12","date_gmt":"2016-03-07T22:52:12","guid":{"rendered":"http:\/\/ltam.newsroom.fb.com\/?p=5360"},"modified":"2019-11-04T13:23:11","modified_gmt":"2019-11-04T19:23:11","slug":"facebook-presenta-plugin-en-wordpress-para-instant-articles","status":"publish","type":"post","link":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/","title":{"rendered":"Facebook presenta PlugIn en WordPress para Instant Articles"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5361\" src=\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/instantarticleswordpresshero-1-1.jpg?resize=960%2C540\" alt=\"InstantArticlesWordPressHero (1)\" width=\"960\" height=\"540\" \/><\/p>\n<p>Por <a href=\"https:\/\/www.facebook.com\/chris.ackermann\"><u>Chris Ackermann<\/u><\/a>, Partner Engineering<\/p>\n<p>Hace unas semanas <a href=\"http:\/\/media.fb.com\/2016\/02\/17\/opening-up-instant-articles\/\"><u>anunciamos<\/u><\/a> que a partir de abril Instant Articles estar\u00e1 disponible para todos los productores de contenido, de cualquier tama\u00f1o y en cualquier parte del mundo.<\/p>\n<p>Hoy queremos anunciar que Facebook se asoci\u00f3 a Automattic, la empresa matriz de WordPress.com VIP, para construir un plugin gratuito para Instant Articles que simplifica el proceso de creaci\u00f3n y publicaci\u00f3n de Instant Articles desde WordPress.<\/p>\n<p>La plataforma de c\u00f3digo abierto WordPress da soporte actualmente a m\u00e1s de un 25% de los sitios en la web, y estamos muy contentos de poder ayudar a millones de editores en todo el mundo a llevar la experiencia Instant Articles a sus lectores.<\/p>\n<p>Hemos trabajado con un grupo peque\u00f1o de productores de contenido en WordPress para probar el plugin en una versi\u00f3n beta, incorporado herramientas interactivas que adaptan de forma sencilla el contenido web al formato Instant Articles y permiten que las historias cobren vida en dispositivos m\u00f3viles.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5362\" src=\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/wp-foreign-policy-1.jpg?resize=960%2C775\" alt=\"WP-Foreign-Policy\" width=\"960\" height=\"775\" \/><\/p>\n<p>El plugin reconoce, por ejemplo, la imagen en este art\u00edculo de <a href=\"http:\/\/foreignpolicy.com\/2016\/02\/19\/are-the-2020-tokyo-olympics-in-trouble\/\">Foreign Policy<\/a> y ajusta la configuraci\u00f3n para que la foto pueda visualizarse correctamente en Instant Articles. La pantalla se expande al tacto y permite su exploraci\u00f3n con una simple inclinaci\u00f3n del tel\u00e9fono.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5363\" src=\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/wp-zap2it-2-1.jpg?resize=960%2C775\" alt=\"WP-zap2it-2\" width=\"960\" height=\"775\" \/><\/p>\n<p>En este ejemplo, el reproductor de video externo incrustado en este art\u00edculo de <a href=\"https:\/\/urldefense.proofpoint.com\/v2\/url?u=http-3A__zap2it.com_2016_03_zootopia-2Dginnifer-2Dgoodwin-2Dcant-2Dhandle-2Djason-2Dbateman-2Dcomedy_&amp;d=CwMFaQ&amp;c=5VD0RTtNlTh3ycd41b3MUw&amp;r=CF1y8tbl_QZf7J5fZcli0DZ1f_1nYYv4ayXkqk_slNU&amp;m=sQ89vZUCGRY4mciYfnnVVKlkbsgoqSqfMOwVrK5YtuM&amp;s=eEz_Fpm2DyYvV8C6KgpZL_D67T811NahX3Q4b57al9o&amp;e=\">Zap2it<\/a> para Tribune Broadcasting est\u00e1 maravillosamente adaptado para la experiencia de Instant Articles. El plugin tambi\u00e9n es compatible con videos de reproducci\u00f3n autom\u00e1tica nativos y con gr\u00e1ficos sociales e interactivos incrustados.<\/p>\n<p>Cuando Instant Articles est\u00e9 disponible masivamente a partir de la conferencia <a href=\"https:\/\/urldefense.proofpoint.com\/v2\/url?u=https-3A__www.fbf8.com_&amp;d=CwMFaQ&amp;c=5VD0RTtNlTh3ycd41b3MUw&amp;r=CF1y8tbl_QZf7J5fZcli0DZ1f_1nYYv4ayXkqk_slNU&amp;m=sQ89vZUCGRY4mciYfnnVVKlkbsgoqSqfMOwVrK5YtuM&amp;s=kc9jjFwVrwX5koK49bscC5VRKvEAvhdWxupUe5ghCgU&amp;e=\">F8<\/a> de Facebook el 12 de abril de 2016, los editores que usen templates est\u00e1ndar en WordPress podr\u00e1n activar el plugin para crear Instant Articles. Quienes quieran una experiencia de producci\u00f3n m\u00e1s personalizada podr\u00e1n extender el plugin para obtener m\u00e1s elementos. Animamos a todos los editores en WordPress que est\u00e9n interesados a revistar la <a href=\"https:\/\/urldefense.proofpoint.com\/v2\/url?u=https-3A__vip.wordpress.com_plugins_instant-2Darticles_&amp;d=CwMFaQ&amp;c=5VD0RTtNlTh3ycd41b3MUw&amp;r=CF1y8tbl_QZf7J5fZcli0DZ1f_1nYYv4ayXkqk_slNU&amp;m=sQ89vZUCGRY4mciYfnnVVKlkbsgoqSqfMOwVrK5YtuM&amp;s=Hnkd2TUmnPpOyKkiR6_4TZ5jO4XE5Nv4H84tRiwgl8U&amp;e=\"><u>documentaci\u00f3n y el FAQs<\/u><\/a> del plugin.<br \/>\nEl plugin es de c\u00f3digo abierto y alentamos a la comunidad a participar de su desarrollo para ayudar a editores a aprovechar de la mejor forma posible la r\u00e1pida y nativa experiencia de Instant Articles. Si tienes comentarios o sugerencias puedes enviarlas como <a href=\"https:\/\/github.com\/Automattic\/facebook-instant-articles-wp\/\"><u>Issue en GitHub<\/u><\/a>. Y si est\u00e1s escribiendo una capa de compatibilidad para otro plugin popular, te animamos a que lo compartas con la comunidad de WordPress a trav\u00e9s de un <a href=\"https:\/\/github.com\/Automattic\/facebook-instant-articles-wp\/\"><u>Pull Request<\/u><\/a>.<\/p>\n<p>Nuestro objetivo ha sido siempre habilitar Instant Articles para todos los productores de contenidos, y nuestra alianza con Automattic es otro paso importante en esa direcci\u00f3n. Continuaremos trabajando en el plugin en las pr\u00f3ximas semanas y estamos ansiosos de colaborar con la comunidad de WordPress para mejorar la experiencia.<\/p>\n<p>Para m\u00e1s informaci\u00f3n, visita <a href=\"http:\/\/instantarticles.fb.com\/\"><u>instantarticles.fb.com<\/u><\/a> y <a href=\"https:\/\/urldefense.proofpoint.com\/v2\/url?u=http-3A__wp.me_p9nvA-2D64Z&amp;d=CwMFaQ&amp;c=5VD0RTtNlTh3ycd41b3MUw&amp;r=CF1y8tbl_QZf7J5fZcli0DZ1f_1nYYv4ayXkqk_slNU&amp;m=sQ89vZUCGRY4mciYfnnVVKlkbsgoqSqfMOwVrK5YtuM&amp;s=4mBhTeraqeiDJD-lVpopvnM1wqu6jKJv8YutUkG6X3k&amp;e=\"><u>vip.wordpress.com\/blog<\/u><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Por Chris Ackermann, Partner Engineering Hace unas semanas anunciamos que a partir de abril Instant Articles estar\u00e1 disponible para todos los productores de contenido, de cualquier tama\u00f1o y en cualquier parte del mundo. Hoy queremos anunciar que Facebook se asoci\u00f3 a Automattic, la empresa matriz de WordPress.com VIP, para construir un plugin gratuito para Instant Articles que simplifica el proceso de creaci\u00f3n y publicaci\u00f3n de Instant Articles desde WordPress. La plataforma de c\u00f3digo abierto WordPress da soporte actualmente a m\u00e1s de un 25% de los sitios en la web, y estamos muy contentos de poder ayudar a millones de editores en todo el mundo a llevar la experiencia Instant Articles a sus lectores. Hemos trabajado con un grupo peque\u00f1o de productores de contenido en WordPress para probar el plugin en una versi\u00f3n beta, incorporado herramientas interactivas que adaptan de forma sencilla el contenido web al formato Instant Articles y permiten que las historias cobren vida en dispositivos m\u00f3viles. El plugin reconoce, por ejemplo, la imagen en este art\u00edculo de Foreign Policy y ajusta la configuraci\u00f3n para que la foto pueda visualizarse correctamente en Instant Articles. La pantalla se expande al tacto y permite su exploraci\u00f3n con una simple inclinaci\u00f3n del tel\u00e9fono. En este ejemplo, el reproductor de video externo incrustado en este art\u00edculo de Zap2it para Tribune Broadcasting est\u00e1 maravillosamente adaptado para la experiencia de Instant Articles. El plugin tambi\u00e9n es compatible con videos de reproducci\u00f3n autom\u00e1tica nativos y con gr\u00e1ficos sociales e interactivos incrustados. Cuando Instant Articles est\u00e9 disponible masivamente a partir de la conferencia F8 de Facebook el 12 de abril de 2016, los editores que usen templates est\u00e1ndar en WordPress podr\u00e1n activar el plugin para crear Instant Articles. Quienes quieran una experiencia de producci\u00f3n m\u00e1s personalizada podr\u00e1n extender el plugin para obtener m\u00e1s elementos. Animamos a todos los editores en WordPress que est\u00e9n interesados a revistar la documentaci\u00f3n y el FAQs del plugin. El plugin es de c\u00f3digo abierto y alentamos a la comunidad a participar de su desarrollo para ayudar a editores a aprovechar de la mejor forma posible la r\u00e1pida y nativa experiencia de Instant Articles. Si tienes comentarios o sugerencias puedes enviarlas como Issue en GitHub. Y si est\u00e1s escribiendo una capa de compatibilidad para otro plugin popular, te animamos a que lo compartas con la comunidad de WordPress a trav\u00e9s de un Pull Request. Nuestro objetivo ha sido siempre habilitar Instant Articles para todos los productores de contenidos, y nuestra alianza con Automattic es otro paso importante en esa direcci\u00f3n. Continuaremos trabajando en el plugin en las pr\u00f3ximas semanas y estamos ansiosos de colaborar con la comunidad de WordPress para mejorar la experiencia. Para m\u00e1s informaci\u00f3n, visita instantarticles.fb.com y vip.wordpress.com\/blog.","protected":false},"author":95829248,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[243907042],"tags":[22411372,243947845],"class_list":["post-5360","post","type-post","status-publish","format-standard","hentry","category-facebook-media","tag-instant-articles","tag-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Facebook presenta PlugIn en WordPress para Instant Articles | Acerca de Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Facebook presenta PlugIn en WordPress para Instant Articles | Acerca de Meta\" \/>\n<meta property=\"og:description\" content=\"Por Chris Ackermann, Partner Engineering Hace unas semanas anunciamos que a partir de abril Instant Articles estar\u00e1 disponible para todos los productores de contenido, de cualquier tama\u00f1o y en cualquier parte del mundo. Hoy queremos anunciar que Facebook se asoci\u00f3 a Automattic, la empresa matriz de WordPress.com VIP, para construir un plugin gratuito para Instant Articles que simplifica el proceso de creaci\u00f3n y publicaci\u00f3n de Instant Articles desde WordPress. La plataforma de c\u00f3digo abierto WordPress da soporte actualmente a m\u00e1s de un 25% de los sitios en la web, y estamos muy contentos de poder ayudar a millones de editores en todo el mundo a llevar la experiencia Instant Articles a sus lectores. Hemos trabajado con un grupo peque\u00f1o de productores de contenido en WordPress para probar el plugin en una versi\u00f3n beta, incorporado herramientas interactivas que adaptan de forma sencilla el contenido web al formato Instant Articles y permiten que las historias cobren vida en dispositivos m\u00f3viles. El plugin reconoce, por ejemplo, la imagen en este art\u00edculo de Foreign Policy y ajusta la configuraci\u00f3n para que la foto pueda visualizarse correctamente en Instant Articles. La pantalla se expande al tacto y permite su exploraci\u00f3n con una simple inclinaci\u00f3n del tel\u00e9fono. En este ejemplo, el reproductor de video externo incrustado en este art\u00edculo de Zap2it para Tribune Broadcasting est\u00e1 maravillosamente adaptado para la experiencia de Instant Articles. El plugin tambi\u00e9n es compatible con videos de reproducci\u00f3n autom\u00e1tica nativos y con gr\u00e1ficos sociales e interactivos incrustados. Cuando Instant Articles est\u00e9 disponible masivamente a partir de la conferencia F8 de Facebook el 12 de abril de 2016, los editores que usen templates est\u00e1ndar en WordPress podr\u00e1n activar el plugin para crear Instant Articles. Quienes quieran una experiencia de producci\u00f3n m\u00e1s personalizada podr\u00e1n extender el plugin para obtener m\u00e1s elementos. Animamos a todos los editores en WordPress que est\u00e9n interesados a revistar la documentaci\u00f3n y el FAQs del plugin. El plugin es de c\u00f3digo abierto y alentamos a la comunidad a participar de su desarrollo para ayudar a editores a aprovechar de la mejor forma posible la r\u00e1pida y nativa experiencia de Instant Articles. Si tienes comentarios o sugerencias puedes enviarlas como Issue en GitHub. Y si est\u00e1s escribiendo una capa de compatibilidad para otro plugin popular, te animamos a que lo compartas con la comunidad de WordPress a trav\u00e9s de un Pull Request. Nuestro objetivo ha sido siempre habilitar Instant Articles para todos los productores de contenidos, y nuestra alianza con Automattic es otro paso importante en esa direcci\u00f3n. Continuaremos trabajando en el plugin en las pr\u00f3ximas semanas y estamos ansiosos de colaborar con la comunidad de WordPress para mejorar la experiencia. Para m\u00e1s informaci\u00f3n, visita instantarticles.fb.com y vip.wordpress.com\/blog.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/\" \/>\n<meta property=\"og:site_name\" content=\"Acerca de Meta\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-07T22:52:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-04T19:23:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/instantarticleswordpresshero-1-1.jpg\" \/>\n<meta name=\"author\" content=\"camilagfb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/\"},\"author\":\"Facebook company\",\"headline\":\"Facebook presenta PlugIn en WordPress para Instant Articles\",\"datePublished\":\"2016-03-07T22:52:12+00:00\",\"dateModified\":\"2019-11-04T19:23:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/\"},\"wordCount\":493,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/#organization\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/instantarticleswordpresshero-1-1.jpg\",\"keywords\":[\"Instant Articles\",\"Media\"],\"articleSection\":[\"Facebook para Medios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/\",\"url\":\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/\",\"name\":\"Facebook presenta PlugIn en WordPress para Instant Articles | Acerca de Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/instantarticleswordpresshero-1-1.jpg\",\"datePublished\":\"2016-03-07T22:52:12+00:00\",\"dateModified\":\"2019-11-04T19:23:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/\"]}],\"author\":\"Acerca de Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#primaryimage\",\"url\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/instantarticleswordpresshero-1-1.jpg?fit=960%2C540\",\"contentUrl\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/instantarticleswordpresshero-1-1.jpg?fit=960%2C540\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/ltam\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facebook presenta PlugIn en WordPress para Instant Articles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/ltam\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"Acerca de Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/ltam\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/ltam\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/ltam\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/about.fb.com\/ltam\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/ltam\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Facebook presenta PlugIn en WordPress para Instant Articles | Acerca de Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/","og_locale":"es_ES","og_type":"article","og_title":"Facebook presenta PlugIn en WordPress para Instant Articles | Acerca de Meta","og_description":"Por Chris Ackermann, Partner Engineering Hace unas semanas anunciamos que a partir de abril Instant Articles estar\u00e1 disponible para todos los productores de contenido, de cualquier tama\u00f1o y en cualquier parte del mundo. Hoy queremos anunciar que Facebook se asoci\u00f3 a Automattic, la empresa matriz de WordPress.com VIP, para construir un plugin gratuito para Instant Articles que simplifica el proceso de creaci\u00f3n y publicaci\u00f3n de Instant Articles desde WordPress. La plataforma de c\u00f3digo abierto WordPress da soporte actualmente a m\u00e1s de un 25% de los sitios en la web, y estamos muy contentos de poder ayudar a millones de editores en todo el mundo a llevar la experiencia Instant Articles a sus lectores. Hemos trabajado con un grupo peque\u00f1o de productores de contenido en WordPress para probar el plugin en una versi\u00f3n beta, incorporado herramientas interactivas que adaptan de forma sencilla el contenido web al formato Instant Articles y permiten que las historias cobren vida en dispositivos m\u00f3viles. El plugin reconoce, por ejemplo, la imagen en este art\u00edculo de Foreign Policy y ajusta la configuraci\u00f3n para que la foto pueda visualizarse correctamente en Instant Articles. La pantalla se expande al tacto y permite su exploraci\u00f3n con una simple inclinaci\u00f3n del tel\u00e9fono. En este ejemplo, el reproductor de video externo incrustado en este art\u00edculo de Zap2it para Tribune Broadcasting est\u00e1 maravillosamente adaptado para la experiencia de Instant Articles. El plugin tambi\u00e9n es compatible con videos de reproducci\u00f3n autom\u00e1tica nativos y con gr\u00e1ficos sociales e interactivos incrustados. Cuando Instant Articles est\u00e9 disponible masivamente a partir de la conferencia F8 de Facebook el 12 de abril de 2016, los editores que usen templates est\u00e1ndar en WordPress podr\u00e1n activar el plugin para crear Instant Articles. Quienes quieran una experiencia de producci\u00f3n m\u00e1s personalizada podr\u00e1n extender el plugin para obtener m\u00e1s elementos. Animamos a todos los editores en WordPress que est\u00e9n interesados a revistar la documentaci\u00f3n y el FAQs del plugin. El plugin es de c\u00f3digo abierto y alentamos a la comunidad a participar de su desarrollo para ayudar a editores a aprovechar de la mejor forma posible la r\u00e1pida y nativa experiencia de Instant Articles. Si tienes comentarios o sugerencias puedes enviarlas como Issue en GitHub. Y si est\u00e1s escribiendo una capa de compatibilidad para otro plugin popular, te animamos a que lo compartas con la comunidad de WordPress a trav\u00e9s de un Pull Request. Nuestro objetivo ha sido siempre habilitar Instant Articles para todos los productores de contenidos, y nuestra alianza con Automattic es otro paso importante en esa direcci\u00f3n. Continuaremos trabajando en el plugin en las pr\u00f3ximas semanas y estamos ansiosos de colaborar con la comunidad de WordPress para mejorar la experiencia. Para m\u00e1s informaci\u00f3n, visita instantarticles.fb.com y vip.wordpress.com\/blog.","og_url":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/","og_site_name":"Acerca de Meta","article_published_time":"2016-03-07T22:52:12+00:00","article_modified_time":"2019-11-04T19:23:11+00:00","og_image":[{"url":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/instantarticleswordpresshero-1-1.jpg","type":"","width":"","height":""}],"author":"camilagfb","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/"},"author":"Facebook company","headline":"Facebook presenta PlugIn en WordPress para Instant Articles","datePublished":"2016-03-07T22:52:12+00:00","dateModified":"2019-11-04T19:23:11+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/"},"wordCount":493,"publisher":{"@id":"https:\/\/about.fb.com\/ltam\/#organization"},"image":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/instantarticleswordpresshero-1-1.jpg","keywords":["Instant Articles","Media"],"articleSection":["Facebook para Medios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/","url":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/","name":"Facebook presenta PlugIn en WordPress para Instant Articles | Acerca de Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/ltam\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#primaryimage"},"image":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/instantarticleswordpresshero-1-1.jpg","datePublished":"2016-03-07T22:52:12+00:00","dateModified":"2019-11-04T19:23:11+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/"]}],"author":"Acerca de Meta"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#primaryimage","url":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/instantarticleswordpresshero-1-1.jpg?fit=960%2C540","contentUrl":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2016\/03\/instantarticleswordpresshero-1-1.jpg?fit=960%2C540","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/ltam\/news\/2016\/03\/facebook-presenta-plugin-en-wordpress-para-instant-articles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/ltam\/"},{"@type":"ListItem","position":2,"name":"Facebook presenta PlugIn en WordPress para Instant Articles"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/ltam\/#website","url":"https:\/\/about.fb.com\/news\/","name":"Acerca de Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/ltam\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/ltam\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/ltam\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/ltam\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/about.fb.com\/ltam\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/ltam\/wp-content\/uploads\/sites\/14\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/ltam\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/posts\/5360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/users\/95829248"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/comments?post=5360"}],"version-history":[{"count":2,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/posts\/5360\/revisions"}],"predecessor-version":[{"id":7950,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/posts\/5360\/revisions\/7950"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/media?parent=5360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/categories?post=5360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/ltam\/wp-json\/wp\/v2\/tags?post=5360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}