{"id":27360,"date":"2022-09-12T14:01:10","date_gmt":"2022-09-12T13:01:10","guid":{"rendered":"https:\/\/about.fb.com\/de\/?p=27360"},"modified":"2022-09-12T14:01:10","modified_gmt":"2022-09-12T13:01:10","slug":"vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung","status":"publish","type":"post","link":"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/","title":{"rendered":"Vorstellung der PyTorch Foundation zur schnelleren Erzielung von Fortschritten in der KI-Forschung"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Von<\/span> <span style=\"font-weight: 400\">Santosh Janardhan, VP, Infrastructure<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Aus PyTorch, einem der f\u00fchrenden Community-gest\u00fctzten Frameworks zur KI-Forschung, entsteht innerhalb der Linux Foundation die neue, unabh\u00e4ngige PyTorch Foundation.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Die PyTorch Foundation soll den freien Zugriff auf modernste KI-Tools, Bibliotheken und andere Komponenten erleichtern, um schneller Fortschritte in der KI-Forschung zu erzielen.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Meta wird auch weiterhin in PyTorch investieren und es als zentrales Framework f\u00fcr die KI-Forschung und Anwendungen im Unternehmen einsetzen.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Seit wir 2016 gemeinsam mit der KI-Community das <\/span><a href=\"https:\/\/pytorch.org\/\"><span style=\"font-weight: 400\">PyTorch<\/span><\/a><span style=\"font-weight: 400\">-Framework zur KI-Forschung ins Leben gerufen haben, ist die offene Zusammenarbeit ein wesentlicher Faktor f\u00fcr dessen Erfolg. Mit PyTorch wurden dank tausender Mitwirkender bereits \u00fcber 150.000 Projekte realisiert. Das macht es zu einer der f\u00fchrenden Plattformen zur Forschung und Produktion in der KI-Gemeinschaft.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Wir freuen uns, heute bekannt geben zu k\u00f6nnen, dass das Projekt in die neu gegr\u00fcndete PyTorch Foundation \u00fcbergeht. Sie wird Teil der gemeinn\u00fctzigen <\/span><a href=\"https:\/\/www.linuxfoundation.org\/\"><span style=\"font-weight: 400\">Linux Foundation<\/span><\/a><span style=\"font-weight: 400\"> sein, einem Technologiekonsortium mit dem <\/span><a href=\"https:\/\/www.linuxfoundation.org\/about\/\"><span style=\"font-weight: 400\">Kernziel<\/span><\/a><span style=\"font-weight: 400\"> der gemeinschaftlichen Entwicklung von Open-Source-Software.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die Gr\u00fcndung der PyTorch Foundation stellt sicher, dass in den kommenden Jahren Entscheidungen offen und transparent durch eine vielf\u00e4ltige Gruppe von Stiftungsratsmitgliedern getroffen werden. Das Stiftungsgremium wird sich aus Vertreter*innen von AMD, Amazon Web Services, Google Cloud, Meta, Microsoft Azure und Nvidia zusammensetzen und soll im Laufe der Zeit weiter vergr\u00f6\u00dfert werden.<\/span><\/p>\n<div style=\"width: 960px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-27360-1\" width=\"960\" height=\"540\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2022\/09\/PyTorch-mp4.mp4?_=1\" \/><a href=\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2022\/09\/PyTorch-mp4.mp4\">https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2022\/09\/PyTorch-mp4.mp4<\/a><\/video><\/div>\n<p><b>Unser Engagement f\u00fcr gemeinschaftliche KI-Forschung<\/b><\/p>\n<p><span style=\"font-weight: 400\">PyTorch wurde mit einer Open-Source-Philosophie erschaffen, bei der die Community an erster Stelle steht \u2013 und das wird sich auch mit dem \u00dcbergang in eine Stiftung nicht \u00e4ndern. Wenn Forscher*innen und Entwickler*innen ihren Code als Open Source zur Verf\u00fcgung stellen, k\u00f6nnen Personen auf der ganzen Welt ihre Arbeit mit anderen teilen, von den Fortschritten anderer lernen und dann ihren eigenen Beitrag zur KI-Gemeinschaft leisten.<\/span><\/p>\n<p><span style=\"font-weight: 400\">In Zukunft profitieren die Mitwirkenden des Frameworks von der kompetenten Leitung, der vielf\u00e4ltigen Stiftungsf\u00fchrung und den zus\u00e4tzlichen Investitionen, die von den neuen Partnern der PyTorch Foundation bereitgestellt werden. Dabei wird die Stiftung vier Grunds\u00e4tzen folgen: Sie wird offen bleiben, ein neutrales Branding beibehalten, fair handeln und eine starke technische Identit\u00e4t aufbauen. Eine ihrer obersten Priorit\u00e4ten wird die klare Trennung zwischen der gesch\u00e4ftlichen und der technischen Leitung von PyTorch sein.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Meta wird auch weiterhin in PyTorch investieren und es als prim\u00e4res Framework f\u00fcr die KI-Forschung und Produktion nutzen. Die Umwandlung selbst bringt keine \u00c4nderungen am Code von PyTorch, am Kernprojekt oder an den Anwendungsmodellen f\u00fcr Entwickler*innen mit sich.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Wir haben konsequent daran gearbeitet, das von der Community angetriebene Wachstum zu f\u00f6rdern, das den Erfolg von PyTorch befl\u00fcgelt hat, indem wir Hunderte von Ingenieur*innen f\u00fcr das Framework eingesetzt und die Produktentwicklung sowie Community-Initiativen unterst\u00fctzt haben.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Im Mittelpunkt unserer KI-Arbeit steht die offene Wissenschaft, sei es die <\/span><a href=\"https:\/\/ai.facebook.com\/blog\/democratizing-access-to-large-scale-language-models-with-opt-175b\/\"><span style=\"font-weight: 400\">Freigabe von Code f\u00fcr Large Language Models<\/span><\/a><span style=\"font-weight: 400\">, <\/span><a href=\"https:\/\/ai.facebook.com\/blog\/dino-paws-computer-vision-with-self-supervised-transformers-and-10x-more-efficient-training\/\"><span style=\"font-weight: 400\">selbst\u00fcberwachte Computer-Vision-Systeme<\/span><\/a><span style=\"font-weight: 400\">, <\/span><a href=\"https:\/\/ai.facebook.com\/blog\/teaching-ai-to-perceive-the-world-through-your-eyes\/\"><span style=\"font-weight: 400\">innovative neue Datens\u00e4tze<\/span><\/a><span style=\"font-weight: 400\">, <\/span><a href=\"https:\/\/ai.facebook.com\/blog\/habitat-20-training-home-assistant-robots-with-faster-simulation-and-new-benchmarks\/\"><span style=\"font-weight: 400\">integrierte KI-Plattformen<\/span><\/a><span style=\"font-weight: 400\"> und vieles mehr. Wir sind davon \u00fcberzeugt, dass dieser Ansatz am schnellsten Fortschritte bei der Entwicklung und dem Einsatz neuer Systeme erm\u00f6glicht, die auf reale Bed\u00fcrfnisse eingehen und grundlegende Fragen \u00fcber die Bedeutung von Intelligenz beantworten. Mit der Gr\u00fcndung der PyTorch Foundation ist die gesamte KI-Gemeinschaft bestens aufgestellt, das Gebiet auf unz\u00e4hlige aufregende neue Arten voranzutreiben.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"Von Santosh Janardhan, VP, Infrastructure Aus PyTorch, einem der f\u00fchrenden Community-gest\u00fctzten Frameworks zur KI-Forschung, entsteht innerhalb der Linux Foundation die neue, unabh\u00e4ngige PyTorch Foundation. Die PyTorch Foundation soll den freien Zugriff auf modernste KI-Tools, Bibliotheken und andere Komponenten erleichtern, um schneller Fortschritte in der KI-Forschung zu erzielen. Meta wird auch weiterhin in PyTorch investieren und es als zentrales Framework f\u00fcr die KI-Forschung und Anwendungen im Unternehmen einsetzen. Seit wir 2016 gemeinsam mit der KI-Community das PyTorch-Framework zur KI-Forschung ins Leben gerufen haben, ist die offene Zusammenarbeit ein wesentlicher Faktor f\u00fcr dessen Erfolg. Mit PyTorch wurden dank tausender Mitwirkender bereits \u00fcber 150.000 Projekte realisiert. Das macht es zu einer der f\u00fchrenden Plattformen zur Forschung und Produktion in der KI-Gemeinschaft. Wir freuen uns, heute bekannt geben zu k\u00f6nnen, dass das Projekt in die neu gegr\u00fcndete PyTorch Foundation \u00fcbergeht. Sie wird Teil der gemeinn\u00fctzigen Linux Foundation sein, einem Technologiekonsortium mit dem Kernziel der gemeinschaftlichen Entwicklung von Open-Source-Software. Die Gr\u00fcndung der PyTorch Foundation stellt sicher, dass in den kommenden Jahren Entscheidungen offen und transparent durch eine vielf\u00e4ltige Gruppe von Stiftungsratsmitgliedern getroffen werden. Das Stiftungsgremium wird sich aus Vertreter*innen von AMD, Amazon Web Services, Google Cloud, Meta, Microsoft Azure und Nvidia zusammensetzen und soll im Laufe der Zeit weiter vergr\u00f6\u00dfert werden. Unser Engagement f\u00fcr gemeinschaftliche KI-Forschung PyTorch wurde mit einer Open-Source-Philosophie erschaffen, bei der die Community an erster Stelle steht \u2013 und das wird sich auch mit dem \u00dcbergang in eine Stiftung nicht \u00e4ndern. Wenn Forscher*innen und Entwickler*innen ihren Code als Open Source zur Verf\u00fcgung stellen, k\u00f6nnen Personen auf der ganzen Welt ihre Arbeit mit anderen teilen, von den Fortschritten anderer lernen und dann ihren eigenen Beitrag zur KI-Gemeinschaft leisten. In Zukunft profitieren die Mitwirkenden des Frameworks von der kompetenten Leitung, der vielf\u00e4ltigen Stiftungsf\u00fchrung und den zus\u00e4tzlichen Investitionen, die von den neuen Partnern der PyTorch Foundation bereitgestellt werden. Dabei wird die Stiftung vier Grunds\u00e4tzen folgen: Sie wird offen bleiben, ein neutrales Branding beibehalten, fair handeln und eine starke technische Identit\u00e4t aufbauen. Eine ihrer obersten Priorit\u00e4ten wird die klare Trennung zwischen der gesch\u00e4ftlichen und der technischen Leitung von PyTorch sein. Meta wird auch weiterhin in PyTorch investieren und es als prim\u00e4res Framework f\u00fcr die KI-Forschung und Produktion nutzen. Die Umwandlung selbst bringt keine \u00c4nderungen am Code von PyTorch, am Kernprojekt oder an den Anwendungsmodellen f\u00fcr Entwickler*innen mit sich. Wir haben konsequent daran gearbeitet, das von der Community angetriebene Wachstum zu f\u00f6rdern, das den Erfolg von PyTorch befl\u00fcgelt hat, indem wir Hunderte von Ingenieur*innen f\u00fcr das Framework eingesetzt und die Produktentwicklung sowie Community-Initiativen unterst\u00fctzt haben. Im Mittelpunkt unserer KI-Arbeit steht die offene Wissenschaft, sei es die Freigabe von Code f\u00fcr Large Language Models, selbst\u00fcberwachte Computer-Vision-Systeme, innovative neue Datens\u00e4tze, integrierte KI-Plattformen und vieles mehr. Wir sind davon \u00fcberzeugt, dass dieser Ansatz am schnellsten Fortschritte bei der Entwicklung und dem Einsatz neuer Systeme erm\u00f6glicht, die auf reale Bed\u00fcrfnisse eingehen und grundlegende Fragen \u00fcber die Bedeutung von Intelligenz beantworten. Mit der Gr\u00fcndung der PyTorch Foundation ist die gesamte KI-Gemeinschaft bestens aufgestellt, das Gebiet auf unz\u00e4hlige aufregende neue Arten voranzutreiben.","protected":false},"author":116770500,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[555973272,555973667,555973442,555973477,555973441],"tags":[555973305,555973306,555973307,555973723],"class_list":["post-27360","post","type-post","status-publish","format-standard","hentry","category-entwicklerthemen","category-innovation","category-meta","category-technologies","category-technology-and-innovation","tag-ai","tag-ki","tag-kuenstliche-intelligenz","tag-linux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vorstellung der PyTorch Foundation zur schnelleren Erzielung von Fortschritten in der KI-Forschung | \u00dcber Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vorstellung der PyTorch Foundation zur schnelleren Erzielung von Fortschritten in der KI-Forschung | \u00dcber Meta\" \/>\n<meta property=\"og:description\" content=\"Von Santosh Janardhan, VP, Infrastructure Aus PyTorch, einem der f\u00fchrenden Community-gest\u00fctzten Frameworks zur KI-Forschung, entsteht innerhalb der Linux Foundation die neue, unabh\u00e4ngige PyTorch Foundation. Die PyTorch Foundation soll den freien Zugriff auf modernste KI-Tools, Bibliotheken und andere Komponenten erleichtern, um schneller Fortschritte in der KI-Forschung zu erzielen. Meta wird auch weiterhin in PyTorch investieren und es als zentrales Framework f\u00fcr die KI-Forschung und Anwendungen im Unternehmen einsetzen. Seit wir 2016 gemeinsam mit der KI-Community das PyTorch-Framework zur KI-Forschung ins Leben gerufen haben, ist die offene Zusammenarbeit ein wesentlicher Faktor f\u00fcr dessen Erfolg. Mit PyTorch wurden dank tausender Mitwirkender bereits \u00fcber 150.000 Projekte realisiert. Das macht es zu einer der f\u00fchrenden Plattformen zur Forschung und Produktion in der KI-Gemeinschaft. Wir freuen uns, heute bekannt geben zu k\u00f6nnen, dass das Projekt in die neu gegr\u00fcndete PyTorch Foundation \u00fcbergeht. Sie wird Teil der gemeinn\u00fctzigen Linux Foundation sein, einem Technologiekonsortium mit dem Kernziel der gemeinschaftlichen Entwicklung von Open-Source-Software. Die Gr\u00fcndung der PyTorch Foundation stellt sicher, dass in den kommenden Jahren Entscheidungen offen und transparent durch eine vielf\u00e4ltige Gruppe von Stiftungsratsmitgliedern getroffen werden. Das Stiftungsgremium wird sich aus Vertreter*innen von AMD, Amazon Web Services, Google Cloud, Meta, Microsoft Azure und Nvidia zusammensetzen und soll im Laufe der Zeit weiter vergr\u00f6\u00dfert werden. Unser Engagement f\u00fcr gemeinschaftliche KI-Forschung PyTorch wurde mit einer Open-Source-Philosophie erschaffen, bei der die Community an erster Stelle steht \u2013 und das wird sich auch mit dem \u00dcbergang in eine Stiftung nicht \u00e4ndern. Wenn Forscher*innen und Entwickler*innen ihren Code als Open Source zur Verf\u00fcgung stellen, k\u00f6nnen Personen auf der ganzen Welt ihre Arbeit mit anderen teilen, von den Fortschritten anderer lernen und dann ihren eigenen Beitrag zur KI-Gemeinschaft leisten. In Zukunft profitieren die Mitwirkenden des Frameworks von der kompetenten Leitung, der vielf\u00e4ltigen Stiftungsf\u00fchrung und den zus\u00e4tzlichen Investitionen, die von den neuen Partnern der PyTorch Foundation bereitgestellt werden. Dabei wird die Stiftung vier Grunds\u00e4tzen folgen: Sie wird offen bleiben, ein neutrales Branding beibehalten, fair handeln und eine starke technische Identit\u00e4t aufbauen. Eine ihrer obersten Priorit\u00e4ten wird die klare Trennung zwischen der gesch\u00e4ftlichen und der technischen Leitung von PyTorch sein. Meta wird auch weiterhin in PyTorch investieren und es als prim\u00e4res Framework f\u00fcr die KI-Forschung und Produktion nutzen. Die Umwandlung selbst bringt keine \u00c4nderungen am Code von PyTorch, am Kernprojekt oder an den Anwendungsmodellen f\u00fcr Entwickler*innen mit sich. Wir haben konsequent daran gearbeitet, das von der Community angetriebene Wachstum zu f\u00f6rdern, das den Erfolg von PyTorch befl\u00fcgelt hat, indem wir Hunderte von Ingenieur*innen f\u00fcr das Framework eingesetzt und die Produktentwicklung sowie Community-Initiativen unterst\u00fctzt haben. Im Mittelpunkt unserer KI-Arbeit steht die offene Wissenschaft, sei es die Freigabe von Code f\u00fcr Large Language Models, selbst\u00fcberwachte Computer-Vision-Systeme, innovative neue Datens\u00e4tze, integrierte KI-Plattformen und vieles mehr. Wir sind davon \u00fcberzeugt, dass dieser Ansatz am schnellsten Fortschritte bei der Entwicklung und dem Einsatz neuer Systeme erm\u00f6glicht, die auf reale Bed\u00fcrfnisse eingehen und grundlegende Fragen \u00fcber die Bedeutung von Intelligenz beantworten. Mit der Gr\u00fcndung der PyTorch Foundation ist die gesamte KI-Gemeinschaft bestens aufgestellt, das Gebiet auf unz\u00e4hlige aufregende neue Arten voranzutreiben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00dcber Meta\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-12T13:01:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?resize=1024,576\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segmentafacebook\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/\"},\"author\":\"Facebook company\",\"headline\":\"Vorstellung der PyTorch Foundation zur schnelleren Erzielung von Fortschritten in der KI-Forschung\",\"datePublished\":\"2022-09-12T13:01:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/\"},\"wordCount\":565,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/de\/#organization\"},\"keywords\":[\"AI\",\"KI\",\"K\u00fcnstliche Intelligenz\",\"Linux\"],\"articleSection\":[\"Entwicklerthemen\",\"Innovation\",\"Meta\",\"Technologies\",\"Technology and Innovation\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/\",\"url\":\"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/\",\"name\":\"Vorstellung der PyTorch Foundation zur schnelleren Erzielung von Fortschritten in der KI-Forschung | \u00dcber Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/de\/#website\"},\"datePublished\":\"2022-09-12T13:01:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/\"]}],\"author\":\"\u00dcber Meta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vorstellung der PyTorch Foundation zur schnelleren Erzielung von Fortschritten in der KI-Forschung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/de\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"\u00dcber Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/de\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/about.fb.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vorstellung der PyTorch Foundation zur schnelleren Erzielung von Fortschritten in der KI-Forschung | \u00dcber Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/","og_locale":"de_DE","og_type":"article","og_title":"Vorstellung der PyTorch Foundation zur schnelleren Erzielung von Fortschritten in der KI-Forschung | \u00dcber Meta","og_description":"Von Santosh Janardhan, VP, Infrastructure Aus PyTorch, einem der f\u00fchrenden Community-gest\u00fctzten Frameworks zur KI-Forschung, entsteht innerhalb der Linux Foundation die neue, unabh\u00e4ngige PyTorch Foundation. Die PyTorch Foundation soll den freien Zugriff auf modernste KI-Tools, Bibliotheken und andere Komponenten erleichtern, um schneller Fortschritte in der KI-Forschung zu erzielen. Meta wird auch weiterhin in PyTorch investieren und es als zentrales Framework f\u00fcr die KI-Forschung und Anwendungen im Unternehmen einsetzen. Seit wir 2016 gemeinsam mit der KI-Community das PyTorch-Framework zur KI-Forschung ins Leben gerufen haben, ist die offene Zusammenarbeit ein wesentlicher Faktor f\u00fcr dessen Erfolg. Mit PyTorch wurden dank tausender Mitwirkender bereits \u00fcber 150.000 Projekte realisiert. Das macht es zu einer der f\u00fchrenden Plattformen zur Forschung und Produktion in der KI-Gemeinschaft. Wir freuen uns, heute bekannt geben zu k\u00f6nnen, dass das Projekt in die neu gegr\u00fcndete PyTorch Foundation \u00fcbergeht. Sie wird Teil der gemeinn\u00fctzigen Linux Foundation sein, einem Technologiekonsortium mit dem Kernziel der gemeinschaftlichen Entwicklung von Open-Source-Software. Die Gr\u00fcndung der PyTorch Foundation stellt sicher, dass in den kommenden Jahren Entscheidungen offen und transparent durch eine vielf\u00e4ltige Gruppe von Stiftungsratsmitgliedern getroffen werden. Das Stiftungsgremium wird sich aus Vertreter*innen von AMD, Amazon Web Services, Google Cloud, Meta, Microsoft Azure und Nvidia zusammensetzen und soll im Laufe der Zeit weiter vergr\u00f6\u00dfert werden. Unser Engagement f\u00fcr gemeinschaftliche KI-Forschung PyTorch wurde mit einer Open-Source-Philosophie erschaffen, bei der die Community an erster Stelle steht \u2013 und das wird sich auch mit dem \u00dcbergang in eine Stiftung nicht \u00e4ndern. Wenn Forscher*innen und Entwickler*innen ihren Code als Open Source zur Verf\u00fcgung stellen, k\u00f6nnen Personen auf der ganzen Welt ihre Arbeit mit anderen teilen, von den Fortschritten anderer lernen und dann ihren eigenen Beitrag zur KI-Gemeinschaft leisten. In Zukunft profitieren die Mitwirkenden des Frameworks von der kompetenten Leitung, der vielf\u00e4ltigen Stiftungsf\u00fchrung und den zus\u00e4tzlichen Investitionen, die von den neuen Partnern der PyTorch Foundation bereitgestellt werden. Dabei wird die Stiftung vier Grunds\u00e4tzen folgen: Sie wird offen bleiben, ein neutrales Branding beibehalten, fair handeln und eine starke technische Identit\u00e4t aufbauen. Eine ihrer obersten Priorit\u00e4ten wird die klare Trennung zwischen der gesch\u00e4ftlichen und der technischen Leitung von PyTorch sein. Meta wird auch weiterhin in PyTorch investieren und es als prim\u00e4res Framework f\u00fcr die KI-Forschung und Produktion nutzen. Die Umwandlung selbst bringt keine \u00c4nderungen am Code von PyTorch, am Kernprojekt oder an den Anwendungsmodellen f\u00fcr Entwickler*innen mit sich. Wir haben konsequent daran gearbeitet, das von der Community angetriebene Wachstum zu f\u00f6rdern, das den Erfolg von PyTorch befl\u00fcgelt hat, indem wir Hunderte von Ingenieur*innen f\u00fcr das Framework eingesetzt und die Produktentwicklung sowie Community-Initiativen unterst\u00fctzt haben. Im Mittelpunkt unserer KI-Arbeit steht die offene Wissenschaft, sei es die Freigabe von Code f\u00fcr Large Language Models, selbst\u00fcberwachte Computer-Vision-Systeme, innovative neue Datens\u00e4tze, integrierte KI-Plattformen und vieles mehr. Wir sind davon \u00fcberzeugt, dass dieser Ansatz am schnellsten Fortschritte bei der Entwicklung und dem Einsatz neuer Systeme erm\u00f6glicht, die auf reale Bed\u00fcrfnisse eingehen und grundlegende Fragen \u00fcber die Bedeutung von Intelligenz beantworten. Mit der Gr\u00fcndung der PyTorch Foundation ist die gesamte KI-Gemeinschaft bestens aufgestellt, das Gebiet auf unz\u00e4hlige aufregende neue Arten voranzutreiben.","og_url":"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/","og_site_name":"\u00dcber Meta","article_published_time":"2022-09-12T13:01:10+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?resize=1024,576","type":"image\/jpeg"}],"author":"segmentafacebook","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/"},"author":"Facebook company","headline":"Vorstellung der PyTorch Foundation zur schnelleren Erzielung von Fortschritten in der KI-Forschung","datePublished":"2022-09-12T13:01:10+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/"},"wordCount":565,"publisher":{"@id":"https:\/\/about.fb.com\/de\/#organization"},"keywords":["AI","KI","K\u00fcnstliche Intelligenz","Linux"],"articleSection":["Entwicklerthemen","Innovation","Meta","Technologies","Technology and Innovation"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/","url":"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/","name":"Vorstellung der PyTorch Foundation zur schnelleren Erzielung von Fortschritten in der KI-Forschung | \u00dcber Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/de\/#website"},"datePublished":"2022-09-12T13:01:10+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/"]}],"author":"\u00dcber Meta"},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/de\/news\/2022\/09\/vorstellung-der-pytorch-foundation-zur-schnelleren-erzielung-von-fortschritten-in-der-ki-forschung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/de\/"},{"@type":"ListItem","position":2,"name":"Vorstellung der PyTorch Foundation zur schnelleren Erzielung von Fortschritten in der KI-Forschung"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/de\/#website","url":"https:\/\/about.fb.com\/news\/","name":"\u00dcber Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/de\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/about.fb.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/de\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/posts\/27360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/users\/116770500"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/comments?post=27360"}],"version-history":[{"count":1,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/posts\/27360\/revisions"}],"predecessor-version":[{"id":27362,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/posts\/27360\/revisions\/27362"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/media?parent=27360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/categories?post=27360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/tags?post=27360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}