{"id":26483,"date":"2021-10-08T10:48:54","date_gmt":"2021-10-08T09:48:54","guid":{"rendered":"https:\/\/about.fb.com\/de\/?p=26483"},"modified":"2021-10-08T10:50:01","modified_gmt":"2021-10-08T09:50:01","slug":"unterstuetzung_fuer_kleinunternehmen","status":"publish","type":"post","link":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/","title":{"rendered":"\u201cEs bedarf auch weiterhin F\u00f6rder- und Unterst\u00fctzungsprogramme speziell f\u00fcr Kleinunternehmer*innen\u201d"},"content":{"rendered":"<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Zehn Wochen wurden Unternehmerinnen dabei unterst\u00fctzt, ihre hybriden Gesch\u00e4ftsmodelle auszubauen<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Unternehmerinnen zeigen sich offen und interessiert, Chancen zu nutzen<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Ank\u00fcndigung: \u00d6ffentliche \u201cDigital Durchstarten\u201d Veranstaltung am 16. Oktober 2021\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Im Rahmen der #Gr\u00fcnderInnenstadt-Kampagne startete am 3. August 2021 die \u201cDurchstarterinnen Academy\u201d, ein exklusives F\u00f6rderprogramm f\u00fcr Unternehmerinnen mit station\u00e4rem Laden. Zehn Wochen lang wurden zehn Unternehmerinnen aus verschiedenen Branchen beim Auf- und Ausbau ihrer hybriden Gesch\u00e4ftsmodelle unterst\u00fctzt. Teilnehmerin Katharina Staniok, Besitzerin des Papier- und B\u00fcrowarenladens <\/span><a href=\"https:\/\/www.facebook.com\/buero.eisenhauer\/\"><span style=\"font-weight: 400\">Eisenhauer<\/span><\/a><span style=\"font-weight: 400\">, sieht hier einen entscheidenden Vorteil: \u201eMehrere Standbeine sind wichtig. Instagram und Facebook sind unser digitales Schaufenster.\u201d Herzst\u00fcck des F\u00f6rderprogramms waren die individuellen Einzelcoachings mit Facebook Marketing-Expert*innen. In den Lerneinheiten erfuhren die Unternehmerinnen mehr dar\u00fcber, wie sie ihre Unternehmensgeschichte erz\u00e4hlen und das Storytelling \u00fcber ihre Person und ihre Produkte verbessern k\u00f6nnen, aber auch, wie sie mit gezielter personalisierter Werbung und \u00fcber Messenger-Kommunikation neue Kunden f\u00fcr sich begeistern oder bestehende Kunden st\u00e4rker an ihr Unternehmen binden k\u00f6nnen.<\/span><\/p>\n<p><b>Die Teilnehmerinnen sind f\u00fcr die Zukunft gewappnet\u00a0\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">Wie ist es den Frauen in den Trainingswochen ergangen und was haben Sie aus Ihren Coaching Sessions mitgenommen? Lisa Heldt, des Food &amp; Retail Store <\/span><a href=\"https:\/\/m.facebook.com\/HonigHeldt\/?locale2=de_DE\"><span style=\"font-weight: 400\">Honig Galerie<\/span><\/a><span style=\"font-weight: 400\">, berichtet: \u201cIch bin dankbar, Teil der Durchstarterinnen Academy sein zu d\u00fcrfen. Durch die vielen Gespr\u00e4che und Einzelcoachings habe ich Instagram neu entdeckt und wertvolle Tipps erhalten, wodurch unser Account lebendiger wurde. Dadurch erhalten wir positives Feedback unserer Kund*innen und machen potenzielle Kund*innen auf uns aufmerksam.\u201d Auch Nicola Neumann von <\/span><a href=\"https:\/\/www.facebook.com\/champagnecharacters\"><span style=\"font-weight: 400\">Champagne Characters<\/span><\/a><span style=\"font-weight: 400\"> in M\u00fcnchen berichten enthusiastisch: \u201cIch bin extrem motiviert und freue mich gemeinsam mit meinem Team das Thema Winzerchampagner in Deutschland und \u00d6sterreich in Kombination mit inspirierenden Orten einer breiten \u00d6ffentlichkeit n\u00e4her zu bringen\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Auch f\u00fcr Facebook waren die letzten zehn Wochen sehr aufschlussreich. \u201cGanz besonders habe ich mich \u00fcber die intensive Beteiligung der Unternehmerinnen unserer Durchstarterinnen Academy gefreut. Ihre Offenheit und das Interesse, Chancen zu nutzen, zeigen mir erneut den hohen Bedarf an F\u00f6rder- und Unterst\u00fctzungsprogrammen speziell f\u00fcr Kleinunternehmer*innen\u201c, so Angelika Gifford, Vice President Central Europe Facebook, nach einer gemeinsamen Diskussionsrunde mit den Unternehmerinnen, mit der Schirmherrin Sylvie Meis und Dara Kossok-Spie\u00df, Referentin f\u00fcr Digitalisierung und Netzpolitik beim Handelsverband Deutschland (HDE).<\/span><\/p>\n<p><i><span style=\"font-weight: 400\">Alle Details zu den Unternehmerinnen und ihren individuellen Herausforderungen, sowie Empfehlungen und Impulse werden kontinuierlich auf der Mittelstandsseite des HDE vorgestellt: <\/span><\/i><a href=\"https:\/\/handel4punkt0.de\/\"><i><span style=\"font-weight: 400\">https:\/\/handel4punkt0.de\/<\/span><\/i><\/a><i><span style=\"font-weight: 400\">.<\/span><\/i><\/p>\n<p><b>Neuer Erlebnisort: Station\u00e4rer Handel\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">Neben den Einzelcoachings wurde das Zusammenspiel aus digitalem und station\u00e4rem Handel stets unterstrichen. Neben exklusiven Diskussionsformaten mit Vertreter*innen aus der Politik gab Retail und Destination Expertin der dan pearlman Group Nicole Srock.Stanley einen umfangreichen \u00dcberblick \u00fcber den Wandel und die Bedeutung der Innenst\u00e4dte. Gemeinsam mit den Unternehmerinnen wurden konkrete Handlungsempfehlungen erarbeitet, um Verkaufsr\u00e4ume attraktiver zu gestalten.\u00a0<\/span><\/p>\n<p><b>Einladung zur \u00f6ffentlichen Veranstaltung<\/b><\/p>\n<p><span style=\"font-weight: 400\">Damit auch weitere Unternehmer*innen von den Ergebnissen der Durchstarterinnen Academy lernen k\u00f6nnen, findet am 13. Oktober eine \u00f6ffentlichen \u201cDigital Durchstarten\u201d Session auf unserer Facebook Politik &amp; Gesellschaft Seite statt. Retail und Destination Expertin Nicole Srock.Stanley und Nicola Neumann von Champagne Characters diskutieren unter der Moderation von Annelies Peiner, von dem Karrierenetzwerk nushu, \u00fcber die Zukunft des Handels. Hier findet die Ausstrahlung statt: <\/span><a href=\"https:\/\/www.facebook.com\/events\/240627038028426\/\"><span style=\"font-weight: 400\">https:\/\/www.facebook.com\/events\/240627038028426\/<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">__________________________________________________________________________________<\/span><\/p>\n<p><span style=\"font-weight: 400\">An der \u201cDurchstarterinnen Academy haben folgende Fellows teilgenommen:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><a href=\"https:\/\/www.facebook.com\/PachamamaLaden\"><span style=\"font-weight: 400\">Pachamama Laden<\/span><\/a><span style=\"font-weight: 400\">, der praktische &amp; umweltbewusste Produkte f\u00fcr die ganze Familie bietet von Madelaine B\u00f6hm aus Brandenburg an der Havel<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Fashion Lable <\/span><a href=\"https:\/\/www.facebook.com\/ncmbaehr\"><span style=\"font-weight: 400\">NCM B\u00e4hr<\/span><\/a><span style=\"font-weight: 400\"> von Nathalie B\u00e4hr aus Hannover<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Champagner-Boutique <\/span><a href=\"https:\/\/www.facebook.com\/champagnecharacters\"><span style=\"font-weight: 400\">Champagne Characters<\/span><\/a><span style=\"font-weight: 400\"> von Nicola Neumann aus M\u00fcnchen\u00a0<\/span><\/li>\n<li style=\"font-weight: 400\"><a href=\"https:\/\/www.facebook.com\/WinzerinIlonkaScheuring\"><span style=\"font-weight: 400\">Weingut Scheuring<\/span><\/a><span style=\"font-weight: 400\"> von Ilonka Scheuring aus Margetsh\u00f6chheim\u00a0<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Food &amp; Retail Store <\/span><a href=\"https:\/\/m.facebook.com\/HonigHeldt\/?locale2=de_DE\"><span style=\"font-weight: 400\">Honig Galerie<\/span><\/a><span style=\"font-weight: 400\"> von Lisa Heldt aus Freiburg\u00a0<\/span><\/li>\n<li style=\"font-weight: 400\"><a href=\"https:\/\/www.facebook.com\/Hoerakustik.Nunner\"><span style=\"font-weight: 400\">H\u00f6rakustik Nunner<\/span><\/a><span style=\"font-weight: 400\"> von Katrin Nunner aus Straubing\u00a0<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Buchhandlung und Caf\u00e9 <\/span><a href=\"https:\/\/www.facebook.com\/lesesaalhamburg\"><span style=\"font-weight: 400\">Lesesaal <\/span><\/a><span style=\"font-weight: 400\">von Stephanie Krawehl aus Hamburg\u00a0<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Nachhaltiger Concept-Store <\/span><a href=\"http:\/\/www.facebook.com\/cobconceptstore\"><span style=\"font-weight: 400\">Cob<\/span><\/a><span style=\"font-weight: 400\"> von Meike Pfeiffer aus Essen<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Papier- und B\u00fcrowarenladen <\/span><a href=\"https:\/\/www.facebook.com\/buero.eisenhauer\/\"><span style=\"font-weight: 400\">Eisenhauer<\/span><\/a><span style=\"font-weight: 400\"> von Katharina Staniok aus Leipzig<\/span><\/li>\n<li style=\"font-weight: 400\">Mode-Boutique <a href=\"https:\/\/www.facebook.com\/boutiquetheovezo\/\">Th\u00e9o V\u00e9zo<\/a> von Theodora Vezo aus Hamburg<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"Zehn Wochen wurden Unternehmerinnen dabei unterst\u00fctzt, ihre hybriden Gesch\u00e4ftsmodelle auszubauen Unternehmerinnen zeigen sich offen und interessiert, Chancen zu nutzen Ank\u00fcndigung: \u00d6ffentliche \u201cDigital Durchstarten\u201d Veranstaltung am 16. Oktober 2021\u00a0 Im Rahmen der #Gr\u00fcnderInnenstadt-Kampagne startete am 3. August 2021 die \u201cDurchstarterinnen Academy\u201d, ein exklusives F\u00f6rderprogramm f\u00fcr Unternehmerinnen mit station\u00e4rem Laden. Zehn Wochen lang wurden zehn Unternehmerinnen aus verschiedenen Branchen beim Auf- und Ausbau ihrer hybriden Gesch\u00e4ftsmodelle unterst\u00fctzt. Teilnehmerin Katharina Staniok, Besitzerin des Papier- und B\u00fcrowarenladens Eisenhauer, sieht hier einen entscheidenden Vorteil: \u201eMehrere Standbeine sind wichtig. Instagram und Facebook sind unser digitales Schaufenster.\u201d Herzst\u00fcck des F\u00f6rderprogramms waren die individuellen Einzelcoachings mit Facebook Marketing-Expert*innen. In den Lerneinheiten erfuhren die Unternehmerinnen mehr dar\u00fcber, wie sie ihre Unternehmensgeschichte erz\u00e4hlen und das Storytelling \u00fcber ihre Person und ihre Produkte verbessern k\u00f6nnen, aber auch, wie sie mit gezielter personalisierter Werbung und \u00fcber Messenger-Kommunikation neue Kunden f\u00fcr sich begeistern oder bestehende Kunden st\u00e4rker an ihr Unternehmen binden k\u00f6nnen. Die Teilnehmerinnen sind f\u00fcr die Zukunft gewappnet\u00a0\u00a0 Wie ist es den Frauen in den Trainingswochen ergangen und was haben Sie aus Ihren Coaching Sessions mitgenommen? Lisa Heldt, des Food &amp; Retail Store Honig Galerie, berichtet: \u201cIch bin dankbar, Teil der Durchstarterinnen Academy sein zu d\u00fcrfen. Durch die vielen Gespr\u00e4che und Einzelcoachings habe ich Instagram neu entdeckt und wertvolle Tipps erhalten, wodurch unser Account lebendiger wurde. Dadurch erhalten wir positives Feedback unserer Kund*innen und machen potenzielle Kund*innen auf uns aufmerksam.\u201d Auch Nicola Neumann von Champagne Characters in M\u00fcnchen berichten enthusiastisch: \u201cIch bin extrem motiviert und freue mich gemeinsam mit meinem Team das Thema Winzerchampagner in Deutschland und \u00d6sterreich in Kombination mit inspirierenden Orten einer breiten \u00d6ffentlichkeit n\u00e4her zu bringen\u201d. Auch f\u00fcr Facebook waren die letzten zehn Wochen sehr aufschlussreich. \u201cGanz besonders habe ich mich \u00fcber die intensive Beteiligung der Unternehmerinnen unserer Durchstarterinnen Academy gefreut. Ihre Offenheit und das Interesse, Chancen zu nutzen, zeigen mir erneut den hohen Bedarf an F\u00f6rder- und Unterst\u00fctzungsprogrammen speziell f\u00fcr Kleinunternehmer*innen\u201c, so Angelika Gifford, Vice President Central Europe Facebook, nach einer gemeinsamen Diskussionsrunde mit den Unternehmerinnen, mit der Schirmherrin Sylvie Meis und Dara Kossok-Spie\u00df, Referentin f\u00fcr Digitalisierung und Netzpolitik beim Handelsverband Deutschland (HDE). Alle Details zu den Unternehmerinnen und ihren individuellen Herausforderungen, sowie Empfehlungen und Impulse werden kontinuierlich auf der Mittelstandsseite des HDE vorgestellt: <a href=\"https:\/\/handel4punkt0.de\/\" rel=\"nofollow\">https:\/\/handel4punkt0.de\/<\/a>. Neuer Erlebnisort: Station\u00e4rer Handel\u00a0 Neben den Einzelcoachings wurde das Zusammenspiel aus digitalem und station\u00e4rem Handel stets unterstrichen. Neben exklusiven Diskussionsformaten mit Vertreter*innen aus der Politik gab Retail und Destination Expertin der dan pearlman Group Nicole Srock.Stanley einen umfangreichen \u00dcberblick \u00fcber den Wandel und die Bedeutung der Innenst\u00e4dte. Gemeinsam mit den Unternehmerinnen wurden konkrete Handlungsempfehlungen erarbeitet, um Verkaufsr\u00e4ume attraktiver zu gestalten.\u00a0 Einladung zur \u00f6ffentlichen Veranstaltung Damit auch weitere Unternehmer*innen von den Ergebnissen der Durchstarterinnen Academy lernen k\u00f6nnen, findet am 13. Oktober eine \u00f6ffentlichen \u201cDigital Durchstarten\u201d Session auf unserer Facebook Politik &amp; Gesellschaft Seite statt. Retail und Destination Expertin Nicole Srock.Stanley und Nicola Neumann von Champagne Characters diskutieren unter der Moderation von Annelies Peiner, von dem Karrierenetzwerk nushu, \u00fcber die Zukunft des Handels. Hier findet die Ausstrahlung statt: <a href=\"https:\/\/www.facebook.com\/events\/240627038028426\/\" rel=\"nofollow\">https:\/\/www.facebook.com\/events\/240627038028426\/<\/a>. __________________________________________________________________________________ An der \u201cDurchstarterinnen Academy haben folgende Fellows teilgenommen: Pachamama Laden, der praktische &amp; umweltbewusste Produkte f\u00fcr die ganze Familie bietet von Madelaine B\u00f6hm aus Brandenburg an der Havel Fashion Lable NCM B\u00e4hr von Nathalie B\u00e4hr aus Hannover Champagner-Boutique Champagne Characters von Nicola Neumann aus M\u00fcnchen\u00a0 Weingut Scheuring von Ilonka Scheuring aus Margetsh\u00f6chheim\u00a0 Food &amp; Retail Store Honig Galerie von Lisa Heldt aus Freiburg\u00a0 H\u00f6rakustik Nunner von Katrin Nunner aus Straubing\u00a0 Buchhandlung und Caf\u00e9 Lesesaal von Stephanie Krawehl aus Hamburg\u00a0 Nachhaltiger Concept-Store Cob von Meike Pfeiffer aus Essen Papier- und B\u00fcrowarenladen Eisenhauer von Katharina Staniok aus Leipzig Mode-Boutique Th\u00e9o V\u00e9zo von Theodora Vezo aus Hamburg","protected":false},"author":116743763,"featured_media":26484,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[555973289,555973394,555973257,30697048,7350],"tags":[555973273,555973644,555973564,81819,555973649,555973645,555973648,555973647,555973592,555973646],"class_list":["post-26483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digital-durchstarten","category-kampagne","category-mittelstand","category-unternehmensmeldungen","category-veranstaltungen","tag-digital-durchstarten","tag-durchstarterinnen-academy","tag-einzelhandel","tag-facebook","tag-geschaeftsmodell","tag-gruenderinnenstadt","tag-hybrid","tag-instagram","tag-mittelstand","tag-zukunft-handel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cEs bedarf auch weiterhin F\u00f6rder- und Unterst\u00fctzungsprogramme speziell f\u00fcr Kleinunternehmer*innen\u201d | \u00dcber Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cEs bedarf auch weiterhin F\u00f6rder- und Unterst\u00fctzungsprogramme speziell f\u00fcr Kleinunternehmer*innen\u201d | \u00dcber Meta\" \/>\n<meta property=\"og:description\" content=\"Zehn Wochen wurden Unternehmerinnen dabei unterst\u00fctzt, ihre hybriden Gesch\u00e4ftsmodelle auszubauen Unternehmerinnen zeigen sich offen und interessiert, Chancen zu nutzen Ank\u00fcndigung: \u00d6ffentliche \u201cDigital Durchstarten\u201d Veranstaltung am 16. Oktober 2021\u00a0 Im Rahmen der #Gr\u00fcnderInnenstadt-Kampagne startete am 3. August 2021 die \u201cDurchstarterinnen Academy\u201d, ein exklusives F\u00f6rderprogramm f\u00fcr Unternehmerinnen mit station\u00e4rem Laden. Zehn Wochen lang wurden zehn Unternehmerinnen aus verschiedenen Branchen beim Auf- und Ausbau ihrer hybriden Gesch\u00e4ftsmodelle unterst\u00fctzt. Teilnehmerin Katharina Staniok, Besitzerin des Papier- und B\u00fcrowarenladens Eisenhauer, sieht hier einen entscheidenden Vorteil: \u201eMehrere Standbeine sind wichtig. Instagram und Facebook sind unser digitales Schaufenster.\u201d Herzst\u00fcck des F\u00f6rderprogramms waren die individuellen Einzelcoachings mit Facebook Marketing-Expert*innen. In den Lerneinheiten erfuhren die Unternehmerinnen mehr dar\u00fcber, wie sie ihre Unternehmensgeschichte erz\u00e4hlen und das Storytelling \u00fcber ihre Person und ihre Produkte verbessern k\u00f6nnen, aber auch, wie sie mit gezielter personalisierter Werbung und \u00fcber Messenger-Kommunikation neue Kunden f\u00fcr sich begeistern oder bestehende Kunden st\u00e4rker an ihr Unternehmen binden k\u00f6nnen. Die Teilnehmerinnen sind f\u00fcr die Zukunft gewappnet\u00a0\u00a0 Wie ist es den Frauen in den Trainingswochen ergangen und was haben Sie aus Ihren Coaching Sessions mitgenommen? Lisa Heldt, des Food &amp; Retail Store Honig Galerie, berichtet: \u201cIch bin dankbar, Teil der Durchstarterinnen Academy sein zu d\u00fcrfen. Durch die vielen Gespr\u00e4che und Einzelcoachings habe ich Instagram neu entdeckt und wertvolle Tipps erhalten, wodurch unser Account lebendiger wurde. Dadurch erhalten wir positives Feedback unserer Kund*innen und machen potenzielle Kund*innen auf uns aufmerksam.\u201d Auch Nicola Neumann von Champagne Characters in M\u00fcnchen berichten enthusiastisch: \u201cIch bin extrem motiviert und freue mich gemeinsam mit meinem Team das Thema Winzerchampagner in Deutschland und \u00d6sterreich in Kombination mit inspirierenden Orten einer breiten \u00d6ffentlichkeit n\u00e4her zu bringen\u201d. Auch f\u00fcr Facebook waren die letzten zehn Wochen sehr aufschlussreich. \u201cGanz besonders habe ich mich \u00fcber die intensive Beteiligung der Unternehmerinnen unserer Durchstarterinnen Academy gefreut. Ihre Offenheit und das Interesse, Chancen zu nutzen, zeigen mir erneut den hohen Bedarf an F\u00f6rder- und Unterst\u00fctzungsprogrammen speziell f\u00fcr Kleinunternehmer*innen\u201c, so Angelika Gifford, Vice President Central Europe Facebook, nach einer gemeinsamen Diskussionsrunde mit den Unternehmerinnen, mit der Schirmherrin Sylvie Meis und Dara Kossok-Spie\u00df, Referentin f\u00fcr Digitalisierung und Netzpolitik beim Handelsverband Deutschland (HDE). Alle Details zu den Unternehmerinnen und ihren individuellen Herausforderungen, sowie Empfehlungen und Impulse werden kontinuierlich auf der Mittelstandsseite des HDE vorgestellt: https:\/\/handel4punkt0.de\/. Neuer Erlebnisort: Station\u00e4rer Handel\u00a0 Neben den Einzelcoachings wurde das Zusammenspiel aus digitalem und station\u00e4rem Handel stets unterstrichen. Neben exklusiven Diskussionsformaten mit Vertreter*innen aus der Politik gab Retail und Destination Expertin der dan pearlman Group Nicole Srock.Stanley einen umfangreichen \u00dcberblick \u00fcber den Wandel und die Bedeutung der Innenst\u00e4dte. Gemeinsam mit den Unternehmerinnen wurden konkrete Handlungsempfehlungen erarbeitet, um Verkaufsr\u00e4ume attraktiver zu gestalten.\u00a0 Einladung zur \u00f6ffentlichen Veranstaltung Damit auch weitere Unternehmer*innen von den Ergebnissen der Durchstarterinnen Academy lernen k\u00f6nnen, findet am 13. Oktober eine \u00f6ffentlichen \u201cDigital Durchstarten\u201d Session auf unserer Facebook Politik &amp; Gesellschaft Seite statt. Retail und Destination Expertin Nicole Srock.Stanley und Nicola Neumann von Champagne Characters diskutieren unter der Moderation von Annelies Peiner, von dem Karrierenetzwerk nushu, \u00fcber die Zukunft des Handels. Hier findet die Ausstrahlung statt: https:\/\/www.facebook.com\/events\/240627038028426\/. __________________________________________________________________________________ An der \u201cDurchstarterinnen Academy haben folgende Fellows teilgenommen: Pachamama Laden, der praktische &amp; umweltbewusste Produkte f\u00fcr die ganze Familie bietet von Madelaine B\u00f6hm aus Brandenburg an der Havel Fashion Lable NCM B\u00e4hr von Nathalie B\u00e4hr aus Hannover Champagner-Boutique Champagne Characters von Nicola Neumann aus M\u00fcnchen\u00a0 Weingut Scheuring von Ilonka Scheuring aus Margetsh\u00f6chheim\u00a0 Food &amp; Retail Store Honig Galerie von Lisa Heldt aus Freiburg\u00a0 H\u00f6rakustik Nunner von Katrin Nunner aus Straubing\u00a0 Buchhandlung und Caf\u00e9 Lesesaal von Stephanie Krawehl aus Hamburg\u00a0 Nachhaltiger Concept-Store Cob von Meike Pfeiffer aus Essen Papier- und B\u00fcrowarenladen Eisenhauer von Katharina Staniok aus Leipzig Mode-Boutique Th\u00e9o V\u00e9zo von Theodora Vezo aus Hamburg\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00dcber Meta\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-08T09:48:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-08T09:50:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/MIKA-fotografie-Berlin-Hamburg-Stephanie-2021-022-XXL.jpg?resize=1024,683\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Trilligent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/\"},\"author\":\"Facebook company\",\"headline\":\"\u201cEs bedarf auch weiterhin F\u00f6rder- und Unterst\u00fctzungsprogramme speziell f\u00fcr Kleinunternehmer*innen\u201d\",\"datePublished\":\"2021-10-08T09:48:54+00:00\",\"dateModified\":\"2021-10-08T09:50:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/\"},\"wordCount\":665,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/MIKA-fotografie-Berlin-Hamburg-Stephanie-2021-022-XXL.jpg?fit=3500%2C2334\",\"keywords\":[\"Digital Durchstarten\",\"Durchstarterinnen Academy\",\"Einzelhandel\",\"Facebook\",\"Gesch\u00e4ftsmodell\",\"Gr\u00fcnderInnenstadt\",\"Hybrid\",\"Instagram\",\"Mittelstand\",\"Zukunft Handel\"],\"articleSection\":[\"Digital Durchstarten\",\"Kampagne\",\"Mittelstand\",\"Unternehmensmeldungen\",\"Veranstaltungen\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/\",\"url\":\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/\",\"name\":\"\u201cEs bedarf auch weiterhin F\u00f6rder- und Unterst\u00fctzungsprogramme speziell f\u00fcr Kleinunternehmer*innen\u201d | \u00dcber Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/MIKA-fotografie-Berlin-Hamburg-Stephanie-2021-022-XXL.jpg?fit=3500%2C2334\",\"datePublished\":\"2021-10-08T09:48:54+00:00\",\"dateModified\":\"2021-10-08T09:50:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/\"]}],\"author\":\"\u00dcber Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#primaryimage\",\"url\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/MIKA-fotografie-Berlin-Hamburg-Stephanie-2021-022-XXL.jpg?fit=3500%2C2334\",\"contentUrl\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/MIKA-fotografie-Berlin-Hamburg-Stephanie-2021-022-XXL.jpg?fit=3500%2C2334\",\"width\":3500,\"height\":2334},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cEs bedarf auch weiterhin F\u00f6rder- und Unterst\u00fctzungsprogramme speziell f\u00fcr Kleinunternehmer*innen\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/de\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"\u00dcber Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/de\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/about.fb.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cEs bedarf auch weiterhin F\u00f6rder- und Unterst\u00fctzungsprogramme speziell f\u00fcr Kleinunternehmer*innen\u201d | \u00dcber Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/","og_locale":"de_DE","og_type":"article","og_title":"\u201cEs bedarf auch weiterhin F\u00f6rder- und Unterst\u00fctzungsprogramme speziell f\u00fcr Kleinunternehmer*innen\u201d | \u00dcber Meta","og_description":"Zehn Wochen wurden Unternehmerinnen dabei unterst\u00fctzt, ihre hybriden Gesch\u00e4ftsmodelle auszubauen Unternehmerinnen zeigen sich offen und interessiert, Chancen zu nutzen Ank\u00fcndigung: \u00d6ffentliche \u201cDigital Durchstarten\u201d Veranstaltung am 16. Oktober 2021\u00a0 Im Rahmen der #Gr\u00fcnderInnenstadt-Kampagne startete am 3. August 2021 die \u201cDurchstarterinnen Academy\u201d, ein exklusives F\u00f6rderprogramm f\u00fcr Unternehmerinnen mit station\u00e4rem Laden. Zehn Wochen lang wurden zehn Unternehmerinnen aus verschiedenen Branchen beim Auf- und Ausbau ihrer hybriden Gesch\u00e4ftsmodelle unterst\u00fctzt. Teilnehmerin Katharina Staniok, Besitzerin des Papier- und B\u00fcrowarenladens Eisenhauer, sieht hier einen entscheidenden Vorteil: \u201eMehrere Standbeine sind wichtig. Instagram und Facebook sind unser digitales Schaufenster.\u201d Herzst\u00fcck des F\u00f6rderprogramms waren die individuellen Einzelcoachings mit Facebook Marketing-Expert*innen. In den Lerneinheiten erfuhren die Unternehmerinnen mehr dar\u00fcber, wie sie ihre Unternehmensgeschichte erz\u00e4hlen und das Storytelling \u00fcber ihre Person und ihre Produkte verbessern k\u00f6nnen, aber auch, wie sie mit gezielter personalisierter Werbung und \u00fcber Messenger-Kommunikation neue Kunden f\u00fcr sich begeistern oder bestehende Kunden st\u00e4rker an ihr Unternehmen binden k\u00f6nnen. Die Teilnehmerinnen sind f\u00fcr die Zukunft gewappnet\u00a0\u00a0 Wie ist es den Frauen in den Trainingswochen ergangen und was haben Sie aus Ihren Coaching Sessions mitgenommen? Lisa Heldt, des Food &amp; Retail Store Honig Galerie, berichtet: \u201cIch bin dankbar, Teil der Durchstarterinnen Academy sein zu d\u00fcrfen. Durch die vielen Gespr\u00e4che und Einzelcoachings habe ich Instagram neu entdeckt und wertvolle Tipps erhalten, wodurch unser Account lebendiger wurde. Dadurch erhalten wir positives Feedback unserer Kund*innen und machen potenzielle Kund*innen auf uns aufmerksam.\u201d Auch Nicola Neumann von Champagne Characters in M\u00fcnchen berichten enthusiastisch: \u201cIch bin extrem motiviert und freue mich gemeinsam mit meinem Team das Thema Winzerchampagner in Deutschland und \u00d6sterreich in Kombination mit inspirierenden Orten einer breiten \u00d6ffentlichkeit n\u00e4her zu bringen\u201d. Auch f\u00fcr Facebook waren die letzten zehn Wochen sehr aufschlussreich. \u201cGanz besonders habe ich mich \u00fcber die intensive Beteiligung der Unternehmerinnen unserer Durchstarterinnen Academy gefreut. Ihre Offenheit und das Interesse, Chancen zu nutzen, zeigen mir erneut den hohen Bedarf an F\u00f6rder- und Unterst\u00fctzungsprogrammen speziell f\u00fcr Kleinunternehmer*innen\u201c, so Angelika Gifford, Vice President Central Europe Facebook, nach einer gemeinsamen Diskussionsrunde mit den Unternehmerinnen, mit der Schirmherrin Sylvie Meis und Dara Kossok-Spie\u00df, Referentin f\u00fcr Digitalisierung und Netzpolitik beim Handelsverband Deutschland (HDE). Alle Details zu den Unternehmerinnen und ihren individuellen Herausforderungen, sowie Empfehlungen und Impulse werden kontinuierlich auf der Mittelstandsseite des HDE vorgestellt: https:\/\/handel4punkt0.de\/. Neuer Erlebnisort: Station\u00e4rer Handel\u00a0 Neben den Einzelcoachings wurde das Zusammenspiel aus digitalem und station\u00e4rem Handel stets unterstrichen. Neben exklusiven Diskussionsformaten mit Vertreter*innen aus der Politik gab Retail und Destination Expertin der dan pearlman Group Nicole Srock.Stanley einen umfangreichen \u00dcberblick \u00fcber den Wandel und die Bedeutung der Innenst\u00e4dte. Gemeinsam mit den Unternehmerinnen wurden konkrete Handlungsempfehlungen erarbeitet, um Verkaufsr\u00e4ume attraktiver zu gestalten.\u00a0 Einladung zur \u00f6ffentlichen Veranstaltung Damit auch weitere Unternehmer*innen von den Ergebnissen der Durchstarterinnen Academy lernen k\u00f6nnen, findet am 13. Oktober eine \u00f6ffentlichen \u201cDigital Durchstarten\u201d Session auf unserer Facebook Politik &amp; Gesellschaft Seite statt. Retail und Destination Expertin Nicole Srock.Stanley und Nicola Neumann von Champagne Characters diskutieren unter der Moderation von Annelies Peiner, von dem Karrierenetzwerk nushu, \u00fcber die Zukunft des Handels. Hier findet die Ausstrahlung statt: https:\/\/www.facebook.com\/events\/240627038028426\/. __________________________________________________________________________________ An der \u201cDurchstarterinnen Academy haben folgende Fellows teilgenommen: Pachamama Laden, der praktische &amp; umweltbewusste Produkte f\u00fcr die ganze Familie bietet von Madelaine B\u00f6hm aus Brandenburg an der Havel Fashion Lable NCM B\u00e4hr von Nathalie B\u00e4hr aus Hannover Champagner-Boutique Champagne Characters von Nicola Neumann aus M\u00fcnchen\u00a0 Weingut Scheuring von Ilonka Scheuring aus Margetsh\u00f6chheim\u00a0 Food &amp; Retail Store Honig Galerie von Lisa Heldt aus Freiburg\u00a0 H\u00f6rakustik Nunner von Katrin Nunner aus Straubing\u00a0 Buchhandlung und Caf\u00e9 Lesesaal von Stephanie Krawehl aus Hamburg\u00a0 Nachhaltiger Concept-Store Cob von Meike Pfeiffer aus Essen Papier- und B\u00fcrowarenladen Eisenhauer von Katharina Staniok aus Leipzig Mode-Boutique Th\u00e9o V\u00e9zo von Theodora Vezo aus Hamburg","og_url":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/","og_site_name":"\u00dcber Meta","article_published_time":"2021-10-08T09:48:54+00:00","article_modified_time":"2021-10-08T09:50:01+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/MIKA-fotografie-Berlin-Hamburg-Stephanie-2021-022-XXL.jpg?resize=1024,683","type":"image\/jpeg"}],"author":"Trilligent","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/"},"author":"Facebook company","headline":"\u201cEs bedarf auch weiterhin F\u00f6rder- und Unterst\u00fctzungsprogramme speziell f\u00fcr Kleinunternehmer*innen\u201d","datePublished":"2021-10-08T09:48:54+00:00","dateModified":"2021-10-08T09:50:01+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/"},"wordCount":665,"publisher":{"@id":"https:\/\/about.fb.com\/de\/#organization"},"image":{"@id":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/MIKA-fotografie-Berlin-Hamburg-Stephanie-2021-022-XXL.jpg?fit=3500%2C2334","keywords":["Digital Durchstarten","Durchstarterinnen Academy","Einzelhandel","Facebook","Gesch\u00e4ftsmodell","Gr\u00fcnderInnenstadt","Hybrid","Instagram","Mittelstand","Zukunft Handel"],"articleSection":["Digital Durchstarten","Kampagne","Mittelstand","Unternehmensmeldungen","Veranstaltungen"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/","url":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/","name":"\u201cEs bedarf auch weiterhin F\u00f6rder- und Unterst\u00fctzungsprogramme speziell f\u00fcr Kleinunternehmer*innen\u201d | \u00dcber Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#primaryimage"},"image":{"@id":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/MIKA-fotografie-Berlin-Hamburg-Stephanie-2021-022-XXL.jpg?fit=3500%2C2334","datePublished":"2021-10-08T09:48:54+00:00","dateModified":"2021-10-08T09:50:01+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/"]}],"author":"\u00dcber Meta"},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#primaryimage","url":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/MIKA-fotografie-Berlin-Hamburg-Stephanie-2021-022-XXL.jpg?fit=3500%2C2334","contentUrl":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/MIKA-fotografie-Berlin-Hamburg-Stephanie-2021-022-XXL.jpg?fit=3500%2C2334","width":3500,"height":2334},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/de\/news\/2021\/10\/unterstuetzung_fuer_kleinunternehmen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/de\/"},{"@type":"ListItem","position":2,"name":"\u201cEs bedarf auch weiterhin F\u00f6rder- und Unterst\u00fctzungsprogramme speziell f\u00fcr Kleinunternehmer*innen\u201d"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/de\/#website","url":"https:\/\/about.fb.com\/news\/","name":"\u00dcber Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/de\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/about.fb.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/de\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/MIKA-fotografie-Berlin-Hamburg-Stephanie-2021-022-XXL.jpg?fit=3500%2C2334","_links":{"self":[{"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/posts\/26483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/users\/116743763"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/comments?post=26483"}],"version-history":[{"count":3,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/posts\/26483\/revisions"}],"predecessor-version":[{"id":26487,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/posts\/26483\/revisions\/26487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/media\/26484"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/media?parent=26483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/categories?post=26483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/tags?post=26483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}