{"id":25781,"date":"2021-04-08T08:57:01","date_gmt":"2021-04-08T07:57:01","guid":{"rendered":"https:\/\/about.fb.com\/de\/?p=25781"},"modified":"2021-04-08T10:46:57","modified_gmt":"2021-04-08T09:46:57","slug":"ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand","status":"publish","type":"post","link":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/","title":{"rendered":"Ein Jahr Corona-Pandemie: Unterst\u00fctzung f\u00fcr und Stimmen aus dem Mittelstand"},"content":{"rendered":"<ul>\n<li><b>74 Prozent der deutschen KMU bleiben trotz angespannter Lage optimistisch\u00a0<\/b><\/li>\n<\/ul>\n<ul>\n<li><b>Erfolgsgeschichten machen Mut: Miriam Jacks, Gr\u00fcnderin von <\/b><a href=\"https:\/\/www.facebook.com\/JACKSbeautyline\"><b>JACKS Beautyline<\/b><\/a><b> &amp; \u00d6zg\u00fcr Aylikci, Gr\u00fcnder der <\/b><a href=\"https:\/\/www.facebook.com\/monoconceptstore\"><b>Mono Concept Stores<\/b><\/a><\/li>\n<\/ul>\n<ul>\n<li><b>Neues Analysetool hilft KMU bei der Digitalstrategie<\/b><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Die Beschr\u00e4nkungen zur Eind\u00e4mmung der Corona-Pandemie begleiten uns mittlerweile schon seit mehr als einem Jahr. Das Herunterfahren des \u00f6ffentlichen Lebens hatte nicht nur gesellschaftliche, sondern auch wirtschaftliche Folgen. Insbesondere kleine und mittelst\u00e4ndische Unternehmen (KMU) waren von Schlie\u00dfungen und massiven Umsatzeinbu\u00dfen betroffen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Zwischen dem 29. Januar und 9. Februar 2021 haben wir im Rahmen der <a href=\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/Global-State-of-Small-Business-Report-April-2021.pdf\">Global State of Small Business Report<\/a> mehr als 35.000 kleine und mittelst\u00e4ndische UnternehmerInnen auf unserer Plattform in 27 L\u00e4ndern weltweit zu den Auswirkungen der Pandemie auf ihr Unternehmen und ihre Zukunftsaussichten befragt.<\/span><\/p>\n<p><b>Im europ\u00e4ischen Vergleich schneiden Deutsche KMU gut ab<\/b><\/p>\n<p><span style=\"font-weight: 400\">W\u00e4hrend der Anteil geschlossener KMU in Europa aufgrund der strikten Beschr\u00e4nkungen zur Eind\u00e4mmung der Pandemie besonders gestiegen sind, berichteten <\/span><b>80 Prozent der befragten KMU in Deutschland, dass sie entweder regul\u00e4r ge\u00f6ffnet haben oder durch ein angepasstes Angebot Ums\u00e4tze generieren k\u00f6nnen.<\/b><span style=\"font-weight: 400\"> Im Vergleich zu Gro\u00dfbritannien (37 Prozent der KMU geschlossen) und Portugal (33 Prozent der KMU geschlossen) schneidet Deutschland damit sehr gut ab.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Dennoch bleibt die Lage f\u00fcr den Mittelstand angespannt: <\/span><b>40 Prozent der Befragten in Deutschland gaben an, deutliche Umsatzeinbu\u00dfen zu verzeichnen.<\/b><span style=\"font-weight: 400\"> Von Frauen gef\u00fchrte KMU berichteten dabei von h\u00f6heren Umsatzeinbu\u00dfen (53 Prozent) als von M\u00e4nnern gef\u00fchrte Unternehmen (37 Prozent), was darauf zur\u00fcckzuf\u00fchren sein kann, dass Frauen tendenziell h\u00e4ufiger Kleinstunternehmen im besonders von der Pandemie betroffenen Dienstleistungssektor f\u00fchren. Diese Zahlen spiegeln den weltweiten Durchschnitt wider, der zeigt, dass Unternehmerinnen von den Auswirkungen der Krise deutlich st\u00e4rker betroffen sind als ihre m\u00e4nnlichen Pendants.\u00a0<\/span><\/p>\n<p><b>Deutsche KMU zeigen sich trotz der schwierigen Situation optimistisch<\/b><\/p>\n<p><span style=\"font-weight: 400\">Nahezu <\/span><b>Dreiviertel <\/b><span style=\"font-weight: 400\">der Befragten (74 Prozent) gaben an, dass sie <\/span><b>zuversichtlich sind, bei gleichbleibenden Umst\u00e4nden mindestens f\u00fcr sechs weitere Monate ge\u00f6ffnet bleiben zu k\u00f6nnen. <\/b><span style=\"font-weight: 400\">Das liegt deutlich \u00fcber dem globalen Durchschnitt von 54 Prozent. Nur 10 Prozent der befragten UnternehmerInnen aus Deutschland gaben au\u00dferdem an, aufgrund der Corona-Krise ihr Personal reduziert zu haben; sowohl im globalen Vergleich (30 Prozent) als auch im Vergleich mit anderen EU-L\u00e4ndern wie Italien (30 Prozent) und Spanien (21 Prozent) ein bemerkenswert niedriger Wert.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Aus Sicht der UnternehmerInnen werden vor allem geringere Nachfrage (laut 14 Prozent der Befragten) und weitere staatlich angeordnete Einschr\u00e4nkungen (laut 31 Prozent der Befragten) problematisch f\u00fcr ihr Unternehmen sein. Dar\u00fcber hinaus hat auch die Mobilit\u00e4t der Kunden weiter abgenommen: Google Mobility Daten zeigen, dass <\/span><b>besonders in Deutschland und dem Vereinigten K\u00f6nigreich die Mobilit\u00e4t deutlich unter dem Vorkrisenniveau liegt <\/b><span style=\"font-weight: 400\">\u2013 Ende Januar lag sie sogar niedriger als beim bisherigen Tiefstand im April 2020. F\u00fcr KMU bedeutet das, dass sie sich auch weiterhin neue kreative Wege werden erschlie\u00dfen m\u00fcssen, um Ums\u00e4tze zu generieren und mit ihrem Business zu wachsen: Hybridmodelle aus station\u00e4rem Handel und Online-Angeboten k\u00f6nnen hier zukunftsweisend sein.<\/span><\/p>\n<p><b>Erfolgsgeschichten von KMU machen Mut\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">Im letzten Jahr haben wir mit unserer Initiative <\/span><a href=\"https:\/\/www.facebook.com\/business\/boost\/wirliebenmittelstand\"><span style=\"font-weight: 400\">#WirliebenMittelstand<\/span><\/a><span style=\"font-weight: 400\"> bereits mehr als 150.000 Unternehmerinnen und Unternehmer gezielt beim Auf- und Ausbau ihrer Digitalstrategie begleiten k\u00f6nnen. Dadurch haben wir in den letzten zw\u00f6lf Monaten zahlreiche inspirierende Beispiele von KMU kennengelernt, die sich in k\u00fcrzester Zeit digitale Tools angeeignet haben, um auch w\u00e4hrend des Lockdowns Ums\u00e4tze zu generieren und mit ihren Kunden in Kontakt zu bleiben.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Zwei von ihnen erz\u00e4hlen heute, wie es ihnen gelungen ist, sich schnell an die Herausforderungen anzupassen und welche Auswirkungen das auf ihr Business hatte:<\/span><\/p>\n<p><b><i>Miriam Jacks, Gr\u00fcnderin von <\/i><\/b><a href=\"https:\/\/www.facebook.com\/JACKSbeautyline\"><b><i>JACKS Beautyline\u00a0<\/i><\/b><\/a><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-25788 alignnone\" src=\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg?resize=177%2C236\" alt=\"\" width=\"177\" height=\"236\" srcset=\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg?w=960 960w, https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg?w=300 300w, https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg?w=225 225w, https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg?w=768 768w, https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg?w=810 810w, https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg?w=450 450w\" sizes=\"auto, (max-width: 177px) 100vw, 177px\" \/><\/p>\n<p><span style=\"font-weight: 400\">Die Idee, ihre eigene Linie f\u00fcr Make-up Pinsel zu entwerfen, hatte Miriam Jacks im Jahr 2009 w\u00e4hrend der Gr\u00fcndung ihres Beauty Stores in Berlin. Heute ist jeder handbemalte, vegane Pinsel ein eigenes kleines Kunstwerk &#8211; und die Produktpalette w\u00e4chst. W\u00e4hrend der Pandemie konnte sie ihr Business dank des Einsatzes von Facebook und Instagram sogar weiterentwickeln. Ihr Monatsumsatz im Webshop ist um fast 1000 Prozent gewachsen. Der erste Lockdown f\u00fchrte zun\u00e4chst zum Stillstand, doch mit gezieltem Influencer-Marketing und digitalen Make-up Workshops fand sie neue, kreative Wege, um ihr Gesch\u00e4ft am Laufen zu halten:<\/span><\/p>\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"Jacks Beauty Line\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/5FF9AIClgOY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p><b><i>\u00d6zg\u00fcr Aylikci, Gr\u00fcnder der <\/i><\/b><a href=\"https:\/\/www.facebook.com\/monoconceptstore\"><b><i>Mono Concept Stores<\/i><\/b><\/a><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-25789 alignnone\" src=\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/O.Aylikci.jpeg?resize=182%2C265\" alt=\"\" width=\"182\" height=\"265\" srcset=\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/O.Aylikci.jpeg?w=880 880w, https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/O.Aylikci.jpeg?w=275 275w, https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/O.Aylikci.jpeg?w=206 206w, https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/O.Aylikci.jpeg?w=768 768w, https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/O.Aylikci.jpeg?w=704 704w, https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/O.Aylikci.jpeg?w=743 743w, https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/O.Aylikci.jpeg?w=413 413w\" sizes=\"auto, (max-width: 182px) 100vw, 182px\" \/><\/p>\n<p><span style=\"font-weight: 400\">\u00d6zg\u00fcr und sein Team haben sich der M\u00e4nnermode verschrieben, fast &#8211; nat\u00fcrlich darf auch f\u00fcr die moderne Frau nichts fehlen. In den Hamburger Concept Stores gibt es t\u00e4gliche Fashion-Inspiration. W\u00e4hrend des ersten Lockdowns musste Mono Room Concept Store seine drei L\u00e4den schlie\u00dfen, doch das Gesch\u00e4ft lief weiter: Obwohl er zuvor 100 Prozent seines Umsatz \u00fcber den station\u00e4ren Handel generierte, gelang es ihm, innerhalb k\u00fcrzester Zeit sein Gesch\u00e4ftsmodell anzupassen und sich der Situation erfolgreich anzupassen. Wie er soziale Medien daf\u00fcr gezielt eingesetzt hat, erz\u00e4hlt er im Video:<\/span><\/p>\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"MonoConcept 1Jahr Corona\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/PAPxb9NeSao?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<p><b>\u00a0Neues Analysetool hilft KMU bei der Digitalstrategie\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">Wie unsere <\/span><a href=\"https:\/\/about.fb.com\/de\/news\/2020\/12\/weltweite-lage-von-kleinunternehmen\/\"><span style=\"font-weight: 400\">digitale Wirtschaftsstudie<\/span><\/a><span style=\"font-weight: 400\"> im letzten Jahr gezeigt hat, hat ein Drittel der befragten KMU mehr als 25 Prozent des Umsatzes \u00fcber digitale Kan\u00e4le generiert. Trotz der schwierigen Lage blieb daher fast die H\u00e4lfte der KMU zuversichtlich &#8211; doch sie gaben auch an, weitere Unterst\u00fctzung zu ben\u00f6tigen. Auch k\u00fcnftig werden eine digitale Pr\u00e4senz und eine langfristige Digitalstrategie f\u00fcr KMU essentiell sein, um zukunftsgerichtet zu wirtschaften &#8211; das gilt nicht nur, solange anhaltende Einschr\u00e4nkungen und unsichere Perspektiven f\u00fcr die n\u00e4chsten Monate sich auf den Mittelstand auswirken.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Daf\u00fcr stellen wir heute ein <\/span><span style=\"font-weight: 400\">neues <a href=\"https:\/\/digitaldiagnostik.de\/?fbclid=IwAR3wHBSuQQGd_M65TNhWeO-v-jxjK860Men4ud7Q_IybgvYbGDPudmJa6yc\">kostenfreies <\/a><\/span><span style=\"font-weight: 400\">Analysetoo<\/span><span style=\"font-weight: 400\">l speziell f\u00fcr KMU vor: Mithilfe dieses Tools k\u00f6nnen KMU ihre digitale Pr\u00e4senz und bisherige Digitalstrategie hinsichtlich ihrer St\u00e4rken und Schw\u00e4chen \u00fcberpr\u00fcfen lassen. Dar\u00fcber hinaus k\u00f6nnen sie ausw\u00e4hlen, welche Ziele sie mit ihrer Digitalstrategie verfolgen, um einen optimierten Plan f\u00fcr k\u00fcnftige digitale Aktivit\u00e4ten zu erhalten.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Mehr als 200 Millionen Unternehmen nutzen unsere Apps jeden Monat als virtuelles Schaufenster und um ihre Kunden zu erreichen &#8211; und Millionen KMU nutzen unsere Tools seit Beginn der Pandemie, um sich eine digitale Pr\u00e4senz aufzubauen und den \u00dcbergang zum hybriden Wirtschaften zwischen Offline- und Onlinehandel zu erleichtern. Dabei m\u00f6chten wir insbesondere den Mittelstand weiterhin zielgerichtet unterst\u00fctzen.<\/span><span style=\"font-weight: 400\"> Interessierte finden hier alle Informationen und spannende Trainings: <\/span><a href=\"https:\/\/www.facebook.com\/business\"><span style=\"font-weight: 400\">https:\/\/www.facebook.com\/business<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"74 Prozent der deutschen KMU bleiben trotz angespannter Lage optimistisch\u00a0 Erfolgsgeschichten machen Mut: Miriam Jacks, Gr\u00fcnderin von JACKS Beautyline &amp; \u00d6zg\u00fcr Aylikci, Gr\u00fcnder der Mono Concept Stores Neues Analysetool hilft KMU bei der Digitalstrategie Die Beschr\u00e4nkungen zur Eind\u00e4mmung der Corona-Pandemie begleiten uns mittlerweile schon seit mehr als einem Jahr. Das Herunterfahren des \u00f6ffentlichen Lebens hatte nicht nur gesellschaftliche, sondern auch wirtschaftliche Folgen. Insbesondere kleine und mittelst\u00e4ndische Unternehmen (KMU) waren von Schlie\u00dfungen und massiven Umsatzeinbu\u00dfen betroffen.\u00a0 Zwischen dem 29. Januar und 9. Februar 2021 haben wir im Rahmen der Global State of Small Business Report mehr als 35.000 kleine und mittelst\u00e4ndische UnternehmerInnen auf unserer Plattform in 27 L\u00e4ndern weltweit zu den Auswirkungen der Pandemie auf ihr Unternehmen und ihre Zukunftsaussichten befragt. Im europ\u00e4ischen Vergleich schneiden Deutsche KMU gut ab W\u00e4hrend der Anteil geschlossener KMU in Europa aufgrund der strikten Beschr\u00e4nkungen zur Eind\u00e4mmung der Pandemie besonders gestiegen sind, berichteten 80 Prozent der befragten KMU in Deutschland, dass sie entweder regul\u00e4r ge\u00f6ffnet haben oder durch ein angepasstes Angebot Ums\u00e4tze generieren k\u00f6nnen. Im Vergleich zu Gro\u00dfbritannien (37 Prozent der KMU geschlossen) und Portugal (33 Prozent der KMU geschlossen) schneidet Deutschland damit sehr gut ab. Dennoch bleibt die Lage f\u00fcr den Mittelstand angespannt: 40 Prozent der Befragten in Deutschland gaben an, deutliche Umsatzeinbu\u00dfen zu verzeichnen. Von Frauen gef\u00fchrte KMU berichteten dabei von h\u00f6heren Umsatzeinbu\u00dfen (53 Prozent) als von M\u00e4nnern gef\u00fchrte Unternehmen (37 Prozent), was darauf zur\u00fcckzuf\u00fchren sein kann, dass Frauen tendenziell h\u00e4ufiger Kleinstunternehmen im besonders von der Pandemie betroffenen Dienstleistungssektor f\u00fchren. Diese Zahlen spiegeln den weltweiten Durchschnitt wider, der zeigt, dass Unternehmerinnen von den Auswirkungen der Krise deutlich st\u00e4rker betroffen sind als ihre m\u00e4nnlichen Pendants.\u00a0 Deutsche KMU zeigen sich trotz der schwierigen Situation optimistisch Nahezu Dreiviertel der Befragten (74 Prozent) gaben an, dass sie zuversichtlich sind, bei gleichbleibenden Umst\u00e4nden mindestens f\u00fcr sechs weitere Monate ge\u00f6ffnet bleiben zu k\u00f6nnen. Das liegt deutlich \u00fcber dem globalen Durchschnitt von 54 Prozent. Nur 10 Prozent der befragten UnternehmerInnen aus Deutschland gaben au\u00dferdem an, aufgrund der Corona-Krise ihr Personal reduziert zu haben; sowohl im globalen Vergleich (30 Prozent) als auch im Vergleich mit anderen EU-L\u00e4ndern wie Italien (30 Prozent) und Spanien (21 Prozent) ein bemerkenswert niedriger Wert. Aus Sicht der UnternehmerInnen werden vor allem geringere Nachfrage (laut 14 Prozent der Befragten) und weitere staatlich angeordnete Einschr\u00e4nkungen (laut 31 Prozent der Befragten) problematisch f\u00fcr ihr Unternehmen sein. Dar\u00fcber hinaus hat auch die Mobilit\u00e4t der Kunden weiter abgenommen: Google Mobility Daten zeigen, dass besonders in Deutschland und dem Vereinigten K\u00f6nigreich die Mobilit\u00e4t deutlich unter dem Vorkrisenniveau liegt \u2013 Ende Januar lag sie sogar niedriger als beim bisherigen Tiefstand im April 2020. F\u00fcr KMU bedeutet das, dass sie sich auch weiterhin neue kreative Wege werden erschlie\u00dfen m\u00fcssen, um Ums\u00e4tze zu generieren und mit ihrem Business zu wachsen: Hybridmodelle aus station\u00e4rem Handel und Online-Angeboten k\u00f6nnen hier zukunftsweisend sein. Erfolgsgeschichten von KMU machen Mut\u00a0 Im letzten Jahr haben wir mit unserer Initiative #WirliebenMittelstand bereits mehr als 150.000 Unternehmerinnen und Unternehmer gezielt beim Auf- und Ausbau ihrer Digitalstrategie begleiten k\u00f6nnen. Dadurch haben wir in den letzten zw\u00f6lf Monaten zahlreiche inspirierende Beispiele von KMU kennengelernt, die sich in k\u00fcrzester Zeit digitale Tools angeeignet haben, um auch w\u00e4hrend des Lockdowns Ums\u00e4tze zu generieren und mit ihren Kunden in Kontakt zu bleiben.\u00a0 Zwei von ihnen erz\u00e4hlen heute, wie es ihnen gelungen ist, sich schnell an die Herausforderungen anzupassen und welche Auswirkungen das auf ihr Business hatte: Miriam Jacks, Gr\u00fcnderin von JACKS Beautyline\u00a0 Die Idee, ihre eigene Linie f\u00fcr Make-up Pinsel zu entwerfen, hatte Miriam Jacks im Jahr 2009 w\u00e4hrend der Gr\u00fcndung ihres Beauty Stores in Berlin. Heute ist jeder handbemalte, vegane Pinsel ein eigenes kleines Kunstwerk &#8211; und die Produktpalette w\u00e4chst. W\u00e4hrend der Pandemie konnte sie ihr Business dank des Einsatzes von Facebook und Instagram sogar weiterentwickeln. Ihr Monatsumsatz im Webshop ist um fast 1000 Prozent gewachsen. Der erste Lockdown f\u00fchrte zun\u00e4chst zum Stillstand, doch mit gezieltem Influencer-Marketing und digitalen Make-up Workshops fand sie neue, kreative Wege, um ihr Gesch\u00e4ft am Laufen zu halten: &nbsp; \u00d6zg\u00fcr Aylikci, Gr\u00fcnder der Mono Concept Stores \u00d6zg\u00fcr und sein Team haben sich der M\u00e4nnermode verschrieben, fast &#8211; nat\u00fcrlich darf auch f\u00fcr die moderne Frau nichts fehlen. In den Hamburger Concept Stores gibt es t\u00e4gliche Fashion-Inspiration. W\u00e4hrend des ersten Lockdowns musste Mono Room Concept Store seine drei L\u00e4den schlie\u00dfen, doch das Gesch\u00e4ft lief weiter: Obwohl er zuvor 100 Prozent seines Umsatz \u00fcber den station\u00e4ren Handel generierte, gelang es ihm, innerhalb k\u00fcrzester Zeit sein Gesch\u00e4ftsmodell anzupassen und sich der Situation erfolgreich anzupassen. Wie er soziale Medien daf\u00fcr gezielt eingesetzt hat, erz\u00e4hlt er im Video: \u00a0Neues Analysetool hilft KMU bei der Digitalstrategie\u00a0 Wie unsere digitale Wirtschaftsstudie im letzten Jahr gezeigt hat, hat ein Drittel der befragten KMU mehr als 25 Prozent des Umsatzes \u00fcber digitale Kan\u00e4le generiert. Trotz der schwierigen Lage blieb daher fast die H\u00e4lfte der KMU zuversichtlich &#8211; doch sie gaben auch an, weitere Unterst\u00fctzung zu ben\u00f6tigen. Auch k\u00fcnftig werden eine digitale Pr\u00e4senz und eine langfristige Digitalstrategie f\u00fcr KMU essentiell sein, um zukunftsgerichtet zu wirtschaften &#8211; das gilt nicht nur, solange anhaltende Einschr\u00e4nkungen und unsichere Perspektiven f\u00fcr die n\u00e4chsten Monate sich auf den Mittelstand auswirken.\u00a0 Daf\u00fcr stellen wir heute ein neues kostenfreies Analysetool speziell f\u00fcr KMU vor: Mithilfe dieses Tools k\u00f6nnen KMU ihre digitale Pr\u00e4senz und bisherige Digitalstrategie hinsichtlich ihrer St\u00e4rken und Schw\u00e4chen \u00fcberpr\u00fcfen lassen. Dar\u00fcber hinaus k\u00f6nnen sie ausw\u00e4hlen, welche Ziele sie mit ihrer Digitalstrategie verfolgen, um einen optimierten Plan f\u00fcr k\u00fcnftige digitale Aktivit\u00e4ten zu erhalten.\u00a0 Mehr als 200 Millionen Unternehmen nutzen unsere Apps jeden Monat als virtuelles Schaufenster und um ihre Kunden zu erreichen &#8211; und Millionen KMU nutzen unsere Tools seit Beginn der Pandemie, um sich eine digitale Pr\u00e4senz aufzubauen und den \u00dcbergang zum hybriden Wirtschaften zwischen Offline- und Onlinehandel zu erleichtern. Dabei m\u00f6chten wir insbesondere den Mittelstand weiterhin zielgerichtet unterst\u00fctzen. Interessierte finden hier alle Informationen und spannende Trainings: <a href=\"https:\/\/www.facebook.com\/business\" rel=\"nofollow\">https:\/\/www.facebook.com\/business<\/a>.","protected":false},"author":116743763,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-25781","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ein Jahr Corona-Pandemie: Unterst\u00fctzung f\u00fcr und Stimmen aus dem Mittelstand | \u00dcber Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein Jahr Corona-Pandemie: Unterst\u00fctzung f\u00fcr und Stimmen aus dem Mittelstand | \u00dcber Meta\" \/>\n<meta property=\"og:description\" content=\"74 Prozent der deutschen KMU bleiben trotz angespannter Lage optimistisch\u00a0 Erfolgsgeschichten machen Mut: Miriam Jacks, Gr\u00fcnderin von JACKS Beautyline &amp; \u00d6zg\u00fcr Aylikci, Gr\u00fcnder der Mono Concept Stores Neues Analysetool hilft KMU bei der Digitalstrategie Die Beschr\u00e4nkungen zur Eind\u00e4mmung der Corona-Pandemie begleiten uns mittlerweile schon seit mehr als einem Jahr. Das Herunterfahren des \u00f6ffentlichen Lebens hatte nicht nur gesellschaftliche, sondern auch wirtschaftliche Folgen. Insbesondere kleine und mittelst\u00e4ndische Unternehmen (KMU) waren von Schlie\u00dfungen und massiven Umsatzeinbu\u00dfen betroffen.\u00a0 Zwischen dem 29. Januar und 9. Februar 2021 haben wir im Rahmen der Global State of Small Business Report mehr als 35.000 kleine und mittelst\u00e4ndische UnternehmerInnen auf unserer Plattform in 27 L\u00e4ndern weltweit zu den Auswirkungen der Pandemie auf ihr Unternehmen und ihre Zukunftsaussichten befragt. Im europ\u00e4ischen Vergleich schneiden Deutsche KMU gut ab W\u00e4hrend der Anteil geschlossener KMU in Europa aufgrund der strikten Beschr\u00e4nkungen zur Eind\u00e4mmung der Pandemie besonders gestiegen sind, berichteten 80 Prozent der befragten KMU in Deutschland, dass sie entweder regul\u00e4r ge\u00f6ffnet haben oder durch ein angepasstes Angebot Ums\u00e4tze generieren k\u00f6nnen. Im Vergleich zu Gro\u00dfbritannien (37 Prozent der KMU geschlossen) und Portugal (33 Prozent der KMU geschlossen) schneidet Deutschland damit sehr gut ab. Dennoch bleibt die Lage f\u00fcr den Mittelstand angespannt: 40 Prozent der Befragten in Deutschland gaben an, deutliche Umsatzeinbu\u00dfen zu verzeichnen. Von Frauen gef\u00fchrte KMU berichteten dabei von h\u00f6heren Umsatzeinbu\u00dfen (53 Prozent) als von M\u00e4nnern gef\u00fchrte Unternehmen (37 Prozent), was darauf zur\u00fcckzuf\u00fchren sein kann, dass Frauen tendenziell h\u00e4ufiger Kleinstunternehmen im besonders von der Pandemie betroffenen Dienstleistungssektor f\u00fchren. Diese Zahlen spiegeln den weltweiten Durchschnitt wider, der zeigt, dass Unternehmerinnen von den Auswirkungen der Krise deutlich st\u00e4rker betroffen sind als ihre m\u00e4nnlichen Pendants.\u00a0 Deutsche KMU zeigen sich trotz der schwierigen Situation optimistisch Nahezu Dreiviertel der Befragten (74 Prozent) gaben an, dass sie zuversichtlich sind, bei gleichbleibenden Umst\u00e4nden mindestens f\u00fcr sechs weitere Monate ge\u00f6ffnet bleiben zu k\u00f6nnen. Das liegt deutlich \u00fcber dem globalen Durchschnitt von 54 Prozent. Nur 10 Prozent der befragten UnternehmerInnen aus Deutschland gaben au\u00dferdem an, aufgrund der Corona-Krise ihr Personal reduziert zu haben; sowohl im globalen Vergleich (30 Prozent) als auch im Vergleich mit anderen EU-L\u00e4ndern wie Italien (30 Prozent) und Spanien (21 Prozent) ein bemerkenswert niedriger Wert. Aus Sicht der UnternehmerInnen werden vor allem geringere Nachfrage (laut 14 Prozent der Befragten) und weitere staatlich angeordnete Einschr\u00e4nkungen (laut 31 Prozent der Befragten) problematisch f\u00fcr ihr Unternehmen sein. Dar\u00fcber hinaus hat auch die Mobilit\u00e4t der Kunden weiter abgenommen: Google Mobility Daten zeigen, dass besonders in Deutschland und dem Vereinigten K\u00f6nigreich die Mobilit\u00e4t deutlich unter dem Vorkrisenniveau liegt \u2013 Ende Januar lag sie sogar niedriger als beim bisherigen Tiefstand im April 2020. F\u00fcr KMU bedeutet das, dass sie sich auch weiterhin neue kreative Wege werden erschlie\u00dfen m\u00fcssen, um Ums\u00e4tze zu generieren und mit ihrem Business zu wachsen: Hybridmodelle aus station\u00e4rem Handel und Online-Angeboten k\u00f6nnen hier zukunftsweisend sein. Erfolgsgeschichten von KMU machen Mut\u00a0 Im letzten Jahr haben wir mit unserer Initiative #WirliebenMittelstand bereits mehr als 150.000 Unternehmerinnen und Unternehmer gezielt beim Auf- und Ausbau ihrer Digitalstrategie begleiten k\u00f6nnen. Dadurch haben wir in den letzten zw\u00f6lf Monaten zahlreiche inspirierende Beispiele von KMU kennengelernt, die sich in k\u00fcrzester Zeit digitale Tools angeeignet haben, um auch w\u00e4hrend des Lockdowns Ums\u00e4tze zu generieren und mit ihren Kunden in Kontakt zu bleiben.\u00a0 Zwei von ihnen erz\u00e4hlen heute, wie es ihnen gelungen ist, sich schnell an die Herausforderungen anzupassen und welche Auswirkungen das auf ihr Business hatte: Miriam Jacks, Gr\u00fcnderin von JACKS Beautyline\u00a0 Die Idee, ihre eigene Linie f\u00fcr Make-up Pinsel zu entwerfen, hatte Miriam Jacks im Jahr 2009 w\u00e4hrend der Gr\u00fcndung ihres Beauty Stores in Berlin. Heute ist jeder handbemalte, vegane Pinsel ein eigenes kleines Kunstwerk &#8211; und die Produktpalette w\u00e4chst. W\u00e4hrend der Pandemie konnte sie ihr Business dank des Einsatzes von Facebook und Instagram sogar weiterentwickeln. Ihr Monatsumsatz im Webshop ist um fast 1000 Prozent gewachsen. Der erste Lockdown f\u00fchrte zun\u00e4chst zum Stillstand, doch mit gezieltem Influencer-Marketing und digitalen Make-up Workshops fand sie neue, kreative Wege, um ihr Gesch\u00e4ft am Laufen zu halten: &nbsp; \u00d6zg\u00fcr Aylikci, Gr\u00fcnder der Mono Concept Stores \u00d6zg\u00fcr und sein Team haben sich der M\u00e4nnermode verschrieben, fast &#8211; nat\u00fcrlich darf auch f\u00fcr die moderne Frau nichts fehlen. In den Hamburger Concept Stores gibt es t\u00e4gliche Fashion-Inspiration. W\u00e4hrend des ersten Lockdowns musste Mono Room Concept Store seine drei L\u00e4den schlie\u00dfen, doch das Gesch\u00e4ft lief weiter: Obwohl er zuvor 100 Prozent seines Umsatz \u00fcber den station\u00e4ren Handel generierte, gelang es ihm, innerhalb k\u00fcrzester Zeit sein Gesch\u00e4ftsmodell anzupassen und sich der Situation erfolgreich anzupassen. Wie er soziale Medien daf\u00fcr gezielt eingesetzt hat, erz\u00e4hlt er im Video: \u00a0Neues Analysetool hilft KMU bei der Digitalstrategie\u00a0 Wie unsere digitale Wirtschaftsstudie im letzten Jahr gezeigt hat, hat ein Drittel der befragten KMU mehr als 25 Prozent des Umsatzes \u00fcber digitale Kan\u00e4le generiert. Trotz der schwierigen Lage blieb daher fast die H\u00e4lfte der KMU zuversichtlich &#8211; doch sie gaben auch an, weitere Unterst\u00fctzung zu ben\u00f6tigen. Auch k\u00fcnftig werden eine digitale Pr\u00e4senz und eine langfristige Digitalstrategie f\u00fcr KMU essentiell sein, um zukunftsgerichtet zu wirtschaften &#8211; das gilt nicht nur, solange anhaltende Einschr\u00e4nkungen und unsichere Perspektiven f\u00fcr die n\u00e4chsten Monate sich auf den Mittelstand auswirken.\u00a0 Daf\u00fcr stellen wir heute ein neues kostenfreies Analysetool speziell f\u00fcr KMU vor: Mithilfe dieses Tools k\u00f6nnen KMU ihre digitale Pr\u00e4senz und bisherige Digitalstrategie hinsichtlich ihrer St\u00e4rken und Schw\u00e4chen \u00fcberpr\u00fcfen lassen. Dar\u00fcber hinaus k\u00f6nnen sie ausw\u00e4hlen, welche Ziele sie mit ihrer Digitalstrategie verfolgen, um einen optimierten Plan f\u00fcr k\u00fcnftige digitale Aktivit\u00e4ten zu erhalten.\u00a0 Mehr als 200 Millionen Unternehmen nutzen unsere Apps jeden Monat als virtuelles Schaufenster und um ihre Kunden zu erreichen &#8211; und Millionen KMU nutzen unsere Tools seit Beginn der Pandemie, um sich eine digitale Pr\u00e4senz aufzubauen und den \u00dcbergang zum hybriden Wirtschaften zwischen Offline- und Onlinehandel zu erleichtern. Dabei m\u00f6chten wir insbesondere den Mittelstand weiterhin zielgerichtet unterst\u00fctzen. Interessierte finden hier alle Informationen und spannende Trainings: https:\/\/www.facebook.com\/business.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00dcber Meta\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-08T07:57:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-08T09:46:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg\" \/>\n<meta name=\"author\" content=\"Trilligent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/\"},\"author\":\"Facebook company\",\"headline\":\"Ein Jahr Corona-Pandemie: Unterst\u00fctzung f\u00fcr und Stimmen aus dem Mittelstand\",\"datePublished\":\"2021-04-08T07:57:01+00:00\",\"dateModified\":\"2021-04-08T09:46:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/\"},\"wordCount\":1079,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/\",\"url\":\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/\",\"name\":\"Ein Jahr Corona-Pandemie: Unterst\u00fctzung f\u00fcr und Stimmen aus dem Mittelstand | \u00dcber Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg\",\"datePublished\":\"2021-04-08T07:57:01+00:00\",\"dateModified\":\"2021-04-08T09:46:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/\"]}],\"author\":\"\u00dcber Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#primaryimage\",\"url\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg?fit=960%2C1280\",\"contentUrl\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg?fit=960%2C1280\",\"width\":960,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein Jahr Corona-Pandemie: Unterst\u00fctzung f\u00fcr und Stimmen aus dem Mittelstand\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/de\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"\u00dcber Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/de\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/about.fb.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein Jahr Corona-Pandemie: Unterst\u00fctzung f\u00fcr und Stimmen aus dem Mittelstand | \u00dcber Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/","og_locale":"de_DE","og_type":"article","og_title":"Ein Jahr Corona-Pandemie: Unterst\u00fctzung f\u00fcr und Stimmen aus dem Mittelstand | \u00dcber Meta","og_description":"74 Prozent der deutschen KMU bleiben trotz angespannter Lage optimistisch\u00a0 Erfolgsgeschichten machen Mut: Miriam Jacks, Gr\u00fcnderin von JACKS Beautyline &amp; \u00d6zg\u00fcr Aylikci, Gr\u00fcnder der Mono Concept Stores Neues Analysetool hilft KMU bei der Digitalstrategie Die Beschr\u00e4nkungen zur Eind\u00e4mmung der Corona-Pandemie begleiten uns mittlerweile schon seit mehr als einem Jahr. Das Herunterfahren des \u00f6ffentlichen Lebens hatte nicht nur gesellschaftliche, sondern auch wirtschaftliche Folgen. Insbesondere kleine und mittelst\u00e4ndische Unternehmen (KMU) waren von Schlie\u00dfungen und massiven Umsatzeinbu\u00dfen betroffen.\u00a0 Zwischen dem 29. Januar und 9. Februar 2021 haben wir im Rahmen der Global State of Small Business Report mehr als 35.000 kleine und mittelst\u00e4ndische UnternehmerInnen auf unserer Plattform in 27 L\u00e4ndern weltweit zu den Auswirkungen der Pandemie auf ihr Unternehmen und ihre Zukunftsaussichten befragt. Im europ\u00e4ischen Vergleich schneiden Deutsche KMU gut ab W\u00e4hrend der Anteil geschlossener KMU in Europa aufgrund der strikten Beschr\u00e4nkungen zur Eind\u00e4mmung der Pandemie besonders gestiegen sind, berichteten 80 Prozent der befragten KMU in Deutschland, dass sie entweder regul\u00e4r ge\u00f6ffnet haben oder durch ein angepasstes Angebot Ums\u00e4tze generieren k\u00f6nnen. Im Vergleich zu Gro\u00dfbritannien (37 Prozent der KMU geschlossen) und Portugal (33 Prozent der KMU geschlossen) schneidet Deutschland damit sehr gut ab. Dennoch bleibt die Lage f\u00fcr den Mittelstand angespannt: 40 Prozent der Befragten in Deutschland gaben an, deutliche Umsatzeinbu\u00dfen zu verzeichnen. Von Frauen gef\u00fchrte KMU berichteten dabei von h\u00f6heren Umsatzeinbu\u00dfen (53 Prozent) als von M\u00e4nnern gef\u00fchrte Unternehmen (37 Prozent), was darauf zur\u00fcckzuf\u00fchren sein kann, dass Frauen tendenziell h\u00e4ufiger Kleinstunternehmen im besonders von der Pandemie betroffenen Dienstleistungssektor f\u00fchren. Diese Zahlen spiegeln den weltweiten Durchschnitt wider, der zeigt, dass Unternehmerinnen von den Auswirkungen der Krise deutlich st\u00e4rker betroffen sind als ihre m\u00e4nnlichen Pendants.\u00a0 Deutsche KMU zeigen sich trotz der schwierigen Situation optimistisch Nahezu Dreiviertel der Befragten (74 Prozent) gaben an, dass sie zuversichtlich sind, bei gleichbleibenden Umst\u00e4nden mindestens f\u00fcr sechs weitere Monate ge\u00f6ffnet bleiben zu k\u00f6nnen. Das liegt deutlich \u00fcber dem globalen Durchschnitt von 54 Prozent. Nur 10 Prozent der befragten UnternehmerInnen aus Deutschland gaben au\u00dferdem an, aufgrund der Corona-Krise ihr Personal reduziert zu haben; sowohl im globalen Vergleich (30 Prozent) als auch im Vergleich mit anderen EU-L\u00e4ndern wie Italien (30 Prozent) und Spanien (21 Prozent) ein bemerkenswert niedriger Wert. Aus Sicht der UnternehmerInnen werden vor allem geringere Nachfrage (laut 14 Prozent der Befragten) und weitere staatlich angeordnete Einschr\u00e4nkungen (laut 31 Prozent der Befragten) problematisch f\u00fcr ihr Unternehmen sein. Dar\u00fcber hinaus hat auch die Mobilit\u00e4t der Kunden weiter abgenommen: Google Mobility Daten zeigen, dass besonders in Deutschland und dem Vereinigten K\u00f6nigreich die Mobilit\u00e4t deutlich unter dem Vorkrisenniveau liegt \u2013 Ende Januar lag sie sogar niedriger als beim bisherigen Tiefstand im April 2020. F\u00fcr KMU bedeutet das, dass sie sich auch weiterhin neue kreative Wege werden erschlie\u00dfen m\u00fcssen, um Ums\u00e4tze zu generieren und mit ihrem Business zu wachsen: Hybridmodelle aus station\u00e4rem Handel und Online-Angeboten k\u00f6nnen hier zukunftsweisend sein. Erfolgsgeschichten von KMU machen Mut\u00a0 Im letzten Jahr haben wir mit unserer Initiative #WirliebenMittelstand bereits mehr als 150.000 Unternehmerinnen und Unternehmer gezielt beim Auf- und Ausbau ihrer Digitalstrategie begleiten k\u00f6nnen. Dadurch haben wir in den letzten zw\u00f6lf Monaten zahlreiche inspirierende Beispiele von KMU kennengelernt, die sich in k\u00fcrzester Zeit digitale Tools angeeignet haben, um auch w\u00e4hrend des Lockdowns Ums\u00e4tze zu generieren und mit ihren Kunden in Kontakt zu bleiben.\u00a0 Zwei von ihnen erz\u00e4hlen heute, wie es ihnen gelungen ist, sich schnell an die Herausforderungen anzupassen und welche Auswirkungen das auf ihr Business hatte: Miriam Jacks, Gr\u00fcnderin von JACKS Beautyline\u00a0 Die Idee, ihre eigene Linie f\u00fcr Make-up Pinsel zu entwerfen, hatte Miriam Jacks im Jahr 2009 w\u00e4hrend der Gr\u00fcndung ihres Beauty Stores in Berlin. Heute ist jeder handbemalte, vegane Pinsel ein eigenes kleines Kunstwerk &#8211; und die Produktpalette w\u00e4chst. W\u00e4hrend der Pandemie konnte sie ihr Business dank des Einsatzes von Facebook und Instagram sogar weiterentwickeln. Ihr Monatsumsatz im Webshop ist um fast 1000 Prozent gewachsen. Der erste Lockdown f\u00fchrte zun\u00e4chst zum Stillstand, doch mit gezieltem Influencer-Marketing und digitalen Make-up Workshops fand sie neue, kreative Wege, um ihr Gesch\u00e4ft am Laufen zu halten: &nbsp; \u00d6zg\u00fcr Aylikci, Gr\u00fcnder der Mono Concept Stores \u00d6zg\u00fcr und sein Team haben sich der M\u00e4nnermode verschrieben, fast &#8211; nat\u00fcrlich darf auch f\u00fcr die moderne Frau nichts fehlen. In den Hamburger Concept Stores gibt es t\u00e4gliche Fashion-Inspiration. W\u00e4hrend des ersten Lockdowns musste Mono Room Concept Store seine drei L\u00e4den schlie\u00dfen, doch das Gesch\u00e4ft lief weiter: Obwohl er zuvor 100 Prozent seines Umsatz \u00fcber den station\u00e4ren Handel generierte, gelang es ihm, innerhalb k\u00fcrzester Zeit sein Gesch\u00e4ftsmodell anzupassen und sich der Situation erfolgreich anzupassen. Wie er soziale Medien daf\u00fcr gezielt eingesetzt hat, erz\u00e4hlt er im Video: \u00a0Neues Analysetool hilft KMU bei der Digitalstrategie\u00a0 Wie unsere digitale Wirtschaftsstudie im letzten Jahr gezeigt hat, hat ein Drittel der befragten KMU mehr als 25 Prozent des Umsatzes \u00fcber digitale Kan\u00e4le generiert. Trotz der schwierigen Lage blieb daher fast die H\u00e4lfte der KMU zuversichtlich &#8211; doch sie gaben auch an, weitere Unterst\u00fctzung zu ben\u00f6tigen. Auch k\u00fcnftig werden eine digitale Pr\u00e4senz und eine langfristige Digitalstrategie f\u00fcr KMU essentiell sein, um zukunftsgerichtet zu wirtschaften &#8211; das gilt nicht nur, solange anhaltende Einschr\u00e4nkungen und unsichere Perspektiven f\u00fcr die n\u00e4chsten Monate sich auf den Mittelstand auswirken.\u00a0 Daf\u00fcr stellen wir heute ein neues kostenfreies Analysetool speziell f\u00fcr KMU vor: Mithilfe dieses Tools k\u00f6nnen KMU ihre digitale Pr\u00e4senz und bisherige Digitalstrategie hinsichtlich ihrer St\u00e4rken und Schw\u00e4chen \u00fcberpr\u00fcfen lassen. Dar\u00fcber hinaus k\u00f6nnen sie ausw\u00e4hlen, welche Ziele sie mit ihrer Digitalstrategie verfolgen, um einen optimierten Plan f\u00fcr k\u00fcnftige digitale Aktivit\u00e4ten zu erhalten.\u00a0 Mehr als 200 Millionen Unternehmen nutzen unsere Apps jeden Monat als virtuelles Schaufenster und um ihre Kunden zu erreichen &#8211; und Millionen KMU nutzen unsere Tools seit Beginn der Pandemie, um sich eine digitale Pr\u00e4senz aufzubauen und den \u00dcbergang zum hybriden Wirtschaften zwischen Offline- und Onlinehandel zu erleichtern. Dabei m\u00f6chten wir insbesondere den Mittelstand weiterhin zielgerichtet unterst\u00fctzen. Interessierte finden hier alle Informationen und spannende Trainings: https:\/\/www.facebook.com\/business.","og_url":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/","og_site_name":"\u00dcber Meta","article_published_time":"2021-04-08T07:57:01+00:00","article_modified_time":"2021-04-08T09:46:57+00:00","og_image":[{"url":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg","type":"","width":"","height":""}],"author":"Trilligent","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"5 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/"},"author":"Facebook company","headline":"Ein Jahr Corona-Pandemie: Unterst\u00fctzung f\u00fcr und Stimmen aus dem Mittelstand","datePublished":"2021-04-08T07:57:01+00:00","dateModified":"2021-04-08T09:46:57+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/"},"wordCount":1079,"publisher":{"@id":"https:\/\/about.fb.com\/de\/#organization"},"image":{"@id":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg","articleSection":["Uncategorized"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/","url":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/","name":"Ein Jahr Corona-Pandemie: Unterst\u00fctzung f\u00fcr und Stimmen aus dem Mittelstand | \u00dcber Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#primaryimage"},"image":{"@id":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg","datePublished":"2021-04-08T07:57:01+00:00","dateModified":"2021-04-08T09:46:57+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/"]}],"author":"\u00dcber Meta"},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#primaryimage","url":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg?fit=960%2C1280","contentUrl":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/04\/IMG_6491.jpeg?fit=960%2C1280","width":960,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/de\/news\/2021\/04\/ein-jahr-corona-pandemie-unterstuetzung-fuer-und-stimmen-aus-dem-mittelstand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/de\/"},{"@type":"ListItem","position":2,"name":"Ein Jahr Corona-Pandemie: Unterst\u00fctzung f\u00fcr und Stimmen aus dem Mittelstand"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/de\/#website","url":"https:\/\/about.fb.com\/news\/","name":"\u00dcber Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/de\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/about.fb.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/de\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/posts\/25781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/users\/116743763"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/comments?post=25781"}],"version-history":[{"count":10,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/posts\/25781\/revisions"}],"predecessor-version":[{"id":25800,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/posts\/25781\/revisions\/25800"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/media?parent=25781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/categories?post=25781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/de\/wp-json\/wp\/v2\/tags?post=25781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}