{"id":6345,"date":"2018-02-09T10:30:17","date_gmt":"2018-02-09T13:30:17","guid":{"rendered":"http:\/\/br.newsroom.fb.com\/?p=6345"},"modified":"2021-06-17T10:10:30","modified_gmt":"2021-06-17T13:10:30","slug":"facebook-anuncia-investimento-em-lideres-de-comunidades","status":"publish","type":"post","link":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/","title":{"rendered":"Facebook anuncia investimento em L\u00edderes de Comunidades"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6346\" src=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/capa-1.jpg?resize=960%2C640\" alt=\"\" width=\"960\" height=\"640\" \/><\/p>\n<p><i>Por Jennifer Dulski, diretora de Grupos e Comunidades, e Ime Archibong, vice-presidente de Parcerias de Produtos<\/i><\/p>\n<p>Hoje, no Summit de Comunidades do Facebook na Europa, anunciamos o Programa de L\u00edderes de Comunidades do Facebook, uma iniciativa global que investe em pessoas que est\u00e3o construindo comunidades. O Facebook est\u00e1 comprometido em investir dezenas de milh\u00f5es de d\u00f3lares no programa, incluindo at\u00e9 US$10 milh\u00f5es em subs\u00eddios que ir\u00e3o diretamente para pessoas construindo e liderando comunidades.<\/p>\n<p>Al\u00e9m disso, adicionamos novas ferramentas para administradores de grupos e a expans\u00e3o de nossa equipe de engenharia em Londres, que desenvolve tecnologia para ajudar a manter as pessoas seguras no Facebook.<\/p>\n<p>Mais de 300 l\u00edderes de comunidades de toda a Europa se reuniram em Londres, incluindo a <a href=\"https:\/\/www.facebook.com\/20531316728\/videos\/10157085333321729\/\">Blind Veterans UK<\/a>, uma organiza\u00e7\u00e3o brit\u00e2nica que oferece apoio a veteranos cegos e suas fam\u00edlias; a <a href=\"https:\/\/www.facebook.com\/20531316728\/videos\/10157085343906729\/\">Donna Mamma<\/a>, um grupo de apoio para m\u00e3es na Fran\u00e7a para compartilhar conselhos e informa\u00e7\u00f5es; a <a href=\"https:\/\/www.facebook.com\/20531316728\/videos\/10157085325776729\/\">Girl Skate UK<\/a>, que celebra e re\u00fane a comunidade feminina de skateboarding; a <a href=\"https:\/\/www.facebook.com\/20531316728\/videos\/10157085336091729\/\">High Society PL<\/a>, um grupo de entusiastas de t\u00eanis que compartilham a mesma paix\u00e3o; e o <a href=\"https:\/\/www.facebook.com\/20531316728\/videos\/10157085348821729\/\">Berlin Bruisers<\/a>, o primeiro clube de rugby gay e inclusivo da Alemanha.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6347\" src=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/1-1.jpg?resize=960%2C640\" alt=\"\" width=\"960\" height=\"640\" \/><br \/>\n<b><u>Programa de L\u00edderes de Comunidades do Facebook<\/u><\/b><\/p>\n<p>L\u00edderes de comunidades muitas vezes nos falam que, com suporte adicional, eles poderiam ter mais impacto. O Programa de L\u00edderes de Comunidades do Facebook foi desenhado para capacitar l\u00edderes de todo o mundo que est\u00e3o criando comunidades por meio da fam\u00edlia de aplicativos e servi\u00e7os do Facebook. O programa inclui:<\/p>\n<p><b>Resid\u00eancia e oportunidade de bolsa<\/b><b>: <\/b>oferece treinamento, suporte e financiamento para l\u00edderes de comunidades ao redor do mundo.<\/p>\n<ul>\n<li>At\u00e9 cinco l\u00edderes ser\u00e3o selecionados para serem <b>l\u00edderes de comunidade em resid\u00eancia<\/b> e premiados com at\u00e9 <b>US$1.000.000*<\/b> cada um para financiar suas propostas.<\/li>\n<li>At\u00e9 100 l\u00edderes ser\u00e3o selecionados para o nosso <b>programa de bolsas<\/b> e receber\u00e3o at\u00e9 <b>US$50.000*<\/b> cada um para uma iniciativa de comunidade espec\u00edfica.<\/li>\n<\/ul>\n<p><b>C\u00edrculos de lideran\u00e7a da comunidade: <\/b>re\u00fane l\u00edderes de comunidades locais para se encontrarem pessoalmente para se conectar, aprender e colaborar. N\u00f3s organizamos tr\u00eas c\u00edrculos piloto nos Estados Unidos em 2017 e vamos expandi-los globalmente este ano.<\/p>\n<p><b>Grupos para o Facebook Power Admins<\/b>, que atualmente conta com mais de 10.000 administradores de grupo nos EUA e no Reino Unido e, agora, est\u00e1 sendo expandido para mais membros para ajud\u00e1-los a compartilhar conselhos uns com os outros e se conectar com nossa equipe para testar novos recursos e compartilhar coment\u00e1rios.<\/p>\n<p>As inscri\u00e7\u00f5es para resid\u00eancia e bolsas est\u00e3o abertas. Para saber mais e candidatar-se, visite <a href=\"http:\/\/communities.fb.com\/\"><u>communities.fb.com<\/u><\/a>.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6348\" src=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/2-1.jpg?resize=960%2C640\" alt=\"\" width=\"960\" height=\"640\" \/><br \/>\n<b><u>Novas Ferramentas para Administradores de Grupo e Membros<\/u><\/b><\/p>\n<p>Administradores de grupos querem manter suas comunidades seguras, organizadas e engajadas. Hoje n\u00f3s adicionamos quatro novos recursos para ajud\u00e1-los:<\/p>\n<ul>\n<li><b>Ferramentas administrativas<\/b>: Agora administradores podem encontrar solicita\u00e7\u00f5es de membros, Insights dos Grupos e mais em um s\u00f3 lugar, facilitando a gest\u00e3o de grupos e otimizando o tempo para que os administradores possam se conectar com os membros.<br \/>\n<b>Novidades do Grupo:<\/b> Os administradores de grupo querem poder compartilhar atualiza\u00e7\u00f5es mais facilmente, ent\u00e3o a partir de agora os administradores podem publicar at\u00e9 10 novidades que aparecer\u00e3o no topo do grupo.<\/li>\n<li><b>Regras do Grupo<\/b>: Manter comunidades seguras \u00e9 importante. Agora os administradores podem criar uma se\u00e7\u00e3o de regras dedicada a ajud\u00e1-los a comunicar efetivamente as regras do grupo aos seus membros.<\/li>\n<\/ul>\n<ul>\n<li><b>Personaliza\u00e7\u00e3o:<\/b> Cada comunidade tem sua pr\u00f3pria identidade &#8211; agora os administradores podem adicionar uma cor personalizada que \u00e9 exibida em todo o grupo.<\/li>\n<\/ul>\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/facebook\/videos\/10157088297566729\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<p><b><u>Expans\u00e3o do time de engenharia em Londres para Seguran\u00e7a das Comunidades<\/u><\/b><\/p>\n<p>Temos uma equipe de engenheiros ao redor do mundo que desenvolve tecnologias que ajudam a manter nossa comunidade segura. Londres \u00e9 o lar do maior centro de engenharia do Facebook fora dos EUA e, at\u00e9 o fim de 2018, duplicaremos o n\u00famero de pessoas que trabalham em Londres em temas relacionados \u00e0 seguran\u00e7a.<\/p>\n<p>Nosso trabalho de engenharia em seguran\u00e7a das comunidades inclui:<\/p>\n<ul>\n<li><b>Detectar e agir contra contas falsas:<\/b> Trabalhando para garantir que o Facebook seja uma comunidade de pessoas reais que possam se conectar de forma aut\u00eantica.<br \/>\n<b>Proteger a integridade das pessoas:<\/b> Reduzindo ass\u00e9dio e golpes que podem acontecer no mundo real e no Facebook, criando melhores ferramentas para detectar esses problemas e remov\u00ea-los.<br \/>\n<b>Melhorar as formas de reportar conte\u00fado: <\/b>Facilitando a forma como as pessoas nos d\u00e3o feedback sobre coisas que n\u00e3o deveriam estar em nossa plataforma, o que funciona em conjunto com nossa detec\u00e7\u00e3o autom\u00e1tica.<\/li>\n<\/ul>\n<p>As pessoas se identificam e encontram suporte em comunidades, online e pessoalmente. Os programas e as ferramentas que anunciamos hoje s\u00e3o projetados para ajudar os administradores que lideram essas comunidades a crescer e fortalecer os v\u00ednculos entre os seus membros. Somos inspirados por esses l\u00edderes e estamos ansiosos para continuar nossos esfor\u00e7os para apoi\u00e1-los.<\/p>\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/facebook\/videos\/10157085333321729\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/facebook\/videos\/10157085343906729\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/facebook\/videos\/10157085325776729\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/facebook\/videos\/10157085336091729\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/facebook\/videos\/10157085348821729\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<p><i>*O valor final pode variar devido \u00e0 varia\u00e7\u00e3o da taxa de c\u00e2mbio no momento do pagamento.<\/i><\/p>\n<p><strong><span class=\"entry-meta-label\">Downloads:<\/span><\/strong><\/p>\n<ul class=\"download-list\">\n<li><a href=\"https:\/\/about-fb-preprod.go-vip.net\/wp-content\/uploads\/2028\/02\/fcs-feature-stills-english.zip\" target=\"_blank\" rel=\"noopener noreferrer\"><i><\/i>Fotos: Ferramentas de Grupos<\/a><\/li>\n<li><a href=\"https:\/\/about-fb-preprod.go-vip.net\/wp-content\/uploads\/2028\/02\/fcs-feature-videos-english.zip\" target=\"_blank\" rel=\"noopener noreferrer\"><i><\/i>V\u00eddeos: Ferramentas de Grupos<\/a><\/li>\n<li><a href=\"https:\/\/about-fb-preprod.go-vip.net\/wp-content\/uploads\/2028\/02\/fclp-video-and-logo.zip\" target=\"_blank\" rel=\"noopener noreferrer\"><i><\/i>Programa de L\u00edderes de Comunidades do Facebook<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"Por Jennifer Dulski, diretora de Grupos e Comunidades, e Ime Archibong, vice-presidente de Parcerias de Produtos Hoje, no Summit de Comunidades do Facebook na Europa, anunciamos o Programa de L\u00edderes de Comunidades do Facebook, uma iniciativa global que investe em pessoas que est\u00e3o construindo comunidades. O Facebook est\u00e1 comprometido em investir dezenas de milh\u00f5es de d\u00f3lares no programa, incluindo at\u00e9 US$10 milh\u00f5es em subs\u00eddios que ir\u00e3o diretamente para pessoas construindo e liderando comunidades. Al\u00e9m disso, adicionamos novas ferramentas para administradores de grupos e a expans\u00e3o de nossa equipe de engenharia em Londres, que desenvolve tecnologia para ajudar a manter as pessoas seguras no Facebook. Mais de 300 l\u00edderes de comunidades de toda a Europa se reuniram em Londres, incluindo a Blind Veterans UK, uma organiza\u00e7\u00e3o brit\u00e2nica que oferece apoio a veteranos cegos e suas fam\u00edlias; a Donna Mamma, um grupo de apoio para m\u00e3es na Fran\u00e7a para compartilhar conselhos e informa\u00e7\u00f5es; a Girl Skate UK, que celebra e re\u00fane a comunidade feminina de skateboarding; a High Society PL, um grupo de entusiastas de t\u00eanis que compartilham a mesma paix\u00e3o; e o Berlin Bruisers, o primeiro clube de rugby gay e inclusivo da Alemanha. Programa de L\u00edderes de Comunidades do Facebook L\u00edderes de comunidades muitas vezes nos falam que, com suporte adicional, eles poderiam ter mais impacto. O Programa de L\u00edderes de Comunidades do Facebook foi desenhado para capacitar l\u00edderes de todo o mundo que est\u00e3o criando comunidades por meio da fam\u00edlia de aplicativos e servi\u00e7os do Facebook. O programa inclui: Resid\u00eancia e oportunidade de bolsa: oferece treinamento, suporte e financiamento para l\u00edderes de comunidades ao redor do mundo. At\u00e9 cinco l\u00edderes ser\u00e3o selecionados para serem l\u00edderes de comunidade em resid\u00eancia e premiados com at\u00e9 US$1.000.000* cada um para financiar suas propostas. At\u00e9 100 l\u00edderes ser\u00e3o selecionados para o nosso programa de bolsas e receber\u00e3o at\u00e9 US$50.000* cada um para uma iniciativa de comunidade espec\u00edfica. C\u00edrculos de lideran\u00e7a da comunidade: re\u00fane l\u00edderes de comunidades locais para se encontrarem pessoalmente para se conectar, aprender e colaborar. N\u00f3s organizamos tr\u00eas c\u00edrculos piloto nos Estados Unidos em 2017 e vamos expandi-los globalmente este ano. Grupos para o Facebook Power Admins, que atualmente conta com mais de 10.000 administradores de grupo nos EUA e no Reino Unido e, agora, est\u00e1 sendo expandido para mais membros para ajud\u00e1-los a compartilhar conselhos uns com os outros e se conectar com nossa equipe para testar novos recursos e compartilhar coment\u00e1rios. As inscri\u00e7\u00f5es para resid\u00eancia e bolsas est\u00e3o abertas. Para saber mais e candidatar-se, visite communities.fb.com. Novas Ferramentas para Administradores de Grupo e Membros Administradores de grupos querem manter suas comunidades seguras, organizadas e engajadas. Hoje n\u00f3s adicionamos quatro novos recursos para ajud\u00e1-los: Ferramentas administrativas: Agora administradores podem encontrar solicita\u00e7\u00f5es de membros, Insights dos Grupos e mais em um s\u00f3 lugar, facilitando a gest\u00e3o de grupos e otimizando o tempo para que os administradores possam se conectar com os membros. Novidades do Grupo: Os administradores de grupo querem poder compartilhar atualiza\u00e7\u00f5es mais facilmente, ent\u00e3o a partir de agora os administradores podem publicar at\u00e9 10 novidades que aparecer\u00e3o no topo do grupo. Regras do Grupo: Manter comunidades seguras \u00e9 importante. Agora os administradores podem criar uma se\u00e7\u00e3o de regras dedicada a ajud\u00e1-los a comunicar efetivamente as regras do grupo aos seus membros. Personaliza\u00e7\u00e3o: Cada comunidade tem sua pr\u00f3pria identidade &#8211; agora os administradores podem adicionar uma cor personalizada que \u00e9 exibida em todo o grupo. Expans\u00e3o do time de engenharia em Londres para Seguran\u00e7a das Comunidades Temos uma equipe de engenheiros ao redor do mundo que desenvolve tecnologias que ajudam a manter nossa comunidade segura. Londres \u00e9 o lar do maior centro de engenharia do Facebook fora dos EUA e, at\u00e9 o fim de 2018, duplicaremos o n\u00famero de pessoas que trabalham em Londres em temas relacionados \u00e0 seguran\u00e7a. Nosso trabalho de engenharia em seguran\u00e7a das comunidades inclui: Detectar e agir contra contas falsas: Trabalhando para garantir que o Facebook seja uma comunidade de pessoas reais que possam se conectar de forma aut\u00eantica. Proteger a integridade das pessoas: Reduzindo ass\u00e9dio e golpes que podem acontecer no mundo real e no Facebook, criando melhores ferramentas para detectar esses problemas e remov\u00ea-los. Melhorar as formas de reportar conte\u00fado: Facilitando a forma como as pessoas nos d\u00e3o feedback sobre coisas que n\u00e3o deveriam estar em nossa plataforma, o que funciona em conjunto com nossa detec\u00e7\u00e3o autom\u00e1tica. As pessoas se identificam e encontram suporte em comunidades, online e pessoalmente. Os programas e as ferramentas que anunciamos hoje s\u00e3o projetados para ajudar os administradores que lideram essas comunidades a crescer e fortalecer os v\u00ednculos entre os seus membros. Somos inspirados por esses l\u00edderes e estamos ansiosos para continuar nossos esfor\u00e7os para apoi\u00e1-los. *O valor final pode variar devido \u00e0 varia\u00e7\u00e3o da taxa de c\u00e2mbio no momento do pagamento. Downloads: Fotos: Ferramentas de Grupos V\u00eddeos: Ferramentas de Grupos Programa de L\u00edderes de Comunidades do Facebook","protected":false},"author":81109636,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6345","post","type-post","status-publish","format-standard","hentry","category-recent-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Facebook anuncia investimento em L\u00edderes de Comunidades | Sobre a Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Facebook anuncia investimento em L\u00edderes de Comunidades | Sobre a Meta\" \/>\n<meta property=\"og:description\" content=\"Por Jennifer Dulski, diretora de Grupos e Comunidades, e Ime Archibong, vice-presidente de Parcerias de Produtos Hoje, no Summit de Comunidades do Facebook na Europa, anunciamos o Programa de L\u00edderes de Comunidades do Facebook, uma iniciativa global que investe em pessoas que est\u00e3o construindo comunidades. O Facebook est\u00e1 comprometido em investir dezenas de milh\u00f5es de d\u00f3lares no programa, incluindo at\u00e9 US$10 milh\u00f5es em subs\u00eddios que ir\u00e3o diretamente para pessoas construindo e liderando comunidades. Al\u00e9m disso, adicionamos novas ferramentas para administradores de grupos e a expans\u00e3o de nossa equipe de engenharia em Londres, que desenvolve tecnologia para ajudar a manter as pessoas seguras no Facebook. Mais de 300 l\u00edderes de comunidades de toda a Europa se reuniram em Londres, incluindo a Blind Veterans UK, uma organiza\u00e7\u00e3o brit\u00e2nica que oferece apoio a veteranos cegos e suas fam\u00edlias; a Donna Mamma, um grupo de apoio para m\u00e3es na Fran\u00e7a para compartilhar conselhos e informa\u00e7\u00f5es; a Girl Skate UK, que celebra e re\u00fane a comunidade feminina de skateboarding; a High Society PL, um grupo de entusiastas de t\u00eanis que compartilham a mesma paix\u00e3o; e o Berlin Bruisers, o primeiro clube de rugby gay e inclusivo da Alemanha. Programa de L\u00edderes de Comunidades do Facebook L\u00edderes de comunidades muitas vezes nos falam que, com suporte adicional, eles poderiam ter mais impacto. O Programa de L\u00edderes de Comunidades do Facebook foi desenhado para capacitar l\u00edderes de todo o mundo que est\u00e3o criando comunidades por meio da fam\u00edlia de aplicativos e servi\u00e7os do Facebook. O programa inclui: Resid\u00eancia e oportunidade de bolsa: oferece treinamento, suporte e financiamento para l\u00edderes de comunidades ao redor do mundo. At\u00e9 cinco l\u00edderes ser\u00e3o selecionados para serem l\u00edderes de comunidade em resid\u00eancia e premiados com at\u00e9 US$1.000.000* cada um para financiar suas propostas. At\u00e9 100 l\u00edderes ser\u00e3o selecionados para o nosso programa de bolsas e receber\u00e3o at\u00e9 US$50.000* cada um para uma iniciativa de comunidade espec\u00edfica. C\u00edrculos de lideran\u00e7a da comunidade: re\u00fane l\u00edderes de comunidades locais para se encontrarem pessoalmente para se conectar, aprender e colaborar. N\u00f3s organizamos tr\u00eas c\u00edrculos piloto nos Estados Unidos em 2017 e vamos expandi-los globalmente este ano. Grupos para o Facebook Power Admins, que atualmente conta com mais de 10.000 administradores de grupo nos EUA e no Reino Unido e, agora, est\u00e1 sendo expandido para mais membros para ajud\u00e1-los a compartilhar conselhos uns com os outros e se conectar com nossa equipe para testar novos recursos e compartilhar coment\u00e1rios. As inscri\u00e7\u00f5es para resid\u00eancia e bolsas est\u00e3o abertas. Para saber mais e candidatar-se, visite communities.fb.com. Novas Ferramentas para Administradores de Grupo e Membros Administradores de grupos querem manter suas comunidades seguras, organizadas e engajadas. Hoje n\u00f3s adicionamos quatro novos recursos para ajud\u00e1-los: Ferramentas administrativas: Agora administradores podem encontrar solicita\u00e7\u00f5es de membros, Insights dos Grupos e mais em um s\u00f3 lugar, facilitando a gest\u00e3o de grupos e otimizando o tempo para que os administradores possam se conectar com os membros. Novidades do Grupo: Os administradores de grupo querem poder compartilhar atualiza\u00e7\u00f5es mais facilmente, ent\u00e3o a partir de agora os administradores podem publicar at\u00e9 10 novidades que aparecer\u00e3o no topo do grupo. Regras do Grupo: Manter comunidades seguras \u00e9 importante. Agora os administradores podem criar uma se\u00e7\u00e3o de regras dedicada a ajud\u00e1-los a comunicar efetivamente as regras do grupo aos seus membros. Personaliza\u00e7\u00e3o: Cada comunidade tem sua pr\u00f3pria identidade &#8211; agora os administradores podem adicionar uma cor personalizada que \u00e9 exibida em todo o grupo. Expans\u00e3o do time de engenharia em Londres para Seguran\u00e7a das Comunidades Temos uma equipe de engenheiros ao redor do mundo que desenvolve tecnologias que ajudam a manter nossa comunidade segura. Londres \u00e9 o lar do maior centro de engenharia do Facebook fora dos EUA e, at\u00e9 o fim de 2018, duplicaremos o n\u00famero de pessoas que trabalham em Londres em temas relacionados \u00e0 seguran\u00e7a. Nosso trabalho de engenharia em seguran\u00e7a das comunidades inclui: Detectar e agir contra contas falsas: Trabalhando para garantir que o Facebook seja uma comunidade de pessoas reais que possam se conectar de forma aut\u00eantica. Proteger a integridade das pessoas: Reduzindo ass\u00e9dio e golpes que podem acontecer no mundo real e no Facebook, criando melhores ferramentas para detectar esses problemas e remov\u00ea-los. Melhorar as formas de reportar conte\u00fado: Facilitando a forma como as pessoas nos d\u00e3o feedback sobre coisas que n\u00e3o deveriam estar em nossa plataforma, o que funciona em conjunto com nossa detec\u00e7\u00e3o autom\u00e1tica. As pessoas se identificam e encontram suporte em comunidades, online e pessoalmente. Os programas e as ferramentas que anunciamos hoje s\u00e3o projetados para ajudar os administradores que lideram essas comunidades a crescer e fortalecer os v\u00ednculos entre os seus membros. Somos inspirados por esses l\u00edderes e estamos ansiosos para continuar nossos esfor\u00e7os para apoi\u00e1-los. *O valor final pode variar devido \u00e0 varia\u00e7\u00e3o da taxa de c\u00e2mbio no momento do pagamento. Downloads: Fotos: Ferramentas de Grupos V\u00eddeos: Ferramentas de Grupos Programa de L\u00edderes de Comunidades do Facebook\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre a Meta\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-09T13:30:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-17T13:10:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/capa-1.jpg\" \/>\n<meta name=\"author\" content=\"facebookbr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/\"},\"author\":\"Facebook company\",\"headline\":\"Facebook anuncia investimento em L\u00edderes de Comunidades\",\"datePublished\":\"2018-02-09T13:30:17+00:00\",\"dateModified\":\"2021-06-17T13:10:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/\"},\"wordCount\":925,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/capa-1.jpg\",\"articleSection\":[\"Recent News\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/\",\"url\":\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/\",\"name\":\"Facebook anuncia investimento em L\u00edderes de Comunidades | Sobre a Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/capa-1.jpg\",\"datePublished\":\"2018-02-09T13:30:17+00:00\",\"dateModified\":\"2021-06-17T13:10:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/\"]}],\"author\":\"Sobre a Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#primaryimage\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/capa-1.jpg\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/capa-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facebook anuncia investimento em L\u00edderes de Comunidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/br\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"Sobre a Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/br\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Facebook anuncia investimento em L\u00edderes de Comunidades | Sobre a Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/","og_locale":"pt_BR","og_type":"article","og_title":"Facebook anuncia investimento em L\u00edderes de Comunidades | Sobre a Meta","og_description":"Por Jennifer Dulski, diretora de Grupos e Comunidades, e Ime Archibong, vice-presidente de Parcerias de Produtos Hoje, no Summit de Comunidades do Facebook na Europa, anunciamos o Programa de L\u00edderes de Comunidades do Facebook, uma iniciativa global que investe em pessoas que est\u00e3o construindo comunidades. O Facebook est\u00e1 comprometido em investir dezenas de milh\u00f5es de d\u00f3lares no programa, incluindo at\u00e9 US$10 milh\u00f5es em subs\u00eddios que ir\u00e3o diretamente para pessoas construindo e liderando comunidades. Al\u00e9m disso, adicionamos novas ferramentas para administradores de grupos e a expans\u00e3o de nossa equipe de engenharia em Londres, que desenvolve tecnologia para ajudar a manter as pessoas seguras no Facebook. Mais de 300 l\u00edderes de comunidades de toda a Europa se reuniram em Londres, incluindo a Blind Veterans UK, uma organiza\u00e7\u00e3o brit\u00e2nica que oferece apoio a veteranos cegos e suas fam\u00edlias; a Donna Mamma, um grupo de apoio para m\u00e3es na Fran\u00e7a para compartilhar conselhos e informa\u00e7\u00f5es; a Girl Skate UK, que celebra e re\u00fane a comunidade feminina de skateboarding; a High Society PL, um grupo de entusiastas de t\u00eanis que compartilham a mesma paix\u00e3o; e o Berlin Bruisers, o primeiro clube de rugby gay e inclusivo da Alemanha. Programa de L\u00edderes de Comunidades do Facebook L\u00edderes de comunidades muitas vezes nos falam que, com suporte adicional, eles poderiam ter mais impacto. O Programa de L\u00edderes de Comunidades do Facebook foi desenhado para capacitar l\u00edderes de todo o mundo que est\u00e3o criando comunidades por meio da fam\u00edlia de aplicativos e servi\u00e7os do Facebook. O programa inclui: Resid\u00eancia e oportunidade de bolsa: oferece treinamento, suporte e financiamento para l\u00edderes de comunidades ao redor do mundo. At\u00e9 cinco l\u00edderes ser\u00e3o selecionados para serem l\u00edderes de comunidade em resid\u00eancia e premiados com at\u00e9 US$1.000.000* cada um para financiar suas propostas. At\u00e9 100 l\u00edderes ser\u00e3o selecionados para o nosso programa de bolsas e receber\u00e3o at\u00e9 US$50.000* cada um para uma iniciativa de comunidade espec\u00edfica. C\u00edrculos de lideran\u00e7a da comunidade: re\u00fane l\u00edderes de comunidades locais para se encontrarem pessoalmente para se conectar, aprender e colaborar. N\u00f3s organizamos tr\u00eas c\u00edrculos piloto nos Estados Unidos em 2017 e vamos expandi-los globalmente este ano. Grupos para o Facebook Power Admins, que atualmente conta com mais de 10.000 administradores de grupo nos EUA e no Reino Unido e, agora, est\u00e1 sendo expandido para mais membros para ajud\u00e1-los a compartilhar conselhos uns com os outros e se conectar com nossa equipe para testar novos recursos e compartilhar coment\u00e1rios. As inscri\u00e7\u00f5es para resid\u00eancia e bolsas est\u00e3o abertas. Para saber mais e candidatar-se, visite communities.fb.com. Novas Ferramentas para Administradores de Grupo e Membros Administradores de grupos querem manter suas comunidades seguras, organizadas e engajadas. Hoje n\u00f3s adicionamos quatro novos recursos para ajud\u00e1-los: Ferramentas administrativas: Agora administradores podem encontrar solicita\u00e7\u00f5es de membros, Insights dos Grupos e mais em um s\u00f3 lugar, facilitando a gest\u00e3o de grupos e otimizando o tempo para que os administradores possam se conectar com os membros. Novidades do Grupo: Os administradores de grupo querem poder compartilhar atualiza\u00e7\u00f5es mais facilmente, ent\u00e3o a partir de agora os administradores podem publicar at\u00e9 10 novidades que aparecer\u00e3o no topo do grupo. Regras do Grupo: Manter comunidades seguras \u00e9 importante. Agora os administradores podem criar uma se\u00e7\u00e3o de regras dedicada a ajud\u00e1-los a comunicar efetivamente as regras do grupo aos seus membros. Personaliza\u00e7\u00e3o: Cada comunidade tem sua pr\u00f3pria identidade &#8211; agora os administradores podem adicionar uma cor personalizada que \u00e9 exibida em todo o grupo. Expans\u00e3o do time de engenharia em Londres para Seguran\u00e7a das Comunidades Temos uma equipe de engenheiros ao redor do mundo que desenvolve tecnologias que ajudam a manter nossa comunidade segura. Londres \u00e9 o lar do maior centro de engenharia do Facebook fora dos EUA e, at\u00e9 o fim de 2018, duplicaremos o n\u00famero de pessoas que trabalham em Londres em temas relacionados \u00e0 seguran\u00e7a. Nosso trabalho de engenharia em seguran\u00e7a das comunidades inclui: Detectar e agir contra contas falsas: Trabalhando para garantir que o Facebook seja uma comunidade de pessoas reais que possam se conectar de forma aut\u00eantica. Proteger a integridade das pessoas: Reduzindo ass\u00e9dio e golpes que podem acontecer no mundo real e no Facebook, criando melhores ferramentas para detectar esses problemas e remov\u00ea-los. Melhorar as formas de reportar conte\u00fado: Facilitando a forma como as pessoas nos d\u00e3o feedback sobre coisas que n\u00e3o deveriam estar em nossa plataforma, o que funciona em conjunto com nossa detec\u00e7\u00e3o autom\u00e1tica. As pessoas se identificam e encontram suporte em comunidades, online e pessoalmente. Os programas e as ferramentas que anunciamos hoje s\u00e3o projetados para ajudar os administradores que lideram essas comunidades a crescer e fortalecer os v\u00ednculos entre os seus membros. Somos inspirados por esses l\u00edderes e estamos ansiosos para continuar nossos esfor\u00e7os para apoi\u00e1-los. *O valor final pode variar devido \u00e0 varia\u00e7\u00e3o da taxa de c\u00e2mbio no momento do pagamento. Downloads: Fotos: Ferramentas de Grupos V\u00eddeos: Ferramentas de Grupos Programa de L\u00edderes de Comunidades do Facebook","og_url":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/","og_site_name":"Sobre a Meta","article_published_time":"2018-02-09T13:30:17+00:00","article_modified_time":"2021-06-17T13:10:30+00:00","og_image":[{"url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/capa-1.jpg","type":"","width":"","height":""}],"author":"facebookbr","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/"},"author":"Facebook company","headline":"Facebook anuncia investimento em L\u00edderes de Comunidades","datePublished":"2018-02-09T13:30:17+00:00","dateModified":"2021-06-17T13:10:30+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/"},"wordCount":925,"publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/capa-1.jpg","articleSection":["Recent News"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/","url":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/","name":"Facebook anuncia investimento em L\u00edderes de Comunidades | Sobre a Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#primaryimage"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/capa-1.jpg","datePublished":"2018-02-09T13:30:17+00:00","dateModified":"2021-06-17T13:10:30+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/"]}],"author":"Sobre a Meta"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#primaryimage","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/capa-1.jpg","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2018\/02\/capa-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/br\/news\/2018\/02\/facebook-anuncia-investimento-em-lideres-de-comunidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/br\/"},{"@type":"ListItem","position":2,"name":"Facebook anuncia investimento em L\u00edderes de Comunidades"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/br\/#website","url":"https:\/\/about.fb.com\/news\/","name":"Sobre a Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/br\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":26214,"url":"https:\/\/about.fb.com\/br\/news\/2025\/03\/26214\/","url_meta":{"origin":6345,"position":0},"title":"Iniciando os testes para Notas da Comunidade no Facebook, Instagram e Threads","author":"Meta","date":"13\/03\/2025","format":false,"excerpt":"Em janeiro, a Meta anunciou que encerrar\u00e1 o programa com organiza\u00e7\u00f5es independentes de verifica\u00e7\u00e3o de fatos e passar\u00e1 a adotar um sistema de Notas da Comunidade baseado em colabora\u00e7\u00e3o coletiva, come\u00e7ando nos Estados Unidos. A partir de 18 de mar\u00e7o, vamos come\u00e7ar a testar essa nova abordagem, permitindo que os\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/03\/03_Rating_Carousel-030.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/03\/03_Rating_Carousel-030.jpg?resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/03\/03_Rating_Carousel-030.jpg?resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/03\/03_Rating_Carousel-030.jpg?resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/03\/03_Rating_Carousel-030.jpg?resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/03\/03_Rating_Carousel-030.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":27127,"url":"https:\/\/about.fb.com\/br\/news\/2026\/05\/novas-medidas-para-garantir-que-adolescentes-tenham-experiencias-adequadas-a-faixa-etaria\/","url_meta":{"origin":6345,"position":1},"title":"Novas medidas para garantir que adolescentes tenham experi\u00eancias adequadas \u00e0 faixa et\u00e1ria","author":"Meta","date":"05\/05\/2026","format":false,"excerpt":"Queremos que os jovens tenham viv\u00eancias online seguras e positivas. \u00c9 por isso que colocamos os adolescentes automaticamente em experi\u00eancias adequadas \u00e0 idade, como as Contas de Adolescente. Hoje, compartilhamos atualiza\u00e7\u00f5es sobre nossos esfor\u00e7os para ajudar a garantir que menores de idade n\u00e3o estejam utilizando nossos apps de forma inadequada\u2026","rel":"","context":"In &quot;Facebook&quot;","block_context":{"text":"Facebook","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/facebook\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/AI-Age-Assurance_Header-1.jpg?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/AI-Age-Assurance_Header-1.jpg?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/AI-Age-Assurance_Header-1.jpg?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/AI-Age-Assurance_Header-1.jpg?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/AI-Age-Assurance_Header-1.jpg?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/AI-Age-Assurance_Header-1.jpg?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]},{"id":26407,"url":"https:\/\/about.fb.com\/br\/news\/2025\/05\/mais-de-meio-trilhao-de-dolares-e-34-milhoes-de-empregos-nos-eua-estao-ligados-as-tecnologias-de-anuncios-com-ia-da-meta\/","url_meta":{"origin":6345,"position":2},"title":"Mais de meio trilh\u00e3o de d\u00f3lares e 3,4 milh\u00f5es de empregos nos EUA est\u00e3o ligados \u00e0s tecnologias de publicidade com IA da Meta","author":"Meta","date":"13\/05\/2025","format":false,"excerpt":"Milh\u00f5es de empresas nos Estados Unidos - desde com\u00e9rcios familiares at\u00e9 grandes marcas globais - usam nossas ferramentas de publicidade personalizada para alcan\u00e7ar clientes e crescer. Nos \u00faltimos anos, temos aprimorado os sistemas de Intelig\u00eancia Artificial (IA) que alimentam essas ferramentas para torn\u00e1-las mais simples e eficientes de usar e\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":26343,"url":"https:\/\/about.fb.com\/br\/news\/2025\/04\/reduzindo-conteudo-com-spam-no-facebook\/","url_meta":{"origin":6345,"position":3},"title":"Reduzindo conte\u00fado com spam no Facebook","author":"Meta","date":"24\/04\/2025","format":false,"excerpt":"Sua opini\u00e3o \u00e9 importante para n\u00f3s. O Feed do Facebook nem sempre oferece posts novos e envolventes, dos quais voc\u00ea sempre gosta. Estamos trabalhando em uma s\u00e9rie de mudan\u00e7as este ano para melhorar o Feed, ajudar os criadores de conte\u00fado a se destacar e dar \u00e0s pessoas mais controle sobre\u2026","rel":"","context":"In &quot;Facebook&quot;","block_context":{"text":"Facebook","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/facebook\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/FB-Spam.jpg?fit=1280%2C720&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/FB-Spam.jpg?fit=1280%2C720&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/FB-Spam.jpg?fit=1280%2C720&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/FB-Spam.jpg?fit=1280%2C720&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/FB-Spam.jpg?fit=1280%2C720&resize=1050%2C600 3x"},"classes":[]},{"id":26380,"url":"https:\/\/about.fb.com\/br\/news\/2025\/05\/protecao-contra-golpes-de-investimento-e-pagamento-on-line\/","url_meta":{"origin":6345,"position":4},"title":"Prote\u00e7\u00e3o contra golpes de investimento e pagamento on-line","author":"Meta","date":"07\/05\/2025","format":false,"excerpt":"Geralmente, golpistas tentam tirar vantagem de eventos e cen\u00e1rios atuais para aplicar golpes relacionados a investimentos e pagamentos. Eles se aproveitam de temores de recess\u00e3o, mudan\u00e7as no com\u00e9rcio global, volatilidade do mercado de a\u00e7\u00f5es ou novos comportamentos em rela\u00e7\u00e3o a criptomoedas para buscar seus alvos. Esses golpes s\u00e3o projetados para\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/05\/WhatsApp-Image-2025-05-06-at-17.56.41.jpeg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/05\/WhatsApp-Image-2025-05-06-at-17.56.41.jpeg?resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/05\/WhatsApp-Image-2025-05-06-at-17.56.41.jpeg?resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/05\/WhatsApp-Image-2025-05-06-at-17.56.41.jpeg?resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/05\/WhatsApp-Image-2025-05-06-at-17.56.41.jpeg?resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/05\/WhatsApp-Image-2025-05-06-at-17.56.41.jpeg?resize=1400%2C800 4x"},"classes":[]},{"id":27074,"url":"https:\/\/about.fb.com\/br\/news\/2026\/04\/apresentamos-o-muse-spark-o-primeiro-modelo-do-msl-desenvolvido-para-priorizar-as-pessoas\/","url_meta":{"origin":6345,"position":5},"title":"Apresentamos o Muse Spark: O Primeiro Modelo do MSL, Desenvolvido para Priorizar as Pessoas","author":"Meta","date":"08\/04\/2026","format":false,"excerpt":"Atualiza\u00e7\u00e3o em 12 de maio de 2026 Quando lan\u00e7amos o Muse Spark no m\u00eas passado, prometemos lev\u00e1-lo a todos os lugares. Hoje, estamos cumprindo essa promessa \u2014 com respostas de voz mais r\u00e1pidas no aplicativo Meta AI, \u00f3culos com IA mais inteligentes e novas maneiras de fazer compras e obter\u2026","rel":"","context":"In &quot;Meta&quot;","block_context":{"text":"Meta","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/meta\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/Introducing-Muse-Spark_Header.gif?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/Introducing-Muse-Spark_Header.gif?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/Introducing-Muse-Spark_Header.gif?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/Introducing-Muse-Spark_Header.gif?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/Introducing-Muse-Spark_Header.gif?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/Introducing-Muse-Spark_Header.gif?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/6345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/users\/81109636"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/comments?post=6345"}],"version-history":[{"count":3,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/6345\/revisions"}],"predecessor-version":[{"id":7974,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/6345\/revisions\/7974"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/media?parent=6345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/categories?post=6345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/tags?post=6345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}