{"id":5951,"date":"2017-04-18T15:42:11","date_gmt":"2017-04-18T18:42:11","guid":{"rendered":"http:\/\/br.newsroom.fb.com\/?p=5951"},"modified":"2021-06-17T10:10:48","modified_gmt":"2021-06-17T13:10:48","slug":"messenger-aproxima-as-pessoas-em-todo-o-mundo","status":"publish","type":"post","link":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/","title":{"rendered":"Messenger aproxima as pessoas, em todo o mundo"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5952\" src=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2017\/04\/m1-1.jpg?resize=960%2C720\" alt=\"\" width=\"960\" height=\"720\" \/><\/p>\n<p><i>Por David Marcus, vice-presidente de Produtos de Mensagens<\/i><\/p>\n<ul>\n<li>Novas formas de descobrir empresas e marcas;<\/li>\n<li>Novas maneiras de se conectar: compartilhe sua m\u00fasica favorita, experimente seus jogos favoritos ou pe\u00e7a sua comida;<\/li>\n<li>Novas maneiras para os desenvolvedores criarem: Messenger Platform 2.0.<\/li>\n<\/ul>\n<p>No <a href=\"https:\/\/newsroom.fb.com\/news\/2016\/04\/messenger-platform-at-f8\/\">\u00faltimo F8<\/a>, abrimos a plataforma do Messenger para a comunidade global de desenvolvedores. Desde ent\u00e3o, temos escutado e aprendido muito, e estamos felizes em v\u00ea-lo se tornar um canal pr\u00f3spero para marcas, desenvolvedores e consumidores para se conectar uns com os outros e com as coisas que eles amam. Tamb\u00e9m passamos os \u00faltimos 12 meses focados em melhorar e lan\u00e7ar produtos e recursos que nos ajudam a permanecer em contato de maneiras agrad\u00e1veis &#8211; desde a nossa nova c\u00e2mera, passando por bate-papos de v\u00eddeo em grupo e at\u00e9 mesmo jogos sociais.<\/p>\n<p>Os n\u00fameros podem ser impressionantes, mas n\u00e3o captam o impacto que bots para o Messenger t\u00eam nas pessoas ao redor do mundo, ou nas maneiras em que comunidades de desenvolvedores t\u00eam constru\u00eddo exemplos para o bem comum. Desde bots que ajudam na tradu\u00e7\u00e3o para refugiados, at\u00e9 bots que respondem a quest\u00f5es de sa\u00fade, oportunidades para apoiar in\u00fameras causas, ou mesmo experi\u00eancias que ajudam alunos com a li\u00e7\u00e3o de casa. A criatividade, a engenhosidade e a vis\u00e3o da nossa comunidade de desenvolvedores de bots tem sido incr\u00edvel.<\/p>\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/messenger\/videos\/1284399245013086\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<p>Pensamos no Messenger como sendo a uma nova sala de estar para o mundo, onde as pessoas podem se encontrar, compartilhar, conversar, jogar ou comprar coisas, sempre perto de qualquer um, onde quer que estejam. Agora imaginamos a combina\u00e7\u00e3o de duas coisas do passado &#8211; a lista telef\u00f4nica (que representa o modo de como costum\u00e1vamos encontrar pessoas) com os classificados (a maneira como costum\u00e1vamos encontrar neg\u00f3cios).<\/p>\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/messenger\/videos\/1284345891685088\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<p>Aqui est\u00e3o todas as nossas novidades sobre o F8:<\/p>\n<p><b>Fazendo do Messenger mais aberto e divertido:<\/b><\/p>\n<ul>\n<ul>\n<li><b>Descoberta no Mundo Digital &#8211; Guia Descoberta:<\/b> Queremos encontrar uma maneira mais f\u00e1cil para que as pessoas encontrem suas empresas preferidas no Messenger. Constru\u00edmos uma guia Descobrir no aplicativo e agora, diretamente da tela inicial, as pessoas podem encontrar categorias relevantes, bots usados recentemente, bots populares e um campo de pesquisa. Os desenvolvedores podem solicitar que seu bot seja inclu\u00eddo nessa guia com curadoria indo <a href=\"https:\/\/developers.facebook.com\/docs\/messenger-platform\/discover\">aqui<\/a>, e essa \u00e9 uma experi\u00eancia que passa a ficar dispon\u00edvel hoje.\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/messenger\/videos\/1284427875010223\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<\/li>\n<li><b>Descoberta no Mundo F\u00edsico &#8211; C\u00f3digos do Messenger:<\/b> nossos novos QR codes param\u00e9tricos permitem que quando as pessoas estiverem fora de casa, como em eventos esportivos ou musicais, elas possam descobrir mais coisas de um bot dispon\u00edvel, apenas digitalizando o c\u00f3digo no Messenger.\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/messenger\/videos\/1284715534981457\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<\/li>\n<li><b>Extens\u00f5es de bate-papo:<\/b> As experi\u00eancias preparadas para o Messenger s\u00e3o inerentemente sociais. Agora, com as extens\u00f5es de bate-papo, \u00e9 poss\u00edvel que v\u00e1rias pessoas conversem com um mesmo neg\u00f3cio simultaneamente. Se n\u00e3o falta anima\u00e7\u00e3o para compartilhar a nova m\u00fasica da vez, agora \u00e9 poss\u00edvel adicionar um bot diretamente em um grupo e compartilhar a experi\u00eancia com seus amigos. Acreditamos que dessa forma a comunidade ir\u00e1 compartilhar naturalmente novos bots. Hoje \u00e9 poss\u00edvel encontrar diversas marcas nos Estados Unidos, como Spotify, TheScore, OpenTable, Food Network, NBA, Wall Street Journal e Kayak &#8211; com muitos mais a caminho.\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/messenger\/videos\/1284423828343961\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<\/li>\n<li><b>Mais para o M:<\/b> O nosso assistente virtual, M, <a href=\"https:\/\/newsroom.fb.com\/news\/2017\/04\/m-now-offers-suggestions-to-make-your-messenger-experience-more-useful-seamless-and-delightful\/\">agora oferece sugest\u00f5es durante as conversas<\/a>, de maneira que torne a vida mais simples. Entre elas est\u00e1 a inclus\u00e3o de adesivos divertidos, como para dizer obrigado, um r\u00e1pido lembrete para encontrar um amigo, ou uma maneira f\u00e1cil, realizar transfer\u00eancia de dinheiro para pessoas via P2P. Alimentado por intelig\u00eancia artificial, M reconhece quando as pessoas est\u00e3o fazendo tarefas espec\u00edficas e fornece sugest\u00f5es adequadas. Pensamos que o pr\u00f3ximo passo \u00e9 oferecer maneiras ainda melhores de simplificar a vida &#8211; por isso, nos Estados Unidos, M consegue fazer pedidos online por meio do site delivery.com. Se voc\u00ea est\u00e1 conversando com amigos sobre o jantar, M pode sugerir fazer um pedido. Toda a experi\u00eancia pode ser conclu\u00edda no pr\u00f3prio Messenger, desde o pedido at\u00e9 o pagamento. Quanto mais o M for usado, mais sugest\u00f5es assertivas ele vai fazer. O recurso est\u00e1 dispon\u00edvel nos Estados Unidos, onde o <a href=\"http:\/\/delivery.com\">delivery.com<\/a> funciona.\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/messenger\/videos\/1284433791676298\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<\/li>\n<li><b>Lan\u00e7ando uma nova maneira de jogar:<\/b> Mais de 1,5 bilh\u00e3o de jogos foram testados nos \u00faltimos 90 dias, e agora estamos adicionando recursos ainda mais novos, como bots e novas maneiras de jogar, tornando a experi\u00eancia ainda mais social. Agora \u00e9 ainda mais f\u00e1cil desafiar os amigos para uma partida no Messenger, apenas escolhendo a guia Jogos na tela inicial do aplicativo &#8211; recurso que est\u00e1 sendo lan\u00e7ado hoje.\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/messenger\/videos\/1284731368313207\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<\/li>\n<\/ul>\n<\/ul>\n<p><b>Ajudando desenvolvedores e neg\u00f3cios a criar mais:<\/b><\/p>\n<ul>\n<ul>\n<li><b>Respostas inteligentes para P\u00e1ginas:<\/b> Um ponto que requer muito esfor\u00e7o para pequenas empresas \u00e9 o gerenciamento das mensagens recebidas. Neg\u00f3cios menores se beneficiam de ter o recurso ativado na p\u00e1gina, pois permite interagir de forma mais r\u00e1pida com seu p\u00fablico. Para aprimorar ainda mais a funcionalidade, estamos lan\u00e7ando hoje a alternativa de oferecer respostas autom\u00e1ticas \u00e0s perguntas mais frequentes, como o hor\u00e1rio de funcionamento, ou refer\u00eancias para chegar at\u00e9 o local. Desenvolvidas pelo bot de intelig\u00eancia artificial <a href=\"https:\/\/wit.ai\/\">Wit.ai<\/a>, as respostas inteligentes oferecem uma API que permite que neg\u00f3cios criem suas pr\u00f3prias respostas a partir da tecnologia.<\/li>\n<li><b>C\u00f3digos Param\u00e9tricos do Messenger: <\/b>As empresas agora s\u00e3o capazes de gerar v\u00e1rios QR codes param\u00e9tricos para um bot, dando mais escolha para seus clientes. Por exemplo, rastreando onde um QR code foi digitalizado, ou ent\u00e3o aplicar um QR code para cada mesa de um restaurante. A funcionalidade permite tamb\u00e9m digitalizar um c\u00f3digo utilizando a pr\u00f3pria c\u00e2mera em vez de um scanner para QR code.<\/li>\n<li><b>Protocolo de Transfer\u00eancia: <\/b>Fornecemos uma forma para que empresas trabalharem com diversos desenvolvedores para experi\u00eancias no Messenger. Por exemplo, uma empresa pode querer ter um bot de compras e outro para disponibilizar servi\u00e7os ao cliente. Diferentes comerciantes e desenvolvedores podem gerenciar as conversas, mediante solicita\u00e7\u00e3o do consumidor.<\/li>\n<\/ul>\n<\/ul>\n<p>Essas s\u00e3o as nossas novidades! Esperamos que a <a href=\"https:\/\/developers.facebook.com\/blog\/post\/2017\/04\/18\/messenger-platform-2.0\/\">Messenger Platform 2.0<\/a> possibilite \u00e0 nossa comunidade de desenvolvedores aprimorar suas experi\u00eancias, alavancar o poder em intelig\u00eancia artificial e construir mais bots para ajudar empresas a se conectar de maneira mais significativa. Sabemos que desenvolvedores continuar\u00e3o a criar experi\u00eancias incr\u00edveis e poderosas para pessoas de todo o mundo, e estamos ansiosos para ver isso se concretizar. A equipe do Messenger se dedica a apoiar todo esse potencial.<\/p>\n","protected":false},"excerpt":{"rendered":"Por David Marcus, vice-presidente de Produtos de Mensagens Novas formas de descobrir empresas e marcas; Novas maneiras de se conectar: compartilhe sua m\u00fasica favorita, experimente seus jogos favoritos ou pe\u00e7a sua comida; Novas maneiras para os desenvolvedores criarem: Messenger Platform 2.0. No \u00faltimo F8, abrimos a plataforma do Messenger para a comunidade global de desenvolvedores. Desde ent\u00e3o, temos escutado e aprendido muito, e estamos felizes em v\u00ea-lo se tornar um canal pr\u00f3spero para marcas, desenvolvedores e consumidores para se conectar uns com os outros e com as coisas que eles amam. Tamb\u00e9m passamos os \u00faltimos 12 meses focados em melhorar e lan\u00e7ar produtos e recursos que nos ajudam a permanecer em contato de maneiras agrad\u00e1veis &#8211; desde a nossa nova c\u00e2mera, passando por bate-papos de v\u00eddeo em grupo e at\u00e9 mesmo jogos sociais. Os n\u00fameros podem ser impressionantes, mas n\u00e3o captam o impacto que bots para o Messenger t\u00eam nas pessoas ao redor do mundo, ou nas maneiras em que comunidades de desenvolvedores t\u00eam constru\u00eddo exemplos para o bem comum. Desde bots que ajudam na tradu\u00e7\u00e3o para refugiados, at\u00e9 bots que respondem a quest\u00f5es de sa\u00fade, oportunidades para apoiar in\u00fameras causas, ou mesmo experi\u00eancias que ajudam alunos com a li\u00e7\u00e3o de casa. A criatividade, a engenhosidade e a vis\u00e3o da nossa comunidade de desenvolvedores de bots tem sido incr\u00edvel. Pensamos no Messenger como sendo a uma nova sala de estar para o mundo, onde as pessoas podem se encontrar, compartilhar, conversar, jogar ou comprar coisas, sempre perto de qualquer um, onde quer que estejam. Agora imaginamos a combina\u00e7\u00e3o de duas coisas do passado &#8211; a lista telef\u00f4nica (que representa o modo de como costum\u00e1vamos encontrar pessoas) com os classificados (a maneira como costum\u00e1vamos encontrar neg\u00f3cios). Aqui est\u00e3o todas as nossas novidades sobre o F8: Fazendo do Messenger mais aberto e divertido: Descoberta no Mundo Digital &#8211; Guia Descoberta: Queremos encontrar uma maneira mais f\u00e1cil para que as pessoas encontrem suas empresas preferidas no Messenger. Constru\u00edmos uma guia Descobrir no aplicativo e agora, diretamente da tela inicial, as pessoas podem encontrar categorias relevantes, bots usados recentemente, bots populares e um campo de pesquisa. Os desenvolvedores podem solicitar que seu bot seja inclu\u00eddo nessa guia com curadoria indo aqui, e essa \u00e9 uma experi\u00eancia que passa a ficar dispon\u00edvel hoje. Descoberta no Mundo F\u00edsico &#8211; C\u00f3digos do Messenger: nossos novos QR codes param\u00e9tricos permitem que quando as pessoas estiverem fora de casa, como em eventos esportivos ou musicais, elas possam descobrir mais coisas de um bot dispon\u00edvel, apenas digitalizando o c\u00f3digo no Messenger. Extens\u00f5es de bate-papo: As experi\u00eancias preparadas para o Messenger s\u00e3o inerentemente sociais. Agora, com as extens\u00f5es de bate-papo, \u00e9 poss\u00edvel que v\u00e1rias pessoas conversem com um mesmo neg\u00f3cio simultaneamente. Se n\u00e3o falta anima\u00e7\u00e3o para compartilhar a nova m\u00fasica da vez, agora \u00e9 poss\u00edvel adicionar um bot diretamente em um grupo e compartilhar a experi\u00eancia com seus amigos. Acreditamos que dessa forma a comunidade ir\u00e1 compartilhar naturalmente novos bots. Hoje \u00e9 poss\u00edvel encontrar diversas marcas nos Estados Unidos, como Spotify, TheScore, OpenTable, Food Network, NBA, Wall Street Journal e Kayak &#8211; com muitos mais a caminho. Mais para o M: O nosso assistente virtual, M, agora oferece sugest\u00f5es durante as conversas, de maneira que torne a vida mais simples. Entre elas est\u00e1 a inclus\u00e3o de adesivos divertidos, como para dizer obrigado, um r\u00e1pido lembrete para encontrar um amigo, ou uma maneira f\u00e1cil, realizar transfer\u00eancia de dinheiro para pessoas via P2P. Alimentado por intelig\u00eancia artificial, M reconhece quando as pessoas est\u00e3o fazendo tarefas espec\u00edficas e fornece sugest\u00f5es adequadas. Pensamos que o pr\u00f3ximo passo \u00e9 oferecer maneiras ainda melhores de simplificar a vida &#8211; por isso, nos Estados Unidos, M consegue fazer pedidos online por meio do site delivery.com. Se voc\u00ea est\u00e1 conversando com amigos sobre o jantar, M pode sugerir fazer um pedido. Toda a experi\u00eancia pode ser conclu\u00edda no pr\u00f3prio Messenger, desde o pedido at\u00e9 o pagamento. Quanto mais o M for usado, mais sugest\u00f5es assertivas ele vai fazer. O recurso est\u00e1 dispon\u00edvel nos Estados Unidos, onde o delivery.com funciona. Lan\u00e7ando uma nova maneira de jogar: Mais de 1,5 bilh\u00e3o de jogos foram testados nos \u00faltimos 90 dias, e agora estamos adicionando recursos ainda mais novos, como bots e novas maneiras de jogar, tornando a experi\u00eancia ainda mais social. Agora \u00e9 ainda mais f\u00e1cil desafiar os amigos para uma partida no Messenger, apenas escolhendo a guia Jogos na tela inicial do aplicativo &#8211; recurso que est\u00e1 sendo lan\u00e7ado hoje. Ajudando desenvolvedores e neg\u00f3cios a criar mais: Respostas inteligentes para P\u00e1ginas: Um ponto que requer muito esfor\u00e7o para pequenas empresas \u00e9 o gerenciamento das mensagens recebidas. Neg\u00f3cios menores se beneficiam de ter o recurso ativado na p\u00e1gina, pois permite interagir de forma mais r\u00e1pida com seu p\u00fablico. Para aprimorar ainda mais a funcionalidade, estamos lan\u00e7ando hoje a alternativa de oferecer respostas autom\u00e1ticas \u00e0s perguntas mais frequentes, como o hor\u00e1rio de funcionamento, ou refer\u00eancias para chegar at\u00e9 o local. Desenvolvidas pelo bot de intelig\u00eancia artificial Wit.ai, as respostas inteligentes oferecem uma API que permite que neg\u00f3cios criem suas pr\u00f3prias respostas a partir da tecnologia. C\u00f3digos Param\u00e9tricos do Messenger: As empresas agora s\u00e3o capazes de gerar v\u00e1rios QR codes param\u00e9tricos para um bot, dando mais escolha para seus clientes. Por exemplo, rastreando onde um QR code foi digitalizado, ou ent\u00e3o aplicar um QR code para cada mesa de um restaurante. A funcionalidade permite tamb\u00e9m digitalizar um c\u00f3digo utilizando a pr\u00f3pria c\u00e2mera em vez de um scanner para QR code. Protocolo de Transfer\u00eancia: Fornecemos uma forma para que empresas trabalharem com diversos desenvolvedores para experi\u00eancias no Messenger. Por exemplo, uma empresa pode querer ter um bot de compras e outro para disponibilizar servi\u00e7os ao cliente. Diferentes comerciantes e desenvolvedores podem gerenciar as conversas, mediante solicita\u00e7\u00e3o do consumidor. Essas s\u00e3o as nossas novidades! Esperamos que a Messenger Platform 2.0 possibilite \u00e0 nossa comunidade de desenvolvedores aprimorar suas experi\u00eancias, alavancar o poder em intelig\u00eancia artificial e construir mais bots para ajudar empresas a se conectar de maneira mais significativa. Sabemos que desenvolvedores continuar\u00e3o a criar experi\u00eancias incr\u00edveis e poderosas para pessoas de todo o mundo, e estamos ansiosos para ver isso se concretizar. A equipe do Messenger se dedica a apoiar todo esse potencial.","protected":false},"author":81109636,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[396541862,396541933,396541887,396541938],"class_list":["post-5951","post","type-post","status-publish","format-standard","hentry","category-recent-news","tag-developers","tag-f8","tag-messenger","tag-messenger-platform-2-0"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Messenger aproxima as pessoas, em todo o mundo | Sobre a Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Messenger aproxima as pessoas, em todo o mundo | Sobre a Meta\" \/>\n<meta property=\"og:description\" content=\"Por David Marcus, vice-presidente de Produtos de Mensagens Novas formas de descobrir empresas e marcas; Novas maneiras de se conectar: compartilhe sua m\u00fasica favorita, experimente seus jogos favoritos ou pe\u00e7a sua comida; Novas maneiras para os desenvolvedores criarem: Messenger Platform 2.0. No \u00faltimo F8, abrimos a plataforma do Messenger para a comunidade global de desenvolvedores. Desde ent\u00e3o, temos escutado e aprendido muito, e estamos felizes em v\u00ea-lo se tornar um canal pr\u00f3spero para marcas, desenvolvedores e consumidores para se conectar uns com os outros e com as coisas que eles amam. Tamb\u00e9m passamos os \u00faltimos 12 meses focados em melhorar e lan\u00e7ar produtos e recursos que nos ajudam a permanecer em contato de maneiras agrad\u00e1veis &#8211; desde a nossa nova c\u00e2mera, passando por bate-papos de v\u00eddeo em grupo e at\u00e9 mesmo jogos sociais. Os n\u00fameros podem ser impressionantes, mas n\u00e3o captam o impacto que bots para o Messenger t\u00eam nas pessoas ao redor do mundo, ou nas maneiras em que comunidades de desenvolvedores t\u00eam constru\u00eddo exemplos para o bem comum. Desde bots que ajudam na tradu\u00e7\u00e3o para refugiados, at\u00e9 bots que respondem a quest\u00f5es de sa\u00fade, oportunidades para apoiar in\u00fameras causas, ou mesmo experi\u00eancias que ajudam alunos com a li\u00e7\u00e3o de casa. A criatividade, a engenhosidade e a vis\u00e3o da nossa comunidade de desenvolvedores de bots tem sido incr\u00edvel. Pensamos no Messenger como sendo a uma nova sala de estar para o mundo, onde as pessoas podem se encontrar, compartilhar, conversar, jogar ou comprar coisas, sempre perto de qualquer um, onde quer que estejam. Agora imaginamos a combina\u00e7\u00e3o de duas coisas do passado &#8211; a lista telef\u00f4nica (que representa o modo de como costum\u00e1vamos encontrar pessoas) com os classificados (a maneira como costum\u00e1vamos encontrar neg\u00f3cios). Aqui est\u00e3o todas as nossas novidades sobre o F8: Fazendo do Messenger mais aberto e divertido: Descoberta no Mundo Digital &#8211; Guia Descoberta: Queremos encontrar uma maneira mais f\u00e1cil para que as pessoas encontrem suas empresas preferidas no Messenger. Constru\u00edmos uma guia Descobrir no aplicativo e agora, diretamente da tela inicial, as pessoas podem encontrar categorias relevantes, bots usados recentemente, bots populares e um campo de pesquisa. Os desenvolvedores podem solicitar que seu bot seja inclu\u00eddo nessa guia com curadoria indo aqui, e essa \u00e9 uma experi\u00eancia que passa a ficar dispon\u00edvel hoje. Descoberta no Mundo F\u00edsico &#8211; C\u00f3digos do Messenger: nossos novos QR codes param\u00e9tricos permitem que quando as pessoas estiverem fora de casa, como em eventos esportivos ou musicais, elas possam descobrir mais coisas de um bot dispon\u00edvel, apenas digitalizando o c\u00f3digo no Messenger. Extens\u00f5es de bate-papo: As experi\u00eancias preparadas para o Messenger s\u00e3o inerentemente sociais. Agora, com as extens\u00f5es de bate-papo, \u00e9 poss\u00edvel que v\u00e1rias pessoas conversem com um mesmo neg\u00f3cio simultaneamente. Se n\u00e3o falta anima\u00e7\u00e3o para compartilhar a nova m\u00fasica da vez, agora \u00e9 poss\u00edvel adicionar um bot diretamente em um grupo e compartilhar a experi\u00eancia com seus amigos. Acreditamos que dessa forma a comunidade ir\u00e1 compartilhar naturalmente novos bots. Hoje \u00e9 poss\u00edvel encontrar diversas marcas nos Estados Unidos, como Spotify, TheScore, OpenTable, Food Network, NBA, Wall Street Journal e Kayak &#8211; com muitos mais a caminho. Mais para o M: O nosso assistente virtual, M, agora oferece sugest\u00f5es durante as conversas, de maneira que torne a vida mais simples. Entre elas est\u00e1 a inclus\u00e3o de adesivos divertidos, como para dizer obrigado, um r\u00e1pido lembrete para encontrar um amigo, ou uma maneira f\u00e1cil, realizar transfer\u00eancia de dinheiro para pessoas via P2P. Alimentado por intelig\u00eancia artificial, M reconhece quando as pessoas est\u00e3o fazendo tarefas espec\u00edficas e fornece sugest\u00f5es adequadas. Pensamos que o pr\u00f3ximo passo \u00e9 oferecer maneiras ainda melhores de simplificar a vida &#8211; por isso, nos Estados Unidos, M consegue fazer pedidos online por meio do site delivery.com. Se voc\u00ea est\u00e1 conversando com amigos sobre o jantar, M pode sugerir fazer um pedido. Toda a experi\u00eancia pode ser conclu\u00edda no pr\u00f3prio Messenger, desde o pedido at\u00e9 o pagamento. Quanto mais o M for usado, mais sugest\u00f5es assertivas ele vai fazer. O recurso est\u00e1 dispon\u00edvel nos Estados Unidos, onde o delivery.com funciona. Lan\u00e7ando uma nova maneira de jogar: Mais de 1,5 bilh\u00e3o de jogos foram testados nos \u00faltimos 90 dias, e agora estamos adicionando recursos ainda mais novos, como bots e novas maneiras de jogar, tornando a experi\u00eancia ainda mais social. Agora \u00e9 ainda mais f\u00e1cil desafiar os amigos para uma partida no Messenger, apenas escolhendo a guia Jogos na tela inicial do aplicativo &#8211; recurso que est\u00e1 sendo lan\u00e7ado hoje. Ajudando desenvolvedores e neg\u00f3cios a criar mais: Respostas inteligentes para P\u00e1ginas: Um ponto que requer muito esfor\u00e7o para pequenas empresas \u00e9 o gerenciamento das mensagens recebidas. Neg\u00f3cios menores se beneficiam de ter o recurso ativado na p\u00e1gina, pois permite interagir de forma mais r\u00e1pida com seu p\u00fablico. Para aprimorar ainda mais a funcionalidade, estamos lan\u00e7ando hoje a alternativa de oferecer respostas autom\u00e1ticas \u00e0s perguntas mais frequentes, como o hor\u00e1rio de funcionamento, ou refer\u00eancias para chegar at\u00e9 o local. Desenvolvidas pelo bot de intelig\u00eancia artificial Wit.ai, as respostas inteligentes oferecem uma API que permite que neg\u00f3cios criem suas pr\u00f3prias respostas a partir da tecnologia. C\u00f3digos Param\u00e9tricos do Messenger: As empresas agora s\u00e3o capazes de gerar v\u00e1rios QR codes param\u00e9tricos para um bot, dando mais escolha para seus clientes. Por exemplo, rastreando onde um QR code foi digitalizado, ou ent\u00e3o aplicar um QR code para cada mesa de um restaurante. A funcionalidade permite tamb\u00e9m digitalizar um c\u00f3digo utilizando a pr\u00f3pria c\u00e2mera em vez de um scanner para QR code. Protocolo de Transfer\u00eancia: Fornecemos uma forma para que empresas trabalharem com diversos desenvolvedores para experi\u00eancias no Messenger. Por exemplo, uma empresa pode querer ter um bot de compras e outro para disponibilizar servi\u00e7os ao cliente. Diferentes comerciantes e desenvolvedores podem gerenciar as conversas, mediante solicita\u00e7\u00e3o do consumidor. Essas s\u00e3o as nossas novidades! Esperamos que a Messenger Platform 2.0 possibilite \u00e0 nossa comunidade de desenvolvedores aprimorar suas experi\u00eancias, alavancar o poder em intelig\u00eancia artificial e construir mais bots para ajudar empresas a se conectar de maneira mais significativa. Sabemos que desenvolvedores continuar\u00e3o a criar experi\u00eancias incr\u00edveis e poderosas para pessoas de todo o mundo, e estamos ansiosos para ver isso se concretizar. A equipe do Messenger se dedica a apoiar todo esse potencial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre a Meta\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-18T18:42:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-17T13:10:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2017\/04\/m1-1.jpg\" \/>\n<meta name=\"author\" content=\"facebookbr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/\"},\"author\":\"Facebook company\",\"headline\":\"Messenger aproxima as pessoas, em todo o mundo\",\"datePublished\":\"2017-04-18T18:42:11+00:00\",\"dateModified\":\"2021-06-17T13:10:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/\"},\"wordCount\":1189,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2017\/04\/m1-1.jpg\",\"keywords\":[\"developers\",\"F8\",\"Messenger\",\"Messenger Platform 2.0\"],\"articleSection\":[\"Recent News\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/\",\"url\":\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/\",\"name\":\"Messenger aproxima as pessoas, em todo o mundo | Sobre a Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2017\/04\/m1-1.jpg\",\"datePublished\":\"2017-04-18T18:42:11+00:00\",\"dateModified\":\"2021-06-17T13:10:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/\"]}],\"author\":\"Sobre a Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#primaryimage\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2017\/04\/m1-1.jpg\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2017\/04\/m1-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Messenger aproxima as pessoas, em todo o mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/br\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"Sobre a Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/br\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Messenger aproxima as pessoas, em todo o mundo | Sobre a Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/","og_locale":"pt_BR","og_type":"article","og_title":"Messenger aproxima as pessoas, em todo o mundo | Sobre a Meta","og_description":"Por David Marcus, vice-presidente de Produtos de Mensagens Novas formas de descobrir empresas e marcas; Novas maneiras de se conectar: compartilhe sua m\u00fasica favorita, experimente seus jogos favoritos ou pe\u00e7a sua comida; Novas maneiras para os desenvolvedores criarem: Messenger Platform 2.0. No \u00faltimo F8, abrimos a plataforma do Messenger para a comunidade global de desenvolvedores. Desde ent\u00e3o, temos escutado e aprendido muito, e estamos felizes em v\u00ea-lo se tornar um canal pr\u00f3spero para marcas, desenvolvedores e consumidores para se conectar uns com os outros e com as coisas que eles amam. Tamb\u00e9m passamos os \u00faltimos 12 meses focados em melhorar e lan\u00e7ar produtos e recursos que nos ajudam a permanecer em contato de maneiras agrad\u00e1veis &#8211; desde a nossa nova c\u00e2mera, passando por bate-papos de v\u00eddeo em grupo e at\u00e9 mesmo jogos sociais. Os n\u00fameros podem ser impressionantes, mas n\u00e3o captam o impacto que bots para o Messenger t\u00eam nas pessoas ao redor do mundo, ou nas maneiras em que comunidades de desenvolvedores t\u00eam constru\u00eddo exemplos para o bem comum. Desde bots que ajudam na tradu\u00e7\u00e3o para refugiados, at\u00e9 bots que respondem a quest\u00f5es de sa\u00fade, oportunidades para apoiar in\u00fameras causas, ou mesmo experi\u00eancias que ajudam alunos com a li\u00e7\u00e3o de casa. A criatividade, a engenhosidade e a vis\u00e3o da nossa comunidade de desenvolvedores de bots tem sido incr\u00edvel. Pensamos no Messenger como sendo a uma nova sala de estar para o mundo, onde as pessoas podem se encontrar, compartilhar, conversar, jogar ou comprar coisas, sempre perto de qualquer um, onde quer que estejam. Agora imaginamos a combina\u00e7\u00e3o de duas coisas do passado &#8211; a lista telef\u00f4nica (que representa o modo de como costum\u00e1vamos encontrar pessoas) com os classificados (a maneira como costum\u00e1vamos encontrar neg\u00f3cios). Aqui est\u00e3o todas as nossas novidades sobre o F8: Fazendo do Messenger mais aberto e divertido: Descoberta no Mundo Digital &#8211; Guia Descoberta: Queremos encontrar uma maneira mais f\u00e1cil para que as pessoas encontrem suas empresas preferidas no Messenger. Constru\u00edmos uma guia Descobrir no aplicativo e agora, diretamente da tela inicial, as pessoas podem encontrar categorias relevantes, bots usados recentemente, bots populares e um campo de pesquisa. Os desenvolvedores podem solicitar que seu bot seja inclu\u00eddo nessa guia com curadoria indo aqui, e essa \u00e9 uma experi\u00eancia que passa a ficar dispon\u00edvel hoje. Descoberta no Mundo F\u00edsico &#8211; C\u00f3digos do Messenger: nossos novos QR codes param\u00e9tricos permitem que quando as pessoas estiverem fora de casa, como em eventos esportivos ou musicais, elas possam descobrir mais coisas de um bot dispon\u00edvel, apenas digitalizando o c\u00f3digo no Messenger. Extens\u00f5es de bate-papo: As experi\u00eancias preparadas para o Messenger s\u00e3o inerentemente sociais. Agora, com as extens\u00f5es de bate-papo, \u00e9 poss\u00edvel que v\u00e1rias pessoas conversem com um mesmo neg\u00f3cio simultaneamente. Se n\u00e3o falta anima\u00e7\u00e3o para compartilhar a nova m\u00fasica da vez, agora \u00e9 poss\u00edvel adicionar um bot diretamente em um grupo e compartilhar a experi\u00eancia com seus amigos. Acreditamos que dessa forma a comunidade ir\u00e1 compartilhar naturalmente novos bots. Hoje \u00e9 poss\u00edvel encontrar diversas marcas nos Estados Unidos, como Spotify, TheScore, OpenTable, Food Network, NBA, Wall Street Journal e Kayak &#8211; com muitos mais a caminho. Mais para o M: O nosso assistente virtual, M, agora oferece sugest\u00f5es durante as conversas, de maneira que torne a vida mais simples. Entre elas est\u00e1 a inclus\u00e3o de adesivos divertidos, como para dizer obrigado, um r\u00e1pido lembrete para encontrar um amigo, ou uma maneira f\u00e1cil, realizar transfer\u00eancia de dinheiro para pessoas via P2P. Alimentado por intelig\u00eancia artificial, M reconhece quando as pessoas est\u00e3o fazendo tarefas espec\u00edficas e fornece sugest\u00f5es adequadas. Pensamos que o pr\u00f3ximo passo \u00e9 oferecer maneiras ainda melhores de simplificar a vida &#8211; por isso, nos Estados Unidos, M consegue fazer pedidos online por meio do site delivery.com. Se voc\u00ea est\u00e1 conversando com amigos sobre o jantar, M pode sugerir fazer um pedido. Toda a experi\u00eancia pode ser conclu\u00edda no pr\u00f3prio Messenger, desde o pedido at\u00e9 o pagamento. Quanto mais o M for usado, mais sugest\u00f5es assertivas ele vai fazer. O recurso est\u00e1 dispon\u00edvel nos Estados Unidos, onde o delivery.com funciona. Lan\u00e7ando uma nova maneira de jogar: Mais de 1,5 bilh\u00e3o de jogos foram testados nos \u00faltimos 90 dias, e agora estamos adicionando recursos ainda mais novos, como bots e novas maneiras de jogar, tornando a experi\u00eancia ainda mais social. Agora \u00e9 ainda mais f\u00e1cil desafiar os amigos para uma partida no Messenger, apenas escolhendo a guia Jogos na tela inicial do aplicativo &#8211; recurso que est\u00e1 sendo lan\u00e7ado hoje. Ajudando desenvolvedores e neg\u00f3cios a criar mais: Respostas inteligentes para P\u00e1ginas: Um ponto que requer muito esfor\u00e7o para pequenas empresas \u00e9 o gerenciamento das mensagens recebidas. Neg\u00f3cios menores se beneficiam de ter o recurso ativado na p\u00e1gina, pois permite interagir de forma mais r\u00e1pida com seu p\u00fablico. Para aprimorar ainda mais a funcionalidade, estamos lan\u00e7ando hoje a alternativa de oferecer respostas autom\u00e1ticas \u00e0s perguntas mais frequentes, como o hor\u00e1rio de funcionamento, ou refer\u00eancias para chegar at\u00e9 o local. Desenvolvidas pelo bot de intelig\u00eancia artificial Wit.ai, as respostas inteligentes oferecem uma API que permite que neg\u00f3cios criem suas pr\u00f3prias respostas a partir da tecnologia. C\u00f3digos Param\u00e9tricos do Messenger: As empresas agora s\u00e3o capazes de gerar v\u00e1rios QR codes param\u00e9tricos para um bot, dando mais escolha para seus clientes. Por exemplo, rastreando onde um QR code foi digitalizado, ou ent\u00e3o aplicar um QR code para cada mesa de um restaurante. A funcionalidade permite tamb\u00e9m digitalizar um c\u00f3digo utilizando a pr\u00f3pria c\u00e2mera em vez de um scanner para QR code. Protocolo de Transfer\u00eancia: Fornecemos uma forma para que empresas trabalharem com diversos desenvolvedores para experi\u00eancias no Messenger. Por exemplo, uma empresa pode querer ter um bot de compras e outro para disponibilizar servi\u00e7os ao cliente. Diferentes comerciantes e desenvolvedores podem gerenciar as conversas, mediante solicita\u00e7\u00e3o do consumidor. Essas s\u00e3o as nossas novidades! Esperamos que a Messenger Platform 2.0 possibilite \u00e0 nossa comunidade de desenvolvedores aprimorar suas experi\u00eancias, alavancar o poder em intelig\u00eancia artificial e construir mais bots para ajudar empresas a se conectar de maneira mais significativa. Sabemos que desenvolvedores continuar\u00e3o a criar experi\u00eancias incr\u00edveis e poderosas para pessoas de todo o mundo, e estamos ansiosos para ver isso se concretizar. A equipe do Messenger se dedica a apoiar todo esse potencial.","og_url":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/","og_site_name":"Sobre a Meta","article_published_time":"2017-04-18T18:42:11+00:00","article_modified_time":"2021-06-17T13:10:48+00:00","og_image":[{"url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2017\/04\/m1-1.jpg","type":"","width":"","height":""}],"author":"facebookbr","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/"},"author":"Facebook company","headline":"Messenger aproxima as pessoas, em todo o mundo","datePublished":"2017-04-18T18:42:11+00:00","dateModified":"2021-06-17T13:10:48+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/"},"wordCount":1189,"publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2017\/04\/m1-1.jpg","keywords":["developers","F8","Messenger","Messenger Platform 2.0"],"articleSection":["Recent News"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/","url":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/","name":"Messenger aproxima as pessoas, em todo o mundo | Sobre a Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#primaryimage"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2017\/04\/m1-1.jpg","datePublished":"2017-04-18T18:42:11+00:00","dateModified":"2021-06-17T13:10:48+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/"]}],"author":"Sobre a Meta"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#primaryimage","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2017\/04\/m1-1.jpg","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2017\/04\/m1-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/br\/news\/2017\/04\/messenger-aproxima-as-pessoas-em-todo-o-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/br\/"},{"@type":"ListItem","position":2,"name":"Messenger aproxima as pessoas, em todo o mundo"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/br\/#website","url":"https:\/\/about.fb.com\/news\/","name":"Sobre a Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/br\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[{"id":27228,"url":"https:\/\/about.fb.com\/br\/news\/2026\/06\/conversations-2026-apresentamos-o-meta-business-agent\/","url_meta":{"origin":5951,"position":0},"title":"Conversations 2026: apresentamos o Meta Business Agent","author":"Meta","date":"03\/06\/2026","format":false,"excerpt":"Os clientes esperam respostas instant\u00e2neas, mas nenhuma equipe pode estar em todos os lugares ao mesmo tempo. Hoje, na Conversations em Londres, estamos apresentando o Meta Business Agent, uma IA que permite que as empresas estejam presentes para cada cliente, em cada momento, como se tivessem uma equipe infinita por\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Brazilian-Portuguese_WhatsApp_conversation-2026-1.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Brazilian-Portuguese_WhatsApp_conversation-2026-1.png?resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Brazilian-Portuguese_WhatsApp_conversation-2026-1.png?resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Brazilian-Portuguese_WhatsApp_conversation-2026-1.png?resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Brazilian-Portuguese_WhatsApp_conversation-2026-1.png?resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Brazilian-Portuguese_WhatsApp_conversation-2026-1.png?resize=1400%2C800 4x"},"classes":[]},{"id":26696,"url":"https:\/\/about.fb.com\/br\/news\/2025\/10\/desempenho-potencializado-por-ia-para-o-agora-e-o-futuro\/","url_meta":{"origin":5951,"position":1},"title":"Desempenho potencializado por IA para o agora e o futuro","author":"Meta","date":"02\/10\/2025","format":false,"excerpt":"Para os profissionais de marketing, cada ponto de desempenho incremental pode significar a diferen\u00e7a entre empatar e bater recordes. Por isso, a Meta continua investindo em solu\u00e7\u00f5es l\u00edderes com IA, incluindo o Advantage+ e a infraestrutura que o sustenta, para ajudar empresas, anunciantes e ag\u00eancias a expandirem rapidamente. Estamos escrevendo\u2026","rel":"","context":"In &quot;Meta&quot;","block_context":{"text":"Meta","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/meta\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=525%2C300 1.5x"},"classes":[]},{"id":26574,"url":"https:\/\/about.fb.com\/br\/news\/2025\/08\/apresentando-o-app-meta-ai-uma-nova-forma-de-acessar-seu-assistente-de-inteligencia-artificial\/","url_meta":{"origin":5951,"position":2},"title":"Apresentando o app Meta AI: uma nova forma de acessar seu assistente de intelig\u00eancia artificial","author":"Meta","date":"11\/08\/2025","format":false,"excerpt":"Estamos lan\u00e7ando no Brasil o novo app Meta AI, desenvolvido com o Llama, um primeiro passo na constru\u00e7\u00e3o de uma IA mais pessoal. Pessoas ao redor do mundo j\u00e1 utilizam a Meta AI diariamente no WhatsApp, Instagram, Facebook e Messenger. Agora, elas tamb\u00e9m poder\u00e3o optar por interagir com uma IA\u2026","rel":"","context":"In &quot;Meta AI&quot;","block_context":{"text":"Meta AI","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/meta-ai\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/C50-Brazil-Launch_Header.gif?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/C50-Brazil-Launch_Header.gif?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/C50-Brazil-Launch_Header.gif?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/C50-Brazil-Launch_Header.gif?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/C50-Brazil-Launch_Header.gif?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/C50-Brazil-Launch_Header.gif?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]},{"id":27104,"url":"https:\/\/about.fb.com\/br\/news\/2026\/04\/conta-meta-a-maneira-mais-simples-de-acessar-seus-apps-e-dispositivos\/","url_meta":{"origin":5951,"position":3},"title":"Conta Meta: a maneira mais simples de acessar seus apps e dispositivos","author":"Meta","date":"23\/04\/2026","format":false,"excerpt":"Mais pessoas do que nunca est\u00e3o usando as tecnologias da Meta, e nos \u00faltimos anos criamos novos apps e dispositivos que se tornaram parte da forma como as pessoas se conectam \u2014 do Threads \u00e0 Meta AI e aos \u00f3culos com IA. Com tantas maneiras de criar, aprender e se\u2026","rel":"","context":"In &quot;Meta&quot;","block_context":{"text":"Meta","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/meta\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/02_A-Central-Place-for-Settings_Carousel-01.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/02_A-Central-Place-for-Settings_Carousel-01.jpg?resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/02_A-Central-Place-for-Settings_Carousel-01.jpg?resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/02_A-Central-Place-for-Settings_Carousel-01.jpg?resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/02_A-Central-Place-for-Settings_Carousel-01.jpg?resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/02_A-Central-Place-for-Settings_Carousel-01.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":26476,"url":"https:\/\/about.fb.com\/br\/news\/2025\/06\/cannes-lions-2025-a-nova-era-da-ia-generativa-para-anunciantes-e-agencias-com-foco-em-personalizacao-em-escala\/","url_meta":{"origin":5951,"position":4},"title":"Cannes Lions 2025: A nova era da IA generativa para anunciantes e ag\u00eancias com foco em personaliza\u00e7\u00e3o em escala","author":"Meta","date":"17\/06\/2025","format":false,"excerpt":"Nesta semana, durante o Festival Internacional de Criatividade Cannes Lions, estamos apresentando a nova era das solu\u00e7\u00f5es de IA generativa para anunciantes e ag\u00eancias, com o objetivo de melhorar o desempenho das campanhas publicit\u00e1rias e impulsionar o crescimento dos neg\u00f3cios. \u00c0 medida que a IA continua evoluindo, ela abre novos\u2026","rel":"","context":"In &quot;Meta&quot;","block_context":{"text":"Meta","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/meta\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=525%2C300 1.5x"},"classes":[]},{"id":27245,"url":"https:\/\/about.fb.com\/br\/news\/2026\/06\/de-cabeca-nos-jogos-tudo-que-os-fas-de-futebol-ao-redor-do-mundo-encontram-nos-apps-da-meta\/","url_meta":{"origin":5951,"position":5},"title":"De Cabe\u00e7a nos Jogos: Tudo que os F\u00e3s de Futebol ao Redor do Mundo Encontram nos Apps da Meta","author":"Meta","date":"11\/06\/2026","format":false,"excerpt":"Destaques Estamos trazendo novas funcionalidades e experi\u00eancias de futebol para Threads, Instagram, Facebook e WhatsApp, incluindo conte\u00fados de atletas, conte\u00fados de partidas e ativa\u00e7\u00f5es dentro dos produtos. O Threads est\u00e1 lan\u00e7ando uma experi\u00eancia de futebol pensada para a forma como os torcedores realmente acompanham o torneio: conversa em tempo real,\u2026","rel":"","context":"In &quot;Facebook&quot;","block_context":{"text":"Facebook","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/facebook\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/2.-01_Threads_Carousel-01.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/2.-01_Threads_Carousel-01.jpg?resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/2.-01_Threads_Carousel-01.jpg?resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/2.-01_Threads_Carousel-01.jpg?resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/2.-01_Threads_Carousel-01.jpg?resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/2.-01_Threads_Carousel-01.jpg?resize=1400%2C800 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/5951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/users\/81109636"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/comments?post=5951"}],"version-history":[{"count":4,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/5951\/revisions"}],"predecessor-version":[{"id":8108,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/5951\/revisions\/8108"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/media?parent=5951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/categories?post=5951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/tags?post=5951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}