{"id":5606,"date":"2016-10-19T10:10:19","date_gmt":"2016-10-19T13:10:19","guid":{"rendered":"http:\/\/br.newsroom.fb.com\/?p=5606"},"modified":"2021-06-17T10:11:03","modified_gmt":"2021-06-17T13:11:03","slug":"facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo","status":"publish","type":"post","link":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/","title":{"rendered":"Facebook lan\u00e7a recurso que possibilita programar v\u00eddeo ao vivo"},"content":{"rendered":"<h2><\/h2>\n<p><em>Por Peter Roybal, gerente de produto, e Brian Lin, engenheiro de software<\/em><\/p>\n<p>Desde o lan\u00e7amento do Facebook Live, temos visto uma incr\u00edvel ado\u00e7\u00e3o e engajamento do p\u00fablico com o novo formato.<\/p>\n<p>Muitos criadores de conte\u00fado queriam ter a possibilidade de agendar suas transmiss\u00f5es e permitir que as pessoas conseguissem se planejar para assistir aos v\u00eddeos. Por isso, estamos disponibilizando esta semana para as p\u00e1ginas verificadas a possibilidade de agendar suas transmiss\u00f5es, come\u00e7ando com os v\u00eddeos ao vivo publicados atrav\u00e9s da API do <a href=\"https:\/\/media.fb.com\/2016\/04\/12\/introducing-the-facebook-live-api\/\">Facebook Live<\/a>. Ao explorar as <a href=\"https:\/\/www.facebook.com\/facebookmedia\/get-started\/live\">ferramentas de publica\u00e7\u00e3o<\/a>, as p\u00e1ginas verificadas encontram um guia com o passo a passo.<\/p>\n<p>O agendamento dos v\u00eddeos ajuda a gerar expectativa antes da transmiss\u00e3o, de modo que, ao come\u00e7ar o v\u00eddeo, sua audi\u00eancia j\u00e1 esteja fortemente reunida e engajada. Ao agendar um Live, um post ser\u00e1 publicado no Feed de Not\u00edcias para avisar seus f\u00e3s sobre a transmiss\u00e3o. As pessoas podem ainda optar por receber uma notifica\u00e7\u00e3o minutos antes que ela comece. Assim, seus f\u00e3s poder\u00e3o se conectar a um lobby antes do v\u00eddeo come\u00e7ar, onde ser\u00e1 poss\u00edvel tamb\u00e9m interagir com outros espectadores.<\/p>\n<p>Com esse novo recurso, ser\u00e1 poss\u00edvel agendar um v\u00eddeo Live com uma semana de anteced\u00eancia e as pessoas poder\u00e3o ingressar no lobby tr\u00eas minutos antes da transmiss\u00e3o. Uma vez programado, ser\u00e1 poss\u00edvel compartilhar o link ou incorpor\u00e1-lo em outros lugares, como sites e blogs.<\/p>\n<p>O recurso estar\u00e1 dispon\u00edvel a partir desta quinta-feira, 20 de outubro, pela ferramenta de publica\u00e7\u00e3o da API do Facebook Live, e dispon\u00edvel para todas as p\u00e1ginas verificadas durante as semanas seguintes. Tamb\u00e9m ser\u00e3o liberadas atualiza\u00e7\u00f5es para habilitar o recurso em <a href=\"https:\/\/www.facebook.com\/facebookmedia\/get-started\/live-video-solutions\">ferramentas externas<\/a>.<\/p>\n<p><b>Como agendar um v\u00eddeo Live<\/b><\/p>\n<p>Se voc\u00ea \u00e9 o administrador da p\u00e1gina utilizando a API do Facebook Live, ser\u00e1 preciso apenas poucos passos para agendar sua transmiss\u00e3o ao vivo.<\/p>\n<p><i>1. Acesse a Ferramenta de Publica\u00e7\u00e3o <\/i><br \/>\nUma vez nela, selecione \u201cBiblioteca de v\u00eddeos\u201d e depois \u201cAo Vivo\u201d.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-5610\" src=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-1-1.jpg?resize=600%2C385\" alt=\"live-1\" width=\"600\" height=\"385\" \/><\/p>\n<p><i>2. Copie sua credencial de transmiss\u00e3o (Ex: a URL do servidor)<\/i><br \/>\nCaso precise procurar sua credencial perto do hor\u00e1rio da transmiss\u00e3o, ela tamb\u00e9m estar\u00e1 dispon\u00edvel ao editar um v\u00eddeo na \u201cBiblioteca de V\u00eddeos\u201d.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-5611\" src=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-2-1.jpg?resize=597%2C400\" alt=\"live-2\" width=\"597\" height=\"400\" \/><br \/>\n<i>3. Crie seu post de an\u00fancio<\/i><br \/>\nColoque uma descri\u00e7\u00e3o atraente e informativa para que seus seguidores saibam o que esperar de sua transmiss\u00e3o. \u00c9 poss\u00edvel atualizar esse conte\u00fado depois.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-5612\" src=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-3-1.jpg?resize=566%2C400\" alt=\"live-3\" width=\"566\" height=\"400\" \/><br \/>\n<i>4. Finalize o agendamento de sua transmiss\u00e3o <\/i><br \/>\nAcrescente os detalhes finais ao post, como imagens personalizadas.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-5609\" src=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-4-1.jpg?resize=568%2C400\" alt=\"live-4\" width=\"568\" height=\"400\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"Por Peter Roybal, gerente de produto, e Brian Lin, engenheiro de software Desde o lan\u00e7amento do Facebook Live, temos visto uma incr\u00edvel ado\u00e7\u00e3o e engajamento do p\u00fablico com o novo formato. Muitos criadores de conte\u00fado queriam ter a possibilidade de agendar suas transmiss\u00f5es e permitir que as pessoas conseguissem se planejar para assistir aos v\u00eddeos. Por isso, estamos disponibilizando esta semana para as p\u00e1ginas verificadas a possibilidade de agendar suas transmiss\u00f5es, come\u00e7ando com os v\u00eddeos ao vivo publicados atrav\u00e9s da API do Facebook Live. Ao explorar as ferramentas de publica\u00e7\u00e3o, as p\u00e1ginas verificadas encontram um guia com o passo a passo. O agendamento dos v\u00eddeos ajuda a gerar expectativa antes da transmiss\u00e3o, de modo que, ao come\u00e7ar o v\u00eddeo, sua audi\u00eancia j\u00e1 esteja fortemente reunida e engajada. Ao agendar um Live, um post ser\u00e1 publicado no Feed de Not\u00edcias para avisar seus f\u00e3s sobre a transmiss\u00e3o. As pessoas podem ainda optar por receber uma notifica\u00e7\u00e3o minutos antes que ela comece. Assim, seus f\u00e3s poder\u00e3o se conectar a um lobby antes do v\u00eddeo come\u00e7ar, onde ser\u00e1 poss\u00edvel tamb\u00e9m interagir com outros espectadores. Com esse novo recurso, ser\u00e1 poss\u00edvel agendar um v\u00eddeo Live com uma semana de anteced\u00eancia e as pessoas poder\u00e3o ingressar no lobby tr\u00eas minutos antes da transmiss\u00e3o. Uma vez programado, ser\u00e1 poss\u00edvel compartilhar o link ou incorpor\u00e1-lo em outros lugares, como sites e blogs. O recurso estar\u00e1 dispon\u00edvel a partir desta quinta-feira, 20 de outubro, pela ferramenta de publica\u00e7\u00e3o da API do Facebook Live, e dispon\u00edvel para todas as p\u00e1ginas verificadas durante as semanas seguintes. Tamb\u00e9m ser\u00e3o liberadas atualiza\u00e7\u00f5es para habilitar o recurso em ferramentas externas. Como agendar um v\u00eddeo Live Se voc\u00ea \u00e9 o administrador da p\u00e1gina utilizando a API do Facebook Live, ser\u00e1 preciso apenas poucos passos para agendar sua transmiss\u00e3o ao vivo. 1. Acesse a Ferramenta de Publica\u00e7\u00e3o Uma vez nela, selecione \u201cBiblioteca de v\u00eddeos\u201d e depois \u201cAo Vivo\u201d. 2. Copie sua credencial de transmiss\u00e3o (Ex: a URL do servidor) Caso precise procurar sua credencial perto do hor\u00e1rio da transmiss\u00e3o, ela tamb\u00e9m estar\u00e1 dispon\u00edvel ao editar um v\u00eddeo na \u201cBiblioteca de V\u00eddeos\u201d. 3. Crie seu post de an\u00fancio Coloque uma descri\u00e7\u00e3o atraente e informativa para que seus seguidores saibam o que esperar de sua transmiss\u00e3o. \u00c9 poss\u00edvel atualizar esse conte\u00fado depois. 4. Finalize o agendamento de sua transmiss\u00e3o Acrescente os detalhes finais ao post, como imagens personalizadas.","protected":false},"author":81109636,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[396532422,396541872,12071,396541874,396541873],"class_list":["post-5606","post","type-post","status-publish","format-standard","hentry","category-recent-news","tag-facebook","tag-facebook-live","tag-live","tag-live-programado","tag-live-videos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Facebook lan\u00e7a recurso que possibilita programar v\u00eddeo ao vivo | Sobre a Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Facebook lan\u00e7a recurso que possibilita programar v\u00eddeo ao vivo | Sobre a Meta\" \/>\n<meta property=\"og:description\" content=\"Por Peter Roybal, gerente de produto, e Brian Lin, engenheiro de software Desde o lan\u00e7amento do Facebook Live, temos visto uma incr\u00edvel ado\u00e7\u00e3o e engajamento do p\u00fablico com o novo formato. Muitos criadores de conte\u00fado queriam ter a possibilidade de agendar suas transmiss\u00f5es e permitir que as pessoas conseguissem se planejar para assistir aos v\u00eddeos. Por isso, estamos disponibilizando esta semana para as p\u00e1ginas verificadas a possibilidade de agendar suas transmiss\u00f5es, come\u00e7ando com os v\u00eddeos ao vivo publicados atrav\u00e9s da API do Facebook Live. Ao explorar as ferramentas de publica\u00e7\u00e3o, as p\u00e1ginas verificadas encontram um guia com o passo a passo. O agendamento dos v\u00eddeos ajuda a gerar expectativa antes da transmiss\u00e3o, de modo que, ao come\u00e7ar o v\u00eddeo, sua audi\u00eancia j\u00e1 esteja fortemente reunida e engajada. Ao agendar um Live, um post ser\u00e1 publicado no Feed de Not\u00edcias para avisar seus f\u00e3s sobre a transmiss\u00e3o. As pessoas podem ainda optar por receber uma notifica\u00e7\u00e3o minutos antes que ela comece. Assim, seus f\u00e3s poder\u00e3o se conectar a um lobby antes do v\u00eddeo come\u00e7ar, onde ser\u00e1 poss\u00edvel tamb\u00e9m interagir com outros espectadores. Com esse novo recurso, ser\u00e1 poss\u00edvel agendar um v\u00eddeo Live com uma semana de anteced\u00eancia e as pessoas poder\u00e3o ingressar no lobby tr\u00eas minutos antes da transmiss\u00e3o. Uma vez programado, ser\u00e1 poss\u00edvel compartilhar o link ou incorpor\u00e1-lo em outros lugares, como sites e blogs. O recurso estar\u00e1 dispon\u00edvel a partir desta quinta-feira, 20 de outubro, pela ferramenta de publica\u00e7\u00e3o da API do Facebook Live, e dispon\u00edvel para todas as p\u00e1ginas verificadas durante as semanas seguintes. Tamb\u00e9m ser\u00e3o liberadas atualiza\u00e7\u00f5es para habilitar o recurso em ferramentas externas. Como agendar um v\u00eddeo Live Se voc\u00ea \u00e9 o administrador da p\u00e1gina utilizando a API do Facebook Live, ser\u00e1 preciso apenas poucos passos para agendar sua transmiss\u00e3o ao vivo. 1. Acesse a Ferramenta de Publica\u00e7\u00e3o Uma vez nela, selecione \u201cBiblioteca de v\u00eddeos\u201d e depois \u201cAo Vivo\u201d. 2. Copie sua credencial de transmiss\u00e3o (Ex: a URL do servidor) Caso precise procurar sua credencial perto do hor\u00e1rio da transmiss\u00e3o, ela tamb\u00e9m estar\u00e1 dispon\u00edvel ao editar um v\u00eddeo na \u201cBiblioteca de V\u00eddeos\u201d. 3. Crie seu post de an\u00fancio Coloque uma descri\u00e7\u00e3o atraente e informativa para que seus seguidores saibam o que esperar de sua transmiss\u00e3o. \u00c9 poss\u00edvel atualizar esse conte\u00fado depois. 4. Finalize o agendamento de sua transmiss\u00e3o Acrescente os detalhes finais ao post, como imagens personalizadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre a Meta\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-19T13:10:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-17T13:11:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-1-1.jpg\" \/>\n<meta name=\"author\" content=\"facebookbr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/\"},\"author\":\"Facebook company\",\"headline\":\"Facebook lan\u00e7a recurso que possibilita programar v\u00eddeo ao vivo\",\"datePublished\":\"2016-10-19T13:10:19+00:00\",\"dateModified\":\"2021-06-17T13:11:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/\"},\"wordCount\":457,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-1-1.jpg\",\"keywords\":[\"Facebook\",\"Facebook Live\",\"Live\",\"Live programado\",\"Live videos\"],\"articleSection\":[\"Recent News\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/\",\"url\":\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/\",\"name\":\"Facebook lan\u00e7a recurso que possibilita programar v\u00eddeo ao vivo | Sobre a Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-1-1.jpg\",\"datePublished\":\"2016-10-19T13:10:19+00:00\",\"dateModified\":\"2021-06-17T13:11:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/\"]}],\"author\":\"Sobre a Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#primaryimage\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-1-1.jpg\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-1-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facebook lan\u00e7a recurso que possibilita programar v\u00eddeo ao vivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/br\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"Sobre a Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/br\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Facebook lan\u00e7a recurso que possibilita programar v\u00eddeo ao vivo | Sobre a Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/","og_locale":"pt_BR","og_type":"article","og_title":"Facebook lan\u00e7a recurso que possibilita programar v\u00eddeo ao vivo | Sobre a Meta","og_description":"Por Peter Roybal, gerente de produto, e Brian Lin, engenheiro de software Desde o lan\u00e7amento do Facebook Live, temos visto uma incr\u00edvel ado\u00e7\u00e3o e engajamento do p\u00fablico com o novo formato. Muitos criadores de conte\u00fado queriam ter a possibilidade de agendar suas transmiss\u00f5es e permitir que as pessoas conseguissem se planejar para assistir aos v\u00eddeos. Por isso, estamos disponibilizando esta semana para as p\u00e1ginas verificadas a possibilidade de agendar suas transmiss\u00f5es, come\u00e7ando com os v\u00eddeos ao vivo publicados atrav\u00e9s da API do Facebook Live. Ao explorar as ferramentas de publica\u00e7\u00e3o, as p\u00e1ginas verificadas encontram um guia com o passo a passo. O agendamento dos v\u00eddeos ajuda a gerar expectativa antes da transmiss\u00e3o, de modo que, ao come\u00e7ar o v\u00eddeo, sua audi\u00eancia j\u00e1 esteja fortemente reunida e engajada. Ao agendar um Live, um post ser\u00e1 publicado no Feed de Not\u00edcias para avisar seus f\u00e3s sobre a transmiss\u00e3o. As pessoas podem ainda optar por receber uma notifica\u00e7\u00e3o minutos antes que ela comece. Assim, seus f\u00e3s poder\u00e3o se conectar a um lobby antes do v\u00eddeo come\u00e7ar, onde ser\u00e1 poss\u00edvel tamb\u00e9m interagir com outros espectadores. Com esse novo recurso, ser\u00e1 poss\u00edvel agendar um v\u00eddeo Live com uma semana de anteced\u00eancia e as pessoas poder\u00e3o ingressar no lobby tr\u00eas minutos antes da transmiss\u00e3o. Uma vez programado, ser\u00e1 poss\u00edvel compartilhar o link ou incorpor\u00e1-lo em outros lugares, como sites e blogs. O recurso estar\u00e1 dispon\u00edvel a partir desta quinta-feira, 20 de outubro, pela ferramenta de publica\u00e7\u00e3o da API do Facebook Live, e dispon\u00edvel para todas as p\u00e1ginas verificadas durante as semanas seguintes. Tamb\u00e9m ser\u00e3o liberadas atualiza\u00e7\u00f5es para habilitar o recurso em ferramentas externas. Como agendar um v\u00eddeo Live Se voc\u00ea \u00e9 o administrador da p\u00e1gina utilizando a API do Facebook Live, ser\u00e1 preciso apenas poucos passos para agendar sua transmiss\u00e3o ao vivo. 1. Acesse a Ferramenta de Publica\u00e7\u00e3o Uma vez nela, selecione \u201cBiblioteca de v\u00eddeos\u201d e depois \u201cAo Vivo\u201d. 2. Copie sua credencial de transmiss\u00e3o (Ex: a URL do servidor) Caso precise procurar sua credencial perto do hor\u00e1rio da transmiss\u00e3o, ela tamb\u00e9m estar\u00e1 dispon\u00edvel ao editar um v\u00eddeo na \u201cBiblioteca de V\u00eddeos\u201d. 3. Crie seu post de an\u00fancio Coloque uma descri\u00e7\u00e3o atraente e informativa para que seus seguidores saibam o que esperar de sua transmiss\u00e3o. \u00c9 poss\u00edvel atualizar esse conte\u00fado depois. 4. Finalize o agendamento de sua transmiss\u00e3o Acrescente os detalhes finais ao post, como imagens personalizadas.","og_url":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/","og_site_name":"Sobre a Meta","article_published_time":"2016-10-19T13:10:19+00:00","article_modified_time":"2021-06-17T13:11:03+00:00","og_image":[{"url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-1-1.jpg","type":"","width":"","height":""}],"author":"facebookbr","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/"},"author":"Facebook company","headline":"Facebook lan\u00e7a recurso que possibilita programar v\u00eddeo ao vivo","datePublished":"2016-10-19T13:10:19+00:00","dateModified":"2021-06-17T13:11:03+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/"},"wordCount":457,"publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-1-1.jpg","keywords":["Facebook","Facebook Live","Live","Live programado","Live videos"],"articleSection":["Recent News"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/","url":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/","name":"Facebook lan\u00e7a recurso que possibilita programar v\u00eddeo ao vivo | Sobre a Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#primaryimage"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-1-1.jpg","datePublished":"2016-10-19T13:10:19+00:00","dateModified":"2021-06-17T13:11:03+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/"]}],"author":"Sobre a Meta"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#primaryimage","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-1-1.jpg","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/3\/2016\/10\/live-1-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/br\/news\/2016\/10\/facebook-lanca-recurso-que-possibilita-programar-video-ao-vivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/br\/"},{"@type":"ListItem","position":2,"name":"Facebook lan\u00e7a recurso que possibilita programar v\u00eddeo ao vivo"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/br\/#website","url":"https:\/\/about.fb.com\/news\/","name":"Sobre a Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/br\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[{"id":27272,"url":"https:\/\/about.fb.com\/br\/news\/2026\/06\/cannes-2026-novas-maneiras-de-transformar-a-descoberta-em-compra-na-meta\/","url_meta":{"origin":5606,"position":0},"title":"Cannes 2026: Novas Maneiras de Transformar a Descoberta em Compra na Meta","author":"Meta","date":"17\/06\/2026","format":false,"excerpt":"Destaques Expans\u00e3o de Afiliados: Estamos expandindo nosso programa de Parceiros Afiliados com a Flipkart e a Lazada, e trazendo Mercado Livre para mais pa\u00edses. An\u00fancios de V\u00eddeo ao Vivo (Live Video Ads): Estamos ampliando a disponibilidade dos An\u00fancios de v\u00eddeo ao vivo, ajudando os profissionais de marketing a alcan\u00e7ar p\u00fablicos\u2026","rel":"","context":"In &quot;Facebook&quot;","block_context":{"text":"Facebook","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/facebook\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/download.gif?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/download.gif?resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/download.gif?resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/download.gif?resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/download.gif?resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/download.gif?resize=1400%2C800 4x"},"classes":[]},{"id":26809,"url":"https:\/\/about.fb.com\/br\/news\/2025\/11\/protecao-de-conteudo-seu-novo-guardiao-da-criatividade-no-facebook\/","url_meta":{"origin":5606,"position":1},"title":"Prote\u00e7\u00e3o de conte\u00fado: Seu novo guardi\u00e3o da criatividade no Facebook","author":"Meta","date":"17\/11\/2025","format":false,"excerpt":"O Facebook est\u00e1 lan\u00e7ando a prote\u00e7\u00e3o de conte\u00fado, uma nova ferramenta para criadores que protege automaticamente seus Reels originais, alerta quando conte\u00fados correspondentes a esses Reels s\u00e3o detectados no Facebook ou Instagram e ajuda voc\u00ea a tomar medidas caso seu trabalho seja usado sem permiss\u00e3o. Seu trabalho original \u00e9 a\u2026","rel":"","context":"In &quot;Facebook&quot;","block_context":{"text":"Facebook","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/facebook\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=525%2C300 1.5x"},"classes":[]},{"id":26696,"url":"https:\/\/about.fb.com\/br\/news\/2025\/10\/desempenho-potencializado-por-ia-para-o-agora-e-o-futuro\/","url_meta":{"origin":5606,"position":2},"title":"Desempenho potencializado por IA para o agora e o futuro","author":"Meta","date":"02\/10\/2025","format":false,"excerpt":"Para os profissionais de marketing, cada ponto de desempenho incremental pode significar a diferen\u00e7a entre empatar e bater recordes. Por isso, a Meta continua investindo em solu\u00e7\u00f5es l\u00edderes com IA, incluindo o Advantage+ e a infraestrutura que o sustenta, para ajudar empresas, anunciantes e ag\u00eancias a expandirem rapidamente. Estamos escrevendo\u2026","rel":"","context":"In &quot;Meta&quot;","block_context":{"text":"Meta","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/meta\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=525%2C300 1.5x"},"classes":[]},{"id":26525,"url":"https:\/\/about.fb.com\/br\/news\/2025\/07\/combatendo-conteudo-nao-original-para-proteger-e-elevar-criadores-no-facebook\/","url_meta":{"origin":5606,"position":3},"title":"Combatendo conte\u00fado n\u00e3o original para proteger e elevar Criadores no Facebook","author":"Meta","date":"14\/07\/2025","format":false,"excerpt":"Acreditamos que os criadores devem ser celebrados por suas vozes e perspectivas \u00fanicas, e n\u00e3o ofuscados por imitadores e contas falsas. Recentemente, lan\u00e7amos uma iniciativa de longo prazo para tornar o Feed mais relevante e ajudar criadores aut\u00eanticos a se destacarem, come\u00e7ando pela redu\u00e7\u00e3o do conte\u00fado com spam. Estamos avan\u00e7ando\u2026","rel":"","context":"In &quot;Facebook&quot;","block_context":{"text":"Facebook","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/facebook\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=525%2C300 1.5x"},"classes":[]},{"id":27127,"url":"https:\/\/about.fb.com\/br\/news\/2026\/05\/novas-medidas-para-garantir-que-adolescentes-tenham-experiencias-adequadas-a-faixa-etaria\/","url_meta":{"origin":5606,"position":4},"title":"Novas medidas para garantir que adolescentes tenham experi\u00eancias adequadas \u00e0 faixa et\u00e1ria","author":"Meta","date":"05\/05\/2026","format":false,"excerpt":"Queremos que os jovens tenham viv\u00eancias online seguras e positivas. \u00c9 por isso que colocamos os adolescentes automaticamente em experi\u00eancias adequadas \u00e0 idade, como as Contas de Adolescente. Hoje, compartilhamos atualiza\u00e7\u00f5es sobre nossos esfor\u00e7os para ajudar a garantir que menores de idade n\u00e3o estejam utilizando nossos apps de forma inadequada\u2026","rel":"","context":"In &quot;Facebook&quot;","block_context":{"text":"Facebook","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/facebook\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/AI-Age-Assurance_Header-1.jpg?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/AI-Age-Assurance_Header-1.jpg?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/AI-Age-Assurance_Header-1.jpg?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/AI-Age-Assurance_Header-1.jpg?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/AI-Age-Assurance_Header-1.jpg?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/AI-Age-Assurance_Header-1.jpg?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]},{"id":26678,"url":"https:\/\/about.fb.com\/br\/news\/2025\/09\/apresentando-o-vibes-uma-nova-forma-de-descobrir-e-criar-videos-com-ia\/","url_meta":{"origin":5606,"position":5},"title":"Apresentando o Vibes: uma nova forma de descobrir e criar v\u00eddeos com IA","author":"Meta","date":"25\/09\/2025","format":false,"excerpt":"Hoje estamos lan\u00e7ando a pr\u00f3xima vers\u00e3o do app Meta AI, incluindo uma pr\u00e9via do Vibes e um novo feed \u2013 tamb\u00e9m dispon\u00edvel em meta.ai \u2013, onde voc\u00ea pode criar e compartilhar v\u00eddeos curtos gerados por IA. O Vibes foi pensado para facilitar a busca por inspira\u00e7\u00e3o criativa e experimentar as\u2026","rel":"","context":"In &quot;Meta AI&quot;","block_context":{"text":"Meta AI","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/meta-ai\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/09\/Vibes_header.gif?fit=960%2C538&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/09\/Vibes_header.gif?fit=960%2C538&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/09\/Vibes_header.gif?fit=960%2C538&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/09\/Vibes_header.gif?fit=960%2C538&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/5606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/users\/81109636"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/comments?post=5606"}],"version-history":[{"count":4,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/5606\/revisions"}],"predecessor-version":[{"id":8216,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/5606\/revisions\/8216"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/media?parent=5606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/categories?post=5606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/tags?post=5606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}