{"id":26927,"date":"2026-01-21T13:59:32","date_gmt":"2026-01-21T16:59:32","guid":{"rendered":"https:\/\/about.fb.com\/br\/?p=26927"},"modified":"2026-01-21T14:00:21","modified_gmt":"2026-01-21T17:00:21","slug":"anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente","status":"publish","type":"post","link":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/","title":{"rendered":"An\u00fancios no Threads: um ano depois \u2013 agora alcan\u00e7ando todos os usu\u00e1rios e mercados globalmente"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Dois anos ap\u00f3s seu lan\u00e7amento, o Threads deixou de ser apenas um novo aplicativo social para se tornar uma plataforma de conversas em r\u00e1pida expans\u00e3o, com comunidades e vozes pr\u00f3prias. Com mais de 400 milh\u00f5es de usu\u00e1rios ativos mensais, o Threads est\u00e1 se consolidando como um dos principais espa\u00e7os para conversas sobre o que importa agora. Para as empresas, a plataforma representa uma oportunidade de ampliar campanhas existentes e participar das conversas que acontecem nesse espa\u00e7o em crescimento.<\/span><\/p>\n<h3><b>Expans\u00e3o dos an\u00fancios no Threads para todos os mercados<\/b><\/h3>\n<p><span style=\"font-weight: 400\">A partir da pr\u00f3xima semana, os an\u00fancios no Threads ser\u00e3o ampliados para usu\u00e1rios em todos os mercados globalmente. A iniciativa sucede o lan\u00e7amento inicial dos an\u00fancios na plataforma, realizado no ano passado.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Os an\u00fancios no Threads s\u00e3o impulsionados pelo sistema de an\u00fancios com tecnologia de IA da Meta, j\u00e1 consolidado, o que significa que as pessoas podem esperar o mesmo n\u00edvel de personaliza\u00e7\u00e3o visto em outras plataformas da Meta, como Facebook e Instagram.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Para os anunciantes, os an\u00fancios no Threads oferecem uma forma simples de ampliar o alcance de campanhas j\u00e1 existentes na Meta, adicionando automaticamente posicionamentos adequados \u00e0 marca no Threads em campanhas Advantage+ e manuais. Os formatos familiares \u2013 imagem, v\u00eddeo e carrossel \u2013 aparecem de forma nativa no feed, ajudando as marcas a alcan\u00e7ar mais pessoas, em mais lugares, dentro da fam\u00edlia de aplicativos da Meta.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A expans\u00e3o dos an\u00fancios no Threads para todos os usu\u00e1rios ser\u00e1 gradual, com a entrega inicial de an\u00fancios permanecendo em n\u00edveis reduzidos \u00e0 medida que avan\u00e7amos na disponibiliza\u00e7\u00e3o global ao longo dos pr\u00f3ximos meses.<\/span><\/p>\n<h3><b>Evolu\u00e7\u00e3o da experi\u00eancia de an\u00fancios no Threads<\/b><\/h3>\n<p><span style=\"font-weight: 400\">Desde o lan\u00e7amento no \u00faltimo ano, seguimos investindo em maior flexibilidade na forma como os an\u00fancios aparecem no Threads, al\u00e9m de introduzir mais recursos de seguran\u00e7a e adequa\u00e7\u00e3o de marca, para que os anunciantes tenham confian\u00e7a em rela\u00e7\u00e3o aos ambientes em que seus an\u00fancios s\u00e3o exibidos.<\/span><\/p>\n<p><b>Gest\u00e3o de contas simplificada:<\/b><span style=\"font-weight: 400\"> A partir de hoje, ficou mais f\u00e1cil gerenciar sua conta do Threads diretamente no Business Settings, junto \u00e0s contas de Facebook, Instagram e WhatsApp. Com isso, \u00e9 poss\u00edvel visualizar as contas do Threads dentro do portf\u00f3lio da empresa para veicular an\u00fancios pelo Gerenciador de An\u00fancios ou fazer o cross-post de conte\u00fado org\u00e2nico usando a su\u00edte Meta Business.<\/span><\/p>\n<p><b>Mais formatos de an\u00fancios:<\/b><span style=\"font-weight: 400\"> Os an\u00fancios no Threads agora contam com propor\u00e7\u00e3o 4:5, formato carrossel e, mais recentemente, a possibilidade de veicular an\u00fancios de cat\u00e1logo Advantage+ e an\u00fancios de aplicativos no Threads.<\/span><\/p>\n<p><b>Verifica\u00e7\u00e3o de seguran\u00e7a e adequa\u00e7\u00e3o de marca por terceiros:<\/b><span style=\"font-weight: 400\"> Expandimos para o feed do Threads a verifica\u00e7\u00e3o de terceiros j\u00e1 dispon\u00edvel no feed e nos Reels do Facebook e do Instagram, por meio dos Parceiros de Neg\u00f3cios da Meta. Sabemos o quanto transpar\u00eancia e controle s\u00e3o importantes para as empresas, por isso temos orgulho de oferecer verifica\u00e7\u00e3o independente de seguran\u00e7a e adequa\u00e7\u00e3o de marca no feed do Threads.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Para as empresas que ainda n\u00e3o participam das conversas no Threads, este \u00e9 o momento \u2013 pois n\u00e3o se trata apenas de uma plataforma de distribui\u00e7\u00e3o; \u00e9 um espa\u00e7o para comunidades engajadas que impulsionam as conversas que moldam a cultura. Com os an\u00fancios no Threads, as marcas podem entrar nesse di\u00e1logo de forma aut\u00eantica e encontrar novas maneiras de se conectar com as pessoas mais interessadas em seus neg\u00f3cios. Saiba mais sobre an\u00fancios no Threads <\/span><a href=\"https:\/\/www.facebook.com\/business\/ads\/threads\"><span style=\"font-weight: 400\">aqui<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"Dois anos ap\u00f3s seu lan\u00e7amento, o Threads deixou de ser apenas um novo aplicativo social para se tornar uma plataforma de conversas em r\u00e1pida expans\u00e3o, com comunidades e vozes pr\u00f3prias. Com mais de 400 milh\u00f5es de usu\u00e1rios ativos mensais, o Threads est\u00e1 se consolidando como um dos principais espa\u00e7os para conversas sobre o que importa agora. Para as empresas, a plataforma representa uma oportunidade de ampliar campanhas existentes e participar das conversas que acontecem nesse espa\u00e7o em crescimento. Expans\u00e3o dos an\u00fancios no Threads para todos os mercados A partir da pr\u00f3xima semana, os an\u00fancios no Threads ser\u00e3o ampliados para usu\u00e1rios em todos os mercados globalmente. A iniciativa sucede o lan\u00e7amento inicial dos an\u00fancios na plataforma, realizado no ano passado. Os an\u00fancios no Threads s\u00e3o impulsionados pelo sistema de an\u00fancios com tecnologia de IA da Meta, j\u00e1 consolidado, o que significa que as pessoas podem esperar o mesmo n\u00edvel de personaliza\u00e7\u00e3o visto em outras plataformas da Meta, como Facebook e Instagram. Para os anunciantes, os an\u00fancios no Threads oferecem uma forma simples de ampliar o alcance de campanhas j\u00e1 existentes na Meta, adicionando automaticamente posicionamentos adequados \u00e0 marca no Threads em campanhas Advantage+ e manuais. Os formatos familiares \u2013 imagem, v\u00eddeo e carrossel \u2013 aparecem de forma nativa no feed, ajudando as marcas a alcan\u00e7ar mais pessoas, em mais lugares, dentro da fam\u00edlia de aplicativos da Meta. A expans\u00e3o dos an\u00fancios no Threads para todos os usu\u00e1rios ser\u00e1 gradual, com a entrega inicial de an\u00fancios permanecendo em n\u00edveis reduzidos \u00e0 medida que avan\u00e7amos na disponibiliza\u00e7\u00e3o global ao longo dos pr\u00f3ximos meses. Evolu\u00e7\u00e3o da experi\u00eancia de an\u00fancios no Threads Desde o lan\u00e7amento no \u00faltimo ano, seguimos investindo em maior flexibilidade na forma como os an\u00fancios aparecem no Threads, al\u00e9m de introduzir mais recursos de seguran\u00e7a e adequa\u00e7\u00e3o de marca, para que os anunciantes tenham confian\u00e7a em rela\u00e7\u00e3o aos ambientes em que seus an\u00fancios s\u00e3o exibidos. Gest\u00e3o de contas simplificada: A partir de hoje, ficou mais f\u00e1cil gerenciar sua conta do Threads diretamente no Business Settings, junto \u00e0s contas de Facebook, Instagram e WhatsApp. Com isso, \u00e9 poss\u00edvel visualizar as contas do Threads dentro do portf\u00f3lio da empresa para veicular an\u00fancios pelo Gerenciador de An\u00fancios ou fazer o cross-post de conte\u00fado org\u00e2nico usando a su\u00edte Meta Business. Mais formatos de an\u00fancios: Os an\u00fancios no Threads agora contam com propor\u00e7\u00e3o 4:5, formato carrossel e, mais recentemente, a possibilidade de veicular an\u00fancios de cat\u00e1logo Advantage+ e an\u00fancios de aplicativos no Threads. Verifica\u00e7\u00e3o de seguran\u00e7a e adequa\u00e7\u00e3o de marca por terceiros: Expandimos para o feed do Threads a verifica\u00e7\u00e3o de terceiros j\u00e1 dispon\u00edvel no feed e nos Reels do Facebook e do Instagram, por meio dos Parceiros de Neg\u00f3cios da Meta. Sabemos o quanto transpar\u00eancia e controle s\u00e3o importantes para as empresas, por isso temos orgulho de oferecer verifica\u00e7\u00e3o independente de seguran\u00e7a e adequa\u00e7\u00e3o de marca no feed do Threads. Para as empresas que ainda n\u00e3o participam das conversas no Threads, este \u00e9 o momento \u2013 pois n\u00e3o se trata apenas de uma plataforma de distribui\u00e7\u00e3o; \u00e9 um espa\u00e7o para comunidades engajadas que impulsionam as conversas que moldam a cultura. Com os an\u00fancios no Threads, as marcas podem entrar nesse di\u00e1logo de forma aut\u00eantica e encontrar novas maneiras de se conectar com as pessoas mais interessadas em seus neg\u00f3cios. Saiba mais sobre an\u00fancios no Threads aqui.","protected":false},"author":164097234,"featured_media":26930,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[396542269],"class_list":["post-26927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recent-news","tag-meta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>An\u00fancios no Threads: um ano depois \u2013 agora alcan\u00e7ando todos os usu\u00e1rios e mercados globalmente | Sobre a Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00fancios no Threads: um ano depois \u2013 agora alcan\u00e7ando todos os usu\u00e1rios e mercados globalmente | Sobre a Meta\" \/>\n<meta property=\"og:description\" content=\"Dois anos ap\u00f3s seu lan\u00e7amento, o Threads deixou de ser apenas um novo aplicativo social para se tornar uma plataforma de conversas em r\u00e1pida expans\u00e3o, com comunidades e vozes pr\u00f3prias. Com mais de 400 milh\u00f5es de usu\u00e1rios ativos mensais, o Threads est\u00e1 se consolidando como um dos principais espa\u00e7os para conversas sobre o que importa agora. Para as empresas, a plataforma representa uma oportunidade de ampliar campanhas existentes e participar das conversas que acontecem nesse espa\u00e7o em crescimento. Expans\u00e3o dos an\u00fancios no Threads para todos os mercados A partir da pr\u00f3xima semana, os an\u00fancios no Threads ser\u00e3o ampliados para usu\u00e1rios em todos os mercados globalmente. A iniciativa sucede o lan\u00e7amento inicial dos an\u00fancios na plataforma, realizado no ano passado. Os an\u00fancios no Threads s\u00e3o impulsionados pelo sistema de an\u00fancios com tecnologia de IA da Meta, j\u00e1 consolidado, o que significa que as pessoas podem esperar o mesmo n\u00edvel de personaliza\u00e7\u00e3o visto em outras plataformas da Meta, como Facebook e Instagram. Para os anunciantes, os an\u00fancios no Threads oferecem uma forma simples de ampliar o alcance de campanhas j\u00e1 existentes na Meta, adicionando automaticamente posicionamentos adequados \u00e0 marca no Threads em campanhas Advantage+ e manuais. Os formatos familiares \u2013 imagem, v\u00eddeo e carrossel \u2013 aparecem de forma nativa no feed, ajudando as marcas a alcan\u00e7ar mais pessoas, em mais lugares, dentro da fam\u00edlia de aplicativos da Meta. A expans\u00e3o dos an\u00fancios no Threads para todos os usu\u00e1rios ser\u00e1 gradual, com a entrega inicial de an\u00fancios permanecendo em n\u00edveis reduzidos \u00e0 medida que avan\u00e7amos na disponibiliza\u00e7\u00e3o global ao longo dos pr\u00f3ximos meses. Evolu\u00e7\u00e3o da experi\u00eancia de an\u00fancios no Threads Desde o lan\u00e7amento no \u00faltimo ano, seguimos investindo em maior flexibilidade na forma como os an\u00fancios aparecem no Threads, al\u00e9m de introduzir mais recursos de seguran\u00e7a e adequa\u00e7\u00e3o de marca, para que os anunciantes tenham confian\u00e7a em rela\u00e7\u00e3o aos ambientes em que seus an\u00fancios s\u00e3o exibidos. Gest\u00e3o de contas simplificada: A partir de hoje, ficou mais f\u00e1cil gerenciar sua conta do Threads diretamente no Business Settings, junto \u00e0s contas de Facebook, Instagram e WhatsApp. Com isso, \u00e9 poss\u00edvel visualizar as contas do Threads dentro do portf\u00f3lio da empresa para veicular an\u00fancios pelo Gerenciador de An\u00fancios ou fazer o cross-post de conte\u00fado org\u00e2nico usando a su\u00edte Meta Business. Mais formatos de an\u00fancios: Os an\u00fancios no Threads agora contam com propor\u00e7\u00e3o 4:5, formato carrossel e, mais recentemente, a possibilidade de veicular an\u00fancios de cat\u00e1logo Advantage+ e an\u00fancios de aplicativos no Threads. Verifica\u00e7\u00e3o de seguran\u00e7a e adequa\u00e7\u00e3o de marca por terceiros: Expandimos para o feed do Threads a verifica\u00e7\u00e3o de terceiros j\u00e1 dispon\u00edvel no feed e nos Reels do Facebook e do Instagram, por meio dos Parceiros de Neg\u00f3cios da Meta. Sabemos o quanto transpar\u00eancia e controle s\u00e3o importantes para as empresas, por isso temos orgulho de oferecer verifica\u00e7\u00e3o independente de seguran\u00e7a e adequa\u00e7\u00e3o de marca no feed do Threads. Para as empresas que ainda n\u00e3o participam das conversas no Threads, este \u00e9 o momento \u2013 pois n\u00e3o se trata apenas de uma plataforma de distribui\u00e7\u00e3o; \u00e9 um espa\u00e7o para comunidades engajadas que impulsionam as conversas que moldam a cultura. Com os an\u00fancios no Threads, as marcas podem entrar nesse di\u00e1logo de forma aut\u00eantica e encontrar novas maneiras de se conectar com as pessoas mais interessadas em seus neg\u00f3cios. Saiba mais sobre an\u00fancios no Threads aqui.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre a Meta\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-21T16:59:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T17:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/download.gif?w=640\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"vivilusor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/\"},\"author\":\"Facebook company\",\"headline\":\"An\u00fancios no Threads: um ano depois \u2013 agora alcan\u00e7ando todos os usu\u00e1rios e mercados globalmente\",\"datePublished\":\"2026-01-21T16:59:32+00:00\",\"dateModified\":\"2026-01-21T17:00:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/\"},\"wordCount\":638,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/download.gif?fit=640%2C360\",\"keywords\":[\"Meta\"],\"articleSection\":[\"Recent News\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/\",\"url\":\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/\",\"name\":\"An\u00fancios no Threads: um ano depois \u2013 agora alcan\u00e7ando todos os usu\u00e1rios e mercados globalmente | Sobre a Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/download.gif?fit=640%2C360\",\"datePublished\":\"2026-01-21T16:59:32+00:00\",\"dateModified\":\"2026-01-21T17:00:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/\"]}],\"author\":\"Sobre a Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#primaryimage\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/download.gif?fit=640%2C360\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/download.gif?fit=640%2C360\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"An\u00fancios no Threads: um ano depois \u2013 agora alcan\u00e7ando todos os usu\u00e1rios e mercados globalmente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/br\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"Sobre a Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/br\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"An\u00fancios no Threads: um ano depois \u2013 agora alcan\u00e7ando todos os usu\u00e1rios e mercados globalmente | Sobre a Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/","og_locale":"pt_BR","og_type":"article","og_title":"An\u00fancios no Threads: um ano depois \u2013 agora alcan\u00e7ando todos os usu\u00e1rios e mercados globalmente | Sobre a Meta","og_description":"Dois anos ap\u00f3s seu lan\u00e7amento, o Threads deixou de ser apenas um novo aplicativo social para se tornar uma plataforma de conversas em r\u00e1pida expans\u00e3o, com comunidades e vozes pr\u00f3prias. Com mais de 400 milh\u00f5es de usu\u00e1rios ativos mensais, o Threads est\u00e1 se consolidando como um dos principais espa\u00e7os para conversas sobre o que importa agora. Para as empresas, a plataforma representa uma oportunidade de ampliar campanhas existentes e participar das conversas que acontecem nesse espa\u00e7o em crescimento. Expans\u00e3o dos an\u00fancios no Threads para todos os mercados A partir da pr\u00f3xima semana, os an\u00fancios no Threads ser\u00e3o ampliados para usu\u00e1rios em todos os mercados globalmente. A iniciativa sucede o lan\u00e7amento inicial dos an\u00fancios na plataforma, realizado no ano passado. Os an\u00fancios no Threads s\u00e3o impulsionados pelo sistema de an\u00fancios com tecnologia de IA da Meta, j\u00e1 consolidado, o que significa que as pessoas podem esperar o mesmo n\u00edvel de personaliza\u00e7\u00e3o visto em outras plataformas da Meta, como Facebook e Instagram. Para os anunciantes, os an\u00fancios no Threads oferecem uma forma simples de ampliar o alcance de campanhas j\u00e1 existentes na Meta, adicionando automaticamente posicionamentos adequados \u00e0 marca no Threads em campanhas Advantage+ e manuais. Os formatos familiares \u2013 imagem, v\u00eddeo e carrossel \u2013 aparecem de forma nativa no feed, ajudando as marcas a alcan\u00e7ar mais pessoas, em mais lugares, dentro da fam\u00edlia de aplicativos da Meta. A expans\u00e3o dos an\u00fancios no Threads para todos os usu\u00e1rios ser\u00e1 gradual, com a entrega inicial de an\u00fancios permanecendo em n\u00edveis reduzidos \u00e0 medida que avan\u00e7amos na disponibiliza\u00e7\u00e3o global ao longo dos pr\u00f3ximos meses. Evolu\u00e7\u00e3o da experi\u00eancia de an\u00fancios no Threads Desde o lan\u00e7amento no \u00faltimo ano, seguimos investindo em maior flexibilidade na forma como os an\u00fancios aparecem no Threads, al\u00e9m de introduzir mais recursos de seguran\u00e7a e adequa\u00e7\u00e3o de marca, para que os anunciantes tenham confian\u00e7a em rela\u00e7\u00e3o aos ambientes em que seus an\u00fancios s\u00e3o exibidos. Gest\u00e3o de contas simplificada: A partir de hoje, ficou mais f\u00e1cil gerenciar sua conta do Threads diretamente no Business Settings, junto \u00e0s contas de Facebook, Instagram e WhatsApp. Com isso, \u00e9 poss\u00edvel visualizar as contas do Threads dentro do portf\u00f3lio da empresa para veicular an\u00fancios pelo Gerenciador de An\u00fancios ou fazer o cross-post de conte\u00fado org\u00e2nico usando a su\u00edte Meta Business. Mais formatos de an\u00fancios: Os an\u00fancios no Threads agora contam com propor\u00e7\u00e3o 4:5, formato carrossel e, mais recentemente, a possibilidade de veicular an\u00fancios de cat\u00e1logo Advantage+ e an\u00fancios de aplicativos no Threads. Verifica\u00e7\u00e3o de seguran\u00e7a e adequa\u00e7\u00e3o de marca por terceiros: Expandimos para o feed do Threads a verifica\u00e7\u00e3o de terceiros j\u00e1 dispon\u00edvel no feed e nos Reels do Facebook e do Instagram, por meio dos Parceiros de Neg\u00f3cios da Meta. Sabemos o quanto transpar\u00eancia e controle s\u00e3o importantes para as empresas, por isso temos orgulho de oferecer verifica\u00e7\u00e3o independente de seguran\u00e7a e adequa\u00e7\u00e3o de marca no feed do Threads. Para as empresas que ainda n\u00e3o participam das conversas no Threads, este \u00e9 o momento \u2013 pois n\u00e3o se trata apenas de uma plataforma de distribui\u00e7\u00e3o; \u00e9 um espa\u00e7o para comunidades engajadas que impulsionam as conversas que moldam a cultura. Com os an\u00fancios no Threads, as marcas podem entrar nesse di\u00e1logo de forma aut\u00eantica e encontrar novas maneiras de se conectar com as pessoas mais interessadas em seus neg\u00f3cios. Saiba mais sobre an\u00fancios no Threads aqui.","og_url":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/","og_site_name":"Sobre a Meta","article_published_time":"2026-01-21T16:59:32+00:00","article_modified_time":"2026-01-21T17:00:21+00:00","og_image":[{"url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/download.gif?w=640","width":640,"height":360,"type":"image\/gif"}],"author":"vivilusor","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/"},"author":"Facebook company","headline":"An\u00fancios no Threads: um ano depois \u2013 agora alcan\u00e7ando todos os usu\u00e1rios e mercados globalmente","datePublished":"2026-01-21T16:59:32+00:00","dateModified":"2026-01-21T17:00:21+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/"},"wordCount":638,"publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/download.gif?fit=640%2C360","keywords":["Meta"],"articleSection":["Recent News"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/","url":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/","name":"An\u00fancios no Threads: um ano depois \u2013 agora alcan\u00e7ando todos os usu\u00e1rios e mercados globalmente | Sobre a Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#primaryimage"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/download.gif?fit=640%2C360","datePublished":"2026-01-21T16:59:32+00:00","dateModified":"2026-01-21T17:00:21+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/"]}],"author":"Sobre a Meta"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#primaryimage","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/download.gif?fit=640%2C360","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/download.gif?fit=640%2C360","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/br\/news\/2026\/01\/anuncios-no-threads-um-ano-depois-agora-alcancando-todos-os-usuarios-e-mercados-globalmente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/br\/"},{"@type":"ListItem","position":2,"name":"An\u00fancios no Threads: um ano depois \u2013 agora alcan\u00e7ando todos os usu\u00e1rios e mercados globalmente"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/br\/#website","url":"https:\/\/about.fb.com\/news\/","name":"Sobre a Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/br\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[{"id":26513,"url":"https:\/\/about.fb.com\/br\/news\/2025\/07\/apresentando-dms-e-destaques-no-threads\/","url_meta":{"origin":26927,"position":0},"title":"Apresentando DMs e Destaques no Threads","author":"Meta","date":"01\/07\/2025","format":false,"excerpt":"Atualiza\u00e7\u00e3o em 12 de setembro de 2025 \u00e0s 14h15 (hor\u00e1rio do Pac\u00edfico): Em breve, voc\u00ea poder\u00e1 enviar mensagens diretas para pessoas que voc\u00ea n\u00e3o segue. Para criadores, isso pode abrir portas para colabora\u00e7\u00f5es com outros criadores e oportunidades de monetiza\u00e7\u00e3o. Mas sabemos que nem todo mundo quer uma caixa de\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Threads_1.jpg?fit=1280%2C720&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Threads_1.jpg?fit=1280%2C720&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Threads_1.jpg?fit=1280%2C720&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Threads_1.jpg?fit=1280%2C720&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Threads_1.jpg?fit=1280%2C720&resize=1050%2C600 3x"},"classes":[]},{"id":27290,"url":"https:\/\/about.fb.com\/br\/news\/2026\/06\/novos-recursos-para-celebrar-500-milhoes-de-usuarios-mensais-no-threads\/","url_meta":{"origin":26927,"position":1},"title":"Novos recursos para celebrar 500 milh\u00f5es de usu\u00e1rios mensais no Threads","author":"Meta","date":"16\/06\/2026","format":false,"excerpt":"Hoje anunciamos que o Threads alcan\u00e7ou 500 milh\u00f5es de usu\u00e1rios ativos mensais, um marco que reflete o desejo das pessoas por um espa\u00e7o p\u00fablico constru\u00eddo em torno da conversa. Esse crescimento \u00e9 impulsionado pelas comunidades \u2014 grupos de pessoas que se re\u00fanem em torno das conversas que mais importam para\u2026","rel":"","context":"In &quot;Meta&quot;","block_context":{"text":"Meta","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/meta\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Threads-Reaches-500M-Monthly-Active-Users_Heres-Whats-Next_Header.jpg?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Threads-Reaches-500M-Monthly-Active-Users_Heres-Whats-Next_Header.jpg?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Threads-Reaches-500M-Monthly-Active-Users_Heres-Whats-Next_Header.jpg?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Threads-Reaches-500M-Monthly-Active-Users_Heres-Whats-Next_Header.jpg?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Threads-Reaches-500M-Monthly-Active-Users_Heres-Whats-Next_Header.jpg?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Threads-Reaches-500M-Monthly-Active-Users_Heres-Whats-Next_Header.jpg?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]},{"id":27142,"url":"https:\/\/about.fb.com\/br\/news\/2026\/05\/novo-controle-de-brand-safety-e-suitability-para-anuncios-no-threads\/","url_meta":{"origin":26927,"position":2},"title":"Novo controle de Brand Safety e Suitability para an\u00fancios no Threads","author":"Meta","date":"18\/05\/2026","format":false,"excerpt":"Destaques: A partir de hoje, estamos levando as listas de bloqueio de conte\u00fado de terceiros (third-party content block lists), que j\u00e1 estavam dispon\u00edveis no Feed e Reels do Facebook e Instagram, para o Feed do\u00a0Threads. Esse controle agora est\u00e1 dispon\u00edvel por meio de todos os nossos quatro parceiros existentes de\u00a0brand\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/Threads.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/Threads.png?resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/Threads.png?resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/Threads.png?resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/Threads.png?resize=1050%2C600 3x"},"classes":[]},{"id":27124,"url":"https:\/\/about.fb.com\/br\/news\/2026\/05\/apresentando-o-trending-now-do-threads-no-brasil\/","url_meta":{"origin":26927,"position":3},"title":"Apresentando o Trending Now do Threads no Brasil","author":"Meta","date":"04\/05\/2026","format":false,"excerpt":"Desde o lan\u00e7amento do Threads, sabemos que as pessoas querem poder descobrir os assuntos em alta para participar das conversas que s\u00e3o importantes para elas e, agora, estamos lan\u00e7ando o \"Trending Now\" no Brasil. O \u201cTrending Now\u201d pode ser encontrado na p\u00e1gina de busca e no feed \u201cPara Voc\u00ea\u201d do\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/Trending_Now_Brazil_16x9.png?fit=3840%2C2160&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/Trending_Now_Brazil_16x9.png?fit=3840%2C2160&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/Trending_Now_Brazil_16x9.png?fit=3840%2C2160&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/Trending_Now_Brazil_16x9.png?fit=3840%2C2160&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/Trending_Now_Brazil_16x9.png?fit=3840%2C2160&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/Trending_Now_Brazil_16x9.png?fit=3840%2C2160&resize=1400%2C800 4x"},"classes":[]},{"id":27268,"url":"https:\/\/about.fb.com\/br\/news\/2026\/06\/nosso-trabalho-para-as-eleicoes-de-2026-no-brasil\/","url_meta":{"origin":26927,"position":4},"title":"Nosso trabalho para proteger as elei\u00e7\u00f5es de 2026 no Brasil","author":"Meta","date":"08\/06\/2026","format":false,"excerpt":"Atualizado em 19 de agosto de 2026 Neste link, disponibilizamos nosso Plano de Conformidade para as elei\u00e7\u00f5es brasileiras de 2026. A vers\u00e3o p\u00fablica do documento suprime trechos confidenciais do plano entregue ao Tribunal Superior Eleitoral (TSE). Atualizado em 17 de agosto de 2026 Em julho de 2026, firmamos um Memorando\u2026","rel":"","context":"In &quot;Meta&quot;","block_context":{"text":"Meta","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/meta\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/Captura-de-tela-2026-07-06-124959.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":27245,"url":"https:\/\/about.fb.com\/br\/news\/2026\/06\/de-cabeca-nos-jogos-tudo-que-os-fas-de-futebol-ao-redor-do-mundo-encontram-nos-apps-da-meta\/","url_meta":{"origin":26927,"position":5},"title":"De Cabe\u00e7a nos Jogos: Tudo que os F\u00e3s de Futebol ao Redor do Mundo Encontram nos Apps da Meta","author":"Meta","date":"11\/06\/2026","format":false,"excerpt":"Destaques Estamos trazendo novas funcionalidades e experi\u00eancias de futebol para Threads, Instagram, Facebook e WhatsApp, incluindo conte\u00fados de atletas, conte\u00fados de partidas e ativa\u00e7\u00f5es dentro dos produtos. O Threads est\u00e1 lan\u00e7ando uma experi\u00eancia de futebol pensada para a forma como os torcedores realmente acompanham o torneio: conversa em tempo real,\u2026","rel":"","context":"In &quot;Facebook&quot;","block_context":{"text":"Facebook","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/facebook\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/2.-01_Threads_Carousel-01.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/2.-01_Threads_Carousel-01.jpg?resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/2.-01_Threads_Carousel-01.jpg?resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/2.-01_Threads_Carousel-01.jpg?resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/2.-01_Threads_Carousel-01.jpg?resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/2.-01_Threads_Carousel-01.jpg?resize=1400%2C800 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/download.gif?fit=640%2C360","_links":{"self":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/26927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/users\/164097234"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/comments?post=26927"}],"version-history":[{"count":3,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/26927\/revisions"}],"predecessor-version":[{"id":26931,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/26927\/revisions\/26931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/media\/26930"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/media?parent=26927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/categories?post=26927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/tags?post=26927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}