{"id":26887,"date":"2025-12-18T10:55:58","date_gmt":"2025-12-18T13:55:58","guid":{"rendered":"https:\/\/about.fb.com\/br\/?p=26887"},"modified":"2025-12-18T10:57:24","modified_gmt":"2025-12-18T13:57:24","slug":"novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina","status":"publish","type":"post","link":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/","title":{"rendered":"Novo estudo revela o impacto potencial da Intelig\u00eancia Artificial no Brasil e na Am\u00e9rica Latina"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Um novo estudo realizado pela Linux Foundation, encomendado pela Meta, apresenta dados e informa\u00e7\u00f5es sobre o cen\u00e1rio do mercado de Intelig\u00eancia Artificial (IA) na Am\u00e9rica Latina, e revela os principais desafios e oportunidades para que a regi\u00e3o possa alavancar essa tecnologia e promover um desenvolvimento tecnol\u00f3gico mais equitativo.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Segundo o relat\u00f3rio <a href=\"https:\/\/www.linuxfoundation.org\/research\/open-source-ai-latam\">\u201cOs impactos econ\u00f4micos e no mercado de trabalho da IA na Am\u00e9rica Latina\u201d<\/a>, a<\/span><span style=\"font-weight: 400\"> IA j\u00e1 representa uma for\u00e7a econ\u00f4mica significativa e em expans\u00e3o na Am\u00e9rica Latina. O mercado regional de IA est\u00e1 avaliado em aproximadamente US$ 12,7 bilh\u00f5es e cresce, em m\u00e9dia, 28,1% ao ano. Algumas outras proje\u00e7\u00f5es s\u00e3o ainda mais otimistas, sugerindo que a IA pode adicionar at\u00e9 US$ 1 trilh\u00e3o \u00e0 economia da Am\u00e9rica Latina at\u00e9 2038.<\/span><\/p>\n<p><span style=\"font-weight: 400\">De fato, os resultados das empresas j\u00e1 refletem uma tend\u00eancia positiva, com \u00edndices de retorno sobre investimento acima da m\u00e9dia global:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">No Brasil, 95% das empresas de m\u00e9dio a grande porte pesquisadas que adotaram IA relatam ROI positivo ou j\u00e1 atingiram o ponto de equil\u00edbrio \u2013 no M\u00e9xico, esse \u00edndice \u00e9 de 83%.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">No M\u00e9xico, 83% dos neg\u00f3cios que adotaram IA indicam um aumento m\u00e9dio de receita de 16%.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">43% das organiza\u00e7\u00f5es na Argentina afirmam que j\u00e1 veem resultados da implementa\u00e7\u00e3o de IA. As principais aplica\u00e7\u00f5es dessa tecnologia no pa\u00eds est\u00e3o em atendimento ao cliente (69%), seguido por marketing (42%) e recursos humanos (28%).<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">O estudo tamb\u00e9m destaca o capital humano da Am\u00e9rica Latina como um ativo competitivo chave. Os latino-americanos demonstram uma disposi\u00e7\u00e3o cultural e otimismo excepcionais em rela\u00e7\u00e3o \u00e0 IA, superando significativamente as m\u00e9dias globais.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Impressionantes 85% dos profissionais latino-americanos est\u00e3o prontos para integrar a IA generativa em suas opera\u00e7\u00f5es, em compara\u00e7\u00e3o com 62% no n\u00edvel global.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">56% dos profissionais na Am\u00e9rica Latina se declaram &#8220;entusiasmados&#8221; com a integra\u00e7\u00e3o da IA, frente a 27% globalmente.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">63% dos latino-americanos veem a IA como mais ben\u00e9fica do que prejudicial.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Essa confian\u00e7a se estende ao ambiente profissional: no Brasil, 81% dos profissionais afirmam que a IA generativa os torna mais produtivos no trabalho. Em termos de confian\u00e7a do consumidor, 73% dos consumidores no M\u00e9xico confiam em agentes de IA em servi\u00e7os financeiros.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Na Argentina, 81% das organiza\u00e7\u00f5es t\u00eam uma vis\u00e3o positiva da IA, e 79% das empresas demonstram forte interesse no uso de IA generativa.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Esse entusiasmo se traduz em r\u00e1pida ado\u00e7\u00e3o: 47% das empresas regionais j\u00e1 est\u00e3o implementando solu\u00e7\u00f5es de IA, uma taxa superior \u00e0 m\u00e9dia global de 42%.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Embora a IA esteja transformando o mercado de trabalho, o principal desafio para a Am\u00e9rica Latina nos pr\u00f3ximos anos\u00a0 \u00e9 a ina\u00e7\u00e3o. Apesar de entre 30% e 40% dos empregos na regi\u00e3o terem algum n\u00edvel de exposi\u00e7\u00e3o \u00e0 IA generativa, apenas uma pequena parcela enfrenta alto risco de automa\u00e7\u00e3o total. A grande oportunidade est\u00e1 na amplia\u00e7\u00e3o de capacidades, tornando milh\u00f5es de trabalhadores mais produtivos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Nesse contexto, a Intelig\u00eancia Artificial open source \u00e9 fundamental para impulsionar o investimento e o desenvolvimento de talentos:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><b>Ado\u00e7\u00e3o:<\/b><span style=\"font-weight: 400\"> 38% das organiza\u00e7\u00f5es latino-americanas j\u00e1 utilizam IA open source. O M\u00e9xico, com 65%, e o Brasil, com 46%, lideram esse movimento na regi\u00e3o.<\/span><\/li>\n<li style=\"font-weight: 400\"><b>Acessibilidade:<\/b><span style=\"font-weight: 400\"> O custo \u00e9 citado como a principal barreira por 50% dos profissionais. Os modelos open source s\u00e3o estrat\u00e9gicos porque podem custar de cinco a sete vezes menos que as alternativas propriet\u00e1rias. Isso \u00e9 especialmente relevante para as PMEs, que representam 99,5% de todos os neg\u00f3cios na Am\u00e9rica Latina \u2013\u00a0 no M\u00e9xico, por exemplo, 94% das PMEs relatam que a IA torna suas opera\u00e7\u00f5es mais eficientes.<\/span>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">A Argentina conta com o chatbot MIA, constru\u00eddo sobre o modelo open source Llama, da Meta, que proporciona \u00e0s PMEs e aos cidad\u00e3os acesso mais r\u00e1pido e seguro a servi\u00e7os governamentais.<\/span><\/li>\n<\/ul>\n<\/li>\n<li style=\"font-weight: 400\"><b>Motor de Talentos:<\/b><span style=\"font-weight: 400\"> A disponibilidade de ferramentas abertas e gratuitas \u00e9 essencial para o desenvolvimento de talentos. O ecossistema open source permite que desenvolvedores adquiram habilidades de ponta e comprovem sua compet\u00eancia de forma audit\u00e1vel. Al\u00e9m disso, a regi\u00e3o \u00e9 um contribuinte ativo: o Brasil ocupa o 4\u00ba lugar mundial em contribui\u00e7\u00f5es para projetos open source.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">O estudo destaca ainda como a Am\u00e9rica Latina vive uma transi\u00e7\u00e3o importante: de consumidora de IA para cocriadora. Para consolidar esse movimento, \u00e9 fundamental que os setores p\u00fablico e privado colaborem. Aproveitando o entusiasmo cultural e a experi\u00eancia adquirida no ecossistema de software open source, a Am\u00e9rica Latina pode se tornar uma l\u00edder global em inova\u00e7\u00e3o em IA open source.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"Um novo estudo realizado pela Linux Foundation, encomendado pela Meta, apresenta dados e informa\u00e7\u00f5es sobre o cen\u00e1rio do mercado de Intelig\u00eancia Artificial (IA) na Am\u00e9rica Latina, e revela os principais desafios e oportunidades para que a regi\u00e3o possa alavancar essa tecnologia e promover um desenvolvimento tecnol\u00f3gico mais equitativo. Segundo o relat\u00f3rio \u201cOs impactos econ\u00f4micos e no mercado de trabalho da IA na Am\u00e9rica Latina\u201d, a IA j\u00e1 representa uma for\u00e7a econ\u00f4mica significativa e em expans\u00e3o na Am\u00e9rica Latina. O mercado regional de IA est\u00e1 avaliado em aproximadamente US$ 12,7 bilh\u00f5es e cresce, em m\u00e9dia, 28,1% ao ano. Algumas outras proje\u00e7\u00f5es s\u00e3o ainda mais otimistas, sugerindo que a IA pode adicionar at\u00e9 US$ 1 trilh\u00e3o \u00e0 economia da Am\u00e9rica Latina at\u00e9 2038. De fato, os resultados das empresas j\u00e1 refletem uma tend\u00eancia positiva, com \u00edndices de retorno sobre investimento acima da m\u00e9dia global: No Brasil, 95% das empresas de m\u00e9dio a grande porte pesquisadas que adotaram IA relatam ROI positivo ou j\u00e1 atingiram o ponto de equil\u00edbrio \u2013 no M\u00e9xico, esse \u00edndice \u00e9 de 83%. No M\u00e9xico, 83% dos neg\u00f3cios que adotaram IA indicam um aumento m\u00e9dio de receita de 16%. 43% das organiza\u00e7\u00f5es na Argentina afirmam que j\u00e1 veem resultados da implementa\u00e7\u00e3o de IA. As principais aplica\u00e7\u00f5es dessa tecnologia no pa\u00eds est\u00e3o em atendimento ao cliente (69%), seguido por marketing (42%) e recursos humanos (28%). O estudo tamb\u00e9m destaca o capital humano da Am\u00e9rica Latina como um ativo competitivo chave. Os latino-americanos demonstram uma disposi\u00e7\u00e3o cultural e otimismo excepcionais em rela\u00e7\u00e3o \u00e0 IA, superando significativamente as m\u00e9dias globais. Impressionantes 85% dos profissionais latino-americanos est\u00e3o prontos para integrar a IA generativa em suas opera\u00e7\u00f5es, em compara\u00e7\u00e3o com 62% no n\u00edvel global. 56% dos profissionais na Am\u00e9rica Latina se declaram &#8220;entusiasmados&#8221; com a integra\u00e7\u00e3o da IA, frente a 27% globalmente. 63% dos latino-americanos veem a IA como mais ben\u00e9fica do que prejudicial. Essa confian\u00e7a se estende ao ambiente profissional: no Brasil, 81% dos profissionais afirmam que a IA generativa os torna mais produtivos no trabalho. Em termos de confian\u00e7a do consumidor, 73% dos consumidores no M\u00e9xico confiam em agentes de IA em servi\u00e7os financeiros. Na Argentina, 81% das organiza\u00e7\u00f5es t\u00eam uma vis\u00e3o positiva da IA, e 79% das empresas demonstram forte interesse no uso de IA generativa. Esse entusiasmo se traduz em r\u00e1pida ado\u00e7\u00e3o: 47% das empresas regionais j\u00e1 est\u00e3o implementando solu\u00e7\u00f5es de IA, uma taxa superior \u00e0 m\u00e9dia global de 42%. Embora a IA esteja transformando o mercado de trabalho, o principal desafio para a Am\u00e9rica Latina nos pr\u00f3ximos anos\u00a0 \u00e9 a ina\u00e7\u00e3o. Apesar de entre 30% e 40% dos empregos na regi\u00e3o terem algum n\u00edvel de exposi\u00e7\u00e3o \u00e0 IA generativa, apenas uma pequena parcela enfrenta alto risco de automa\u00e7\u00e3o total. A grande oportunidade est\u00e1 na amplia\u00e7\u00e3o de capacidades, tornando milh\u00f5es de trabalhadores mais produtivos. Nesse contexto, a Intelig\u00eancia Artificial open source \u00e9 fundamental para impulsionar o investimento e o desenvolvimento de talentos: Ado\u00e7\u00e3o: 38% das organiza\u00e7\u00f5es latino-americanas j\u00e1 utilizam IA open source. O M\u00e9xico, com 65%, e o Brasil, com 46%, lideram esse movimento na regi\u00e3o. Acessibilidade: O custo \u00e9 citado como a principal barreira por 50% dos profissionais. Os modelos open source s\u00e3o estrat\u00e9gicos porque podem custar de cinco a sete vezes menos que as alternativas propriet\u00e1rias. Isso \u00e9 especialmente relevante para as PMEs, que representam 99,5% de todos os neg\u00f3cios na Am\u00e9rica Latina \u2013\u00a0 no M\u00e9xico, por exemplo, 94% das PMEs relatam que a IA torna suas opera\u00e7\u00f5es mais eficientes. A Argentina conta com o chatbot MIA, constru\u00eddo sobre o modelo open source Llama, da Meta, que proporciona \u00e0s PMEs e aos cidad\u00e3os acesso mais r\u00e1pido e seguro a servi\u00e7os governamentais. Motor de Talentos: A disponibilidade de ferramentas abertas e gratuitas \u00e9 essencial para o desenvolvimento de talentos. O ecossistema open source permite que desenvolvedores adquiram habilidades de ponta e comprovem sua compet\u00eancia de forma audit\u00e1vel. Al\u00e9m disso, a regi\u00e3o \u00e9 um contribuinte ativo: o Brasil ocupa o 4\u00ba lugar mundial em contribui\u00e7\u00f5es para projetos open source. O estudo destaca ainda como a Am\u00e9rica Latina vive uma transi\u00e7\u00e3o importante: de consumidora de IA para cocriadora. Para consolidar esse movimento, \u00e9 fundamental que os setores p\u00fablico e privado colaborem. Aproveitando o entusiasmo cultural e a experi\u00eancia adquirida no ecossistema de software open source, a Am\u00e9rica Latina pode se tornar uma l\u00edder global em inova\u00e7\u00e3o em IA open source.","protected":false},"author":164097234,"featured_media":26888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[396542145,396542114,1,396542170],"tags":[],"class_list":["post-26887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-impacto-economico","category-meta","category-recent-news","category-tecnologia-e-inovacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novo estudo revela o impacto potencial da Intelig\u00eancia Artificial no Brasil e na Am\u00e9rica Latina | Sobre a Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novo estudo revela o impacto potencial da Intelig\u00eancia Artificial no Brasil e na Am\u00e9rica Latina | Sobre a Meta\" \/>\n<meta property=\"og:description\" content=\"Um novo estudo realizado pela Linux Foundation, encomendado pela Meta, apresenta dados e informa\u00e7\u00f5es sobre o cen\u00e1rio do mercado de Intelig\u00eancia Artificial (IA) na Am\u00e9rica Latina, e revela os principais desafios e oportunidades para que a regi\u00e3o possa alavancar essa tecnologia e promover um desenvolvimento tecnol\u00f3gico mais equitativo. Segundo o relat\u00f3rio \u201cOs impactos econ\u00f4micos e no mercado de trabalho da IA na Am\u00e9rica Latina\u201d, a IA j\u00e1 representa uma for\u00e7a econ\u00f4mica significativa e em expans\u00e3o na Am\u00e9rica Latina. O mercado regional de IA est\u00e1 avaliado em aproximadamente US$ 12,7 bilh\u00f5es e cresce, em m\u00e9dia, 28,1% ao ano. Algumas outras proje\u00e7\u00f5es s\u00e3o ainda mais otimistas, sugerindo que a IA pode adicionar at\u00e9 US$ 1 trilh\u00e3o \u00e0 economia da Am\u00e9rica Latina at\u00e9 2038. De fato, os resultados das empresas j\u00e1 refletem uma tend\u00eancia positiva, com \u00edndices de retorno sobre investimento acima da m\u00e9dia global: No Brasil, 95% das empresas de m\u00e9dio a grande porte pesquisadas que adotaram IA relatam ROI positivo ou j\u00e1 atingiram o ponto de equil\u00edbrio \u2013 no M\u00e9xico, esse \u00edndice \u00e9 de 83%. No M\u00e9xico, 83% dos neg\u00f3cios que adotaram IA indicam um aumento m\u00e9dio de receita de 16%. 43% das organiza\u00e7\u00f5es na Argentina afirmam que j\u00e1 veem resultados da implementa\u00e7\u00e3o de IA. As principais aplica\u00e7\u00f5es dessa tecnologia no pa\u00eds est\u00e3o em atendimento ao cliente (69%), seguido por marketing (42%) e recursos humanos (28%). O estudo tamb\u00e9m destaca o capital humano da Am\u00e9rica Latina como um ativo competitivo chave. Os latino-americanos demonstram uma disposi\u00e7\u00e3o cultural e otimismo excepcionais em rela\u00e7\u00e3o \u00e0 IA, superando significativamente as m\u00e9dias globais. Impressionantes 85% dos profissionais latino-americanos est\u00e3o prontos para integrar a IA generativa em suas opera\u00e7\u00f5es, em compara\u00e7\u00e3o com 62% no n\u00edvel global. 56% dos profissionais na Am\u00e9rica Latina se declaram &#8220;entusiasmados&#8221; com a integra\u00e7\u00e3o da IA, frente a 27% globalmente. 63% dos latino-americanos veem a IA como mais ben\u00e9fica do que prejudicial. Essa confian\u00e7a se estende ao ambiente profissional: no Brasil, 81% dos profissionais afirmam que a IA generativa os torna mais produtivos no trabalho. Em termos de confian\u00e7a do consumidor, 73% dos consumidores no M\u00e9xico confiam em agentes de IA em servi\u00e7os financeiros. Na Argentina, 81% das organiza\u00e7\u00f5es t\u00eam uma vis\u00e3o positiva da IA, e 79% das empresas demonstram forte interesse no uso de IA generativa. Esse entusiasmo se traduz em r\u00e1pida ado\u00e7\u00e3o: 47% das empresas regionais j\u00e1 est\u00e3o implementando solu\u00e7\u00f5es de IA, uma taxa superior \u00e0 m\u00e9dia global de 42%. Embora a IA esteja transformando o mercado de trabalho, o principal desafio para a Am\u00e9rica Latina nos pr\u00f3ximos anos\u00a0 \u00e9 a ina\u00e7\u00e3o. Apesar de entre 30% e 40% dos empregos na regi\u00e3o terem algum n\u00edvel de exposi\u00e7\u00e3o \u00e0 IA generativa, apenas uma pequena parcela enfrenta alto risco de automa\u00e7\u00e3o total. A grande oportunidade est\u00e1 na amplia\u00e7\u00e3o de capacidades, tornando milh\u00f5es de trabalhadores mais produtivos. Nesse contexto, a Intelig\u00eancia Artificial open source \u00e9 fundamental para impulsionar o investimento e o desenvolvimento de talentos: Ado\u00e7\u00e3o: 38% das organiza\u00e7\u00f5es latino-americanas j\u00e1 utilizam IA open source. O M\u00e9xico, com 65%, e o Brasil, com 46%, lideram esse movimento na regi\u00e3o. Acessibilidade: O custo \u00e9 citado como a principal barreira por 50% dos profissionais. Os modelos open source s\u00e3o estrat\u00e9gicos porque podem custar de cinco a sete vezes menos que as alternativas propriet\u00e1rias. Isso \u00e9 especialmente relevante para as PMEs, que representam 99,5% de todos os neg\u00f3cios na Am\u00e9rica Latina \u2013\u00a0 no M\u00e9xico, por exemplo, 94% das PMEs relatam que a IA torna suas opera\u00e7\u00f5es mais eficientes. A Argentina conta com o chatbot MIA, constru\u00eddo sobre o modelo open source Llama, da Meta, que proporciona \u00e0s PMEs e aos cidad\u00e3os acesso mais r\u00e1pido e seguro a servi\u00e7os governamentais. Motor de Talentos: A disponibilidade de ferramentas abertas e gratuitas \u00e9 essencial para o desenvolvimento de talentos. O ecossistema open source permite que desenvolvedores adquiram habilidades de ponta e comprovem sua compet\u00eancia de forma audit\u00e1vel. Al\u00e9m disso, a regi\u00e3o \u00e9 um contribuinte ativo: o Brasil ocupa o 4\u00ba lugar mundial em contribui\u00e7\u00f5es para projetos open source. O estudo destaca ainda como a Am\u00e9rica Latina vive uma transi\u00e7\u00e3o importante: de consumidora de IA para cocriadora. Para consolidar esse movimento, \u00e9 fundamental que os setores p\u00fablico e privado colaborem. Aproveitando o entusiasmo cultural e a experi\u00eancia adquirida no ecossistema de software open source, a Am\u00e9rica Latina pode se tornar uma l\u00edder global em inova\u00e7\u00e3o em IA open source.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre a Meta\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-18T13:55:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T13:57:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/Economic-and-Workforce-Impacts-of-OS-AI-Linux-Foundation-paper-1.jpg?resize=1024,576\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vivilusor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/\"},\"author\":\"Facebook company\",\"headline\":\"Novo estudo revela o impacto potencial da Intelig\u00eancia Artificial no Brasil e na Am\u00e9rica Latina\",\"datePublished\":\"2025-12-18T13:55:58+00:00\",\"dateModified\":\"2025-12-18T13:57:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/\"},\"wordCount\":783,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/Economic-and-Workforce-Impacts-of-OS-AI-Linux-Foundation-paper-1.jpg?fit=1920%2C1080\",\"articleSection\":[\"Impacto Econ\u00f4mico\",\"Meta\",\"Recent News\",\"Tecnologia e Inova\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/\",\"url\":\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/\",\"name\":\"Novo estudo revela o impacto potencial da Intelig\u00eancia Artificial no Brasil e na Am\u00e9rica Latina | Sobre a Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/Economic-and-Workforce-Impacts-of-OS-AI-Linux-Foundation-paper-1.jpg?fit=1920%2C1080\",\"datePublished\":\"2025-12-18T13:55:58+00:00\",\"dateModified\":\"2025-12-18T13:57:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/\"]}],\"author\":\"Sobre a Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#primaryimage\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/Economic-and-Workforce-Impacts-of-OS-AI-Linux-Foundation-paper-1.jpg?fit=1920%2C1080\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/Economic-and-Workforce-Impacts-of-OS-AI-Linux-Foundation-paper-1.jpg?fit=1920%2C1080\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novo estudo revela o impacto potencial da Intelig\u00eancia Artificial no Brasil e na Am\u00e9rica Latina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/br\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"Sobre a Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/br\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novo estudo revela o impacto potencial da Intelig\u00eancia Artificial no Brasil e na Am\u00e9rica Latina | Sobre a Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/","og_locale":"pt_BR","og_type":"article","og_title":"Novo estudo revela o impacto potencial da Intelig\u00eancia Artificial no Brasil e na Am\u00e9rica Latina | Sobre a Meta","og_description":"Um novo estudo realizado pela Linux Foundation, encomendado pela Meta, apresenta dados e informa\u00e7\u00f5es sobre o cen\u00e1rio do mercado de Intelig\u00eancia Artificial (IA) na Am\u00e9rica Latina, e revela os principais desafios e oportunidades para que a regi\u00e3o possa alavancar essa tecnologia e promover um desenvolvimento tecnol\u00f3gico mais equitativo. Segundo o relat\u00f3rio \u201cOs impactos econ\u00f4micos e no mercado de trabalho da IA na Am\u00e9rica Latina\u201d, a IA j\u00e1 representa uma for\u00e7a econ\u00f4mica significativa e em expans\u00e3o na Am\u00e9rica Latina. O mercado regional de IA est\u00e1 avaliado em aproximadamente US$ 12,7 bilh\u00f5es e cresce, em m\u00e9dia, 28,1% ao ano. Algumas outras proje\u00e7\u00f5es s\u00e3o ainda mais otimistas, sugerindo que a IA pode adicionar at\u00e9 US$ 1 trilh\u00e3o \u00e0 economia da Am\u00e9rica Latina at\u00e9 2038. De fato, os resultados das empresas j\u00e1 refletem uma tend\u00eancia positiva, com \u00edndices de retorno sobre investimento acima da m\u00e9dia global: No Brasil, 95% das empresas de m\u00e9dio a grande porte pesquisadas que adotaram IA relatam ROI positivo ou j\u00e1 atingiram o ponto de equil\u00edbrio \u2013 no M\u00e9xico, esse \u00edndice \u00e9 de 83%. No M\u00e9xico, 83% dos neg\u00f3cios que adotaram IA indicam um aumento m\u00e9dio de receita de 16%. 43% das organiza\u00e7\u00f5es na Argentina afirmam que j\u00e1 veem resultados da implementa\u00e7\u00e3o de IA. As principais aplica\u00e7\u00f5es dessa tecnologia no pa\u00eds est\u00e3o em atendimento ao cliente (69%), seguido por marketing (42%) e recursos humanos (28%). O estudo tamb\u00e9m destaca o capital humano da Am\u00e9rica Latina como um ativo competitivo chave. Os latino-americanos demonstram uma disposi\u00e7\u00e3o cultural e otimismo excepcionais em rela\u00e7\u00e3o \u00e0 IA, superando significativamente as m\u00e9dias globais. Impressionantes 85% dos profissionais latino-americanos est\u00e3o prontos para integrar a IA generativa em suas opera\u00e7\u00f5es, em compara\u00e7\u00e3o com 62% no n\u00edvel global. 56% dos profissionais na Am\u00e9rica Latina se declaram &#8220;entusiasmados&#8221; com a integra\u00e7\u00e3o da IA, frente a 27% globalmente. 63% dos latino-americanos veem a IA como mais ben\u00e9fica do que prejudicial. Essa confian\u00e7a se estende ao ambiente profissional: no Brasil, 81% dos profissionais afirmam que a IA generativa os torna mais produtivos no trabalho. Em termos de confian\u00e7a do consumidor, 73% dos consumidores no M\u00e9xico confiam em agentes de IA em servi\u00e7os financeiros. Na Argentina, 81% das organiza\u00e7\u00f5es t\u00eam uma vis\u00e3o positiva da IA, e 79% das empresas demonstram forte interesse no uso de IA generativa. Esse entusiasmo se traduz em r\u00e1pida ado\u00e7\u00e3o: 47% das empresas regionais j\u00e1 est\u00e3o implementando solu\u00e7\u00f5es de IA, uma taxa superior \u00e0 m\u00e9dia global de 42%. Embora a IA esteja transformando o mercado de trabalho, o principal desafio para a Am\u00e9rica Latina nos pr\u00f3ximos anos\u00a0 \u00e9 a ina\u00e7\u00e3o. Apesar de entre 30% e 40% dos empregos na regi\u00e3o terem algum n\u00edvel de exposi\u00e7\u00e3o \u00e0 IA generativa, apenas uma pequena parcela enfrenta alto risco de automa\u00e7\u00e3o total. A grande oportunidade est\u00e1 na amplia\u00e7\u00e3o de capacidades, tornando milh\u00f5es de trabalhadores mais produtivos. Nesse contexto, a Intelig\u00eancia Artificial open source \u00e9 fundamental para impulsionar o investimento e o desenvolvimento de talentos: Ado\u00e7\u00e3o: 38% das organiza\u00e7\u00f5es latino-americanas j\u00e1 utilizam IA open source. O M\u00e9xico, com 65%, e o Brasil, com 46%, lideram esse movimento na regi\u00e3o. Acessibilidade: O custo \u00e9 citado como a principal barreira por 50% dos profissionais. Os modelos open source s\u00e3o estrat\u00e9gicos porque podem custar de cinco a sete vezes menos que as alternativas propriet\u00e1rias. Isso \u00e9 especialmente relevante para as PMEs, que representam 99,5% de todos os neg\u00f3cios na Am\u00e9rica Latina \u2013\u00a0 no M\u00e9xico, por exemplo, 94% das PMEs relatam que a IA torna suas opera\u00e7\u00f5es mais eficientes. A Argentina conta com o chatbot MIA, constru\u00eddo sobre o modelo open source Llama, da Meta, que proporciona \u00e0s PMEs e aos cidad\u00e3os acesso mais r\u00e1pido e seguro a servi\u00e7os governamentais. Motor de Talentos: A disponibilidade de ferramentas abertas e gratuitas \u00e9 essencial para o desenvolvimento de talentos. O ecossistema open source permite que desenvolvedores adquiram habilidades de ponta e comprovem sua compet\u00eancia de forma audit\u00e1vel. Al\u00e9m disso, a regi\u00e3o \u00e9 um contribuinte ativo: o Brasil ocupa o 4\u00ba lugar mundial em contribui\u00e7\u00f5es para projetos open source. O estudo destaca ainda como a Am\u00e9rica Latina vive uma transi\u00e7\u00e3o importante: de consumidora de IA para cocriadora. Para consolidar esse movimento, \u00e9 fundamental que os setores p\u00fablico e privado colaborem. Aproveitando o entusiasmo cultural e a experi\u00eancia adquirida no ecossistema de software open source, a Am\u00e9rica Latina pode se tornar uma l\u00edder global em inova\u00e7\u00e3o em IA open source.","og_url":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/","og_site_name":"Sobre a Meta","article_published_time":"2025-12-18T13:55:58+00:00","article_modified_time":"2025-12-18T13:57:24+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/Economic-and-Workforce-Impacts-of-OS-AI-Linux-Foundation-paper-1.jpg?resize=1024,576","type":"image\/jpeg"}],"author":"vivilusor","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/"},"author":"Facebook company","headline":"Novo estudo revela o impacto potencial da Intelig\u00eancia Artificial no Brasil e na Am\u00e9rica Latina","datePublished":"2025-12-18T13:55:58+00:00","dateModified":"2025-12-18T13:57:24+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/"},"wordCount":783,"publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/Economic-and-Workforce-Impacts-of-OS-AI-Linux-Foundation-paper-1.jpg?fit=1920%2C1080","articleSection":["Impacto Econ\u00f4mico","Meta","Recent News","Tecnologia e Inova\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/","url":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/","name":"Novo estudo revela o impacto potencial da Intelig\u00eancia Artificial no Brasil e na Am\u00e9rica Latina | Sobre a Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#primaryimage"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/Economic-and-Workforce-Impacts-of-OS-AI-Linux-Foundation-paper-1.jpg?fit=1920%2C1080","datePublished":"2025-12-18T13:55:58+00:00","dateModified":"2025-12-18T13:57:24+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/"]}],"author":"Sobre a Meta"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#primaryimage","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/Economic-and-Workforce-Impacts-of-OS-AI-Linux-Foundation-paper-1.jpg?fit=1920%2C1080","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/Economic-and-Workforce-Impacts-of-OS-AI-Linux-Foundation-paper-1.jpg?fit=1920%2C1080","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/br\/news\/2025\/12\/novo-estudo-revela-o-impacto-potencial-da-inteligencia-artificial-no-brasil-e-na-america-latina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/br\/"},{"@type":"ListItem","position":2,"name":"Novo estudo revela o impacto potencial da Intelig\u00eancia Artificial no Brasil e na Am\u00e9rica Latina"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/br\/#website","url":"https:\/\/about.fb.com\/news\/","name":"Sobre a Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/br\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[{"id":26598,"url":"https:\/\/about.fb.com\/br\/news\/2025\/08\/26598-pesquisa-revela-o-impacto-da-meta-nas-mpmes-da-america-latina\/","url_meta":{"origin":26887,"position":0},"title":"Pesquisa revela o impacto da Meta nas MPMEs da Am\u00e9rica Latina","author":"Meta","date":"26\/08\/2025","format":false,"excerpt":"As ferramentas da Meta n\u00e3o apenas conectam as MPMEs da Am\u00e9rica Latina aos seus clientes, como tamb\u00e9m criam novas oportunidades de crescimento. 9 em cada 10 empresas que utilizaram um ou mais produtos da Meta relataram aumento de receita. Aumento de receita por pa\u00eds: Argentina: 84% das empresas que usam\u2026","rel":"","context":"In &quot;Meta&quot;","block_context":{"text":"Meta","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/meta\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/Portada_Sin-texto.jpg?fit=3544%2C3544&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/Portada_Sin-texto.jpg?fit=3544%2C3544&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/Portada_Sin-texto.jpg?fit=3544%2C3544&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/Portada_Sin-texto.jpg?fit=3544%2C3544&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/Portada_Sin-texto.jpg?fit=3544%2C3544&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/Portada_Sin-texto.jpg?fit=3544%2C3544&resize=1400%2C800 4x"},"classes":[]},{"id":27433,"url":"https:\/\/about.fb.com\/br\/news\/2026\/07\/o-futuro-da-ia-e-para-todos\/","url_meta":{"origin":26887,"position":1},"title":"O futuro da IA \u00e9 para todos","author":"Meta","date":"28\/07\/2026","format":false,"excerpt":"Por Mark Zuckerberg, CEO e Fundador da Meta A hist\u00f3ria da democracia e da economia provou que o poder centralizado sufoca o potencial humano. Temos a sorte de viver um momento incr\u00edvel da hist\u00f3ria. Nos pr\u00f3ximos anos, as pessoas poder\u00e3o usar uma superintelig\u00eancia al\u00e9m da capacidade humana para criar e\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":27025,"url":"https:\/\/about.fb.com\/br\/news\/2026\/03\/apresentando-uma-nova-era-de-descoberta-de-produtos-impulsionada-por-ia-e-criadores\/","url_meta":{"origin":26887,"position":2},"title":"Apresentando uma nova era de descoberta de produtos impulsionada por IA e criadores","author":"Meta","date":"25\/03\/2026","format":false,"excerpt":"Todos os dias, bilh\u00f5es de pessoas acessam os aplicativos da Meta para descobrir algo novo \u2014 um produto que um criador adora, uma marca que chama sua aten\u00e7\u00e3o ou um estilo que elas nem sabiam que estavam procurando.A IA est\u00e1 ajudando a impulsionar esses momentos de descoberta, seja exibindo conte\u00fados\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/03\/newsroom-shoptalk.gif?w=312&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":26574,"url":"https:\/\/about.fb.com\/br\/news\/2025\/08\/apresentando-o-app-meta-ai-uma-nova-forma-de-acessar-seu-assistente-de-inteligencia-artificial\/","url_meta":{"origin":26887,"position":3},"title":"Apresentando o app Meta AI: uma nova forma de acessar seu assistente de intelig\u00eancia artificial","author":"Meta","date":"11\/08\/2025","format":false,"excerpt":"Estamos lan\u00e7ando no Brasil o novo app Meta AI, desenvolvido com o Llama, um primeiro passo na constru\u00e7\u00e3o de uma IA mais pessoal. Pessoas ao redor do mundo j\u00e1 utilizam a Meta AI diariamente no WhatsApp, Instagram, Facebook e Messenger. Agora, elas tamb\u00e9m poder\u00e3o optar por interagir com uma IA\u2026","rel":"","context":"In &quot;Meta AI&quot;","block_context":{"text":"Meta AI","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/meta-ai\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/C50-Brazil-Launch_Header.gif?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/C50-Brazil-Launch_Header.gif?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/C50-Brazil-Launch_Header.gif?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/C50-Brazil-Launch_Header.gif?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/C50-Brazil-Launch_Header.gif?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/C50-Brazil-Launch_Header.gif?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]},{"id":26453,"url":"https:\/\/about.fb.com\/br\/news\/2025\/06\/performance-talks-galeria\/","url_meta":{"origin":26887,"position":4},"title":"Performance Talks &#8211; GALERIA","author":"Meta","date":"13\/06\/2025","format":false,"excerpt":"O uso de ferramentas baseadas em Intelig\u00eancia Artificial com foco em automa\u00e7\u00e3o e melhor uso de dados tem transformado o trabalho da GALERIA, uma das ag\u00eancias l\u00edderes no mercado brasileiro. A expans\u00e3o da criatividade por meio da parceria entre humanos e IA generativa tamb\u00e9m t\u00eam gerado resultados mais interessantes para\u2026","rel":"","context":"In &quot;Homepage - Hidden&quot;","block_context":{"text":"Homepage - Hidden","link":"https:\/\/about.fb.com\/br\/news\/category\/homepage-hidden\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":27308,"url":"https:\/\/about.fb.com\/br\/news\/2026\/06\/meta-e-essilorluxottica-apresentam-meta-glasses-uma-nova-linha-de-oculos-com-ia-feita-para-voce\/","url_meta":{"origin":26887,"position":5},"title":"Meta e EssilorLuxottica apresentam Meta Glasses: uma nova linha de \u00f3culos com IA feita para voc\u00ea","author":"Meta","date":"23\/06\/2026","format":false,"excerpt":"\u00d3culos s\u00e3o a categoria de hardware mais empolgante da era da IA \u2014 o dispositivo ideal para experimentar um assistente de IA para o dia todo que entende o mundo do seu ponto de vista. Nos \u00faltimos cinco anos, fomos pioneiros nesta categoria com a EssilorLuxottica, vendendo milh\u00f5es de unidades\u2026","rel":"","context":"In &quot;Meta&quot;","block_context":{"text":"Meta","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/meta\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/NRP_Meta-Glasses-1.jpg?fit=960%2C540&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/NRP_Meta-Glasses-1.jpg?fit=960%2C540&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/NRP_Meta-Glasses-1.jpg?fit=960%2C540&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/06\/NRP_Meta-Glasses-1.jpg?fit=960%2C540&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/Economic-and-Workforce-Impacts-of-OS-AI-Linux-Foundation-paper-1.jpg?fit=1920%2C1080","_links":{"self":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/26887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/users\/164097234"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/comments?post=26887"}],"version-history":[{"count":2,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/26887\/revisions"}],"predecessor-version":[{"id":26893,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/26887\/revisions\/26893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/media\/26888"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/media?parent=26887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/categories?post=26887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/tags?post=26887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}