{"id":26752,"date":"2025-10-21T09:52:55","date_gmt":"2025-10-21T12:52:55","guid":{"rendered":"https:\/\/about.fb.com\/br\/?p=26752"},"modified":"2025-10-22T11:14:57","modified_gmt":"2025-10-22T14:14:57","slug":"mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online","status":"publish","type":"post","link":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/","title":{"rendered":"M\u00eas da Conscientiza\u00e7\u00e3o sobre Ciberseguran\u00e7a: Ajudando idosos a evitar golpes online"},"content":{"rendered":"<p><span style=\"font-weight: 400\">O <\/span><a href=\"https:\/\/www.ic3.gov\/AnnualReport\/Reports\/2024_IC3Report.pdf\"><span style=\"font-weight: 400\">Relat\u00f3rio de Crimes Cibern\u00e9ticos de 2024 do FBI<\/span><\/a><span style=\"font-weight: 400\"> indica que adultos com 60 anos ou mais nos EUA perderam um valor combinado de 4,8 bilh\u00f5es de d\u00f3lares em golpes somente em\u00a0 2024. Criminosos usam uma variedade de t\u00e1ticas para ganhar a confian\u00e7a das pessoas e, em determinadas circunst\u00e2ncias, comprometem suas contas online, muitas vezes com o objetivo de atrair seus contatos pr\u00f3ximos para esquemas fraudulentos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Neste M\u00eas da Conscientiza\u00e7\u00e3o sobre Seguran\u00e7a Cibern\u00e9tica, como parte de nossa campanha global cont\u00ednua de conscientiza\u00e7\u00e3o contra golpes, estamos compartilhando as \u00faltimas tend\u00eancias em tentativas de golpe direcionadas a idosos, novas ferramentas de seguran\u00e7a e dicas sobre como identificar e evitar a intera\u00e7\u00e3o com golpistas online.<\/span><\/p>\n<h3><b>Tentativas de golpe em que se deve prestar aten\u00e7\u00e3o<\/b><\/h3>\n<p><span style=\"font-weight: 400\">Al\u00e9m de nossas investiga\u00e7\u00f5es cont\u00ednuas, fizemos uma parceria com pesquisadores de c\u00f3digo aberto da <\/span><a href=\"http:\/\/graphika.com\/vulnerability-vultures\"><span style=\"font-weight: 400\">Graphika<\/span><\/a><span style=\"font-weight: 400\"> para encontrar e interromper tentativas de golpe direcionadas a idosos na Internet. Quando essas situa\u00e7\u00f5es\u00a0 apareceram em nossos aplicativos, tomamos medidas: bloqueamos os sites dos golpistas em nossas plataformas e exclu\u00edmos suas contas.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><b>Servi\u00e7os falsos de reforma de casas e de renegocia\u00e7\u00e3o de d\u00edvidas: <\/b>Os golpistas criaram sites destinados a solicitar informa\u00e7\u00f5es pessoais sob o pretexto de oferecer benef\u00edcios governamentais fict\u00edcios para idosos, incluindo renegocia\u00e7\u00e3o de d\u00edvidas e reformas residenciais a baixo custo ou sem custo. Eles tentaram atrair pessoas para esses sites usando an\u00fancios online, inclusive no Facebook e no Google.<\/li>\n<\/ul>\n<ul>\n<li><b>Servi\u00e7os fraudulentos de recupera\u00e7\u00e3o de dinheiro: <\/b>Golpistas criaram sites se passando pelo portal oficial do Centro de Queixas de Crimes na Internet (IC3) do FBI, sob o pretexto de ajudar pessoas a recuperar fundos, inclusive de golpes de criptomoedas. Eles tamb\u00e9m mantiveram contas falsas em v\u00e1rios servi\u00e7os, incluindo Facebook, Instagram, Telegram, Threads, TikTok, YouTube e X, se passando por agentes que podem ajudar as v\u00edtimas de fraudes a recuperar seu dinheiro.<\/li>\n<\/ul>\n<ul>\n<li><b>Servi\u00e7o falso de atendimento ao cliente: <\/b>Os golpistas criaram contas online e p\u00e1ginas no Facebook fingindo ser representantes de atendimento ao cliente de companhias a\u00e9reas, ag\u00eancias de viagens, bancos e outros. Eles responderam aos coment\u00e1rios nas postagens das marcas oficiais na tentativa de redirecionar as pessoas para mensagens diretas ou formul\u00e1rios do Google, sob o pretexto de processar o reembolso.<\/li>\n<\/ul>\n<h3><b>Dicas para Idosos: Mantendo-se a Salvo de Golpes Comuns<\/b><b><\/b><\/h3>\n<ul>\n<li><b>Tenha cuidado com mensagens ou chamadas de voz n\u00e3o solicitadas. <\/b><span style=\"font-weight: 400\"><span style=\"font-weight: 400\">Nunca compartilhe informa\u00e7\u00f5es pessoais ou financeiras, como seu n\u00famero de documento ou n\u00fameros de contas, em resposta a liga\u00e7\u00f5es, e-mails ou mensagens de texto inesperadas. Empresas leg\u00edtimas e \u00f3rg\u00e3os governamentais n\u00e3o solicitam essas informa\u00e7\u00f5es do nada.<\/span><\/span><\/li>\n<li><b>Pare e converse com pessoas em quem voc\u00ea confia. <\/b><span style=\"font-weight: 400\">Os golpistas costumam criar uma falsa sensa\u00e7\u00e3o de urg\u00eancia ou p\u00e2nico. Se algu\u00e9m pressionar voc\u00ea a agir rapidamente ou manter as coisas em segredo, isso \u00e9 um sinal de alerta. Pare um momento e converse com algu\u00e9m em quem voc\u00ea confia antes de responder.<br \/>\n<\/span><\/li>\n<li><b>Use canais oficiais de atendimento ao cliente. <\/b><span style=\"font-weight: 400\">Se precisar de ajuda, ligue para a central de atendimento ou acesse o site oficial para verificar as informa\u00e7\u00f5es de contato. N\u00e3o clique em links em emails ou mensagens de texto e evite postar reclama\u00e7\u00f5es em f\u00f3runs p\u00fablicos \u2014 os golpistas costumam monitorar esses espa\u00e7os em busca de v\u00edtimas.<\/span><\/li>\n<\/ul>\n<h2><b>Dicas Para as Fam\u00edlias Ajudarem os Idosos a Permanecerem Seguros Online<\/b><\/h2>\n\n    <div\n        id=\"gallery-26754,26755,26756-1-slideshow\" \n        class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" \n        data-trans=\"fade\" \n        data-autostart=\"true\" \n        data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/about.fb.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/10\\\/01_Tips_Carousel-1_pt_BR.png?fit=1920%2C1672&quot;,&quot;id&quot;:&quot;26754&quot;,&quot;title&quot;:&quot;01_Tips_Carousel 1_pt_BR&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/about.fb.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/10\\\/02_Tips_Carousel-2_pt_BR.png?fit=1920%2C1672&quot;,&quot;id&quot;:&quot;26755&quot;,&quot;title&quot;:&quot;02_Tips_Carousel 2_pt_BR&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/about.fb.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/10\\\/03_Tips_Carousel-3_pt_BR.png?fit=1920%2C1672&quot;,&quot;id&quot;:&quot;26756&quot;,&quot;title&quot;:&quot;03_Tips_Carousel 3_pt_BR&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" \n        itemscope \n        itemtype=\"https:\/\/schema.org\/ImageGallery\">\n    <\/div>\n\n    \n<h3><b>Tomando Medidas Contra Golpistas<\/b><\/h3>\n<p><span style=\"font-weight: 400\">Redes criminosas internacionais continuam a operar em grande escala globalmente e usam esquemas sofisticados para atingir pessoas \u2014 incluindo idosos \u2014 em muitos setores por meio de mensagens, aplicativos de namoro, redes sociais, criptomoedas e outros aplicativos. N\u00f3s continuamos a buscar e bloquear tentativas de cria\u00e7\u00e3o de contas em nossas plataformas por centros de golpes administrados por\u00a0 organiza\u00e7\u00f5es criminosas. De janeiro a setembro de 2025, nossas equipes de especialistas detectaram e interromperam cerca de 8 milh\u00f5es de contas associadas a esses centros de golpes em Mianmar, Laos, Camboja, Emirados \u00c1rabes Unidos e Filipinas. Al\u00e9m disso, tomamos medidas contra mais de 21.000 P\u00e1ginas e contas que se passavam por suporte ao cliente na tentativa de induzir as pessoas a compartilhar suas informa\u00e7\u00f5es.<\/span><\/p>\n<h3><b>Trabalhando em Conjunto para Proteger as Pessoas Contra Golpes<\/b><\/h3>\n<p><span style=\"font-weight: 400\">Os golpistas evoluem constantemente suas t\u00e1ticas para evitar a detec\u00e7\u00e3o e raramente, ou nunca, visam uma \u00fanica plataforma. Isso torna a colabora\u00e7\u00e3o com as autoridades e entre as ind\u00fastrias crucial em nossos esfor\u00e7os contra golpes.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A Meta est\u00e1 se unindo ao <\/span><a href=\"https:\/\/www.fightelderfraud.org\/\"><span style=\"font-weight: 400\">National Elder Fraud Coordination Center<\/span><\/a><span style=\"font-weight: 400\"> (NEFCC), uma organiza\u00e7\u00e3o sem fins lucrativos que re\u00fane autoridades policiais e empresas como AARP, Amazon, Capital One, Google, Microsoft e Walmart, para combater fraudes que visam idosos. Trabalharemos junto com os membros do NEFCC para combater fraudes em n\u00edvel local, estadual e nacional, com foco na prote\u00e7\u00e3o de idosos, compartilhando recursos e apoiando investiga\u00e7\u00f5es de opera\u00e7\u00f5es fraudulentas em grande escala.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Como parte da Tech Against Scams Coalition (TASC), recentemente trabalhamos com o Match Group para desativar grupos do Facebook que alegavam vender contas de namoro para serem usadas em golpes. Os golpistas disfar\u00e7avam os grupos do Facebook como sendo \u201cservi\u00e7os de suporte a relacionamentos&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400\">No in\u00edcio deste m\u00eas, apoiamos a organiza\u00e7\u00e3o do treinamento \u201c<\/span><a href=\"https:\/\/www.facebook.com\/bma.health\/posts\/live-%E0%B8%81%E0%B8%B4%E0%B8%88%E0%B8%81%E0%B8%A3%E0%B8%A3%E0%B8%A1%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9D%E0%B8%B6%E0%B8%81%E0%B8%AD%E0%B8%9A%E0%B8%A3%E0%B8%A1-cyber-smart-senior\/1238114661684799\/\"><span style=\"font-weight: 400\">Cyber Smart Senior<\/span><\/a><span style=\"font-weight: 400\">\u201d em Bangcoc (Tail\u00e2ndia), para ajudar a equipar mais de 100 idosos tailandeses e funcion\u00e1rios de 69 centros de sa\u00fade p\u00fablicos com habilidades essenciais de seguran\u00e7a online e alfabetiza\u00e7\u00e3o digital, incluindo como identificar e evitar golpes. O evento foi realizado em parceria com a Administra\u00e7\u00e3o Metropolitana de Bangcoc e o Departamento de Sa\u00fade P\u00fablica, a Ag\u00eancia de Desenvolvimento de Transa\u00e7\u00f5es Eletr\u00f4nicas, o Departamento de Investiga\u00e7\u00e3o de Crimes Cibern\u00e9ticos da Pol\u00edcia Real Tailandesa, a Esta\u00e7\u00e3o de Televis\u00e3o da Pol\u00edcia Nacional e a Funda\u00e7\u00e3o Kenan \u00c1sia.<\/span><\/p>\n<h3><b>Conscientiza\u00e7\u00e3o Sobre Ciberseguran\u00e7a em Todo o Mundo\u00a0<\/b><\/h3>\n<p><span style=\"font-weight: 400\">Estamos realizando esfor\u00e7os cont\u00ednuos de educa\u00e7\u00e3o sobre seguran\u00e7a em todo o mundo com nossos parceiros. Aqui est\u00e3o alguns exemplos recentes:<\/span><\/p>\n<p><span style=\"font-weight: 400\">Na Europa, fizemos parceria com v\u00e1rios criadores de conte\u00fado para conscientizar os idosos sobre como identificar e se proteger contra golpes, incluindo <\/span><a href=\"https:\/\/www.instagram.com\/p\/DPmPusaDaDK\/\"><span style=\"font-weight: 400\">Amanda Lamb<\/span><\/a><span style=\"font-weight: 400\"> e <\/span><a href=\"https:\/\/www.instagram.com\/reel\/DP_3wtZgnZE\/?igsh=eDBwYzI3YW1lYnBj\"><span style=\"font-weight: 400\">mum_and_a_mic<\/span><\/a><span style=\"font-weight: 400\"> no Reino Unido, <\/span><a href=\"https:\/\/www.instagram.com\/reel\/DKRm2XAMNIF\/\"><span style=\"font-weight: 400\">oliva_sinhache<\/span><\/a><span style=\"font-weight: 400\"> na Espanha e <\/span><a href=\"https:\/\/www.facebook.com\/madrababcia?mibextid=wwXIfr\"><span style=\"font-weight: 400\">M\u0105dra Babcia<\/span><\/a><span style=\"font-weight: 400\"> e a Escola de Economia SGH de Vars\u00f3via na Pol\u00f4nia.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Na \u00cdndia, fizemos parceria com <\/span><a href=\"https:\/\/www.instagram.com\/reel\/DMuT2YtNbG0\/?utm_source=ig_web_copy_link&amp;igsh=YzA2OGU0YjhlMQ%3D%3D\"><span style=\"font-weight: 400\">Signboard_wala<\/span><\/a><span style=\"font-weight: 400\"> (tamb\u00e9m conhecido como \u201co cara com a placa\u201d) e v\u00e1rios criadores de com\u00e9dia\u00a0 para aumentar a conscientiza\u00e7\u00e3o sobre golpes em espa\u00e7os p\u00fablicos. A iniciativa utiliza narrativas culturalmente relevantes e visualmente impactantes para destacar os recursos de seguran\u00e7a da Meta, como autentica\u00e7\u00e3o de dois fatores e bloquear e denunciar, al\u00e9m de compartilhar li\u00e7\u00f5es importantes sobre seguran\u00e7a digital.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Como parte de nossos <\/span><a href=\"https:\/\/about.fb.com\/news\/tag\/scams\/\"><span style=\"font-weight: 400\">esfor\u00e7os cont\u00ednuos<\/span><\/a><span style=\"font-weight: 400\"> para proteger as pessoas contra criminosos, continuaremos a compartilhar atualiza\u00e7\u00f5es regulares sobre nosso trabalho para combater golpes de forma mais ampla, incluindo dicas de seguran\u00e7a e atualiza\u00e7\u00f5es de produtos em nossos aplicativos.<\/span><\/p>\n<h2><b>Nossas ferramentas antifraude mais recentes\u00a0<\/b><\/h2>\n<p><b>No WhatsApp, estamos lan\u00e7ando avisos <\/b><span style=\"font-weight: 400\">quando voc\u00ea tenta compartilhar sua tela com um contato desconhecido durante uma chamada de v\u00eddeo. Sabemos que os golpistas podem pressionar seus alvos a compartilhar suas telas para induzi-los a fornecer informa\u00e7\u00f5es confidenciais, incluindo dados banc\u00e1rios ou c\u00f3digos de verifica\u00e7\u00e3o. Com essa nova ferramenta, oferecemos aos nossos usu\u00e1rios mais contexto para identificar e evitar fraudes.\u00a0<\/span><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-26757\" src=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/pt_BR.png?w=499&#038;resize=385%2C790\" alt=\"\" width=\"385\" height=\"790\" srcset=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/pt_BR.png?w=1081 1081w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/pt_BR.png?w=195 195w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/pt_BR.png?w=146 146w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/pt_BR.png?w=768 768w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/pt_BR.png?w=499 499w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/pt_BR.png?w=748 748w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/pt_BR.png?w=998 998w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/pt_BR.png?w=526 526w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/pt_BR.png?w=1052 1052w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/pt_BR.png?w=292 292w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\" \/><\/p>\n<p><b>No Messenger<\/b><span style=\"font-weight: 400\">, estamos testando uma detec\u00e7\u00e3o de golpes mais avan\u00e7ada nas conversas. Quando essa fun\u00e7\u00e3o est\u00e1 ativada e um novo contato envia uma mensagem potencialmente fraudulenta, avisamos voc\u00ea e oferecemos a op\u00e7\u00e3o de enviar as mensagens recentes da conversa para an\u00e1lise por IA. Se um poss\u00edvel golpe for detectado, voc\u00ea receber\u00e1 mais informa\u00e7\u00f5es sobre golpes comuns e vamos sugerir a\u00e7\u00f5es, incluindo bloquear ou denunciar a conta suspeita. Saiba mais <\/span><a href=\"https:\/\/www.facebook.com\/help\/messenger-app\/1164256635594872\"><span style=\"font-weight: 400\">aqui<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><b>No Facebook, Messenger e WhatsApp<\/b><span style=\"font-weight: 400\">, voc\u00ea pode configurar <\/span><a href=\"https:\/\/about.fb.com\/br\/news\/2025\/06\/apresentamos-chaves-de-acesso-no-facebook-para-facilitar-o-login\/\"><span style=\"font-weight: 400\">senhas<\/span><\/a><span style=\"font-weight: 400\"> de acesso para tornar o login mais seguro, usando a mesma impress\u00e3o digital, reconhecimento facial ou PIN que voc\u00ea j\u00e1 utiliza em seu dispositivo m\u00f3vel para verificar sua identidade<\/span><\/p>\n<p><b>No <\/b><a href=\"https:\/\/www.facebook.com\/help\/securitycheckup\"><b>Facebook<\/b><\/a><b> e no <\/b><a href=\"https:\/\/about.instagram.com\/safety\/account-security\"><b>Instagram<\/b><\/a><b>, voc\u00ea pode usar o Checkup de Seguran\u00e7a <\/b><span style=\"font-weight: 400\">para revisar suas configura\u00e7\u00f5es e obter recomenda\u00e7\u00f5es sobre a\u00e7\u00f5es de seguran\u00e7a, como atualizar sua senha. <\/span><b>No WhatsApp<\/b><span style=\"font-weight: 400\">, o <\/span><a href=\"https:\/\/faq.whatsapp.com\/143990998547188\/?helpref=uf_share\"><span style=\"font-weight: 400\">Checkup de Privacidade<\/span><\/a><span style=\"font-weight: 400\"> orienta voc\u00ea atrav\u00e9s de configura\u00e7\u00f5es importantes de privacidade &#8211; como decidir quem pode adicion\u00e1-lo a grupos &#8211; para ajudar voc\u00ea a escolher o n\u00edvel certo de prote\u00e7\u00e3o, tudo em um s\u00f3 lugar.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"O Relat\u00f3rio de Crimes Cibern\u00e9ticos de 2024 do FBI indica que adultos com 60 anos ou mais nos EUA perderam um valor combinado de 4,8 bilh\u00f5es de d\u00f3lares em golpes somente em\u00a0 2024. Criminosos usam uma variedade de t\u00e1ticas para ganhar a confian\u00e7a das pessoas e, em determinadas circunst\u00e2ncias, comprometem suas contas online, muitas vezes com o objetivo de atrair seus contatos pr\u00f3ximos para esquemas fraudulentos. Neste M\u00eas da Conscientiza\u00e7\u00e3o sobre Seguran\u00e7a Cibern\u00e9tica, como parte de nossa campanha global cont\u00ednua de conscientiza\u00e7\u00e3o contra golpes, estamos compartilhando as \u00faltimas tend\u00eancias em tentativas de golpe direcionadas a idosos, novas ferramentas de seguran\u00e7a e dicas sobre como identificar e evitar a intera\u00e7\u00e3o com golpistas online. Tentativas de golpe em que se deve prestar aten\u00e7\u00e3o Al\u00e9m de nossas investiga\u00e7\u00f5es cont\u00ednuas, fizemos uma parceria com pesquisadores de c\u00f3digo aberto da Graphika para encontrar e interromper tentativas de golpe direcionadas a idosos na Internet. Quando essas situa\u00e7\u00f5es\u00a0 apareceram em nossos aplicativos, tomamos medidas: bloqueamos os sites dos golpistas em nossas plataformas e exclu\u00edmos suas contas. Servi\u00e7os falsos de reforma de casas e de renegocia\u00e7\u00e3o de d\u00edvidas: Os golpistas criaram sites destinados a solicitar informa\u00e7\u00f5es pessoais sob o pretexto de oferecer benef\u00edcios governamentais fict\u00edcios para idosos, incluindo renegocia\u00e7\u00e3o de d\u00edvidas e reformas residenciais a baixo custo ou sem custo. Eles tentaram atrair pessoas para esses sites usando an\u00fancios online, inclusive no Facebook e no Google. Servi\u00e7os fraudulentos de recupera\u00e7\u00e3o de dinheiro: Golpistas criaram sites se passando pelo portal oficial do Centro de Queixas de Crimes na Internet (IC3) do FBI, sob o pretexto de ajudar pessoas a recuperar fundos, inclusive de golpes de criptomoedas. Eles tamb\u00e9m mantiveram contas falsas em v\u00e1rios servi\u00e7os, incluindo Facebook, Instagram, Telegram, Threads, TikTok, YouTube e X, se passando por agentes que podem ajudar as v\u00edtimas de fraudes a recuperar seu dinheiro. Servi\u00e7o falso de atendimento ao cliente: Os golpistas criaram contas online e p\u00e1ginas no Facebook fingindo ser representantes de atendimento ao cliente de companhias a\u00e9reas, ag\u00eancias de viagens, bancos e outros. Eles responderam aos coment\u00e1rios nas postagens das marcas oficiais na tentativa de redirecionar as pessoas para mensagens diretas ou formul\u00e1rios do Google, sob o pretexto de processar o reembolso. Dicas para Idosos: Mantendo-se a Salvo de Golpes Comuns Tenha cuidado com mensagens ou chamadas de voz n\u00e3o solicitadas. Nunca compartilhe informa\u00e7\u00f5es pessoais ou financeiras, como seu n\u00famero de documento ou n\u00fameros de contas, em resposta a liga\u00e7\u00f5es, e-mails ou mensagens de texto inesperadas. Empresas leg\u00edtimas e \u00f3rg\u00e3os governamentais n\u00e3o solicitam essas informa\u00e7\u00f5es do nada. Pare e converse com pessoas em quem voc\u00ea confia. Os golpistas costumam criar uma falsa sensa\u00e7\u00e3o de urg\u00eancia ou p\u00e2nico. Se algu\u00e9m pressionar voc\u00ea a agir rapidamente ou manter as coisas em segredo, isso \u00e9 um sinal de alerta. Pare um momento e converse com algu\u00e9m em quem voc\u00ea confia antes de responder. Use canais oficiais de atendimento ao cliente. Se precisar de ajuda, ligue para a central de atendimento ou acesse o site oficial para verificar as informa\u00e7\u00f5es de contato. N\u00e3o clique em links em emails ou mensagens de texto e evite postar reclama\u00e7\u00f5es em f\u00f3runs p\u00fablicos \u2014 os golpistas costumam monitorar esses espa\u00e7os em busca de v\u00edtimas. Dicas Para as Fam\u00edlias Ajudarem os Idosos a Permanecerem Seguros Online Tomando Medidas Contra Golpistas Redes criminosas internacionais continuam a operar em grande escala globalmente e usam esquemas sofisticados para atingir pessoas \u2014 incluindo idosos \u2014 em muitos setores por meio de mensagens, aplicativos de namoro, redes sociais, criptomoedas e outros aplicativos. N\u00f3s continuamos a buscar e bloquear tentativas de cria\u00e7\u00e3o de contas em nossas plataformas por centros de golpes administrados por\u00a0 organiza\u00e7\u00f5es criminosas. De janeiro a setembro de 2025, nossas equipes de especialistas detectaram e interromperam cerca de 8 milh\u00f5es de contas associadas a esses centros de golpes em Mianmar, Laos, Camboja, Emirados \u00c1rabes Unidos e Filipinas. Al\u00e9m disso, tomamos medidas contra mais de 21.000 P\u00e1ginas e contas que se passavam por suporte ao cliente na tentativa de induzir as pessoas a compartilhar suas informa\u00e7\u00f5es. Trabalhando em Conjunto para Proteger as Pessoas Contra Golpes Os golpistas evoluem constantemente suas t\u00e1ticas para evitar a detec\u00e7\u00e3o e raramente, ou nunca, visam uma \u00fanica plataforma. Isso torna a colabora\u00e7\u00e3o com as autoridades e entre as ind\u00fastrias crucial em nossos esfor\u00e7os contra golpes. A Meta est\u00e1 se unindo ao National Elder Fraud Coordination Center (NEFCC), uma organiza\u00e7\u00e3o sem fins lucrativos que re\u00fane autoridades policiais e empresas como AARP, Amazon, Capital One, Google, Microsoft e Walmart, para combater fraudes que visam idosos. Trabalharemos junto com os membros do NEFCC para combater fraudes em n\u00edvel local, estadual e nacional, com foco na prote\u00e7\u00e3o de idosos, compartilhando recursos e apoiando investiga\u00e7\u00f5es de opera\u00e7\u00f5es fraudulentas em grande escala. Como parte da Tech Against Scams Coalition (TASC), recentemente trabalhamos com o Match Group para desativar grupos do Facebook que alegavam vender contas de namoro para serem usadas em golpes. Os golpistas disfar\u00e7avam os grupos do Facebook como sendo \u201cservi\u00e7os de suporte a relacionamentos&#8221;. No in\u00edcio deste m\u00eas, apoiamos a organiza\u00e7\u00e3o do treinamento \u201cCyber Smart Senior\u201d em Bangcoc (Tail\u00e2ndia), para ajudar a equipar mais de 100 idosos tailandeses e funcion\u00e1rios de 69 centros de sa\u00fade p\u00fablicos com habilidades essenciais de seguran\u00e7a online e alfabetiza\u00e7\u00e3o digital, incluindo como identificar e evitar golpes. O evento foi realizado em parceria com a Administra\u00e7\u00e3o Metropolitana de Bangcoc e o Departamento de Sa\u00fade P\u00fablica, a Ag\u00eancia de Desenvolvimento de Transa\u00e7\u00f5es Eletr\u00f4nicas, o Departamento de Investiga\u00e7\u00e3o de Crimes Cibern\u00e9ticos da Pol\u00edcia Real Tailandesa, a Esta\u00e7\u00e3o de Televis\u00e3o da Pol\u00edcia Nacional e a Funda\u00e7\u00e3o Kenan \u00c1sia. Conscientiza\u00e7\u00e3o Sobre Ciberseguran\u00e7a em Todo o Mundo\u00a0 Estamos realizando esfor\u00e7os cont\u00ednuos de educa\u00e7\u00e3o sobre seguran\u00e7a em todo o mundo com nossos parceiros. Aqui est\u00e3o alguns exemplos recentes: Na Europa, fizemos parceria com v\u00e1rios criadores de conte\u00fado para conscientizar os idosos sobre como identificar e se proteger contra golpes, incluindo Amanda Lamb e mum_and_a_mic no Reino Unido, oliva_sinhache na Espanha e M\u0105dra Babcia e a Escola de Economia SGH de Vars\u00f3via na Pol\u00f4nia. Na \u00cdndia, fizemos parceria com Signboard_wala (tamb\u00e9m conhecido como \u201co cara com a placa\u201d) e v\u00e1rios criadores de com\u00e9dia\u00a0 para aumentar a conscientiza\u00e7\u00e3o sobre golpes em espa\u00e7os p\u00fablicos. A iniciativa utiliza narrativas culturalmente relevantes e visualmente impactantes para destacar os recursos de seguran\u00e7a da Meta, como autentica\u00e7\u00e3o de dois fatores e bloquear e denunciar, al\u00e9m de compartilhar li\u00e7\u00f5es importantes sobre seguran\u00e7a digital. Como parte de nossos esfor\u00e7os cont\u00ednuos para proteger as pessoas contra criminosos, continuaremos a compartilhar atualiza\u00e7\u00f5es regulares sobre nosso trabalho para combater golpes de forma mais ampla, incluindo dicas de seguran\u00e7a e atualiza\u00e7\u00f5es de produtos em nossos aplicativos. Nossas ferramentas antifraude mais recentes\u00a0 No WhatsApp, estamos lan\u00e7ando avisos quando voc\u00ea tenta compartilhar sua tela com um contato desconhecido durante uma chamada de v\u00eddeo. Sabemos que os golpistas podem pressionar seus alvos a compartilhar suas telas para induzi-los a fornecer informa\u00e7\u00f5es confidenciais, incluindo dados banc\u00e1rios ou c\u00f3digos de verifica\u00e7\u00e3o. Com essa nova ferramenta, oferecemos aos nossos usu\u00e1rios mais contexto para identificar e evitar fraudes.\u00a0 No Messenger, estamos testando uma detec\u00e7\u00e3o de golpes mais avan\u00e7ada nas conversas. Quando essa fun\u00e7\u00e3o est\u00e1 ativada e um novo contato envia uma mensagem potencialmente fraudulenta, avisamos voc\u00ea e oferecemos a op\u00e7\u00e3o de enviar as mensagens recentes da conversa para an\u00e1lise por IA. Se um poss\u00edvel golpe for detectado, voc\u00ea receber\u00e1 mais informa\u00e7\u00f5es sobre golpes comuns e vamos sugerir a\u00e7\u00f5es, incluindo bloquear ou denunciar a conta suspeita. Saiba mais aqui. No Facebook, Messenger e WhatsApp, voc\u00ea pode configurar senhas de acesso para tornar o login mais seguro, usando a mesma impress\u00e3o digital, reconhecimento facial ou PIN que voc\u00ea j\u00e1 utiliza em seu dispositivo m\u00f3vel para verificar sua identidade No Facebook e no Instagram, voc\u00ea pode usar o Checkup de Seguran\u00e7a para revisar suas configura\u00e7\u00f5es e obter recomenda\u00e7\u00f5es sobre a\u00e7\u00f5es de seguran\u00e7a, como atualizar sua senha. No WhatsApp, o Checkup de Privacidade orienta voc\u00ea atrav\u00e9s de configura\u00e7\u00f5es importantes de privacidade &#8211; como decidir quem pode adicion\u00e1-lo a grupos &#8211; para ajudar voc\u00ea a escolher o n\u00edvel certo de prote\u00e7\u00e3o, tudo em um s\u00f3 lugar.","protected":false},"author":164097234,"featured_media":26770,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[396542169,396542111,396542114],"tags":[396542264],"class_list":["post-26752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dados-e-privacidade","category-comunidades","category-meta","tag-scams"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00eas da Conscientiza\u00e7\u00e3o sobre Ciberseguran\u00e7a: Ajudando idosos a evitar golpes online | Sobre a Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00eas da Conscientiza\u00e7\u00e3o sobre Ciberseguran\u00e7a: Ajudando idosos a evitar golpes online | Sobre a Meta\" \/>\n<meta property=\"og:description\" content=\"O Relat\u00f3rio de Crimes Cibern\u00e9ticos de 2024 do FBI indica que adultos com 60 anos ou mais nos EUA perderam um valor combinado de 4,8 bilh\u00f5es de d\u00f3lares em golpes somente em\u00a0 2024. Criminosos usam uma variedade de t\u00e1ticas para ganhar a confian\u00e7a das pessoas e, em determinadas circunst\u00e2ncias, comprometem suas contas online, muitas vezes com o objetivo de atrair seus contatos pr\u00f3ximos para esquemas fraudulentos. Neste M\u00eas da Conscientiza\u00e7\u00e3o sobre Seguran\u00e7a Cibern\u00e9tica, como parte de nossa campanha global cont\u00ednua de conscientiza\u00e7\u00e3o contra golpes, estamos compartilhando as \u00faltimas tend\u00eancias em tentativas de golpe direcionadas a idosos, novas ferramentas de seguran\u00e7a e dicas sobre como identificar e evitar a intera\u00e7\u00e3o com golpistas online. Tentativas de golpe em que se deve prestar aten\u00e7\u00e3o Al\u00e9m de nossas investiga\u00e7\u00f5es cont\u00ednuas, fizemos uma parceria com pesquisadores de c\u00f3digo aberto da Graphika para encontrar e interromper tentativas de golpe direcionadas a idosos na Internet. Quando essas situa\u00e7\u00f5es\u00a0 apareceram em nossos aplicativos, tomamos medidas: bloqueamos os sites dos golpistas em nossas plataformas e exclu\u00edmos suas contas. Servi\u00e7os falsos de reforma de casas e de renegocia\u00e7\u00e3o de d\u00edvidas: Os golpistas criaram sites destinados a solicitar informa\u00e7\u00f5es pessoais sob o pretexto de oferecer benef\u00edcios governamentais fict\u00edcios para idosos, incluindo renegocia\u00e7\u00e3o de d\u00edvidas e reformas residenciais a baixo custo ou sem custo. Eles tentaram atrair pessoas para esses sites usando an\u00fancios online, inclusive no Facebook e no Google. Servi\u00e7os fraudulentos de recupera\u00e7\u00e3o de dinheiro: Golpistas criaram sites se passando pelo portal oficial do Centro de Queixas de Crimes na Internet (IC3) do FBI, sob o pretexto de ajudar pessoas a recuperar fundos, inclusive de golpes de criptomoedas. Eles tamb\u00e9m mantiveram contas falsas em v\u00e1rios servi\u00e7os, incluindo Facebook, Instagram, Telegram, Threads, TikTok, YouTube e X, se passando por agentes que podem ajudar as v\u00edtimas de fraudes a recuperar seu dinheiro. Servi\u00e7o falso de atendimento ao cliente: Os golpistas criaram contas online e p\u00e1ginas no Facebook fingindo ser representantes de atendimento ao cliente de companhias a\u00e9reas, ag\u00eancias de viagens, bancos e outros. Eles responderam aos coment\u00e1rios nas postagens das marcas oficiais na tentativa de redirecionar as pessoas para mensagens diretas ou formul\u00e1rios do Google, sob o pretexto de processar o reembolso. Dicas para Idosos: Mantendo-se a Salvo de Golpes Comuns Tenha cuidado com mensagens ou chamadas de voz n\u00e3o solicitadas. Nunca compartilhe informa\u00e7\u00f5es pessoais ou financeiras, como seu n\u00famero de documento ou n\u00fameros de contas, em resposta a liga\u00e7\u00f5es, e-mails ou mensagens de texto inesperadas. Empresas leg\u00edtimas e \u00f3rg\u00e3os governamentais n\u00e3o solicitam essas informa\u00e7\u00f5es do nada. Pare e converse com pessoas em quem voc\u00ea confia. Os golpistas costumam criar uma falsa sensa\u00e7\u00e3o de urg\u00eancia ou p\u00e2nico. Se algu\u00e9m pressionar voc\u00ea a agir rapidamente ou manter as coisas em segredo, isso \u00e9 um sinal de alerta. Pare um momento e converse com algu\u00e9m em quem voc\u00ea confia antes de responder. Use canais oficiais de atendimento ao cliente. Se precisar de ajuda, ligue para a central de atendimento ou acesse o site oficial para verificar as informa\u00e7\u00f5es de contato. N\u00e3o clique em links em emails ou mensagens de texto e evite postar reclama\u00e7\u00f5es em f\u00f3runs p\u00fablicos \u2014 os golpistas costumam monitorar esses espa\u00e7os em busca de v\u00edtimas. Dicas Para as Fam\u00edlias Ajudarem os Idosos a Permanecerem Seguros Online Tomando Medidas Contra Golpistas Redes criminosas internacionais continuam a operar em grande escala globalmente e usam esquemas sofisticados para atingir pessoas \u2014 incluindo idosos \u2014 em muitos setores por meio de mensagens, aplicativos de namoro, redes sociais, criptomoedas e outros aplicativos. N\u00f3s continuamos a buscar e bloquear tentativas de cria\u00e7\u00e3o de contas em nossas plataformas por centros de golpes administrados por\u00a0 organiza\u00e7\u00f5es criminosas. De janeiro a setembro de 2025, nossas equipes de especialistas detectaram e interromperam cerca de 8 milh\u00f5es de contas associadas a esses centros de golpes em Mianmar, Laos, Camboja, Emirados \u00c1rabes Unidos e Filipinas. Al\u00e9m disso, tomamos medidas contra mais de 21.000 P\u00e1ginas e contas que se passavam por suporte ao cliente na tentativa de induzir as pessoas a compartilhar suas informa\u00e7\u00f5es. Trabalhando em Conjunto para Proteger as Pessoas Contra Golpes Os golpistas evoluem constantemente suas t\u00e1ticas para evitar a detec\u00e7\u00e3o e raramente, ou nunca, visam uma \u00fanica plataforma. Isso torna a colabora\u00e7\u00e3o com as autoridades e entre as ind\u00fastrias crucial em nossos esfor\u00e7os contra golpes. A Meta est\u00e1 se unindo ao National Elder Fraud Coordination Center (NEFCC), uma organiza\u00e7\u00e3o sem fins lucrativos que re\u00fane autoridades policiais e empresas como AARP, Amazon, Capital One, Google, Microsoft e Walmart, para combater fraudes que visam idosos. Trabalharemos junto com os membros do NEFCC para combater fraudes em n\u00edvel local, estadual e nacional, com foco na prote\u00e7\u00e3o de idosos, compartilhando recursos e apoiando investiga\u00e7\u00f5es de opera\u00e7\u00f5es fraudulentas em grande escala. Como parte da Tech Against Scams Coalition (TASC), recentemente trabalhamos com o Match Group para desativar grupos do Facebook que alegavam vender contas de namoro para serem usadas em golpes. Os golpistas disfar\u00e7avam os grupos do Facebook como sendo \u201cservi\u00e7os de suporte a relacionamentos&#8221;. No in\u00edcio deste m\u00eas, apoiamos a organiza\u00e7\u00e3o do treinamento \u201cCyber Smart Senior\u201d em Bangcoc (Tail\u00e2ndia), para ajudar a equipar mais de 100 idosos tailandeses e funcion\u00e1rios de 69 centros de sa\u00fade p\u00fablicos com habilidades essenciais de seguran\u00e7a online e alfabetiza\u00e7\u00e3o digital, incluindo como identificar e evitar golpes. O evento foi realizado em parceria com a Administra\u00e7\u00e3o Metropolitana de Bangcoc e o Departamento de Sa\u00fade P\u00fablica, a Ag\u00eancia de Desenvolvimento de Transa\u00e7\u00f5es Eletr\u00f4nicas, o Departamento de Investiga\u00e7\u00e3o de Crimes Cibern\u00e9ticos da Pol\u00edcia Real Tailandesa, a Esta\u00e7\u00e3o de Televis\u00e3o da Pol\u00edcia Nacional e a Funda\u00e7\u00e3o Kenan \u00c1sia. Conscientiza\u00e7\u00e3o Sobre Ciberseguran\u00e7a em Todo o Mundo\u00a0 Estamos realizando esfor\u00e7os cont\u00ednuos de educa\u00e7\u00e3o sobre seguran\u00e7a em todo o mundo com nossos parceiros. Aqui est\u00e3o alguns exemplos recentes: Na Europa, fizemos parceria com v\u00e1rios criadores de conte\u00fado para conscientizar os idosos sobre como identificar e se proteger contra golpes, incluindo Amanda Lamb e mum_and_a_mic no Reino Unido, oliva_sinhache na Espanha e M\u0105dra Babcia e a Escola de Economia SGH de Vars\u00f3via na Pol\u00f4nia. Na \u00cdndia, fizemos parceria com Signboard_wala (tamb\u00e9m conhecido como \u201co cara com a placa\u201d) e v\u00e1rios criadores de com\u00e9dia\u00a0 para aumentar a conscientiza\u00e7\u00e3o sobre golpes em espa\u00e7os p\u00fablicos. A iniciativa utiliza narrativas culturalmente relevantes e visualmente impactantes para destacar os recursos de seguran\u00e7a da Meta, como autentica\u00e7\u00e3o de dois fatores e bloquear e denunciar, al\u00e9m de compartilhar li\u00e7\u00f5es importantes sobre seguran\u00e7a digital. Como parte de nossos esfor\u00e7os cont\u00ednuos para proteger as pessoas contra criminosos, continuaremos a compartilhar atualiza\u00e7\u00f5es regulares sobre nosso trabalho para combater golpes de forma mais ampla, incluindo dicas de seguran\u00e7a e atualiza\u00e7\u00f5es de produtos em nossos aplicativos. Nossas ferramentas antifraude mais recentes\u00a0 No WhatsApp, estamos lan\u00e7ando avisos quando voc\u00ea tenta compartilhar sua tela com um contato desconhecido durante uma chamada de v\u00eddeo. Sabemos que os golpistas podem pressionar seus alvos a compartilhar suas telas para induzi-los a fornecer informa\u00e7\u00f5es confidenciais, incluindo dados banc\u00e1rios ou c\u00f3digos de verifica\u00e7\u00e3o. Com essa nova ferramenta, oferecemos aos nossos usu\u00e1rios mais contexto para identificar e evitar fraudes.\u00a0 No Messenger, estamos testando uma detec\u00e7\u00e3o de golpes mais avan\u00e7ada nas conversas. Quando essa fun\u00e7\u00e3o est\u00e1 ativada e um novo contato envia uma mensagem potencialmente fraudulenta, avisamos voc\u00ea e oferecemos a op\u00e7\u00e3o de enviar as mensagens recentes da conversa para an\u00e1lise por IA. Se um poss\u00edvel golpe for detectado, voc\u00ea receber\u00e1 mais informa\u00e7\u00f5es sobre golpes comuns e vamos sugerir a\u00e7\u00f5es, incluindo bloquear ou denunciar a conta suspeita. Saiba mais aqui. No Facebook, Messenger e WhatsApp, voc\u00ea pode configurar senhas de acesso para tornar o login mais seguro, usando a mesma impress\u00e3o digital, reconhecimento facial ou PIN que voc\u00ea j\u00e1 utiliza em seu dispositivo m\u00f3vel para verificar sua identidade No Facebook e no Instagram, voc\u00ea pode usar o Checkup de Seguran\u00e7a para revisar suas configura\u00e7\u00f5es e obter recomenda\u00e7\u00f5es sobre a\u00e7\u00f5es de seguran\u00e7a, como atualizar sua senha. No WhatsApp, o Checkup de Privacidade orienta voc\u00ea atrav\u00e9s de configura\u00e7\u00f5es importantes de privacidade &#8211; como decidir quem pode adicion\u00e1-lo a grupos &#8211; para ajudar voc\u00ea a escolher o n\u00edvel certo de prote\u00e7\u00e3o, tudo em um s\u00f3 lugar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre a Meta\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-21T12:52:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T14:14:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Cybersecurity-Awareness-Month_Header.jpg?resize=1024,576\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vivilusor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/\"},\"author\":\"Facebook company\",\"headline\":\"M\u00eas da Conscientiza\u00e7\u00e3o sobre Ciberseguran\u00e7a: Ajudando idosos a evitar golpes online\",\"datePublished\":\"2025-10-21T12:52:55+00:00\",\"dateModified\":\"2025-10-22T14:14:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/\"},\"wordCount\":1500,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Cybersecurity-Awareness-Month_Header.jpg?fit=1920%2C1080\",\"keywords\":[\"scams;\"],\"articleSection\":[\"Dados e Privacidade\",\"Fortalecendo Comunidades\",\"Meta\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/\",\"url\":\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/\",\"name\":\"M\u00eas da Conscientiza\u00e7\u00e3o sobre Ciberseguran\u00e7a: Ajudando idosos a evitar golpes online | Sobre a Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Cybersecurity-Awareness-Month_Header.jpg?fit=1920%2C1080\",\"datePublished\":\"2025-10-21T12:52:55+00:00\",\"dateModified\":\"2025-10-22T14:14:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/\"]}],\"author\":\"Sobre a Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#primaryimage\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Cybersecurity-Awareness-Month_Header.jpg?fit=1920%2C1080\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Cybersecurity-Awareness-Month_Header.jpg?fit=1920%2C1080\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00eas da Conscientiza\u00e7\u00e3o sobre Ciberseguran\u00e7a: Ajudando idosos a evitar golpes online\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/br\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"Sobre a Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/br\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00eas da Conscientiza\u00e7\u00e3o sobre Ciberseguran\u00e7a: Ajudando idosos a evitar golpes online | Sobre a Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/","og_locale":"pt_BR","og_type":"article","og_title":"M\u00eas da Conscientiza\u00e7\u00e3o sobre Ciberseguran\u00e7a: Ajudando idosos a evitar golpes online | Sobre a Meta","og_description":"O Relat\u00f3rio de Crimes Cibern\u00e9ticos de 2024 do FBI indica que adultos com 60 anos ou mais nos EUA perderam um valor combinado de 4,8 bilh\u00f5es de d\u00f3lares em golpes somente em\u00a0 2024. Criminosos usam uma variedade de t\u00e1ticas para ganhar a confian\u00e7a das pessoas e, em determinadas circunst\u00e2ncias, comprometem suas contas online, muitas vezes com o objetivo de atrair seus contatos pr\u00f3ximos para esquemas fraudulentos. Neste M\u00eas da Conscientiza\u00e7\u00e3o sobre Seguran\u00e7a Cibern\u00e9tica, como parte de nossa campanha global cont\u00ednua de conscientiza\u00e7\u00e3o contra golpes, estamos compartilhando as \u00faltimas tend\u00eancias em tentativas de golpe direcionadas a idosos, novas ferramentas de seguran\u00e7a e dicas sobre como identificar e evitar a intera\u00e7\u00e3o com golpistas online. Tentativas de golpe em que se deve prestar aten\u00e7\u00e3o Al\u00e9m de nossas investiga\u00e7\u00f5es cont\u00ednuas, fizemos uma parceria com pesquisadores de c\u00f3digo aberto da Graphika para encontrar e interromper tentativas de golpe direcionadas a idosos na Internet. Quando essas situa\u00e7\u00f5es\u00a0 apareceram em nossos aplicativos, tomamos medidas: bloqueamos os sites dos golpistas em nossas plataformas e exclu\u00edmos suas contas. Servi\u00e7os falsos de reforma de casas e de renegocia\u00e7\u00e3o de d\u00edvidas: Os golpistas criaram sites destinados a solicitar informa\u00e7\u00f5es pessoais sob o pretexto de oferecer benef\u00edcios governamentais fict\u00edcios para idosos, incluindo renegocia\u00e7\u00e3o de d\u00edvidas e reformas residenciais a baixo custo ou sem custo. Eles tentaram atrair pessoas para esses sites usando an\u00fancios online, inclusive no Facebook e no Google. Servi\u00e7os fraudulentos de recupera\u00e7\u00e3o de dinheiro: Golpistas criaram sites se passando pelo portal oficial do Centro de Queixas de Crimes na Internet (IC3) do FBI, sob o pretexto de ajudar pessoas a recuperar fundos, inclusive de golpes de criptomoedas. Eles tamb\u00e9m mantiveram contas falsas em v\u00e1rios servi\u00e7os, incluindo Facebook, Instagram, Telegram, Threads, TikTok, YouTube e X, se passando por agentes que podem ajudar as v\u00edtimas de fraudes a recuperar seu dinheiro. Servi\u00e7o falso de atendimento ao cliente: Os golpistas criaram contas online e p\u00e1ginas no Facebook fingindo ser representantes de atendimento ao cliente de companhias a\u00e9reas, ag\u00eancias de viagens, bancos e outros. Eles responderam aos coment\u00e1rios nas postagens das marcas oficiais na tentativa de redirecionar as pessoas para mensagens diretas ou formul\u00e1rios do Google, sob o pretexto de processar o reembolso. Dicas para Idosos: Mantendo-se a Salvo de Golpes Comuns Tenha cuidado com mensagens ou chamadas de voz n\u00e3o solicitadas. Nunca compartilhe informa\u00e7\u00f5es pessoais ou financeiras, como seu n\u00famero de documento ou n\u00fameros de contas, em resposta a liga\u00e7\u00f5es, e-mails ou mensagens de texto inesperadas. Empresas leg\u00edtimas e \u00f3rg\u00e3os governamentais n\u00e3o solicitam essas informa\u00e7\u00f5es do nada. Pare e converse com pessoas em quem voc\u00ea confia. Os golpistas costumam criar uma falsa sensa\u00e7\u00e3o de urg\u00eancia ou p\u00e2nico. Se algu\u00e9m pressionar voc\u00ea a agir rapidamente ou manter as coisas em segredo, isso \u00e9 um sinal de alerta. Pare um momento e converse com algu\u00e9m em quem voc\u00ea confia antes de responder. Use canais oficiais de atendimento ao cliente. Se precisar de ajuda, ligue para a central de atendimento ou acesse o site oficial para verificar as informa\u00e7\u00f5es de contato. N\u00e3o clique em links em emails ou mensagens de texto e evite postar reclama\u00e7\u00f5es em f\u00f3runs p\u00fablicos \u2014 os golpistas costumam monitorar esses espa\u00e7os em busca de v\u00edtimas. Dicas Para as Fam\u00edlias Ajudarem os Idosos a Permanecerem Seguros Online Tomando Medidas Contra Golpistas Redes criminosas internacionais continuam a operar em grande escala globalmente e usam esquemas sofisticados para atingir pessoas \u2014 incluindo idosos \u2014 em muitos setores por meio de mensagens, aplicativos de namoro, redes sociais, criptomoedas e outros aplicativos. N\u00f3s continuamos a buscar e bloquear tentativas de cria\u00e7\u00e3o de contas em nossas plataformas por centros de golpes administrados por\u00a0 organiza\u00e7\u00f5es criminosas. De janeiro a setembro de 2025, nossas equipes de especialistas detectaram e interromperam cerca de 8 milh\u00f5es de contas associadas a esses centros de golpes em Mianmar, Laos, Camboja, Emirados \u00c1rabes Unidos e Filipinas. Al\u00e9m disso, tomamos medidas contra mais de 21.000 P\u00e1ginas e contas que se passavam por suporte ao cliente na tentativa de induzir as pessoas a compartilhar suas informa\u00e7\u00f5es. Trabalhando em Conjunto para Proteger as Pessoas Contra Golpes Os golpistas evoluem constantemente suas t\u00e1ticas para evitar a detec\u00e7\u00e3o e raramente, ou nunca, visam uma \u00fanica plataforma. Isso torna a colabora\u00e7\u00e3o com as autoridades e entre as ind\u00fastrias crucial em nossos esfor\u00e7os contra golpes. A Meta est\u00e1 se unindo ao National Elder Fraud Coordination Center (NEFCC), uma organiza\u00e7\u00e3o sem fins lucrativos que re\u00fane autoridades policiais e empresas como AARP, Amazon, Capital One, Google, Microsoft e Walmart, para combater fraudes que visam idosos. Trabalharemos junto com os membros do NEFCC para combater fraudes em n\u00edvel local, estadual e nacional, com foco na prote\u00e7\u00e3o de idosos, compartilhando recursos e apoiando investiga\u00e7\u00f5es de opera\u00e7\u00f5es fraudulentas em grande escala. Como parte da Tech Against Scams Coalition (TASC), recentemente trabalhamos com o Match Group para desativar grupos do Facebook que alegavam vender contas de namoro para serem usadas em golpes. Os golpistas disfar\u00e7avam os grupos do Facebook como sendo \u201cservi\u00e7os de suporte a relacionamentos&#8221;. No in\u00edcio deste m\u00eas, apoiamos a organiza\u00e7\u00e3o do treinamento \u201cCyber Smart Senior\u201d em Bangcoc (Tail\u00e2ndia), para ajudar a equipar mais de 100 idosos tailandeses e funcion\u00e1rios de 69 centros de sa\u00fade p\u00fablicos com habilidades essenciais de seguran\u00e7a online e alfabetiza\u00e7\u00e3o digital, incluindo como identificar e evitar golpes. O evento foi realizado em parceria com a Administra\u00e7\u00e3o Metropolitana de Bangcoc e o Departamento de Sa\u00fade P\u00fablica, a Ag\u00eancia de Desenvolvimento de Transa\u00e7\u00f5es Eletr\u00f4nicas, o Departamento de Investiga\u00e7\u00e3o de Crimes Cibern\u00e9ticos da Pol\u00edcia Real Tailandesa, a Esta\u00e7\u00e3o de Televis\u00e3o da Pol\u00edcia Nacional e a Funda\u00e7\u00e3o Kenan \u00c1sia. Conscientiza\u00e7\u00e3o Sobre Ciberseguran\u00e7a em Todo o Mundo\u00a0 Estamos realizando esfor\u00e7os cont\u00ednuos de educa\u00e7\u00e3o sobre seguran\u00e7a em todo o mundo com nossos parceiros. Aqui est\u00e3o alguns exemplos recentes: Na Europa, fizemos parceria com v\u00e1rios criadores de conte\u00fado para conscientizar os idosos sobre como identificar e se proteger contra golpes, incluindo Amanda Lamb e mum_and_a_mic no Reino Unido, oliva_sinhache na Espanha e M\u0105dra Babcia e a Escola de Economia SGH de Vars\u00f3via na Pol\u00f4nia. Na \u00cdndia, fizemos parceria com Signboard_wala (tamb\u00e9m conhecido como \u201co cara com a placa\u201d) e v\u00e1rios criadores de com\u00e9dia\u00a0 para aumentar a conscientiza\u00e7\u00e3o sobre golpes em espa\u00e7os p\u00fablicos. A iniciativa utiliza narrativas culturalmente relevantes e visualmente impactantes para destacar os recursos de seguran\u00e7a da Meta, como autentica\u00e7\u00e3o de dois fatores e bloquear e denunciar, al\u00e9m de compartilhar li\u00e7\u00f5es importantes sobre seguran\u00e7a digital. Como parte de nossos esfor\u00e7os cont\u00ednuos para proteger as pessoas contra criminosos, continuaremos a compartilhar atualiza\u00e7\u00f5es regulares sobre nosso trabalho para combater golpes de forma mais ampla, incluindo dicas de seguran\u00e7a e atualiza\u00e7\u00f5es de produtos em nossos aplicativos. Nossas ferramentas antifraude mais recentes\u00a0 No WhatsApp, estamos lan\u00e7ando avisos quando voc\u00ea tenta compartilhar sua tela com um contato desconhecido durante uma chamada de v\u00eddeo. Sabemos que os golpistas podem pressionar seus alvos a compartilhar suas telas para induzi-los a fornecer informa\u00e7\u00f5es confidenciais, incluindo dados banc\u00e1rios ou c\u00f3digos de verifica\u00e7\u00e3o. Com essa nova ferramenta, oferecemos aos nossos usu\u00e1rios mais contexto para identificar e evitar fraudes.\u00a0 No Messenger, estamos testando uma detec\u00e7\u00e3o de golpes mais avan\u00e7ada nas conversas. Quando essa fun\u00e7\u00e3o est\u00e1 ativada e um novo contato envia uma mensagem potencialmente fraudulenta, avisamos voc\u00ea e oferecemos a op\u00e7\u00e3o de enviar as mensagens recentes da conversa para an\u00e1lise por IA. Se um poss\u00edvel golpe for detectado, voc\u00ea receber\u00e1 mais informa\u00e7\u00f5es sobre golpes comuns e vamos sugerir a\u00e7\u00f5es, incluindo bloquear ou denunciar a conta suspeita. Saiba mais aqui. No Facebook, Messenger e WhatsApp, voc\u00ea pode configurar senhas de acesso para tornar o login mais seguro, usando a mesma impress\u00e3o digital, reconhecimento facial ou PIN que voc\u00ea j\u00e1 utiliza em seu dispositivo m\u00f3vel para verificar sua identidade No Facebook e no Instagram, voc\u00ea pode usar o Checkup de Seguran\u00e7a para revisar suas configura\u00e7\u00f5es e obter recomenda\u00e7\u00f5es sobre a\u00e7\u00f5es de seguran\u00e7a, como atualizar sua senha. No WhatsApp, o Checkup de Privacidade orienta voc\u00ea atrav\u00e9s de configura\u00e7\u00f5es importantes de privacidade &#8211; como decidir quem pode adicion\u00e1-lo a grupos &#8211; para ajudar voc\u00ea a escolher o n\u00edvel certo de prote\u00e7\u00e3o, tudo em um s\u00f3 lugar.","og_url":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/","og_site_name":"Sobre a Meta","article_published_time":"2025-10-21T12:52:55+00:00","article_modified_time":"2025-10-22T14:14:57+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Cybersecurity-Awareness-Month_Header.jpg?resize=1024,576","type":"image\/jpeg"}],"author":"vivilusor","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/"},"author":"Facebook company","headline":"M\u00eas da Conscientiza\u00e7\u00e3o sobre Ciberseguran\u00e7a: Ajudando idosos a evitar golpes online","datePublished":"2025-10-21T12:52:55+00:00","dateModified":"2025-10-22T14:14:57+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/"},"wordCount":1500,"publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Cybersecurity-Awareness-Month_Header.jpg?fit=1920%2C1080","keywords":["scams;"],"articleSection":["Dados e Privacidade","Fortalecendo Comunidades","Meta"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/","url":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/","name":"M\u00eas da Conscientiza\u00e7\u00e3o sobre Ciberseguran\u00e7a: Ajudando idosos a evitar golpes online | Sobre a Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#primaryimage"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Cybersecurity-Awareness-Month_Header.jpg?fit=1920%2C1080","datePublished":"2025-10-21T12:52:55+00:00","dateModified":"2025-10-22T14:14:57+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/"]}],"author":"Sobre a Meta"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#primaryimage","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Cybersecurity-Awareness-Month_Header.jpg?fit=1920%2C1080","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Cybersecurity-Awareness-Month_Header.jpg?fit=1920%2C1080","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/br\/news\/2025\/10\/mes-da-conscientizacao-sobre-ciberseguranca-ajudando-idosos-a-evitar-golpes-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/br\/"},{"@type":"ListItem","position":2,"name":"M\u00eas da Conscientiza\u00e7\u00e3o sobre Ciberseguran\u00e7a: Ajudando idosos a evitar golpes online"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/br\/#website","url":"https:\/\/about.fb.com\/news\/","name":"Sobre a Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/br\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_featured_media_url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Cybersecurity-Awareness-Month_Header.jpg?fit=1920%2C1080","jetpack-related-posts":[{"id":26774,"url":"https:\/\/about.fb.com\/br\/news\/2025\/10\/febraban-e-meta-se-unem-em-campanha-de-conscientizacao-contra-tentativas-de-golpes-online\/","url_meta":{"origin":26752,"position":0},"title":"Febraban e Meta se unem em campanha de conscientiza\u00e7\u00e3o contra tentativas de golpes online","author":"Meta","date":"22\/10\/2025","format":false,"excerpt":"Hoje estamos lan\u00e7ando a campanha \u201cDiga n\u00e3o aos golpes: Sua Seguran\u00e7a \u00e9 Coisa S\u00e9ria\u201d em parceria com a Febraban (Federa\u00e7\u00e3o Brasileira de Bancos),\u00a0 com o objetivo disseminar informa\u00e7\u00f5es \u00fateis de forma leve e acess\u00edvel para conscientizar o p\u00fablico sobre tentativas de golpes e fraudes online.\u00a0 A a\u00e7\u00e3o faz parte da\u2026","rel":"","context":"In &quot;Fortalecendo Comunidades&quot;","block_context":{"text":"Fortalecendo Comunidades","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/comunidades\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=525%2C300 1.5x"},"classes":[]},{"id":26380,"url":"https:\/\/about.fb.com\/br\/news\/2025\/05\/protecao-contra-golpes-de-investimento-e-pagamento-on-line\/","url_meta":{"origin":26752,"position":1},"title":"Prote\u00e7\u00e3o contra golpes de investimento e pagamento on-line","author":"Meta","date":"07\/05\/2025","format":false,"excerpt":"Geralmente, golpistas tentam tirar vantagem de eventos e cen\u00e1rios atuais para aplicar golpes relacionados a investimentos e pagamentos. Eles se aproveitam de temores de recess\u00e3o, mudan\u00e7as no com\u00e9rcio global, volatilidade do mercado de a\u00e7\u00f5es ou novos comportamentos em rela\u00e7\u00e3o a criptomoedas para buscar seus alvos. Esses golpes s\u00e3o projetados para\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/05\/WhatsApp-Image-2025-05-06-at-17.56.41.jpeg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/05\/WhatsApp-Image-2025-05-06-at-17.56.41.jpeg?resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/05\/WhatsApp-Image-2025-05-06-at-17.56.41.jpeg?resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/05\/WhatsApp-Image-2025-05-06-at-17.56.41.jpeg?resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/05\/WhatsApp-Image-2025-05-06-at-17.56.41.jpeg?resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/05\/WhatsApp-Image-2025-05-06-at-17.56.41.jpeg?resize=1400%2C800 4x"},"classes":[]},{"id":27001,"url":"https:\/\/about.fb.com\/br\/news\/2026\/03\/combatendo-golpistas-e-protegendo-pessoas-com-novas-tecnologias-e-parcerias\/","url_meta":{"origin":26752,"position":2},"title":"Combatendo golpistas e protegendo pessoas com novas tecnologias e parcerias","author":"Meta","date":"11\/03\/2026","format":false,"excerpt":"Os golpistas est\u00e3o constantemente evoluindo suas t\u00e1ticas \u2014 e n\u00f3s tamb\u00e9m. Todos os dias, criminosos usam m\u00e9todos cada vez mais sofisticados para enganar pessoas em nossas plataformas e pela Internet. Por isso, estamos anunciando novos investimentos em IA avan\u00e7ada, ferramentas para ajudar as pessoas a identificarem e evitarem golpistas, al\u00e9m\u2026","rel":"","context":"In &quot;Combatendo Desinforma\u00e7\u00e3o&quot;","block_context":{"text":"Combatendo Desinforma\u00e7\u00e3o","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/combatendo-desinformacao\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/03\/Scams.jpg?fit=819%2C460&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/03\/Scams.jpg?fit=819%2C460&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/03\/Scams.jpg?fit=819%2C460&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/03\/Scams.jpg?fit=819%2C460&resize=700%2C400 2x"},"classes":[]},{"id":27189,"url":"https:\/\/about.fb.com\/br\/news\/2026\/05\/protegendo-jogadores-e-torcedores-durante-a-copa-do-mundo-da-fifa-2026\/","url_meta":{"origin":26752,"position":3},"title":"Protegendo jogadores e torcedores durante a Copa do Mundo da FIFA 2026\u2122","author":"Meta","date":"28\/05\/2026","format":false,"excerpt":"Nos pr\u00f3ximos meses, torcedores de futebol ao redor do mundo usar\u00e3o nossos aplicativos para se conectar e viver juntos a Copa do Mundo da FIFA 2026\u2122. Enquanto a maioria estar\u00e1 torcendo por seus times e jogadores favoritos, infelizmente pode haver atores mal-intencionados que tentar\u00e3o atrair outras pessoas para golpes ou\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/HIDDEN_.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/HIDDEN_.png?resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/HIDDEN_.png?resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/HIDDEN_.png?resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/05\/HIDDEN_.png?resize=1050%2C600 3x"},"classes":[]},{"id":26834,"url":"https:\/\/about.fb.com\/br\/news\/2025\/12\/golpes-sao-ruins-para-os-negocios-nossos-esforcos-continuos-para-combater-fraudes\/","url_meta":{"origin":26752,"position":4},"title":"Golpes S\u00e3o Ruins para os Neg\u00f3cios: Nossos esfor\u00e7os cont\u00ednuos para combater fraudes","author":"Meta","date":"03\/12\/2025","format":false,"excerpt":"O aumento dos golpes est\u00e1 ocorrendo em toda a internet \u2014 desde aplicativos de namoro e jogos online, at\u00e9 plataformas de criptomoedas e mensagens de texto. Ningu\u00e9m gosta disso. Nem as pessoas que utilizam nossos servi\u00e7os. Nem os anunciantes. E certamente nem n\u00f3s. Os criminosos sofisticados por tr\u00e1s dos golpes\u2026","rel":"","context":"In &quot;Fortalecendo Comunidades&quot;","block_context":{"text":"Fortalecendo Comunidades","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/comunidades\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/GASA-Scams-Work_Header.jpg?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/GASA-Scams-Work_Header.jpg?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/GASA-Scams-Work_Header.jpg?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/GASA-Scams-Work_Header.jpg?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/GASA-Scams-Work_Header.jpg?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/GASA-Scams-Work_Header.jpg?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]},{"id":26558,"url":"https:\/\/about.fb.com\/br\/news\/2025\/08\/novas-ferramentas-e-dicas-do-whatsapp-para-combater-os-golpes-por-mensagem\/","url_meta":{"origin":26752,"position":5},"title":"Novas ferramentas e dicas do WhatsApp para combater os golpes por mensagem","author":"Meta","date":"05\/08\/2025","format":false,"excerpt":"Todos os dias, criminosos que aplicam golpes tentam se aproveitar da ansiedade das pessoas em rela\u00e7\u00e3o \u00e0 economia para engan\u00e1-las (dispon\u00edvel em ingl\u00eas) com ofertas que s\u00e3o boas demais para ser verdade e esquemas de pir\u00e2mide para ganhar dinheiro f\u00e1cil. Como parte dos nossos esfor\u00e7os cont\u00ednuos para proteger as pessoas\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/Anti-Scam-Bundle-PSA_Whatsapp_Header.jpg?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/Anti-Scam-Bundle-PSA_Whatsapp_Header.jpg?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/Anti-Scam-Bundle-PSA_Whatsapp_Header.jpg?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/Anti-Scam-Bundle-PSA_Whatsapp_Header.jpg?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/Anti-Scam-Bundle-PSA_Whatsapp_Header.jpg?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/08\/Anti-Scam-Bundle-PSA_Whatsapp_Header.jpg?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/26752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/users\/164097234"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/comments?post=26752"}],"version-history":[{"count":13,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/26752\/revisions"}],"predecessor-version":[{"id":26772,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/26752\/revisions\/26772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/media\/26770"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/media?parent=26752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/categories?post=26752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/tags?post=26752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}