{"id":26084,"date":"2025-01-07T10:04:03","date_gmt":"2025-01-07T13:04:03","guid":{"rendered":"https:\/\/about.fb.com\/br\/?p=26084"},"modified":"2025-01-07T10:04:03","modified_gmt":"2025-01-07T13:04:03","slug":"mais-expressao-e-menos-erros","status":"publish","type":"post","link":"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/","title":{"rendered":"Mais express\u00e3o e menos erros"},"content":{"rendered":"<p><span style=\"font-weight: 400\">As plataformas da Meta s\u00e3o constru\u00eddas para serem lugares em que as pessoas podem se expressar livremente. Isso pode ser um pouco ca\u00f3tico. Em plataformas nas quais bilh\u00f5es de pessoas podem ter voz, tudo o que \u00e9 bom, ruim e feio est\u00e1 exposto. Mas isso \u00e9 a livre express\u00e3o.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Em 2019, em seu discurso na Universidade de Georgetown, Mark Zuckerberg argumentou que a liberdade de express\u00e3o tem sido a for\u00e7a motriz por tr\u00e1s do progresso da sociedade norte-americana e ao redor do mundo, ao passo que inibir a fala, independentemente de raz\u00f5es bem-intencionadas para faz\u00ea-lo, \u00e9 algo que frequentemente refor\u00e7a as institui\u00e7\u00f5es e as estruturas de poder existentes em vez de empoderar as pessoas. Ele disse: &#8220;H\u00e1 quem acredite que dar mais voz \u00e0s pessoas est\u00e1 provocando cis\u00f5es em vez de nos unir. Mais pessoas em todo o espectro acreditam que atingir os resultados pol\u00edticos que acham que importam \u00e9 mais importante do que cada pessoa ter uma voz. Eu acho que isso \u00e9 perigoso.&#8221;<\/span><\/p>\n<p><span style=\"font-weight: 400\">Nos \u00faltimos anos, desenvolvemos sistemas cada vez mais complexos para gerenciar conte\u00fado em nossas plataformas, em parte como resposta \u00e0 press\u00e3o p\u00fablica e pol\u00edtica para moderar conte\u00fado. Essa abordagem foi longe demais. Embora muitos desses esfor\u00e7os tenham sido bem-intencionados, eles se ampliaram ao longo do tempo at\u00e9 o ponto em que estamos cometendo muitos erros, frustrando nossos usu\u00e1rios e, com frequ\u00eancia, impedindo a livre express\u00e3o que pretendemos viabilizar. Muito conte\u00fado inofensivo \u00e9 censurado, muitas pessoas se veem trancadas injustamente na &#8220;cadeia do Facebook&#8221; e, com frequ\u00eancia, somos lentos em respond\u00ea-las.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Queremos consertar isso e voltar \u00e0quele compromisso fundamental com a livre express\u00e3o. Hoje, estamos fazendo algumas mudan\u00e7as para permanecermos fi\u00e9is a esse ideal.<\/span><\/p>\n<h4><b>Encerramento do programa de verifica\u00e7\u00e3o de fatos e migra\u00e7\u00e3o para Notas da Comunidade<\/b><\/h4>\n<p><span style=\"font-weight: 400\">Quando lan\u00e7amos nosso programa independente de verifica\u00e7\u00e3o de fatos em 2016, fomos claros sobre n\u00e3o querermos ser os \u00e1rbitros da verdade. Adotamos o que consideramos ser a melhor e mais razo\u00e1vel escolha na \u00e9poca, que era deixar essa tarefa para organiza\u00e7\u00f5es independentes de verifica\u00e7\u00e3o de fatos. A inten\u00e7\u00e3o do programa era fornecer \u00e0s pessoas mais contexto e informa\u00e7\u00f5es sobre as coisas que elas veem online, em especial rumores e especula\u00e7\u00f5es que viralizam, para que elas possam julgar por si mesmas o que veem e leem.<\/span><\/p>\n<p><span style=\"font-weight: 400\">No entanto, n\u00e3o foi assim que o processo se desenrolou, especialmente nos Estados Unidos. Especialistas, assim como todos, t\u00eam suas pr\u00f3prias perspectivas, e isso se manifestou nas escolhas que alguns fizeram sobre o que verificar e como. Ao longo do tempo, acabamos por ter muito conte\u00fado sendo verificado que as pessoas entendiam como discurso pol\u00edtico leg\u00edtimo e debate. Nosso sistema ent\u00e3o adicionou consequ\u00eancias reais na forma de r\u00f3tulos intrusivos e distribui\u00e7\u00e3o reduzida. Um programa destinado a dar mais informa\u00e7\u00e3o para as pessoas se tornou, com frequ\u00eancia, uma ferramenta de censura.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Agora estamos mudando essa abordagem. Vamos encerrar o atual programa de verifica\u00e7\u00e3o de fatos com terceiros nos EUA e come\u00e7ar a migrar para um programa de Notas da Comunidade. J\u00e1 vimos essa abordagem funcionar no X \u2013 onde eles empoderam a comunidade para decidir quando postagens s\u00e3o potencialmente enganosas e precisam de mais contexto, e pessoas de uma ampla gama de perspectivas estabelecem que tipo de contexto \u00e9 \u00fatil para outros usu\u00e1rios verem. Acreditamos que essa pode ser uma maneira mais efetiva e diversa de alcan\u00e7ar nossa inten\u00e7\u00e3o original de fornecer \u00e0s pessoas informa\u00e7\u00f5es sobre o que est\u00e3o vendo &#8211; e uma que \u00e9 menos propensa a vieses.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Uma vez que o programa estiver em execu\u00e7\u00e3o, a Meta n\u00e3o escrever\u00e1 Notas da Comunidade ou decidir\u00e1 quais delas ser\u00e3o exibidas. Elas ser\u00e3o escritas e avaliadas por usu\u00e1rios colaboradores.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Assim como fazem no X, as Notas da Comunidade exigir\u00e3o consenso entre pessoas com uma ampla gama de perspectivas para ajudar a prevenir avalia\u00e7\u00f5es tendenciosas.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Pretendemos ser transparentes sobre como diferentes pontos de vista fundamentam as Notas exibidas em nossos aplicativos e estamos trabalhando para encontrar a melhor maneira de compartilhar essa informa\u00e7\u00e3o.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Pessoas interessadas nos Estados Unidos podem se inscrever hoje para ter a oportunidade de estarem entre os primeiros colaboradores para esse programa \u00e0 medida que ele se tornar dispon\u00edvel.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Planejamos implementar as Notas da Comunidade primeiro nos EUA, ao longo dos pr\u00f3ximos meses, e continuaremos a aprimor\u00e1-las ao longo do ano. Enquanto fazemos a transi\u00e7\u00e3o, vamos parar de reduzir a distribui\u00e7\u00e3o deste de conte\u00fado verificado e, em vez de exibir advert\u00eancias em tela cheia nas quais voc\u00ea precisa clicar antes de poder ver a postagem, vamos usar um r\u00f3tulo muito menos intrusivo indicando que h\u00e1 informa\u00e7\u00f5es adicionais sobre o post para quem desejar v\u00ea-las.<\/span><\/p>\n<h4><b>Mais espa\u00e7o para o debate<\/b><\/h4>\n<p><span style=\"font-weight: 400\">Ao longo do tempo, desenvolvemos sistemas complexos para gerenciar conte\u00fado em nossas plataformas, cuja aplica\u00e7\u00e3o tem se tornado cada vez mais complicada. Como resultado, temos exagerado na aplica\u00e7\u00e3o de nossas regras, limitando debate pol\u00edtico leg\u00edtimo e excluindo conte\u00fado trivial, e submetendo muitas pessoas a a\u00e7\u00f5es frustrantes de aplica\u00e7\u00e3o de pol\u00edticas.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Em dezembro de 2024, por exemplo, removemos milh\u00f5es de posts todos os dias. Embora essas medidas representem menos de 1% do conte\u00fado produzido diariamente, acreditamos que de uma a duas em cada 10 dessas a\u00e7\u00f5es podem ter sido equivocadas (ou seja, o conte\u00fado removido pode n\u00e3o ter violado nossas pol\u00edticas). Esse dado n\u00e3o leva em conta as a\u00e7\u00f5es que tomamos para lidar com ataques em larga escala. Planejamos expandir nosso relat\u00f3rio de transpar\u00eancia para compartilhar regularmente n\u00fameros sobre nossos erros, para que as pessoas possam acompanhar nosso progresso. Como parte disso, tamb\u00e9m incluiremos mais detalhes sobre os equ\u00edvocos que cometemos ao aplicar nossas pol\u00edticas de spam.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Queremos reverter a extens\u00e3o dos esfor\u00e7os que tornaram nossas regras muito restritivas e propensas \u00e0 aplica\u00e7\u00e3o excessiva dessas regras. Estamos eliminando uma s\u00e9rie de restri\u00e7\u00f5es em t\u00f3picos como imigra\u00e7\u00e3o, identidade de g\u00eanero e g\u00eanero que s\u00e3o frequentemente objeto de discurso pol\u00edtico e debate. N\u00e3o \u00e9 certo que coisas possam ser ditas na TV ou no plen\u00e1rio do Congresso, mas n\u00e3o em nossas plataformas. Essas mudan\u00e7as de pol\u00edtica podem levar algumas semanas para serem implementadas integralmente.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Tamb\u00e9m vamos mudar como aplicamos nossas pol\u00edticas para reduzir os tipos de erros que respondem pela maioria da censura em nossas plataformas. At\u00e9 agora, temos usado sistemas automatizados para detectar viola\u00e7\u00f5es a pol\u00edticas, mas isso resultou em muito conte\u00fado erroneamente removido e em muito conte\u00fado sendo censurado que n\u00e3o deveria ter sido. Portanto, vamos concentrar o uso desses sistemas para lidar com conte\u00fado ilegal e viola\u00e7\u00f5es de alta severidade, como terrorismo, explora\u00e7\u00e3o sexual infantil, drogas, fraudes e scams. Para viola\u00e7\u00f5es de pol\u00edtica menos graves, vamos nos basear nas den\u00fancias das pessoas antes de tomar qualquer a\u00e7\u00e3o. Tamb\u00e9m reduzimos a visibilidade de muito conte\u00fado que nossos sistemas preveem que pode violar nossas regras Estamos no processo de eliminar muitas dessas restri\u00e7\u00f5es e requerer um grau de confian\u00e7a maior de que o conte\u00fado \u00e9 de fato uma viola\u00e7\u00e3o, al\u00e9m de ajustar nossos sistemas para garantir um n\u00edvel maior de certeza antes que um conte\u00fado seja removido. Como parte dessas mudan\u00e7as, nosso time de Trust and Safety que escreve nossas pol\u00edticas de conte\u00fado e revisa os conte\u00fados sair\u00e1 da Calif\u00f3rnia para o Texas e outras localidades nos EUA.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Geralmente as pessoas t\u00eam a chance de recorrer das nossas decis\u00f5es quando s\u00e3o tomadas medidas corretivas sobre suas contas e conte\u00fados, solicitando que revisemos nossas a\u00e7\u00f5es. No entanto, esse processo pode ser frustrantemente lento e nem sempre chega ao resultado devido. Aumentamos o n\u00famero de pessoas dedicadas a esse trabalho e ampliamos o n\u00famero de casos para os quais exigimos que v\u00e1rios revisores cheguem a um consenso antes de uma remo\u00e7\u00e3o de conte\u00fado. Estamos trabalhando em maneiras de tornar a recupera\u00e7\u00e3o de contas mais direta e testando tecnologia de reconhecimento facial, al\u00e9m de come\u00e7armos a usar modelos de linguagem de larga escala de Intelig\u00eancia Artificial (LLMs) para uma segunda opini\u00e3o sobre alguns conte\u00fados antes de tomarmos medidas.<\/span><\/p>\n<h4><b>Uma abordagem personalizada para conte\u00fado pol\u00edtico<\/b><\/h4>\n<p><span style=\"font-weight: 400\">Desde 2021, temos feito mudan\u00e7as para reduzir a quantidade de conte\u00fado c\u00edvico que as pessoas veem em nossas plataformas &#8211; posts sobre elei\u00e7\u00f5es, pol\u00edtica ou quest\u00f5es sociais. Essas mudan\u00e7as ocorreram com base no feedback dos nossos usu\u00e1rios, que nos disseram que queriam ver menos esse tipo de conte\u00fado. Mas essa medida foi um tanto brusca. Vamos come\u00e7ar a reintroduzir conte\u00fados dessa natureza no Facebook, Instagram e Threads com uma abordagem mais personalizada, para que as pessoas que querem ver mais conte\u00fado pol\u00edtico em seus feeds tenham essa possibilidade.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Estamos constantemente testando como entregamos experi\u00eancias personalizadas e recentemente realizamos testes em torno do conte\u00fado c\u00edvico. Como resultado, vamos come\u00e7ar a tratar o conte\u00fado c\u00edvico das pessoas e P\u00e1ginas que voc\u00ea segue no Facebook da mesma forma que qualquer outro conte\u00fado em seu feed, e passaremos a ranquear e mostrar esse conte\u00fado com base em sinais expl\u00edcitos (por exemplo, curtir um conte\u00fado) e sinais impl\u00edcitos (como visualizar posts) que nos ajudam a prever o que \u00e9 significativo para as pessoas. Tamb\u00e9m vamos recomendar mais conte\u00fado pol\u00edtico com base nesses sinais personalizados, e estamos ampliando as op\u00e7\u00f5es que as pessoas t\u00eam para controlar o quanto desse conte\u00fado elas veem.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Essas mudan\u00e7as s\u00e3o uma tentativa de retornar ao compromisso com a livre express\u00e3o que Mark Zuckerberg estabeleceu em seu discurso na Universidade de Georgetown. Isso significa ser vigilante sobre o impacto que nossas pol\u00edticas e sistemas est\u00e3o tendo na capacidade de as pessoas fazerem sua voz ser ouvida e ter a humildade de mudar nossa abordagem quando sabemos que estamos fazendo a coisa errada.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"As plataformas da Meta s\u00e3o constru\u00eddas para serem lugares em que as pessoas podem se expressar livremente. Isso pode ser um pouco ca\u00f3tico. Em plataformas nas quais bilh\u00f5es de pessoas podem ter voz, tudo o que \u00e9 bom, ruim e feio est\u00e1 exposto. Mas isso \u00e9 a livre express\u00e3o.\u00a0 Em 2019, em seu discurso na Universidade de Georgetown, Mark Zuckerberg argumentou que a liberdade de express\u00e3o tem sido a for\u00e7a motriz por tr\u00e1s do progresso da sociedade norte-americana e ao redor do mundo, ao passo que inibir a fala, independentemente de raz\u00f5es bem-intencionadas para faz\u00ea-lo, \u00e9 algo que frequentemente refor\u00e7a as institui\u00e7\u00f5es e as estruturas de poder existentes em vez de empoderar as pessoas. Ele disse: &#8220;H\u00e1 quem acredite que dar mais voz \u00e0s pessoas est\u00e1 provocando cis\u00f5es em vez de nos unir. Mais pessoas em todo o espectro acreditam que atingir os resultados pol\u00edticos que acham que importam \u00e9 mais importante do que cada pessoa ter uma voz. Eu acho que isso \u00e9 perigoso.&#8221; Nos \u00faltimos anos, desenvolvemos sistemas cada vez mais complexos para gerenciar conte\u00fado em nossas plataformas, em parte como resposta \u00e0 press\u00e3o p\u00fablica e pol\u00edtica para moderar conte\u00fado. Essa abordagem foi longe demais. Embora muitos desses esfor\u00e7os tenham sido bem-intencionados, eles se ampliaram ao longo do tempo at\u00e9 o ponto em que estamos cometendo muitos erros, frustrando nossos usu\u00e1rios e, com frequ\u00eancia, impedindo a livre express\u00e3o que pretendemos viabilizar. Muito conte\u00fado inofensivo \u00e9 censurado, muitas pessoas se veem trancadas injustamente na &#8220;cadeia do Facebook&#8221; e, com frequ\u00eancia, somos lentos em respond\u00ea-las. Queremos consertar isso e voltar \u00e0quele compromisso fundamental com a livre express\u00e3o. Hoje, estamos fazendo algumas mudan\u00e7as para permanecermos fi\u00e9is a esse ideal. Encerramento do programa de verifica\u00e7\u00e3o de fatos e migra\u00e7\u00e3o para Notas da Comunidade Quando lan\u00e7amos nosso programa independente de verifica\u00e7\u00e3o de fatos em 2016, fomos claros sobre n\u00e3o querermos ser os \u00e1rbitros da verdade. Adotamos o que consideramos ser a melhor e mais razo\u00e1vel escolha na \u00e9poca, que era deixar essa tarefa para organiza\u00e7\u00f5es independentes de verifica\u00e7\u00e3o de fatos. A inten\u00e7\u00e3o do programa era fornecer \u00e0s pessoas mais contexto e informa\u00e7\u00f5es sobre as coisas que elas veem online, em especial rumores e especula\u00e7\u00f5es que viralizam, para que elas possam julgar por si mesmas o que veem e leem. No entanto, n\u00e3o foi assim que o processo se desenrolou, especialmente nos Estados Unidos. Especialistas, assim como todos, t\u00eam suas pr\u00f3prias perspectivas, e isso se manifestou nas escolhas que alguns fizeram sobre o que verificar e como. Ao longo do tempo, acabamos por ter muito conte\u00fado sendo verificado que as pessoas entendiam como discurso pol\u00edtico leg\u00edtimo e debate. Nosso sistema ent\u00e3o adicionou consequ\u00eancias reais na forma de r\u00f3tulos intrusivos e distribui\u00e7\u00e3o reduzida. Um programa destinado a dar mais informa\u00e7\u00e3o para as pessoas se tornou, com frequ\u00eancia, uma ferramenta de censura.\u00a0 Agora estamos mudando essa abordagem. Vamos encerrar o atual programa de verifica\u00e7\u00e3o de fatos com terceiros nos EUA e come\u00e7ar a migrar para um programa de Notas da Comunidade. J\u00e1 vimos essa abordagem funcionar no X \u2013 onde eles empoderam a comunidade para decidir quando postagens s\u00e3o potencialmente enganosas e precisam de mais contexto, e pessoas de uma ampla gama de perspectivas estabelecem que tipo de contexto \u00e9 \u00fatil para outros usu\u00e1rios verem. Acreditamos que essa pode ser uma maneira mais efetiva e diversa de alcan\u00e7ar nossa inten\u00e7\u00e3o original de fornecer \u00e0s pessoas informa\u00e7\u00f5es sobre o que est\u00e3o vendo &#8211; e uma que \u00e9 menos propensa a vieses. Uma vez que o programa estiver em execu\u00e7\u00e3o, a Meta n\u00e3o escrever\u00e1 Notas da Comunidade ou decidir\u00e1 quais delas ser\u00e3o exibidas. Elas ser\u00e3o escritas e avaliadas por usu\u00e1rios colaboradores.\u00a0 Assim como fazem no X, as Notas da Comunidade exigir\u00e3o consenso entre pessoas com uma ampla gama de perspectivas para ajudar a prevenir avalia\u00e7\u00f5es tendenciosas. Pretendemos ser transparentes sobre como diferentes pontos de vista fundamentam as Notas exibidas em nossos aplicativos e estamos trabalhando para encontrar a melhor maneira de compartilhar essa informa\u00e7\u00e3o. Pessoas interessadas nos Estados Unidos podem se inscrever hoje para ter a oportunidade de estarem entre os primeiros colaboradores para esse programa \u00e0 medida que ele se tornar dispon\u00edvel. Planejamos implementar as Notas da Comunidade primeiro nos EUA, ao longo dos pr\u00f3ximos meses, e continuaremos a aprimor\u00e1-las ao longo do ano. Enquanto fazemos a transi\u00e7\u00e3o, vamos parar de reduzir a distribui\u00e7\u00e3o deste de conte\u00fado verificado e, em vez de exibir advert\u00eancias em tela cheia nas quais voc\u00ea precisa clicar antes de poder ver a postagem, vamos usar um r\u00f3tulo muito menos intrusivo indicando que h\u00e1 informa\u00e7\u00f5es adicionais sobre o post para quem desejar v\u00ea-las. Mais espa\u00e7o para o debate Ao longo do tempo, desenvolvemos sistemas complexos para gerenciar conte\u00fado em nossas plataformas, cuja aplica\u00e7\u00e3o tem se tornado cada vez mais complicada. Como resultado, temos exagerado na aplica\u00e7\u00e3o de nossas regras, limitando debate pol\u00edtico leg\u00edtimo e excluindo conte\u00fado trivial, e submetendo muitas pessoas a a\u00e7\u00f5es frustrantes de aplica\u00e7\u00e3o de pol\u00edticas. Em dezembro de 2024, por exemplo, removemos milh\u00f5es de posts todos os dias. Embora essas medidas representem menos de 1% do conte\u00fado produzido diariamente, acreditamos que de uma a duas em cada 10 dessas a\u00e7\u00f5es podem ter sido equivocadas (ou seja, o conte\u00fado removido pode n\u00e3o ter violado nossas pol\u00edticas). Esse dado n\u00e3o leva em conta as a\u00e7\u00f5es que tomamos para lidar com ataques em larga escala. Planejamos expandir nosso relat\u00f3rio de transpar\u00eancia para compartilhar regularmente n\u00fameros sobre nossos erros, para que as pessoas possam acompanhar nosso progresso. Como parte disso, tamb\u00e9m incluiremos mais detalhes sobre os equ\u00edvocos que cometemos ao aplicar nossas pol\u00edticas de spam. Queremos reverter a extens\u00e3o dos esfor\u00e7os que tornaram nossas regras muito restritivas e propensas \u00e0 aplica\u00e7\u00e3o excessiva dessas regras. Estamos eliminando uma s\u00e9rie de restri\u00e7\u00f5es em t\u00f3picos como imigra\u00e7\u00e3o, identidade de g\u00eanero e g\u00eanero que s\u00e3o frequentemente objeto de discurso pol\u00edtico e debate. N\u00e3o \u00e9 certo que coisas possam ser ditas na TV ou no plen\u00e1rio do Congresso, mas n\u00e3o em nossas plataformas. Essas mudan\u00e7as de pol\u00edtica podem levar algumas semanas para serem implementadas integralmente. Tamb\u00e9m vamos mudar como aplicamos nossas pol\u00edticas para reduzir os tipos de erros que respondem pela maioria da censura em nossas plataformas. At\u00e9 agora, temos usado sistemas automatizados para detectar viola\u00e7\u00f5es a pol\u00edticas, mas isso resultou em muito conte\u00fado erroneamente removido e em muito conte\u00fado sendo censurado que n\u00e3o deveria ter sido. Portanto, vamos concentrar o uso desses sistemas para lidar com conte\u00fado ilegal e viola\u00e7\u00f5es de alta severidade, como terrorismo, explora\u00e7\u00e3o sexual infantil, drogas, fraudes e scams. Para viola\u00e7\u00f5es de pol\u00edtica menos graves, vamos nos basear nas den\u00fancias das pessoas antes de tomar qualquer a\u00e7\u00e3o. Tamb\u00e9m reduzimos a visibilidade de muito conte\u00fado que nossos sistemas preveem que pode violar nossas regras Estamos no processo de eliminar muitas dessas restri\u00e7\u00f5es e requerer um grau de confian\u00e7a maior de que o conte\u00fado \u00e9 de fato uma viola\u00e7\u00e3o, al\u00e9m de ajustar nossos sistemas para garantir um n\u00edvel maior de certeza antes que um conte\u00fado seja removido. Como parte dessas mudan\u00e7as, nosso time de Trust and Safety que escreve nossas pol\u00edticas de conte\u00fado e revisa os conte\u00fados sair\u00e1 da Calif\u00f3rnia para o Texas e outras localidades nos EUA.\u00a0 Geralmente as pessoas t\u00eam a chance de recorrer das nossas decis\u00f5es quando s\u00e3o tomadas medidas corretivas sobre suas contas e conte\u00fados, solicitando que revisemos nossas a\u00e7\u00f5es. No entanto, esse processo pode ser frustrantemente lento e nem sempre chega ao resultado devido. Aumentamos o n\u00famero de pessoas dedicadas a esse trabalho e ampliamos o n\u00famero de casos para os quais exigimos que v\u00e1rios revisores cheguem a um consenso antes de uma remo\u00e7\u00e3o de conte\u00fado. Estamos trabalhando em maneiras de tornar a recupera\u00e7\u00e3o de contas mais direta e testando tecnologia de reconhecimento facial, al\u00e9m de come\u00e7armos a usar modelos de linguagem de larga escala de Intelig\u00eancia Artificial (LLMs) para uma segunda opini\u00e3o sobre alguns conte\u00fados antes de tomarmos medidas. Uma abordagem personalizada para conte\u00fado pol\u00edtico Desde 2021, temos feito mudan\u00e7as para reduzir a quantidade de conte\u00fado c\u00edvico que as pessoas veem em nossas plataformas &#8211; posts sobre elei\u00e7\u00f5es, pol\u00edtica ou quest\u00f5es sociais. Essas mudan\u00e7as ocorreram com base no feedback dos nossos usu\u00e1rios, que nos disseram que queriam ver menos esse tipo de conte\u00fado. Mas essa medida foi um tanto brusca. Vamos come\u00e7ar a reintroduzir conte\u00fados dessa natureza no Facebook, Instagram e Threads com uma abordagem mais personalizada, para que as pessoas que querem ver mais conte\u00fado pol\u00edtico em seus feeds tenham essa possibilidade. Estamos constantemente testando como entregamos experi\u00eancias personalizadas e recentemente realizamos testes em torno do conte\u00fado c\u00edvico. Como resultado, vamos come\u00e7ar a tratar o conte\u00fado c\u00edvico das pessoas e P\u00e1ginas que voc\u00ea segue no Facebook da mesma forma que qualquer outro conte\u00fado em seu feed, e passaremos a ranquear e mostrar esse conte\u00fado com base em sinais expl\u00edcitos (por exemplo, curtir um conte\u00fado) e sinais impl\u00edcitos (como visualizar posts) que nos ajudam a prever o que \u00e9 significativo para as pessoas. Tamb\u00e9m vamos recomendar mais conte\u00fado pol\u00edtico com base nesses sinais personalizados, e estamos ampliando as op\u00e7\u00f5es que as pessoas t\u00eam para controlar o quanto desse conte\u00fado elas veem. Essas mudan\u00e7as s\u00e3o uma tentativa de retornar ao compromisso com a livre express\u00e3o que Mark Zuckerberg estabeleceu em seu discurso na Universidade de Georgetown. Isso significa ser vigilante sobre o impacto que nossas pol\u00edticas e sistemas est\u00e3o tendo na capacidade de as pessoas fazerem sua voz ser ouvida e ter a humildade de mudar nossa abordagem quando sabemos que estamos fazendo a coisa errada.","protected":false},"author":164097234,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-26084","post","type-post","status-publish","format-standard","hentry","category-recent-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mais express\u00e3o e menos erros | Sobre a Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mais express\u00e3o e menos erros | Sobre a Meta\" \/>\n<meta property=\"og:description\" content=\"As plataformas da Meta s\u00e3o constru\u00eddas para serem lugares em que as pessoas podem se expressar livremente. Isso pode ser um pouco ca\u00f3tico. Em plataformas nas quais bilh\u00f5es de pessoas podem ter voz, tudo o que \u00e9 bom, ruim e feio est\u00e1 exposto. Mas isso \u00e9 a livre express\u00e3o.\u00a0 Em 2019, em seu discurso na Universidade de Georgetown, Mark Zuckerberg argumentou que a liberdade de express\u00e3o tem sido a for\u00e7a motriz por tr\u00e1s do progresso da sociedade norte-americana e ao redor do mundo, ao passo que inibir a fala, independentemente de raz\u00f5es bem-intencionadas para faz\u00ea-lo, \u00e9 algo que frequentemente refor\u00e7a as institui\u00e7\u00f5es e as estruturas de poder existentes em vez de empoderar as pessoas. Ele disse: &#8220;H\u00e1 quem acredite que dar mais voz \u00e0s pessoas est\u00e1 provocando cis\u00f5es em vez de nos unir. Mais pessoas em todo o espectro acreditam que atingir os resultados pol\u00edticos que acham que importam \u00e9 mais importante do que cada pessoa ter uma voz. Eu acho que isso \u00e9 perigoso.&#8221; Nos \u00faltimos anos, desenvolvemos sistemas cada vez mais complexos para gerenciar conte\u00fado em nossas plataformas, em parte como resposta \u00e0 press\u00e3o p\u00fablica e pol\u00edtica para moderar conte\u00fado. Essa abordagem foi longe demais. Embora muitos desses esfor\u00e7os tenham sido bem-intencionados, eles se ampliaram ao longo do tempo at\u00e9 o ponto em que estamos cometendo muitos erros, frustrando nossos usu\u00e1rios e, com frequ\u00eancia, impedindo a livre express\u00e3o que pretendemos viabilizar. Muito conte\u00fado inofensivo \u00e9 censurado, muitas pessoas se veem trancadas injustamente na &#8220;cadeia do Facebook&#8221; e, com frequ\u00eancia, somos lentos em respond\u00ea-las. Queremos consertar isso e voltar \u00e0quele compromisso fundamental com a livre express\u00e3o. Hoje, estamos fazendo algumas mudan\u00e7as para permanecermos fi\u00e9is a esse ideal. Encerramento do programa de verifica\u00e7\u00e3o de fatos e migra\u00e7\u00e3o para Notas da Comunidade Quando lan\u00e7amos nosso programa independente de verifica\u00e7\u00e3o de fatos em 2016, fomos claros sobre n\u00e3o querermos ser os \u00e1rbitros da verdade. Adotamos o que consideramos ser a melhor e mais razo\u00e1vel escolha na \u00e9poca, que era deixar essa tarefa para organiza\u00e7\u00f5es independentes de verifica\u00e7\u00e3o de fatos. A inten\u00e7\u00e3o do programa era fornecer \u00e0s pessoas mais contexto e informa\u00e7\u00f5es sobre as coisas que elas veem online, em especial rumores e especula\u00e7\u00f5es que viralizam, para que elas possam julgar por si mesmas o que veem e leem. No entanto, n\u00e3o foi assim que o processo se desenrolou, especialmente nos Estados Unidos. Especialistas, assim como todos, t\u00eam suas pr\u00f3prias perspectivas, e isso se manifestou nas escolhas que alguns fizeram sobre o que verificar e como. Ao longo do tempo, acabamos por ter muito conte\u00fado sendo verificado que as pessoas entendiam como discurso pol\u00edtico leg\u00edtimo e debate. Nosso sistema ent\u00e3o adicionou consequ\u00eancias reais na forma de r\u00f3tulos intrusivos e distribui\u00e7\u00e3o reduzida. Um programa destinado a dar mais informa\u00e7\u00e3o para as pessoas se tornou, com frequ\u00eancia, uma ferramenta de censura.\u00a0 Agora estamos mudando essa abordagem. Vamos encerrar o atual programa de verifica\u00e7\u00e3o de fatos com terceiros nos EUA e come\u00e7ar a migrar para um programa de Notas da Comunidade. J\u00e1 vimos essa abordagem funcionar no X \u2013 onde eles empoderam a comunidade para decidir quando postagens s\u00e3o potencialmente enganosas e precisam de mais contexto, e pessoas de uma ampla gama de perspectivas estabelecem que tipo de contexto \u00e9 \u00fatil para outros usu\u00e1rios verem. Acreditamos que essa pode ser uma maneira mais efetiva e diversa de alcan\u00e7ar nossa inten\u00e7\u00e3o original de fornecer \u00e0s pessoas informa\u00e7\u00f5es sobre o que est\u00e3o vendo &#8211; e uma que \u00e9 menos propensa a vieses. Uma vez que o programa estiver em execu\u00e7\u00e3o, a Meta n\u00e3o escrever\u00e1 Notas da Comunidade ou decidir\u00e1 quais delas ser\u00e3o exibidas. Elas ser\u00e3o escritas e avaliadas por usu\u00e1rios colaboradores.\u00a0 Assim como fazem no X, as Notas da Comunidade exigir\u00e3o consenso entre pessoas com uma ampla gama de perspectivas para ajudar a prevenir avalia\u00e7\u00f5es tendenciosas. Pretendemos ser transparentes sobre como diferentes pontos de vista fundamentam as Notas exibidas em nossos aplicativos e estamos trabalhando para encontrar a melhor maneira de compartilhar essa informa\u00e7\u00e3o. Pessoas interessadas nos Estados Unidos podem se inscrever hoje para ter a oportunidade de estarem entre os primeiros colaboradores para esse programa \u00e0 medida que ele se tornar dispon\u00edvel. Planejamos implementar as Notas da Comunidade primeiro nos EUA, ao longo dos pr\u00f3ximos meses, e continuaremos a aprimor\u00e1-las ao longo do ano. Enquanto fazemos a transi\u00e7\u00e3o, vamos parar de reduzir a distribui\u00e7\u00e3o deste de conte\u00fado verificado e, em vez de exibir advert\u00eancias em tela cheia nas quais voc\u00ea precisa clicar antes de poder ver a postagem, vamos usar um r\u00f3tulo muito menos intrusivo indicando que h\u00e1 informa\u00e7\u00f5es adicionais sobre o post para quem desejar v\u00ea-las. Mais espa\u00e7o para o debate Ao longo do tempo, desenvolvemos sistemas complexos para gerenciar conte\u00fado em nossas plataformas, cuja aplica\u00e7\u00e3o tem se tornado cada vez mais complicada. Como resultado, temos exagerado na aplica\u00e7\u00e3o de nossas regras, limitando debate pol\u00edtico leg\u00edtimo e excluindo conte\u00fado trivial, e submetendo muitas pessoas a a\u00e7\u00f5es frustrantes de aplica\u00e7\u00e3o de pol\u00edticas. Em dezembro de 2024, por exemplo, removemos milh\u00f5es de posts todos os dias. Embora essas medidas representem menos de 1% do conte\u00fado produzido diariamente, acreditamos que de uma a duas em cada 10 dessas a\u00e7\u00f5es podem ter sido equivocadas (ou seja, o conte\u00fado removido pode n\u00e3o ter violado nossas pol\u00edticas). Esse dado n\u00e3o leva em conta as a\u00e7\u00f5es que tomamos para lidar com ataques em larga escala. Planejamos expandir nosso relat\u00f3rio de transpar\u00eancia para compartilhar regularmente n\u00fameros sobre nossos erros, para que as pessoas possam acompanhar nosso progresso. Como parte disso, tamb\u00e9m incluiremos mais detalhes sobre os equ\u00edvocos que cometemos ao aplicar nossas pol\u00edticas de spam. Queremos reverter a extens\u00e3o dos esfor\u00e7os que tornaram nossas regras muito restritivas e propensas \u00e0 aplica\u00e7\u00e3o excessiva dessas regras. Estamos eliminando uma s\u00e9rie de restri\u00e7\u00f5es em t\u00f3picos como imigra\u00e7\u00e3o, identidade de g\u00eanero e g\u00eanero que s\u00e3o frequentemente objeto de discurso pol\u00edtico e debate. N\u00e3o \u00e9 certo que coisas possam ser ditas na TV ou no plen\u00e1rio do Congresso, mas n\u00e3o em nossas plataformas. Essas mudan\u00e7as de pol\u00edtica podem levar algumas semanas para serem implementadas integralmente. Tamb\u00e9m vamos mudar como aplicamos nossas pol\u00edticas para reduzir os tipos de erros que respondem pela maioria da censura em nossas plataformas. At\u00e9 agora, temos usado sistemas automatizados para detectar viola\u00e7\u00f5es a pol\u00edticas, mas isso resultou em muito conte\u00fado erroneamente removido e em muito conte\u00fado sendo censurado que n\u00e3o deveria ter sido. Portanto, vamos concentrar o uso desses sistemas para lidar com conte\u00fado ilegal e viola\u00e7\u00f5es de alta severidade, como terrorismo, explora\u00e7\u00e3o sexual infantil, drogas, fraudes e scams. Para viola\u00e7\u00f5es de pol\u00edtica menos graves, vamos nos basear nas den\u00fancias das pessoas antes de tomar qualquer a\u00e7\u00e3o. Tamb\u00e9m reduzimos a visibilidade de muito conte\u00fado que nossos sistemas preveem que pode violar nossas regras Estamos no processo de eliminar muitas dessas restri\u00e7\u00f5es e requerer um grau de confian\u00e7a maior de que o conte\u00fado \u00e9 de fato uma viola\u00e7\u00e3o, al\u00e9m de ajustar nossos sistemas para garantir um n\u00edvel maior de certeza antes que um conte\u00fado seja removido. Como parte dessas mudan\u00e7as, nosso time de Trust and Safety que escreve nossas pol\u00edticas de conte\u00fado e revisa os conte\u00fados sair\u00e1 da Calif\u00f3rnia para o Texas e outras localidades nos EUA.\u00a0 Geralmente as pessoas t\u00eam a chance de recorrer das nossas decis\u00f5es quando s\u00e3o tomadas medidas corretivas sobre suas contas e conte\u00fados, solicitando que revisemos nossas a\u00e7\u00f5es. No entanto, esse processo pode ser frustrantemente lento e nem sempre chega ao resultado devido. Aumentamos o n\u00famero de pessoas dedicadas a esse trabalho e ampliamos o n\u00famero de casos para os quais exigimos que v\u00e1rios revisores cheguem a um consenso antes de uma remo\u00e7\u00e3o de conte\u00fado. Estamos trabalhando em maneiras de tornar a recupera\u00e7\u00e3o de contas mais direta e testando tecnologia de reconhecimento facial, al\u00e9m de come\u00e7armos a usar modelos de linguagem de larga escala de Intelig\u00eancia Artificial (LLMs) para uma segunda opini\u00e3o sobre alguns conte\u00fados antes de tomarmos medidas. Uma abordagem personalizada para conte\u00fado pol\u00edtico Desde 2021, temos feito mudan\u00e7as para reduzir a quantidade de conte\u00fado c\u00edvico que as pessoas veem em nossas plataformas &#8211; posts sobre elei\u00e7\u00f5es, pol\u00edtica ou quest\u00f5es sociais. Essas mudan\u00e7as ocorreram com base no feedback dos nossos usu\u00e1rios, que nos disseram que queriam ver menos esse tipo de conte\u00fado. Mas essa medida foi um tanto brusca. Vamos come\u00e7ar a reintroduzir conte\u00fados dessa natureza no Facebook, Instagram e Threads com uma abordagem mais personalizada, para que as pessoas que querem ver mais conte\u00fado pol\u00edtico em seus feeds tenham essa possibilidade. Estamos constantemente testando como entregamos experi\u00eancias personalizadas e recentemente realizamos testes em torno do conte\u00fado c\u00edvico. Como resultado, vamos come\u00e7ar a tratar o conte\u00fado c\u00edvico das pessoas e P\u00e1ginas que voc\u00ea segue no Facebook da mesma forma que qualquer outro conte\u00fado em seu feed, e passaremos a ranquear e mostrar esse conte\u00fado com base em sinais expl\u00edcitos (por exemplo, curtir um conte\u00fado) e sinais impl\u00edcitos (como visualizar posts) que nos ajudam a prever o que \u00e9 significativo para as pessoas. Tamb\u00e9m vamos recomendar mais conte\u00fado pol\u00edtico com base nesses sinais personalizados, e estamos ampliando as op\u00e7\u00f5es que as pessoas t\u00eam para controlar o quanto desse conte\u00fado elas veem. Essas mudan\u00e7as s\u00e3o uma tentativa de retornar ao compromisso com a livre express\u00e3o que Mark Zuckerberg estabeleceu em seu discurso na Universidade de Georgetown. Isso significa ser vigilante sobre o impacto que nossas pol\u00edticas e sistemas est\u00e3o tendo na capacidade de as pessoas fazerem sua voz ser ouvida e ter a humildade de mudar nossa abordagem quando sabemos que estamos fazendo a coisa errada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre a Meta\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-07T13:04:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?resize=1024,576\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vivilusor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/\"},\"author\":\"Facebook company\",\"headline\":\"Mais express\u00e3o e menos erros\",\"datePublished\":\"2025-01-07T13:04:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/\"},\"wordCount\":1749,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"articleSection\":[\"Recent News\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/\",\"url\":\"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/\",\"name\":\"Mais express\u00e3o e menos erros | Sobre a Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/#website\"},\"datePublished\":\"2025-01-07T13:04:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/\"]}],\"author\":\"Sobre a Meta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mais express\u00e3o e menos erros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/br\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"Sobre a Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/br\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mais express\u00e3o e menos erros | Sobre a Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/","og_locale":"pt_BR","og_type":"article","og_title":"Mais express\u00e3o e menos erros | Sobre a Meta","og_description":"As plataformas da Meta s\u00e3o constru\u00eddas para serem lugares em que as pessoas podem se expressar livremente. Isso pode ser um pouco ca\u00f3tico. Em plataformas nas quais bilh\u00f5es de pessoas podem ter voz, tudo o que \u00e9 bom, ruim e feio est\u00e1 exposto. Mas isso \u00e9 a livre express\u00e3o.\u00a0 Em 2019, em seu discurso na Universidade de Georgetown, Mark Zuckerberg argumentou que a liberdade de express\u00e3o tem sido a for\u00e7a motriz por tr\u00e1s do progresso da sociedade norte-americana e ao redor do mundo, ao passo que inibir a fala, independentemente de raz\u00f5es bem-intencionadas para faz\u00ea-lo, \u00e9 algo que frequentemente refor\u00e7a as institui\u00e7\u00f5es e as estruturas de poder existentes em vez de empoderar as pessoas. Ele disse: &#8220;H\u00e1 quem acredite que dar mais voz \u00e0s pessoas est\u00e1 provocando cis\u00f5es em vez de nos unir. Mais pessoas em todo o espectro acreditam que atingir os resultados pol\u00edticos que acham que importam \u00e9 mais importante do que cada pessoa ter uma voz. Eu acho que isso \u00e9 perigoso.&#8221; Nos \u00faltimos anos, desenvolvemos sistemas cada vez mais complexos para gerenciar conte\u00fado em nossas plataformas, em parte como resposta \u00e0 press\u00e3o p\u00fablica e pol\u00edtica para moderar conte\u00fado. Essa abordagem foi longe demais. Embora muitos desses esfor\u00e7os tenham sido bem-intencionados, eles se ampliaram ao longo do tempo at\u00e9 o ponto em que estamos cometendo muitos erros, frustrando nossos usu\u00e1rios e, com frequ\u00eancia, impedindo a livre express\u00e3o que pretendemos viabilizar. Muito conte\u00fado inofensivo \u00e9 censurado, muitas pessoas se veem trancadas injustamente na &#8220;cadeia do Facebook&#8221; e, com frequ\u00eancia, somos lentos em respond\u00ea-las. Queremos consertar isso e voltar \u00e0quele compromisso fundamental com a livre express\u00e3o. Hoje, estamos fazendo algumas mudan\u00e7as para permanecermos fi\u00e9is a esse ideal. Encerramento do programa de verifica\u00e7\u00e3o de fatos e migra\u00e7\u00e3o para Notas da Comunidade Quando lan\u00e7amos nosso programa independente de verifica\u00e7\u00e3o de fatos em 2016, fomos claros sobre n\u00e3o querermos ser os \u00e1rbitros da verdade. Adotamos o que consideramos ser a melhor e mais razo\u00e1vel escolha na \u00e9poca, que era deixar essa tarefa para organiza\u00e7\u00f5es independentes de verifica\u00e7\u00e3o de fatos. A inten\u00e7\u00e3o do programa era fornecer \u00e0s pessoas mais contexto e informa\u00e7\u00f5es sobre as coisas que elas veem online, em especial rumores e especula\u00e7\u00f5es que viralizam, para que elas possam julgar por si mesmas o que veem e leem. No entanto, n\u00e3o foi assim que o processo se desenrolou, especialmente nos Estados Unidos. Especialistas, assim como todos, t\u00eam suas pr\u00f3prias perspectivas, e isso se manifestou nas escolhas que alguns fizeram sobre o que verificar e como. Ao longo do tempo, acabamos por ter muito conte\u00fado sendo verificado que as pessoas entendiam como discurso pol\u00edtico leg\u00edtimo e debate. Nosso sistema ent\u00e3o adicionou consequ\u00eancias reais na forma de r\u00f3tulos intrusivos e distribui\u00e7\u00e3o reduzida. Um programa destinado a dar mais informa\u00e7\u00e3o para as pessoas se tornou, com frequ\u00eancia, uma ferramenta de censura.\u00a0 Agora estamos mudando essa abordagem. Vamos encerrar o atual programa de verifica\u00e7\u00e3o de fatos com terceiros nos EUA e come\u00e7ar a migrar para um programa de Notas da Comunidade. J\u00e1 vimos essa abordagem funcionar no X \u2013 onde eles empoderam a comunidade para decidir quando postagens s\u00e3o potencialmente enganosas e precisam de mais contexto, e pessoas de uma ampla gama de perspectivas estabelecem que tipo de contexto \u00e9 \u00fatil para outros usu\u00e1rios verem. Acreditamos que essa pode ser uma maneira mais efetiva e diversa de alcan\u00e7ar nossa inten\u00e7\u00e3o original de fornecer \u00e0s pessoas informa\u00e7\u00f5es sobre o que est\u00e3o vendo &#8211; e uma que \u00e9 menos propensa a vieses. Uma vez que o programa estiver em execu\u00e7\u00e3o, a Meta n\u00e3o escrever\u00e1 Notas da Comunidade ou decidir\u00e1 quais delas ser\u00e3o exibidas. Elas ser\u00e3o escritas e avaliadas por usu\u00e1rios colaboradores.\u00a0 Assim como fazem no X, as Notas da Comunidade exigir\u00e3o consenso entre pessoas com uma ampla gama de perspectivas para ajudar a prevenir avalia\u00e7\u00f5es tendenciosas. Pretendemos ser transparentes sobre como diferentes pontos de vista fundamentam as Notas exibidas em nossos aplicativos e estamos trabalhando para encontrar a melhor maneira de compartilhar essa informa\u00e7\u00e3o. Pessoas interessadas nos Estados Unidos podem se inscrever hoje para ter a oportunidade de estarem entre os primeiros colaboradores para esse programa \u00e0 medida que ele se tornar dispon\u00edvel. Planejamos implementar as Notas da Comunidade primeiro nos EUA, ao longo dos pr\u00f3ximos meses, e continuaremos a aprimor\u00e1-las ao longo do ano. Enquanto fazemos a transi\u00e7\u00e3o, vamos parar de reduzir a distribui\u00e7\u00e3o deste de conte\u00fado verificado e, em vez de exibir advert\u00eancias em tela cheia nas quais voc\u00ea precisa clicar antes de poder ver a postagem, vamos usar um r\u00f3tulo muito menos intrusivo indicando que h\u00e1 informa\u00e7\u00f5es adicionais sobre o post para quem desejar v\u00ea-las. Mais espa\u00e7o para o debate Ao longo do tempo, desenvolvemos sistemas complexos para gerenciar conte\u00fado em nossas plataformas, cuja aplica\u00e7\u00e3o tem se tornado cada vez mais complicada. Como resultado, temos exagerado na aplica\u00e7\u00e3o de nossas regras, limitando debate pol\u00edtico leg\u00edtimo e excluindo conte\u00fado trivial, e submetendo muitas pessoas a a\u00e7\u00f5es frustrantes de aplica\u00e7\u00e3o de pol\u00edticas. Em dezembro de 2024, por exemplo, removemos milh\u00f5es de posts todos os dias. Embora essas medidas representem menos de 1% do conte\u00fado produzido diariamente, acreditamos que de uma a duas em cada 10 dessas a\u00e7\u00f5es podem ter sido equivocadas (ou seja, o conte\u00fado removido pode n\u00e3o ter violado nossas pol\u00edticas). Esse dado n\u00e3o leva em conta as a\u00e7\u00f5es que tomamos para lidar com ataques em larga escala. Planejamos expandir nosso relat\u00f3rio de transpar\u00eancia para compartilhar regularmente n\u00fameros sobre nossos erros, para que as pessoas possam acompanhar nosso progresso. Como parte disso, tamb\u00e9m incluiremos mais detalhes sobre os equ\u00edvocos que cometemos ao aplicar nossas pol\u00edticas de spam. Queremos reverter a extens\u00e3o dos esfor\u00e7os que tornaram nossas regras muito restritivas e propensas \u00e0 aplica\u00e7\u00e3o excessiva dessas regras. Estamos eliminando uma s\u00e9rie de restri\u00e7\u00f5es em t\u00f3picos como imigra\u00e7\u00e3o, identidade de g\u00eanero e g\u00eanero que s\u00e3o frequentemente objeto de discurso pol\u00edtico e debate. N\u00e3o \u00e9 certo que coisas possam ser ditas na TV ou no plen\u00e1rio do Congresso, mas n\u00e3o em nossas plataformas. Essas mudan\u00e7as de pol\u00edtica podem levar algumas semanas para serem implementadas integralmente. Tamb\u00e9m vamos mudar como aplicamos nossas pol\u00edticas para reduzir os tipos de erros que respondem pela maioria da censura em nossas plataformas. At\u00e9 agora, temos usado sistemas automatizados para detectar viola\u00e7\u00f5es a pol\u00edticas, mas isso resultou em muito conte\u00fado erroneamente removido e em muito conte\u00fado sendo censurado que n\u00e3o deveria ter sido. Portanto, vamos concentrar o uso desses sistemas para lidar com conte\u00fado ilegal e viola\u00e7\u00f5es de alta severidade, como terrorismo, explora\u00e7\u00e3o sexual infantil, drogas, fraudes e scams. Para viola\u00e7\u00f5es de pol\u00edtica menos graves, vamos nos basear nas den\u00fancias das pessoas antes de tomar qualquer a\u00e7\u00e3o. Tamb\u00e9m reduzimos a visibilidade de muito conte\u00fado que nossos sistemas preveem que pode violar nossas regras Estamos no processo de eliminar muitas dessas restri\u00e7\u00f5es e requerer um grau de confian\u00e7a maior de que o conte\u00fado \u00e9 de fato uma viola\u00e7\u00e3o, al\u00e9m de ajustar nossos sistemas para garantir um n\u00edvel maior de certeza antes que um conte\u00fado seja removido. Como parte dessas mudan\u00e7as, nosso time de Trust and Safety que escreve nossas pol\u00edticas de conte\u00fado e revisa os conte\u00fados sair\u00e1 da Calif\u00f3rnia para o Texas e outras localidades nos EUA.\u00a0 Geralmente as pessoas t\u00eam a chance de recorrer das nossas decis\u00f5es quando s\u00e3o tomadas medidas corretivas sobre suas contas e conte\u00fados, solicitando que revisemos nossas a\u00e7\u00f5es. No entanto, esse processo pode ser frustrantemente lento e nem sempre chega ao resultado devido. Aumentamos o n\u00famero de pessoas dedicadas a esse trabalho e ampliamos o n\u00famero de casos para os quais exigimos que v\u00e1rios revisores cheguem a um consenso antes de uma remo\u00e7\u00e3o de conte\u00fado. Estamos trabalhando em maneiras de tornar a recupera\u00e7\u00e3o de contas mais direta e testando tecnologia de reconhecimento facial, al\u00e9m de come\u00e7armos a usar modelos de linguagem de larga escala de Intelig\u00eancia Artificial (LLMs) para uma segunda opini\u00e3o sobre alguns conte\u00fados antes de tomarmos medidas. Uma abordagem personalizada para conte\u00fado pol\u00edtico Desde 2021, temos feito mudan\u00e7as para reduzir a quantidade de conte\u00fado c\u00edvico que as pessoas veem em nossas plataformas &#8211; posts sobre elei\u00e7\u00f5es, pol\u00edtica ou quest\u00f5es sociais. Essas mudan\u00e7as ocorreram com base no feedback dos nossos usu\u00e1rios, que nos disseram que queriam ver menos esse tipo de conte\u00fado. Mas essa medida foi um tanto brusca. Vamos come\u00e7ar a reintroduzir conte\u00fados dessa natureza no Facebook, Instagram e Threads com uma abordagem mais personalizada, para que as pessoas que querem ver mais conte\u00fado pol\u00edtico em seus feeds tenham essa possibilidade. Estamos constantemente testando como entregamos experi\u00eancias personalizadas e recentemente realizamos testes em torno do conte\u00fado c\u00edvico. Como resultado, vamos come\u00e7ar a tratar o conte\u00fado c\u00edvico das pessoas e P\u00e1ginas que voc\u00ea segue no Facebook da mesma forma que qualquer outro conte\u00fado em seu feed, e passaremos a ranquear e mostrar esse conte\u00fado com base em sinais expl\u00edcitos (por exemplo, curtir um conte\u00fado) e sinais impl\u00edcitos (como visualizar posts) que nos ajudam a prever o que \u00e9 significativo para as pessoas. Tamb\u00e9m vamos recomendar mais conte\u00fado pol\u00edtico com base nesses sinais personalizados, e estamos ampliando as op\u00e7\u00f5es que as pessoas t\u00eam para controlar o quanto desse conte\u00fado elas veem. Essas mudan\u00e7as s\u00e3o uma tentativa de retornar ao compromisso com a livre express\u00e3o que Mark Zuckerberg estabeleceu em seu discurso na Universidade de Georgetown. Isso significa ser vigilante sobre o impacto que nossas pol\u00edticas e sistemas est\u00e3o tendo na capacidade de as pessoas fazerem sua voz ser ouvida e ter a humildade de mudar nossa abordagem quando sabemos que estamos fazendo a coisa errada.","og_url":"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/","og_site_name":"Sobre a Meta","article_published_time":"2025-01-07T13:04:03+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?resize=1024,576","type":"image\/jpeg"}],"author":"vivilusor","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/"},"author":"Facebook company","headline":"Mais express\u00e3o e menos erros","datePublished":"2025-01-07T13:04:03+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/"},"wordCount":1749,"publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"articleSection":["Recent News"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/","url":"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/","name":"Mais express\u00e3o e menos erros | Sobre a Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/#website"},"datePublished":"2025-01-07T13:04:03+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/"]}],"author":"Sobre a Meta"},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/br\/news\/2025\/01\/mais-expressao-e-menos-erros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/br\/"},{"@type":"ListItem","position":2,"name":"Mais express\u00e3o e menos erros"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/br\/#website","url":"https:\/\/about.fb.com\/news\/","name":"Sobre a Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/br\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":26476,"url":"https:\/\/about.fb.com\/br\/news\/2025\/06\/cannes-lions-2025-a-nova-era-da-ia-generativa-para-anunciantes-e-agencias-com-foco-em-personalizacao-em-escala\/","url_meta":{"origin":26084,"position":0},"title":"Cannes Lions 2025: A nova era da IA generativa para anunciantes e ag\u00eancias com foco em personaliza\u00e7\u00e3o em escala","author":"Meta","date":"17\/06\/2025","format":false,"excerpt":"Nesta semana, durante o Festival Internacional de Criatividade Cannes Lions, estamos apresentando a nova era das solu\u00e7\u00f5es de IA generativa para anunciantes e ag\u00eancias, com o objetivo de melhorar o desempenho das campanhas publicit\u00e1rias e impulsionar o crescimento dos neg\u00f3cios. \u00c0 medida que a IA continua evoluindo, ela abre novos\u2026","rel":"","context":"In &quot;Meta&quot;","block_context":{"text":"Meta","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/meta\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/07\/Logo-Meta-1.jpg?fit=633%2C356&resize=525%2C300 1.5x"},"classes":[]},{"id":26343,"url":"https:\/\/about.fb.com\/br\/news\/2025\/04\/reduzindo-conteudo-com-spam-no-facebook\/","url_meta":{"origin":26084,"position":1},"title":"Reduzindo conte\u00fado com spam no Facebook","author":"Meta","date":"24\/04\/2025","format":false,"excerpt":"Sua opini\u00e3o \u00e9 importante para n\u00f3s. O Feed do Facebook nem sempre oferece posts novos e envolventes, dos quais voc\u00ea sempre gosta. Estamos trabalhando em uma s\u00e9rie de mudan\u00e7as este ano para melhorar o Feed, ajudar os criadores de conte\u00fado a se destacar e dar \u00e0s pessoas mais controle sobre\u2026","rel":"","context":"In &quot;Facebook&quot;","block_context":{"text":"Facebook","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/facebook\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/FB-Spam.jpg?fit=1280%2C720&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/FB-Spam.jpg?fit=1280%2C720&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/FB-Spam.jpg?fit=1280%2C720&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/FB-Spam.jpg?fit=1280%2C720&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/FB-Spam.jpg?fit=1280%2C720&resize=1050%2C600 3x"},"classes":[]},{"id":26872,"url":"https:\/\/about.fb.com\/br\/news\/2025\/12\/resumo-dos-novos-recursos-recados-para-ligacoes-nao-atendidas-novas-figurinhas-de-status-e-muito-mais\/","url_meta":{"origin":26084,"position":2},"title":"Resumo dos novos recursos: recados para liga\u00e7\u00f5es n\u00e3o atendidas, novas figurinhas de status e muito mais!","author":"Meta","date":"11\/12\/2025","format":false,"excerpt":"Estamos lan\u00e7ando mais um pacote de recursos a tempo das festas de fim de ano. Esta edi\u00e7\u00e3o est\u00e1 repleta de novas atualiza\u00e7\u00f5es interessantes, incluindo recados para liga\u00e7\u00f5es n\u00e3o atendidas, figurinhas divertidas para o status, gera\u00e7\u00e3o de imagens com a Meta AI aprimorada e muito mais. Tudo isso para facilitar ainda\u2026","rel":"","context":"In &quot;Feed - Categorias&quot;","block_context":{"text":"Feed - Categorias","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/596387419_1360761639062906_2694588393236778653_n.png?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/596387419_1360761639062906_2694588393236778653_n.png?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/596387419_1360761639062906_2694588393236778653_n.png?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/596387419_1360761639062906_2694588393236778653_n.png?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/596387419_1360761639062906_2694588393236778653_n.png?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/596387419_1360761639062906_2694588393236778653_n.png?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]},{"id":26214,"url":"https:\/\/about.fb.com\/br\/news\/2025\/03\/26214\/","url_meta":{"origin":26084,"position":3},"title":"Iniciando os testes para Notas da Comunidade no Facebook, Instagram e Threads","author":"Meta","date":"13\/03\/2025","format":false,"excerpt":"Em janeiro, a Meta anunciou que encerrar\u00e1 o programa com organiza\u00e7\u00f5es independentes de verifica\u00e7\u00e3o de fatos e passar\u00e1 a adotar um sistema de Notas da Comunidade baseado em colabora\u00e7\u00e3o coletiva, come\u00e7ando nos Estados Unidos. A partir de 18 de mar\u00e7o, vamos come\u00e7ar a testar essa nova abordagem, permitindo que os\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/03\/03_Rating_Carousel-030.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/03\/03_Rating_Carousel-030.jpg?resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/03\/03_Rating_Carousel-030.jpg?resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/03\/03_Rating_Carousel-030.jpg?resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/03\/03_Rating_Carousel-030.jpg?resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/03\/03_Rating_Carousel-030.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":26916,"url":"https:\/\/about.fb.com\/br\/news\/2026\/01\/eleve-o-nivel-das-suas-conversas-em-grupo-do-whatsapp-com-as-novas-etiquetas-de-membros-figurinhas-de-texto-e-muito-mais\/","url_meta":{"origin":26084,"position":4},"title":"Eleve o n\u00edvel das suas conversas em grupo do WhatsApp com as novas etiquetas de membros, figurinhas de texto e muito mais","author":"Meta","date":"07\/01\/2026","format":false,"excerpt":"O novo ano \u00e9 um excelente momento para fazer algumas melhorias nas suas conversas em grupo. Os grupos do WhatsApp facilitam a conex\u00e3o com as pessoas que fazem parte da sua vida, com qualquer dispositivo. Seja para compartilhar suas metas para o ano novo, se preparar para uma ocasi\u00e3o especial\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/WhatsApp_Etiquetas-de-membros-figurinhas-de-texto-e-muito-mais.jpg?fit=960%2C540&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/WhatsApp_Etiquetas-de-membros-figurinhas-de-texto-e-muito-mais.jpg?fit=960%2C540&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/WhatsApp_Etiquetas-de-membros-figurinhas-de-texto-e-muito-mais.jpg?fit=960%2C540&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/WhatsApp_Etiquetas-de-membros-figurinhas-de-texto-e-muito-mais.jpg?fit=960%2C540&resize=700%2C400 2x"},"classes":[]},{"id":26692,"url":"https:\/\/about.fb.com\/br\/news\/2025\/10\/melhorando-suas-recomendacoes-em-nossos-aplicativos-com-ia-na-meta\/","url_meta":{"origin":26084,"position":5},"title":"Melhorando suas recomenda\u00e7\u00f5es em nossos aplicativos com IA na Meta","author":"Meta","date":"01\/10\/2025","format":false,"excerpt":"Mais de 1 bilh\u00e3o de pessoas usam Meta AI todo m\u00eas. Continuamos a melhorar a forma como nossos produtos de IA se mostram relevantes para voc\u00ea, entendem seus objetivos e ajudam a realizar tarefas de maneira mais eficiente. Tamb\u00e9m estamos usando Meta AI, bem como outros recursos de IA para\u2026","rel":"","context":"In &quot;Meta&quot;","block_context":{"text":"Meta","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/meta\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Meta-Privacy-Update_Header.jpg?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Meta-Privacy-Update_Header.jpg?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Meta-Privacy-Update_Header.jpg?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Meta-Privacy-Update_Header.jpg?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Meta-Privacy-Update_Header.jpg?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Meta-Privacy-Update_Header.jpg?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/26084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/users\/164097234"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/comments?post=26084"}],"version-history":[{"count":2,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/26084\/revisions"}],"predecessor-version":[{"id":26086,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/26084\/revisions\/26086"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/media?parent=26084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/categories?post=26084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/tags?post=26084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}