{"id":21348,"date":"2020-04-24T12:47:35","date_gmt":"2020-04-24T15:47:35","guid":{"rendered":"https:\/\/about.fb.com\/br\/?p=21348"},"modified":"2021-06-17T10:09:41","modified_gmt":"2021-06-17T13:09:41","slug":"acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade","status":"publish","type":"post","link":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/","title":{"rendered":"Acordo final com FTC representa um novo n\u00edvel de compromisso com privacidade"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Na quinta-feira, um tribunal federal aprovou oficialmente o acordo que chegamos com a Comiss\u00e3o Federal de Com\u00e9rcio (FTC, na sigla em Ingl\u00eas), em julho do ano passado. Isso conclui a investiga\u00e7\u00e3o da FTC que come\u00e7ou ap\u00f3s os eventos em torno do caso Cambridge Analytica, em 2018.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Como descrevemos no <\/span><a href=\"https:\/\/about.fb.com\/br\/news\/2019\/07\/acordo-com-ftc-traz-novos-padroes-rigorosos-para-proteger-sua-privacidade\/\"><span style=\"font-weight: 400\">ano passado<\/span><\/a><span style=\"font-weight: 400\">, o Facebook concordou em mudar fundamentalmente nossa abordagem na prote\u00e7\u00e3o \u00e0 privacidade das pessoas e pagar uma multa de US$ 5 bilh\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Na minha fun\u00e7\u00e3o de diretor de Privacidade de Produto, estou comprometido em ajudar o Facebook a fazer altera\u00e7\u00f5es importantes na maneira como lidamos com privacidade em toda a empresa ao implementar a <\/span><span style=\"font-weight: 400\">ordem<\/span><span style=\"font-weight: 400\">. Come\u00e7amos de forma positiva, com grande parte do trabalho exigido pelo acordo j\u00e1 em andamento.<\/span><\/p>\n<p><b>Criando um novo n\u00edvel de presta\u00e7\u00e3o de contas<\/b><\/p>\n<p><span style=\"font-weight: 400\">Este acordo j\u00e1 trouxe mudan\u00e7as fundamentais em nossa empresa e avan\u00e7os na forma como protegemos a privacidade das pessoas que v\u00e3o al\u00e9m de tudo que fizemos antes. Isso mudou a forma como trabalhamos, como constru\u00edmos novos produtos e tecnologias e como lidamos com as informa\u00e7\u00f5es das pessoas. Acima de tudo, ele traz um novo n\u00edvel de presta\u00e7\u00e3o de contas e garante que privacidade seja responsabilidade de todos no Facebook.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Com este acordo agora em vigor, os l\u00edderes executivos da empresa, incluindo nosso CEO, agora certificam que estamos cumprindo o acordo de forma trimestral e anual \u00e0 FTC. Tamb\u00e9m estamos criando um novo Comit\u00ea de Privacidade em nosso Conselho Administrativo, que ser\u00e1 composto somente por diretores independentes, e trabalharemos com um assessor terceiro independente que se reportar\u00e1 regularmente e diretamente ao Comit\u00ea de Privacidade sobre o compliance do nosso programa de privacidade.<\/span><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21350\" src=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=890&#038;resize=890%2C946\" alt=\"\" width=\"890\" height=\"946\" srcset=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=3855 3855w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=376 376w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=282 282w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=768 768w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=964 964w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=1446 1446w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=1928 1928w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=1016 1016w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=2033 2033w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=565 565w, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=2880 2880w\" sizes=\"auto, (max-width: 890px) 100vw, 890px\" \/><\/p>\n<p><b>O progresso que fizemos<\/b><\/p>\n<p><span style=\"font-weight: 400\">Embora tenhamos mais a fazer, j\u00e1 fizemos progressos significativos em aprimoramentos de privacidade em toda a empresa. Atualizamos nossa ferramenta de <\/span><a href=\"https:\/\/about.fb.com\/br\/news\/2020\/01\/guiando-voce-pelas-suas-escolhas-de-privacidade\/\"><span style=\"font-weight: 400\">Verifica\u00e7\u00e3o de Privacidade<\/span><\/a><span style=\"font-weight: 400\"> para orientar as pessoas em algumas de suas op\u00e7\u00f5es mais importantes de privacidade no Facebook, e relembramos as pessoas em todo o mundo para que <\/span><a href=\"https:\/\/about.fb.com\/br\/news\/2020\/01\/oferecendo-a-voce-mais-controle-sobre-sua-privacidade\/\"><span style=\"font-weight: 400\">revisassem suas configura\u00e7\u00f5es de privacidade<\/span><\/a><span style=\"font-weight: 400\">. Terminamos de lan\u00e7ar nossa ferramenta de <\/span><a href=\"https:\/\/about.fb.com\/br\/news\/2019\/08\/agora-voce-pode-ver-e-controlar-os-dados-que-os-aplicativos-e-os-sites-compartilham-com-o-facebook\/\"><span style=\"font-weight: 400\">Atividade Fora do Facebook<\/span><\/a><span style=\"font-weight: 400\">, para que as pessoas possam ver um resumo das informa\u00e7\u00f5es que as empresas compartilham conosco e limp\u00e1-las de suas contas, se quiserem. Tamb\u00e9m come\u00e7amos a publicar detalhes sobre nossa abordagem de privacidade e as prote\u00e7\u00f5es que incorporamos a nossos produtos em uma s\u00e9rie chamada <\/span><a href=\"https:\/\/about.fb.com\/news\/tag\/privacy-matters\/\"><span style=\"font-weight: 400\">Privacy Matters<\/span><\/a><span style=\"font-weight: 400\">. Por exemplo, aqui est\u00e1 nossa postagem sobre quest\u00f5es de privacidade do <\/span><a href=\"https:\/\/about.fb.com\/news\/2019\/11\/privacy-matters-facebook-pay\/\"><span style=\"font-weight: 400\">Facebook Pay<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Nosso trabalho de privacidade nunca termina, e entendemos que esse compromisso significa focar neste trabalho diariamente.<\/span><\/p>\n<p><b>Fazendo da Privacidade uma responsabilidade de todos no Facebook<\/b><\/p>\n<p><span style=\"font-weight: 400\">Reunimos alguns de nossos l\u00edderes mais respeitados e experientes para implementar esse acordo por toda a empresa.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Erin Egan, nossa diretora de Privacidade para Pol\u00edticas P\u00fablicas, lidera nosso envolvimento na discuss\u00e3o p\u00fablica global sobre privacidade e garante que o feedback de governos e especialistas de todo o mundo seja incorporado \u00e0s nossas pr\u00e1ticas e pol\u00edticas.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Vladimir Fedorov, vice-presidente de Engenharia, lidera o time de produtos e infraestrutura de privacidade, que est\u00e1 conduzindo todas as altera\u00e7\u00f5es subjacentes aos produtos, ferramentas e infraestrutura que estamos fazendo.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Delfina Eberly, vice-presidente de Infraestrutura, lidera o time de gerenciamento de programas de privacidade, conduzindo design, implementa\u00e7\u00e3o e testes.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Nosso time jur\u00eddico continua a crescer, com o objetivo de melhor apoiar nosso trabalho cont\u00ednuo de privacidade.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Criamos dezenas de equipes, tanto t\u00e9cnicas quanto n\u00e3o t\u00e9cnicas, focadas exclusivamente em privacidade. Agora analisamos mais rigorosamente o uso de dados em todas as nossas opera\u00e7\u00f5es. Isso significa que analisamos como os dados s\u00e3o coletados, usados e armazenados, desde o momento em que as pessoas compartilham novos dados conosco at\u00e9 o momento em que esses dados s\u00e3o exclu\u00eddos. Garantimos que sejam usados corretamente por meio de um Processo de Avalia\u00e7\u00e3o de Riscos; uma auditoria abrangente de como usamos os dados em toda a empresa &#8211; avaliando riscos e implementando salvaguardas para resolv\u00ea-los. Atualmente, temos milhares de pessoas trabalhando nesses projetos relacionados \u00e0 privacidade e estamos contratando muito mais.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Este acordo foi um catalisador para mudar a cultura da nossa empresa. Mudamos o processo pelo qual treinamos todos os novos funcion\u00e1rios do Facebook para garantir que eles pensem em seu papel atrav\u00e9s de uma vis\u00e3o de privacidade, projetem com a privacidade em mente desde o in\u00edcio e trabalhem proativamente para identificar poss\u00edveis riscos \u00e0 privacidade, para que mitiga\u00e7\u00f5es possam ser implementadas. Todos os funcion\u00e1rios novos e existentes s\u00e3o obrigados a concluir o treinamento de privacidade anual.<\/span><\/p>\n<p><b>Um roteiro para maior presta\u00e7\u00e3o de contas em todo o setor<\/b><\/p>\n<p><span style=\"font-weight: 400\">O acordo aprovado hoje vai al\u00e9m de qualquer exig\u00eancia legal dos EUA, e acreditamos que pode e deve servir como um roteiro para uma regulamenta\u00e7\u00e3o de privacidade mais abrangente, como outras partes do mundo t\u00eam explorado. Esperamos que isso leve a mais progressos no desenvolvimento de uma legisla\u00e7\u00e3o consistente nos EUA e em outros lugares.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Por fim, nosso objetivo \u00e9 honrar a privacidade das pessoas e focar em fazer o que \u00e9 certo para elas. Acreditamos que \u00e9 isso que os bilh\u00f5es de pessoas que usam nossos produtos esperam de n\u00f3s e continuaremos fazendo esse trabalho para elas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"Na quinta-feira, um tribunal federal aprovou oficialmente o acordo que chegamos com a Comiss\u00e3o Federal de Com\u00e9rcio (FTC, na sigla em Ingl\u00eas), em julho do ano passado. Isso conclui a investiga\u00e7\u00e3o da FTC que come\u00e7ou ap\u00f3s os eventos em torno do caso Cambridge Analytica, em 2018. Como descrevemos no ano passado, o Facebook concordou em mudar fundamentalmente nossa abordagem na prote\u00e7\u00e3o \u00e0 privacidade das pessoas e pagar uma multa de US$ 5 bilh\u00f5es. Na minha fun\u00e7\u00e3o de diretor de Privacidade de Produto, estou comprometido em ajudar o Facebook a fazer altera\u00e7\u00f5es importantes na maneira como lidamos com privacidade em toda a empresa ao implementar a ordem. Come\u00e7amos de forma positiva, com grande parte do trabalho exigido pelo acordo j\u00e1 em andamento. Criando um novo n\u00edvel de presta\u00e7\u00e3o de contas Este acordo j\u00e1 trouxe mudan\u00e7as fundamentais em nossa empresa e avan\u00e7os na forma como protegemos a privacidade das pessoas que v\u00e3o al\u00e9m de tudo que fizemos antes. Isso mudou a forma como trabalhamos, como constru\u00edmos novos produtos e tecnologias e como lidamos com as informa\u00e7\u00f5es das pessoas. Acima de tudo, ele traz um novo n\u00edvel de presta\u00e7\u00e3o de contas e garante que privacidade seja responsabilidade de todos no Facebook. Com este acordo agora em vigor, os l\u00edderes executivos da empresa, incluindo nosso CEO, agora certificam que estamos cumprindo o acordo de forma trimestral e anual \u00e0 FTC. Tamb\u00e9m estamos criando um novo Comit\u00ea de Privacidade em nosso Conselho Administrativo, que ser\u00e1 composto somente por diretores independentes, e trabalharemos com um assessor terceiro independente que se reportar\u00e1 regularmente e diretamente ao Comit\u00ea de Privacidade sobre o compliance do nosso programa de privacidade. O progresso que fizemos Embora tenhamos mais a fazer, j\u00e1 fizemos progressos significativos em aprimoramentos de privacidade em toda a empresa. Atualizamos nossa ferramenta de Verifica\u00e7\u00e3o de Privacidade para orientar as pessoas em algumas de suas op\u00e7\u00f5es mais importantes de privacidade no Facebook, e relembramos as pessoas em todo o mundo para que revisassem suas configura\u00e7\u00f5es de privacidade. Terminamos de lan\u00e7ar nossa ferramenta de Atividade Fora do Facebook, para que as pessoas possam ver um resumo das informa\u00e7\u00f5es que as empresas compartilham conosco e limp\u00e1-las de suas contas, se quiserem. Tamb\u00e9m come\u00e7amos a publicar detalhes sobre nossa abordagem de privacidade e as prote\u00e7\u00f5es que incorporamos a nossos produtos em uma s\u00e9rie chamada Privacy Matters. Por exemplo, aqui est\u00e1 nossa postagem sobre quest\u00f5es de privacidade do Facebook Pay. Nosso trabalho de privacidade nunca termina, e entendemos que esse compromisso significa focar neste trabalho diariamente. Fazendo da Privacidade uma responsabilidade de todos no Facebook Reunimos alguns de nossos l\u00edderes mais respeitados e experientes para implementar esse acordo por toda a empresa. Erin Egan, nossa diretora de Privacidade para Pol\u00edticas P\u00fablicas, lidera nosso envolvimento na discuss\u00e3o p\u00fablica global sobre privacidade e garante que o feedback de governos e especialistas de todo o mundo seja incorporado \u00e0s nossas pr\u00e1ticas e pol\u00edticas. Vladimir Fedorov, vice-presidente de Engenharia, lidera o time de produtos e infraestrutura de privacidade, que est\u00e1 conduzindo todas as altera\u00e7\u00f5es subjacentes aos produtos, ferramentas e infraestrutura que estamos fazendo. Delfina Eberly, vice-presidente de Infraestrutura, lidera o time de gerenciamento de programas de privacidade, conduzindo design, implementa\u00e7\u00e3o e testes. Nosso time jur\u00eddico continua a crescer, com o objetivo de melhor apoiar nosso trabalho cont\u00ednuo de privacidade. Criamos dezenas de equipes, tanto t\u00e9cnicas quanto n\u00e3o t\u00e9cnicas, focadas exclusivamente em privacidade. Agora analisamos mais rigorosamente o uso de dados em todas as nossas opera\u00e7\u00f5es. Isso significa que analisamos como os dados s\u00e3o coletados, usados e armazenados, desde o momento em que as pessoas compartilham novos dados conosco at\u00e9 o momento em que esses dados s\u00e3o exclu\u00eddos. Garantimos que sejam usados corretamente por meio de um Processo de Avalia\u00e7\u00e3o de Riscos; uma auditoria abrangente de como usamos os dados em toda a empresa &#8211; avaliando riscos e implementando salvaguardas para resolv\u00ea-los. Atualmente, temos milhares de pessoas trabalhando nesses projetos relacionados \u00e0 privacidade e estamos contratando muito mais. Este acordo foi um catalisador para mudar a cultura da nossa empresa. Mudamos o processo pelo qual treinamos todos os novos funcion\u00e1rios do Facebook para garantir que eles pensem em seu papel atrav\u00e9s de uma vis\u00e3o de privacidade, projetem com a privacidade em mente desde o in\u00edcio e trabalhem proativamente para identificar poss\u00edveis riscos \u00e0 privacidade, para que mitiga\u00e7\u00f5es possam ser implementadas. Todos os funcion\u00e1rios novos e existentes s\u00e3o obrigados a concluir o treinamento de privacidade anual. Um roteiro para maior presta\u00e7\u00e3o de contas em todo o setor O acordo aprovado hoje vai al\u00e9m de qualquer exig\u00eancia legal dos EUA, e acreditamos que pode e deve servir como um roteiro para uma regulamenta\u00e7\u00e3o de privacidade mais abrangente, como outras partes do mundo t\u00eam explorado. Esperamos que isso leve a mais progressos no desenvolvimento de uma legisla\u00e7\u00e3o consistente nos EUA e em outros lugares. Por fim, nosso objetivo \u00e9 honrar a privacidade das pessoas e focar em fazer o que \u00e9 certo para elas. Acreditamos que \u00e9 isso que os bilh\u00f5es de pessoas que usam nossos produtos esperam de n\u00f3s e continuaremos fazendo esse trabalho para elas.","protected":false},"author":81109636,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[396542133],"class_list":["post-21348","post","type-post","status-publish","format-standard","hentry","category-recent-news","tag-privacidade-importa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acordo final com FTC representa um novo n\u00edvel de compromisso com privacidade | Sobre a Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acordo final com FTC representa um novo n\u00edvel de compromisso com privacidade | Sobre a Meta\" \/>\n<meta property=\"og:description\" content=\"Na quinta-feira, um tribunal federal aprovou oficialmente o acordo que chegamos com a Comiss\u00e3o Federal de Com\u00e9rcio (FTC, na sigla em Ingl\u00eas), em julho do ano passado. Isso conclui a investiga\u00e7\u00e3o da FTC que come\u00e7ou ap\u00f3s os eventos em torno do caso Cambridge Analytica, em 2018. Como descrevemos no ano passado, o Facebook concordou em mudar fundamentalmente nossa abordagem na prote\u00e7\u00e3o \u00e0 privacidade das pessoas e pagar uma multa de US$ 5 bilh\u00f5es. Na minha fun\u00e7\u00e3o de diretor de Privacidade de Produto, estou comprometido em ajudar o Facebook a fazer altera\u00e7\u00f5es importantes na maneira como lidamos com privacidade em toda a empresa ao implementar a ordem. Come\u00e7amos de forma positiva, com grande parte do trabalho exigido pelo acordo j\u00e1 em andamento. Criando um novo n\u00edvel de presta\u00e7\u00e3o de contas Este acordo j\u00e1 trouxe mudan\u00e7as fundamentais em nossa empresa e avan\u00e7os na forma como protegemos a privacidade das pessoas que v\u00e3o al\u00e9m de tudo que fizemos antes. Isso mudou a forma como trabalhamos, como constru\u00edmos novos produtos e tecnologias e como lidamos com as informa\u00e7\u00f5es das pessoas. Acima de tudo, ele traz um novo n\u00edvel de presta\u00e7\u00e3o de contas e garante que privacidade seja responsabilidade de todos no Facebook. Com este acordo agora em vigor, os l\u00edderes executivos da empresa, incluindo nosso CEO, agora certificam que estamos cumprindo o acordo de forma trimestral e anual \u00e0 FTC. Tamb\u00e9m estamos criando um novo Comit\u00ea de Privacidade em nosso Conselho Administrativo, que ser\u00e1 composto somente por diretores independentes, e trabalharemos com um assessor terceiro independente que se reportar\u00e1 regularmente e diretamente ao Comit\u00ea de Privacidade sobre o compliance do nosso programa de privacidade. O progresso que fizemos Embora tenhamos mais a fazer, j\u00e1 fizemos progressos significativos em aprimoramentos de privacidade em toda a empresa. Atualizamos nossa ferramenta de Verifica\u00e7\u00e3o de Privacidade para orientar as pessoas em algumas de suas op\u00e7\u00f5es mais importantes de privacidade no Facebook, e relembramos as pessoas em todo o mundo para que revisassem suas configura\u00e7\u00f5es de privacidade. Terminamos de lan\u00e7ar nossa ferramenta de Atividade Fora do Facebook, para que as pessoas possam ver um resumo das informa\u00e7\u00f5es que as empresas compartilham conosco e limp\u00e1-las de suas contas, se quiserem. Tamb\u00e9m come\u00e7amos a publicar detalhes sobre nossa abordagem de privacidade e as prote\u00e7\u00f5es que incorporamos a nossos produtos em uma s\u00e9rie chamada Privacy Matters. Por exemplo, aqui est\u00e1 nossa postagem sobre quest\u00f5es de privacidade do Facebook Pay. Nosso trabalho de privacidade nunca termina, e entendemos que esse compromisso significa focar neste trabalho diariamente. Fazendo da Privacidade uma responsabilidade de todos no Facebook Reunimos alguns de nossos l\u00edderes mais respeitados e experientes para implementar esse acordo por toda a empresa. Erin Egan, nossa diretora de Privacidade para Pol\u00edticas P\u00fablicas, lidera nosso envolvimento na discuss\u00e3o p\u00fablica global sobre privacidade e garante que o feedback de governos e especialistas de todo o mundo seja incorporado \u00e0s nossas pr\u00e1ticas e pol\u00edticas. Vladimir Fedorov, vice-presidente de Engenharia, lidera o time de produtos e infraestrutura de privacidade, que est\u00e1 conduzindo todas as altera\u00e7\u00f5es subjacentes aos produtos, ferramentas e infraestrutura que estamos fazendo. Delfina Eberly, vice-presidente de Infraestrutura, lidera o time de gerenciamento de programas de privacidade, conduzindo design, implementa\u00e7\u00e3o e testes. Nosso time jur\u00eddico continua a crescer, com o objetivo de melhor apoiar nosso trabalho cont\u00ednuo de privacidade. Criamos dezenas de equipes, tanto t\u00e9cnicas quanto n\u00e3o t\u00e9cnicas, focadas exclusivamente em privacidade. Agora analisamos mais rigorosamente o uso de dados em todas as nossas opera\u00e7\u00f5es. Isso significa que analisamos como os dados s\u00e3o coletados, usados e armazenados, desde o momento em que as pessoas compartilham novos dados conosco at\u00e9 o momento em que esses dados s\u00e3o exclu\u00eddos. Garantimos que sejam usados corretamente por meio de um Processo de Avalia\u00e7\u00e3o de Riscos; uma auditoria abrangente de como usamos os dados em toda a empresa &#8211; avaliando riscos e implementando salvaguardas para resolv\u00ea-los. Atualmente, temos milhares de pessoas trabalhando nesses projetos relacionados \u00e0 privacidade e estamos contratando muito mais. Este acordo foi um catalisador para mudar a cultura da nossa empresa. Mudamos o processo pelo qual treinamos todos os novos funcion\u00e1rios do Facebook para garantir que eles pensem em seu papel atrav\u00e9s de uma vis\u00e3o de privacidade, projetem com a privacidade em mente desde o in\u00edcio e trabalhem proativamente para identificar poss\u00edveis riscos \u00e0 privacidade, para que mitiga\u00e7\u00f5es possam ser implementadas. Todos os funcion\u00e1rios novos e existentes s\u00e3o obrigados a concluir o treinamento de privacidade anual. Um roteiro para maior presta\u00e7\u00e3o de contas em todo o setor O acordo aprovado hoje vai al\u00e9m de qualquer exig\u00eancia legal dos EUA, e acreditamos que pode e deve servir como um roteiro para uma regulamenta\u00e7\u00e3o de privacidade mais abrangente, como outras partes do mundo t\u00eam explorado. Esperamos que isso leve a mais progressos no desenvolvimento de uma legisla\u00e7\u00e3o consistente nos EUA e em outros lugares. Por fim, nosso objetivo \u00e9 honrar a privacidade das pessoas e focar em fazer o que \u00e9 certo para elas. Acreditamos que \u00e9 isso que os bilh\u00f5es de pessoas que usam nossos produtos esperam de n\u00f3s e continuaremos fazendo esse trabalho para elas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre a Meta\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-24T15:47:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-17T13:09:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=890\" \/>\n<meta name=\"author\" content=\"facebookbr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/\"},\"author\":\"Facebook company\",\"headline\":\"Acordo final com FTC representa um novo n\u00edvel de compromisso com privacidade\",\"datePublished\":\"2020-04-24T15:47:35+00:00\",\"dateModified\":\"2021-06-17T13:09:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/\"},\"wordCount\":910,\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=890\",\"keywords\":[\"Privacidade Importa\"],\"articleSection\":[\"Recent News\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/\",\"url\":\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/\",\"name\":\"Acordo final com FTC representa um novo n\u00edvel de compromisso com privacidade | Sobre a Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about.fb.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=890\",\"datePublished\":\"2020-04-24T15:47:35+00:00\",\"dateModified\":\"2021-06-17T13:09:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/\"]}],\"author\":\"Sobre a Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#primaryimage\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=890\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=890\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about.fb.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acordo final com FTC representa um novo n\u00edvel de compromisso com privacidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about.fb.com\/br\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"Sobre a Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about.fb.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about.fb.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about.fb.com\/br\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about.fb.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acordo final com FTC representa um novo n\u00edvel de compromisso com privacidade | Sobre a Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Acordo final com FTC representa um novo n\u00edvel de compromisso com privacidade | Sobre a Meta","og_description":"Na quinta-feira, um tribunal federal aprovou oficialmente o acordo que chegamos com a Comiss\u00e3o Federal de Com\u00e9rcio (FTC, na sigla em Ingl\u00eas), em julho do ano passado. Isso conclui a investiga\u00e7\u00e3o da FTC que come\u00e7ou ap\u00f3s os eventos em torno do caso Cambridge Analytica, em 2018. Como descrevemos no ano passado, o Facebook concordou em mudar fundamentalmente nossa abordagem na prote\u00e7\u00e3o \u00e0 privacidade das pessoas e pagar uma multa de US$ 5 bilh\u00f5es. Na minha fun\u00e7\u00e3o de diretor de Privacidade de Produto, estou comprometido em ajudar o Facebook a fazer altera\u00e7\u00f5es importantes na maneira como lidamos com privacidade em toda a empresa ao implementar a ordem. Come\u00e7amos de forma positiva, com grande parte do trabalho exigido pelo acordo j\u00e1 em andamento. Criando um novo n\u00edvel de presta\u00e7\u00e3o de contas Este acordo j\u00e1 trouxe mudan\u00e7as fundamentais em nossa empresa e avan\u00e7os na forma como protegemos a privacidade das pessoas que v\u00e3o al\u00e9m de tudo que fizemos antes. Isso mudou a forma como trabalhamos, como constru\u00edmos novos produtos e tecnologias e como lidamos com as informa\u00e7\u00f5es das pessoas. Acima de tudo, ele traz um novo n\u00edvel de presta\u00e7\u00e3o de contas e garante que privacidade seja responsabilidade de todos no Facebook. Com este acordo agora em vigor, os l\u00edderes executivos da empresa, incluindo nosso CEO, agora certificam que estamos cumprindo o acordo de forma trimestral e anual \u00e0 FTC. Tamb\u00e9m estamos criando um novo Comit\u00ea de Privacidade em nosso Conselho Administrativo, que ser\u00e1 composto somente por diretores independentes, e trabalharemos com um assessor terceiro independente que se reportar\u00e1 regularmente e diretamente ao Comit\u00ea de Privacidade sobre o compliance do nosso programa de privacidade. O progresso que fizemos Embora tenhamos mais a fazer, j\u00e1 fizemos progressos significativos em aprimoramentos de privacidade em toda a empresa. Atualizamos nossa ferramenta de Verifica\u00e7\u00e3o de Privacidade para orientar as pessoas em algumas de suas op\u00e7\u00f5es mais importantes de privacidade no Facebook, e relembramos as pessoas em todo o mundo para que revisassem suas configura\u00e7\u00f5es de privacidade. Terminamos de lan\u00e7ar nossa ferramenta de Atividade Fora do Facebook, para que as pessoas possam ver um resumo das informa\u00e7\u00f5es que as empresas compartilham conosco e limp\u00e1-las de suas contas, se quiserem. Tamb\u00e9m come\u00e7amos a publicar detalhes sobre nossa abordagem de privacidade e as prote\u00e7\u00f5es que incorporamos a nossos produtos em uma s\u00e9rie chamada Privacy Matters. Por exemplo, aqui est\u00e1 nossa postagem sobre quest\u00f5es de privacidade do Facebook Pay. Nosso trabalho de privacidade nunca termina, e entendemos que esse compromisso significa focar neste trabalho diariamente. Fazendo da Privacidade uma responsabilidade de todos no Facebook Reunimos alguns de nossos l\u00edderes mais respeitados e experientes para implementar esse acordo por toda a empresa. Erin Egan, nossa diretora de Privacidade para Pol\u00edticas P\u00fablicas, lidera nosso envolvimento na discuss\u00e3o p\u00fablica global sobre privacidade e garante que o feedback de governos e especialistas de todo o mundo seja incorporado \u00e0s nossas pr\u00e1ticas e pol\u00edticas. Vladimir Fedorov, vice-presidente de Engenharia, lidera o time de produtos e infraestrutura de privacidade, que est\u00e1 conduzindo todas as altera\u00e7\u00f5es subjacentes aos produtos, ferramentas e infraestrutura que estamos fazendo. Delfina Eberly, vice-presidente de Infraestrutura, lidera o time de gerenciamento de programas de privacidade, conduzindo design, implementa\u00e7\u00e3o e testes. Nosso time jur\u00eddico continua a crescer, com o objetivo de melhor apoiar nosso trabalho cont\u00ednuo de privacidade. Criamos dezenas de equipes, tanto t\u00e9cnicas quanto n\u00e3o t\u00e9cnicas, focadas exclusivamente em privacidade. Agora analisamos mais rigorosamente o uso de dados em todas as nossas opera\u00e7\u00f5es. Isso significa que analisamos como os dados s\u00e3o coletados, usados e armazenados, desde o momento em que as pessoas compartilham novos dados conosco at\u00e9 o momento em que esses dados s\u00e3o exclu\u00eddos. Garantimos que sejam usados corretamente por meio de um Processo de Avalia\u00e7\u00e3o de Riscos; uma auditoria abrangente de como usamos os dados em toda a empresa &#8211; avaliando riscos e implementando salvaguardas para resolv\u00ea-los. Atualmente, temos milhares de pessoas trabalhando nesses projetos relacionados \u00e0 privacidade e estamos contratando muito mais. Este acordo foi um catalisador para mudar a cultura da nossa empresa. Mudamos o processo pelo qual treinamos todos os novos funcion\u00e1rios do Facebook para garantir que eles pensem em seu papel atrav\u00e9s de uma vis\u00e3o de privacidade, projetem com a privacidade em mente desde o in\u00edcio e trabalhem proativamente para identificar poss\u00edveis riscos \u00e0 privacidade, para que mitiga\u00e7\u00f5es possam ser implementadas. Todos os funcion\u00e1rios novos e existentes s\u00e3o obrigados a concluir o treinamento de privacidade anual. Um roteiro para maior presta\u00e7\u00e3o de contas em todo o setor O acordo aprovado hoje vai al\u00e9m de qualquer exig\u00eancia legal dos EUA, e acreditamos que pode e deve servir como um roteiro para uma regulamenta\u00e7\u00e3o de privacidade mais abrangente, como outras partes do mundo t\u00eam explorado. Esperamos que isso leve a mais progressos no desenvolvimento de uma legisla\u00e7\u00e3o consistente nos EUA e em outros lugares. Por fim, nosso objetivo \u00e9 honrar a privacidade das pessoas e focar em fazer o que \u00e9 certo para elas. Acreditamos que \u00e9 isso que os bilh\u00f5es de pessoas que usam nossos produtos esperam de n\u00f3s e continuaremos fazendo esse trabalho para elas.","og_url":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/","og_site_name":"Sobre a Meta","article_published_time":"2020-04-24T15:47:35+00:00","article_modified_time":"2021-06-17T13:09:41+00:00","og_image":[{"url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=890","type":"","width":"","height":""}],"author":"facebookbr","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#article","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/"},"author":"Facebook company","headline":"Acordo final com FTC representa um novo n\u00edvel de compromisso com privacidade","datePublished":"2020-04-24T15:47:35+00:00","dateModified":"2021-06-17T13:09:41+00:00","mainEntityOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/"},"wordCount":910,"publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=890","keywords":["Privacidade Importa"],"articleSection":["Recent News"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/","url":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/","name":"Acordo final com FTC representa um novo n\u00edvel de compromisso com privacidade | Sobre a Meta","isPartOf":{"@id":"https:\/\/about.fb.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#primaryimage"},"image":{"@id":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#primaryimage"},"thumbnailUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=890","datePublished":"2020-04-24T15:47:35+00:00","dateModified":"2021-06-17T13:09:41+00:00","breadcrumb":{"@id":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/"]}],"author":"Sobre a Meta"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#primaryimage","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=890","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2020\/04\/NRP-2404.jpeg?w=890"},{"@type":"BreadcrumbList","@id":"https:\/\/about.fb.com\/br\/news\/2020\/04\/acordo-final-com-ftc-representa-um-novo-nivel-de-compromisso-com-privacidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about.fb.com\/br\/"},{"@type":"ListItem","position":2,"name":"Acordo final com FTC representa um novo n\u00edvel de compromisso com privacidade"}]},{"@type":"WebSite","@id":"https:\/\/about.fb.com\/br\/#website","url":"https:\/\/about.fb.com\/news\/","name":"Sobre a Meta","description":"","publisher":{"@id":"https:\/\/about.fb.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about.fb.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about.fb.com\/br\/#organization","name":"Meta","url":"https:\/\/about.fb.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about.fb.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":26313,"url":"https:\/\/about.fb.com\/br\/news\/2025\/04\/o-caso-da-ftc-contra-a-meta-e-fragil-e-ignora-a-realidade\/","url_meta":{"origin":21348,"position":0},"title":"O caso da FTC contra a Meta \u00e9 fr\u00e1gil e ignora a realidade","author":"Meta","date":"14\/04\/2025","format":false,"excerpt":"Por Jennifer Newstead, Chief Legal Officer Na segunda-feira, 14 de abril, come\u00e7ar\u00e1 o julgamento do fr\u00e1gil processo antitruste movido pela FTC, tentando desfazer as aquisi\u00e7\u00f5es do Instagram e do WhatsApp que foram aprovadas h\u00e1 mais de 10 anos. O caso da FTC ignora como o mercado realmente funciona e busca\u2026","rel":"","context":"In &quot;Facebook&quot;","block_context":{"text":"Facebook","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/facebook\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/Screenshot-2025-04-14-at-10.35.14.png?fit=1568%2C878&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/Screenshot-2025-04-14-at-10.35.14.png?fit=1568%2C878&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/Screenshot-2025-04-14-at-10.35.14.png?fit=1568%2C878&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/Screenshot-2025-04-14-at-10.35.14.png?fit=1568%2C878&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/Screenshot-2025-04-14-at-10.35.14.png?fit=1568%2C878&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/04\/Screenshot-2025-04-14-at-10.35.14.png?fit=1568%2C878&resize=1400%2C800 4x"},"classes":[]},{"id":26975,"url":"https:\/\/about.fb.com\/br\/news\/2026\/01\/protecao-de-privacidade-mais-recente-do-whatsapp-configuracoes-rigorosas-da-conta\/","url_meta":{"origin":21348,"position":1},"title":"Prote\u00e7\u00e3o de privacidade mais recente do WhatsApp: configura\u00e7\u00f5es rigorosas da conta","author":"Meta","date":"27\/01\/2026","format":false,"excerpt":"N\u00f3s acreditamos que as pessoas devem conseguir ter conversas privadas no WhatsApp, assim como fazem na vida real. Sempre defenderemos o direito \u00e0 privacidade para todos, come\u00e7ando com a criptografia de ponta a ponta padr\u00e3o. Contudo, para al\u00e9m disso, sabemos que algumas pessoas que usam nossos servi\u00e7os, como jornalistas ou\u2026","rel":"","context":"In &quot;WhatsApp&quot;","block_context":{"text":"WhatsApp","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/whatsapp\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/WhatsApp_Protecao-de-Seguranca.jpg?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/WhatsApp_Protecao-de-Seguranca.jpg?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/WhatsApp_Protecao-de-Seguranca.jpg?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/WhatsApp_Protecao-de-Seguranca.jpg?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/WhatsApp_Protecao-de-Seguranca.jpg?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/WhatsApp_Protecao-de-Seguranca.jpg?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]},{"id":27007,"url":"https:\/\/about.fb.com\/br\/news\/2026\/03\/apresentamos-as-contas-gerenciadas-por-pais-no-whatsapp\/","url_meta":{"origin":21348,"position":2},"title":"Apresentamos as contas gerenciadas por pais no WhatsApp","author":"Meta","date":"11\/03\/2026","format":false,"excerpt":"O WhatsApp \u00e9 um espa\u00e7o seguro usado para a comunica\u00e7\u00e3o das fam\u00edlias porque \u00e9 simples, privado e confi\u00e1vel. Gra\u00e7as \u00e0s opini\u00f5es recebidas de fam\u00edlias e especialistas, estamos implementando as novas contas gerenciadas por pais, m\u00e3es ou respons\u00e1veis. Essas contas permitem configurar o WhatsApp para pr\u00e9-adolescentes, com novos controles que limitam\u2026","rel":"","context":"In &quot;Fortalecendo Comunidades&quot;","block_context":{"text":"Fortalecendo Comunidades","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/comunidades\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/03\/Brazilian-Portuguese_WhatsApp_parent-managed-accounts-1.png?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/03\/Brazilian-Portuguese_WhatsApp_parent-managed-accounts-1.png?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/03\/Brazilian-Portuguese_WhatsApp_parent-managed-accounts-1.png?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/03\/Brazilian-Portuguese_WhatsApp_parent-managed-accounts-1.png?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/03\/Brazilian-Portuguese_WhatsApp_parent-managed-accounts-1.png?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2026\/03\/Brazilian-Portuguese_WhatsApp_parent-managed-accounts-1.png?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]},{"id":26776,"url":"https:\/\/about.fb.com\/br\/news\/2025\/10\/fique-por-dentro-das-conversas-com-os-resumos-privados-de-mensagens\/","url_meta":{"origin":21348,"position":3},"title":"Fique por dentro das conversas com os resumos privados de mensagens","author":"Meta","date":"13\/10\/2025","format":false,"excerpt":"Todos j\u00e1 passamos por essa situa\u00e7\u00e3o: aquele momento em que voc\u00ea est\u00e1 correndo de uma reuni\u00e3o para a outra, tentando se atualizar depois de passar horas em um voo sem Wi-Fi ou simplesmente com mensagens demais para ler. \u00c0s vezes, tudo o que voc\u00ea precisa \u00e9 ficar por dentro do\u2026","rel":"","context":"In &quot;WhatsApp&quot;","block_context":{"text":"WhatsApp","link":"https:\/\/about.fb.com\/br\/news\/category\/technologies\/whatsapp\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/560785433_1346342276984081_8287918595290981758_n-1.png?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/560785433_1346342276984081_8287918595290981758_n-1.png?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/560785433_1346342276984081_8287918595290981758_n-1.png?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/560785433_1346342276984081_8287918595290981758_n-1.png?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/560785433_1346342276984081_8287918595290981758_n-1.png?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/560785433_1346342276984081_8287918595290981758_n-1.png?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]},{"id":26895,"url":"https:\/\/about.fb.com\/br\/news\/2025\/12\/ajudando-bilhoes-de-pessoas-a-celebrar-o-ano-novo-no-whatsapp\/","url_meta":{"origin":21348,"position":4},"title":"Ajudando bilh\u00f5es de pessoas a celebrar o Ano Novo no WhatsApp","author":"Meta","date":"29\/12\/2025","format":false,"excerpt":"O Ano Novo \u00e9 o dia mais importante para o WhatsApp. A cada ano, batemos novos recordes de mensagens e liga\u00e7\u00f5es entre amigos e familiares. Em um dia comum, promovemos o envio de 100 bilh\u00f5es de mensagens e 2 bilh\u00f5es de liga\u00e7\u00f5es, mas as 24 horas em que o mundo\u2026","rel":"","context":"In &quot;Recent News&quot;","block_context":{"text":"Recent News","link":"https:\/\/about.fb.com\/br\/news\/category\/recent-news\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/597777742_1672249653829860_6610202159098060728_n.jpg?fit=1600%2C900&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/597777742_1672249653829860_6610202159098060728_n.jpg?fit=1600%2C900&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/597777742_1672249653829860_6610202159098060728_n.jpg?fit=1600%2C900&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/597777742_1672249653829860_6610202159098060728_n.jpg?fit=1600%2C900&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/597777742_1672249653829860_6610202159098060728_n.jpg?fit=1600%2C900&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/12\/597777742_1672249653829860_6610202159098060728_n.jpg?fit=1600%2C900&resize=1400%2C800 4x"},"classes":[]},{"id":26692,"url":"https:\/\/about.fb.com\/br\/news\/2025\/10\/melhorando-suas-recomendacoes-em-nossos-aplicativos-com-ia-na-meta\/","url_meta":{"origin":21348,"position":5},"title":"Melhorando suas recomenda\u00e7\u00f5es em nossos aplicativos com IA na Meta","author":"Meta","date":"01\/10\/2025","format":false,"excerpt":"Mais de 1 bilh\u00e3o de pessoas usam Meta AI todo m\u00eas. Continuamos a melhorar a forma como nossos produtos de IA se mostram relevantes para voc\u00ea, entendem seus objetivos e ajudam a realizar tarefas de maneira mais eficiente. Tamb\u00e9m estamos usando Meta AI, bem como outros recursos de IA para\u2026","rel":"","context":"In &quot;Meta&quot;","block_context":{"text":"Meta","link":"https:\/\/about.fb.com\/br\/news\/category\/temas-home\/meta\/"},"img":{"alt_text":"","src":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Meta-Privacy-Update_Header.jpg?fit=1920%2C1080&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Meta-Privacy-Update_Header.jpg?fit=1920%2C1080&resize=350%2C200 1x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Meta-Privacy-Update_Header.jpg?fit=1920%2C1080&resize=525%2C300 1.5x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Meta-Privacy-Update_Header.jpg?fit=1920%2C1080&resize=700%2C400 2x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Meta-Privacy-Update_Header.jpg?fit=1920%2C1080&resize=1050%2C600 3x, https:\/\/about.fb.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Meta-Privacy-Update_Header.jpg?fit=1920%2C1080&resize=1400%2C800 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/21348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/users\/81109636"}],"replies":[{"embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/comments?post=21348"}],"version-history":[{"count":3,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/21348\/revisions"}],"predecessor-version":[{"id":21352,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/posts\/21348\/revisions\/21352"}],"wp:attachment":[{"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/media?parent=21348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/categories?post=21348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about.fb.com\/br\/wp-json\/wp\/v2\/tags?post=21348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}